{"id":597399,"date":"2025-07-23T13:30:01","date_gmt":"2025-07-23T11:30:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=597399&#038;preview=true&#038;preview_id=597399"},"modified":"2025-07-23T13:34:12","modified_gmt":"2025-07-23T11:34:12","slug":"transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/","title":{"rendered":"Transferts PSG : Paris entre dans la danse pour signer Rodrygo"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS &#8211; Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-marseille-piste-loic-bade\/\" target=\"_blank\" rel=\"noopener\">Transferts OM : Marseille piste Lo\u00efc Bad\u00e9<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Alors que les joueurs du <strong>Paris Saint-Germain<\/strong> sont en vacances depuis quelques jours et <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-clubs-2025-chelsea-corrige-le-psg-en-finale\/\">la finale de la Coupe du monde des clubs perdue face \u00e0 Chelsea (3-0)<\/a>, les dirigeants sont au travail pour le recrutement. \u00c0 date, le <strong>PSG<\/strong> n&rsquo;a boucl\u00e9 aucun dossier, alors que plusieurs joueurs vont revenir de leur pr\u00eat, dont l&rsquo;international <strong>Randal<\/strong> <strong>Kolo<\/strong> <strong>Muani<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Le PSG suit Rodrygo<\/h2>\n<p style=\"text-align: justify;\">Les Parisiens sont en qu\u00eate d&rsquo;un d\u00e9fenseur central et plusieurs pistes ont \u00e9t\u00e9 activ\u00e9es en ce sens, sans qu&rsquo;aucun dossier n&rsquo;aboutisse pour le moment. Devant, malgr\u00e9 le recrutement de <strong>Khvicha<\/strong> <strong>Kvaratskhelia<\/strong> l&rsquo;hiver dernier, le club de la Capitale est en qu\u00eate d&rsquo;un ailier suppl\u00e9mentaire pour la saison prochain et suivrait avec attention la situation de <strong>Rodrygo<\/strong>. <strong>Tottenham<\/strong> serait aussi en embuscade sur ce dossier complexe et on\u00e9reux.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a class=\"row-title\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-la-fin-de-la-piste-igor-paixao-a-marseille\/\" aria-label=\"\u00ab\u00a0Transferts OM : La fin de la piste Igor Paixao \u00e0 Marseille ?\u00a0\u00bb (Modifier)\">Transferts OM : La fin de la piste Igor Paixao \u00e0 Marseille ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00c9cart\u00e9 au <strong>Real<\/strong> <strong>Madrid<\/strong>, l&rsquo;attaquant br\u00e9silien est en qu\u00eate d&rsquo;un nouveau projet et c&rsquo;est Liverpool qui semble tenir la corde. Alors que les <em>Merengues<\/em> sont gourmands et r\u00e9clament pas moins de 100 millions d&rsquo;euros, les <em>Reds<\/em> sont l&rsquo;\u00e9quipe qui a le plus avanc\u00e9 sur cette piste. Le <strong>Paris Saint-Germain<\/strong> reste \u00e0 l&rsquo;aff\u00fbt et fait partie du peu de clubs capables de r\u00e9aliser l&rsquo;op\u00e9ration d&rsquo;un point de vue financier. Le recrutement de <strong>Rodrygo<\/strong> pourrait, en revanche, \u00eatre une mauvaise nouvelle pour les Fran\u00e7ais du <strong>PSG<\/strong>, <strong>Bradley<\/strong> <strong>Barcola<\/strong> et <strong>D\u00e9sir\u00e9<\/strong> <strong>Dou\u00e9<\/strong>, qui se sont partag\u00e9s la troisi\u00e8me place offensive sur la fin de la derni\u00e8re saison.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"text-align: justify;\">\u00c0 ce sujet<\/span><\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-psg-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato PSG 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato PSG 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato PSG 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS PSG - Retrouvez tous les mouvements du Paris Saint-Germain pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS &#8211; Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":597404,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,14093,7762],"class_list":["post-597399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-mercato-football","tag-mercato-psg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts PSG : Paris entre dans la danse pour signer Rodrygo<\/title>\n<meta name=\"description\" content=\"TRANSFERTS - Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts PSG : Paris entre dans la danse pour signer Rodrygo\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS - Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-23T11:30:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T11:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts PSG : Paris entre dans la danse pour signer Rodrygo\",\"datePublished\":\"2025-07-23T11:30:01+00:00\",\"dateModified\":\"2025-07-23T11:34:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png\",\"keywords\":[\"br\u00e8ve\",\"Mercato football\",\"Mercato PSG\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\",\"name\":\"Transferts PSG : Paris entre dans la danse pour signer Rodrygo\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png\",\"datePublished\":\"2025-07-23T11:30:01+00:00\",\"dateModified\":\"2025-07-23T11:34:12+00:00\",\"description\":\"TRANSFERTS - Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts PSG : Paris entre dans la danse pour signer Rodrygo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts PSG : Paris entre dans la danse pour signer Rodrygo","description":"TRANSFERTS - Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts PSG : Paris entre dans la danse pour signer Rodrygo","og_description":"TRANSFERTS - Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-07-23T11:30:01+00:00","article_modified_time":"2025-07-23T11:34:12+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts PSG : Paris entre dans la danse pour signer Rodrygo","datePublished":"2025-07-23T11:30:01+00:00","dateModified":"2025-07-23T11:34:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png","keywords":["br\u00e8ve","Mercato football","Mercato PSG"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/","name":"Transferts PSG : Paris entre dans la danse pour signer Rodrygo","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png","datePublished":"2025-07-23T11:30:01+00:00","dateModified":"2025-07-23T11:34:12+00:00","description":"TRANSFERTS - Selon Florian Plettenberg, le Paris Saint-Germain serait aussi dans la course \u00e0 la signature de Rodrygo.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/Transferts-PSG-Paris-entre-dans-la-danse-pour-Rodrygo.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-paris-entre-dans-la-danse-pour-signer-rodrygo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts PSG : Paris entre dans la danse pour signer Rodrygo"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=597399"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597399\/revisions"}],"predecessor-version":[{"id":597408,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597399\/revisions\/597408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/597404"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=597399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=597399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=597399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}