{"id":597421,"date":"2025-07-22T17:55:01","date_gmt":"2025-07-22T15:55:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=597421&#038;preview=true&#038;preview_id=597421"},"modified":"2025-07-23T15:33:36","modified_gmt":"2025-07-23T13:33:36","slug":"ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/","title":{"rendered":"Ben Healy entre dans l&rsquo;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique"},"content":{"rendered":"<p style=\"text-align: justify;\">Ben Healy a grav\u00e9 son nom dans l&rsquo;histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France. Ce moment historique s&rsquo;est d\u00e9roul\u00e9 lors de la 10e \u00e9tape de l&rsquo;\u00e9dition 2025, apr\u00e8s une course \u00e9prouvante \u00e0 travers le Massif Central qui a vu le coureur de 24 ans se hisser en t\u00eate du classement g\u00e9n\u00e9ral. Sa performance \u00e9voque des comparaisons avec de grands noms irlandais comme Stephen Roche, Sean Kelly et Shay Elliott, pla\u00e7ant Healy fermement dans une compagnie d&rsquo;\u00e9lite et ravivant l&rsquo;enthousiasme des fans de cyclisme irlandais.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9tape, longue de 165,3 kilom\u00e8tres entre Ennezat et Le Mont-Dore Puy de Sancy, a \u00e9t\u00e9 un test \u00e9reintant d&rsquo;endurance et de strat\u00e9gie. Comportant huit ascensions r\u00e9pertori\u00e9es, ce n&rsquo;\u00e9tait pas une course facile. Healy faisait partie d&rsquo;une \u00e9chapp\u00e9e de 29 hommes et a r\u00e9alis\u00e9 un effort tactiquement parfait, menant le groupe sur de longues distances et gardant le peloton \u00e0 distance. Bien qu&rsquo;il n&rsquo;ait pas remport\u00e9 l&rsquo;\u00e9tape, terminant derri\u00e8re Simon Yates, Healy a pris 29 secondes d&rsquo;avance sur Tadej Pogacar, le champion en titre et figure dominante des Tours r\u00e9cents.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;engagement des fans autour de Ben Healy et du Tour de France 2025 a atteint des niveaux exceptionnels, caract\u00e9ris\u00e9s par la fiert\u00e9, l&rsquo;\u00e9motion et l&rsquo;inclusivit\u00e9. Les r\u00e9actions sur les r\u00e9seaux sociaux, les r\u00e9actions sinc\u00e8res, et les bookmakers et les sites de <a href=\"https:\/\/www.user2019.fr\/\">retrait instantan\u00e9 paris sportif<\/a>, qui consid\u00e9raient Tadej Pogacar et Jonas Vingegaard comme les favoris, ont \u00e9t\u00e9 contraints de mettre \u00e0 jour les cotes r\u00e9guli\u00e8rement au fur et \u00e0 mesure que la course se d\u00e9roulait. La performance dramatique et l&rsquo;exploit historique de Healy dans le Tour de France 2025 ont g\u00e9n\u00e9r\u00e9 une formidable augmentation de l&rsquo;engagement des fans, tant en Irlande qu&rsquo;\u00e0 l&rsquo;\u00e9chelle internationale, montrant comment ses exploits extraordinaires ont raviv\u00e9 la passion et l&rsquo;int\u00e9r\u00eat pour le cyclisme bien au-del\u00e0 de son pays d&rsquo;origine.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;ascension de Healy vers la notori\u00e9t\u00e9 n&rsquo;a rien eu d&rsquo;accidentel. N\u00e9 en Angleterre mais courant pour l&rsquo;Irlande, il a embrass\u00e9 son h\u00e9ritage et perfectionn\u00e9 ses comp\u00e9tences au sein d&rsquo;\u00e9quipes de clubs britanniques, notamment Team Wiggins le Col. Des premi\u00e8res victoires dans les comp\u00e9titions jeunesse \u00e0 son titre de plus jeune vainqueur d&rsquo;\u00e9tape du Tour de l&rsquo;Avenir, le potentiel de Healy a toujours \u00e9t\u00e9 \u00e9vident. Sa progression constante \u00e0 travers les titres des moins de 23 ans et ses performances marquantes ont culmin\u00e9 avec ses d\u00e9buts en WorldTour avec EF Education-EasyPost en 2022, o\u00f9 il a commenc\u00e9 \u00e0 v\u00e9ritablement d\u00e9montrer ses capacit\u00e9s sur la sc\u00e8ne internationale.<\/p>\n<p style=\"text-align: justify;\">La saison 2023 s&rsquo;est av\u00e9r\u00e9e \u00eatre la campagne de r\u00e9v\u00e9lation de Healy. Un triomphe en solitaire de 50 km au Giro d&rsquo;Italia et de solides performances dans les Classiques ardennaises ont soulign\u00e9 son style caract\u00e9ristique, ses attaques de loin, son rythme implacable et son instinct pour saisir les moments cl\u00e9s. Ces caract\u00e9ristiques ont \u00e9t\u00e9 pleinement d\u00e9montr\u00e9es dans le Tour de cette ann\u00e9e, en particulier lors de la 6e \u00e9tape et de l&rsquo;effort r\u00e9cent de la 10e \u00e9tape qui lui a valu le maillot jaune. Healy roule avec conviction et pr\u00e9cision, m\u00ealant le sens tactique \u00e0 la puissance brute, des qualit\u00e9s qui portent d\u00e9sormais leurs fruits sur la plus grande sc\u00e8ne du cyclisme.<\/p>\n<p style=\"text-align: justify;\">Derri\u00e8re chaque grand coureur, il y a une \u00e9quipe, et l&rsquo;\u00e9quipe EF Education-EasyPost de Healy a jou\u00e9 un r\u00f4le essentiel. Le manager Jonathan Vaughters a lou\u00e9 la combinaison de force mentale et d&rsquo;endurance physiologique de Healy, notant \u00e0 quel point il est rare de trouver les deux traits chez un m\u00eame coureur. Des co\u00e9quipiers comme Alex Baudin et Harry Sweeny ont \u00e9t\u00e9 essentiels pour g\u00e9rer les \u00e9chapp\u00e9es et d\u00e9fendre les positions. Cette unit\u00e9 et cette coh\u00e9sion strat\u00e9gique ont permis \u00e0 Healy de rouler agressivement sans sacrifier les objectifs \u00e0 long terme, un \u00e9quilibre que de nombreux coureurs peinent \u00e0 ma\u00eetriser.<\/p>\n<p style=\"text-align: justify;\">Le <a href=\"https:\/\/www.lequipe.fr\/Cyclisme-sur-route\/Actualites\/Tour-de-france-2025-victoire-de-simon-yates-et-maillot-jaune-pour-ben-healy-l-echappee-fait-coup-double-sur-la-10e-etape\/1578099\">moment de Healy en jaune<\/a> r\u00e9sonne bien au-del\u00e0 de l&rsquo;individu. Porter le maillot est un symbole d&rsquo;excellence, \u00e9levant non seulement l&rsquo;athl\u00e8te, mais aussi l&rsquo;\u00e9quipe et la nation derri\u00e8re lui. Les fans irlandais, tant chez eux qu&rsquo;au bord de la route, se r\u00e9jouissent du retour des couleurs de leur pays sous les feux de la rampe du Tour. Pour beaucoup, cela ressemble \u00e0 un renouveau de l&rsquo;\u00e2ge d&rsquo;or du cyclisme irlandais. La r\u00e9action \u00e9motionnelle de Healy en recevant le maillot, les larmes, l&rsquo;incr\u00e9dulit\u00e9 et la pure joie, ont captur\u00e9 la gravit\u00e9 de ce qu&rsquo;il avait accompli et de ce que cela repr\u00e9sente.<\/p>\n<p style=\"text-align: justify;\">Alors que le Tour entre dans sa seconde moiti\u00e9, Healy fait face \u00e0 son d\u00e9fi le plus difficile : conserver le maillot jaune \u00e0 travers les hautes Alpes et les contre-la-montre techniques. Tadej Pogacar reste une menace s\u00e9rieuse, avec d&rsquo;autres pr\u00e9tendants au classement g\u00e9n\u00e9ral juste derri\u00e8re. Chaque ascension, descente et d\u00e9cision tactique a d\u00e9sormais un poids plus important. La pression sera immense, mais si les dix premi\u00e8res \u00e9tapes sont une indication, Healy a \u00e0 la fois le sang-froid et la force de continuer \u00e0 se battre. La semaine prochaine d\u00e9terminera si ce conte de f\u00e9es se poursuit ou prend un tournant dramatique.<\/p>\n<p style=\"text-align: justify;\">Au-del\u00e0 de ce Tour, l&rsquo;impact de Healy pourrait s&rsquo;\u00e9tendre au monde du cyclisme au sens large. Son style audacieux et agressif et sa personnalit\u00e9 pos\u00e9e apportent une nouvelle saveur au peloton, d\u00e9fiant les dynamiques \u00e9tablies et offrant un nouveau r\u00e9cit aux fans. \u00c0 seulement 24 ans, son potentiel semble incroyablement \u00e9lev\u00e9. Qu&rsquo;il porte ou non le maillot jaune \u00e0 Paris, Ben Healy a d\u00e9j\u00e0 prouv\u00e9 qu&rsquo;il fait partie de l&rsquo;\u00e9lite du sport, et son parcours inspirera la prochaine g\u00e9n\u00e9ration de coureurs irlandais.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;ascension de Ben Healy vers le maillot jaune est plus qu&rsquo;une perc\u00e9e ; c&rsquo;est un moment historique en devenir. Gr\u00e2ce \u00e0 la pers\u00e9v\u00e9rance, \u00e0 une brillance tactique et \u00e0 une <a href=\"https:\/\/www.lepoint.fr\/sport\/tour-de-france-ben-healy-mister-panache-15-07-2025-2594384_26.php\">ambition implacable<\/a>, il a raviv\u00e9 la passion pour le cyclisme irlandais et captiv\u00e9 les publics du monde entier. Alors que la course entre dans ses \u00e9tapes d\u00e9cisives, tous les regards restent tourn\u00e9s vers l&rsquo;homme en jaune, symbole de promesse, de courage et d&rsquo;un coureur qui red\u00e9finit ce qui est possible dans la plus grande course du monde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ben Healy a grav\u00e9 son nom dans l&rsquo;histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.<\/p>\n","protected":false},"author":1,"featured_media":594082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"0","footnotes":""},"categories":[2307],"tags":[],"class_list":["post-597421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ben Healy entre dans l&#039;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique<\/title>\n<meta name=\"description\" content=\"Ben Healy a grav\u00e9 son nom dans l&#039;histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ben Healy entre dans l&#039;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique\" \/>\n<meta property=\"og:description\" content=\"Ben Healy a grav\u00e9 son nom dans l&#039;histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-22T15:55:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T13:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ben Healy entre dans l&#039;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Ben Healy entre dans l&rsquo;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique\",\"datePublished\":\"2025-07-22T15:55:01+00:00\",\"dateModified\":\"2025-07-23T13:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\"},\"wordCount\":1135,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png\",\"articleSection\":[\"Cyclisme\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\",\"name\":\"Ben Healy entre dans l'histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png\",\"datePublished\":\"2025-07-22T15:55:01+00:00\",\"dateModified\":\"2025-07-23T13:33:36+00:00\",\"description\":\"Ben Healy a grav\u00e9 son nom dans l'histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png\",\"width\":1200,\"height\":674,\"caption\":\"6\u00e8me \u00e9tape Tour de France 2025 Ben Healy s\u2019offre la victoire au terme d\u2019un grand num\u00e9ro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ben Healy entre dans l&rsquo;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<meta name=\"Googlebot-News\" content=\"noindex\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ben Healy entre dans l'histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique","description":"Ben Healy a grav\u00e9 son nom dans l'histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/","og_locale":"fr_FR","og_type":"article","og_title":"Ben Healy entre dans l'histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique","og_description":"Ben Healy a grav\u00e9 son nom dans l'histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.","og_url":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-07-22T15:55:01+00:00","article_modified_time":"2025-07-23T13:33:36+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Ben Healy entre dans l'histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Ben Healy entre dans l&rsquo;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique","datePublished":"2025-07-22T15:55:01+00:00","dateModified":"2025-07-23T13:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/"},"wordCount":1135,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png","articleSection":["Cyclisme"],"inLanguage":"fr-FR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/","url":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/","name":"Ben Healy entre dans l'histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png","datePublished":"2025-07-22T15:55:01+00:00","dateModified":"2025-07-23T13:33:36+00:00","description":"Ben Healy a grav\u00e9 son nom dans l'histoire du cyclisme en devenant le premier Irlandais en 38 ans \u00e0 enfiler le tr\u00e8s convoit\u00e9 maillot jaune du Tour de France.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/07\/6eme-etape-Tour-de-France-2025-Ben-Healy-soffre-la-victoire-au-terme-dun-grand-numero.png","width":1200,"height":674,"caption":"6\u00e8me \u00e9tape Tour de France 2025 Ben Healy s\u2019offre la victoire au terme d\u2019un grand num\u00e9ro"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ben-healy-entre-dans-lhistoire-en-jaune-tous-les-regards-sur-healy-alors-que-le-tour-entre-dans-une-phase-critique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ben Healy entre dans l&rsquo;histoire en jaune : Tous les regards sur Healy alors que le Tour entre dans une phase critique"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]},"Googlebot_News":"noindex"},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=597421"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597421\/revisions"}],"predecessor-version":[{"id":597422,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/597421\/revisions\/597422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/594082"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=597421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=597421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=597421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}