{"id":59879,"date":"2020-02-11T17:25:49","date_gmt":"2020-02-11T16:25:49","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=59879&#038;preview=true&#038;preview_id=59879"},"modified":"2020-02-12T08:11:30","modified_gmt":"2020-02-12T07:11:30","slug":"maillot-des-bleus-pour-euro-2020-hommage-france-98","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/","title":{"rendered":"Le maillot des Bleus pour l&rsquo;Euro 2020 en hommage \u00e0 France 98 ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Si ce n&rsquo;est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l&rsquo;\u00e9quipe de France pour cette ann\u00e9e 2020, et donc pour le prochain Euro.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Selon des photos du site <strong><em>Footy Headlines<\/em><\/strong>\u00a0relay\u00e9es par <strong><em>Eurosport<\/em><\/strong>, le futur maillot de l&rsquo;<strong>\u00e9quipe de France de football<\/strong> sera plac\u00e9 sous le signe d&rsquo;un retour dans le pass\u00e9. Un hommage \u00e0 celui port\u00e9 par les Bleus, vainqueurs de la Coupe du monde en 1998. Une bande horizontale rouge, puis quatre lignes blanches en-dessous. Pas de doute, ce maillot va rappeler de grands souvenirs.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-59880 aligncenter\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/86177726_1373986502803537_2737045197312491520_n.jpg\" alt=\"\" width=\"720\" height=\"801\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/86177726_1373986502803537_2737045197312491520_n.jpg 720w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/86177726_1373986502803537_2737045197312491520_n-270x300.jpg 270w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si ce n&rsquo;est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l&rsquo;\u00e9quipe de France pour cette ann\u00e9e 2020, et donc pour le prochain Euro.<\/p>\n","protected":false},"author":1,"featured_media":59884,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[199,75,30],"class_list":["post-59879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-equipe-de-france","tag-football","tag-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le maillot des Bleus pour l&#039;Euro 2020 en hommage \u00e0 France 98 ?<\/title>\n<meta name=\"description\" content=\"Si ce n&#039;est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l&#039;\u00e9quipe de France pour l&#039;Euro 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le maillot des Bleus pour l&#039;Euro 2020 en hommage \u00e0 France 98 ?\" \/>\n<meta property=\"og:description\" content=\"Si ce n&#039;est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l&#039;\u00e9quipe de France pour l&#039;Euro 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-11T16:25:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-12T07:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le maillot des Bleus pour l&#039;Euro 2020 en hommage \u00e0 France 98 ?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Le maillot des Bleus pour l&rsquo;Euro 2020 en hommage \u00e0 France 98 ?\",\"datePublished\":\"2020-02-11T16:25:49+00:00\",\"dateModified\":\"2020-02-12T07:11:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\"},\"wordCount\":107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png\",\"keywords\":[\"\u00c9quipe de France\",\"Football\",\"France\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\",\"name\":\"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98 ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png\",\"datePublished\":\"2020-02-11T16:25:49+00:00\",\"dateModified\":\"2020-02-12T07:11:30+00:00\",\"description\":\"Si ce n'est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l'\u00e9quipe de France pour l'Euro 2020.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png\",\"width\":800,\"height\":445,\"caption\":\"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le maillot des Bleus pour l&rsquo;Euro 2020 en hommage \u00e0 France 98 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98 ?","description":"Si ce n'est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l'\u00e9quipe de France pour l'Euro 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/","og_locale":"fr_FR","og_type":"article","og_title":"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98 ?","og_description":"Si ce n'est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l'\u00e9quipe de France pour l'Euro 2020.","og_url":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-02-11T16:25:49+00:00","article_modified_time":"2020-02-12T07:11:30+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98 ?","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Le maillot des Bleus pour l&rsquo;Euro 2020 en hommage \u00e0 France 98 ?","datePublished":"2020-02-11T16:25:49+00:00","dateModified":"2020-02-12T07:11:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/"},"wordCount":107,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png","keywords":["\u00c9quipe de France","Football","France"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/","url":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/","name":"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98 ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png","datePublished":"2020-02-11T16:25:49+00:00","dateModified":"2020-02-12T07:11:30+00:00","description":"Si ce n'est pas encore officiel, plusieurs fuites ont r\u00e9v\u00e9l\u00e9 le probable maillot de l'\u00e9quipe de France pour l'Euro 2020.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/02\/Le-maillot-des-Bleus-pour-lEuro-2020-en-hommage-\u00e0-France-98.png","width":800,"height":445,"caption":"Le maillot des Bleus pour l'Euro 2020 en hommage \u00e0 France 98"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/maillot-des-bleus-pour-euro-2020-hommage-france-98\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le maillot des Bleus pour l&rsquo;Euro 2020 en hommage \u00e0 France 98 ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/59879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=59879"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/59879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/59884"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=59879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=59879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=59879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}