{"id":600107,"date":"2025-08-03T13:54:42","date_gmt":"2025-08-03T11:54:42","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=600107&#038;preview=true&#038;preview_id=600107"},"modified":"2025-08-06T13:03:21","modified_gmt":"2025-08-06T11:03:21","slug":"transferts-florian-thauvin-proche-de-signer-a-lens","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/","title":{"rendered":"Transferts : Florian Thauvin proche de signer \u00e0 Lens"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>TRANSFERTS &#8211; Selon <a href=\"https:\/\/www.lequipe.fr\/Football\/Article\/Mercato-lens-fonce-sur-florian-thauvin\/1582809\">L&rsquo;\u00c9quipe<\/a>, le RC Lens serait proche d&rsquo;obtenir la signature de Florian Thauvin (Udinese).\u00a0<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-om-timothy-weah-va-enfin-signer-a-marseille\/\">Transferts OM : Timothy Weah va enfin signer \u00e0 Marseille<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le RC Lens devait faire des \u00e9conomies cet \u00e9t\u00e9, et a vendu plusieurs joueurs de premier plan comme <strong>Facundo<\/strong> <strong>Medina<\/strong> \u00e0 l&rsquo;Olympique de Marseille, et <strong>Neil El Aynaoui<\/strong> \u00e0 l&rsquo;AS Rome. Dans le sens des arriv\u00e9es, les Lensois ont fait des recrues \u00e0 prix r\u00e9duit, comme <strong>Mathieu<\/strong> <strong>Udol,<\/strong> qui arrive de Metz, ou encore <strong>Samson<\/strong> <strong>Baidoo<\/strong> qui d\u00e9barque de Strasbourg.<\/p>\n<h2 style=\"text-align: justify;\">Florian Thauvin \u00e0 un pas de Lens<\/h2>\n<p style=\"text-align: justify;\">Mais depuis plusieurs semaines, le duo compos\u00e9 de <strong>Jean-Louis<\/strong> <strong>Leca<\/strong> et <strong>Benjamin<\/strong> <strong>Parrot<\/strong> travaille sur un gros dossier en sous-marin. Et sauf retournement de situation, les Sang et Or devraient recruter l&rsquo;international fran\u00e7ais, <strong>Florian<\/strong> <strong>Thuavin<\/strong>. Courtis\u00e9 par la <strong>Fiorentina<\/strong> voil\u00e0 quelques semaines, l&rsquo;ancien joueur de l&rsquo;<strong>OM<\/strong> devrait finalement faire son retour en Ligue 1.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-rennes-arsenal-veut-signer-jeremy-jacquet\/\">Transferts Rennes : Arsenal veut signer J\u00e9r\u00e9my Jacquet<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Florian Thauvin<\/strong> n&rsquo;a plus qu&rsquo;un an de contrat \u00e0 l&rsquo;<strong>Udinese,<\/strong> et sort d&rsquo;une belle saison \u00e0 9 buts et 5 passes d\u00e9cisives. Alors qu&rsquo;il a donn\u00e9 son accord au <strong>RC<\/strong> <strong>Lens<\/strong> il y a quelques jours, les deux clubs sont en train de trouver un accord pour un transfert estim\u00e9 \u00e0 6 millions d&rsquo;euros. D\u00e9j\u00e0 peu appr\u00e9ci\u00e9 \u00e0 Lille \u00e0 cause de sa vraie-fausse venue il y a quelques saisons, <strong>Florian<\/strong> <strong>Thauvin<\/strong> va donc signer chez le grand rival dans les jours \u00e0 venir.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"text-align: justify;\">\u00c0 ce sujet<\/span><\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-lens-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato Lens 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Lens-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato Lens 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Lens-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Lens-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Lens-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-Lens-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato Lens 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS LENS - Retrouvez tous les mouvements du Racing Club de Lens pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS &#8211; Selon L&rsquo;\u00c9quipe, le RC Lens serait proche d&rsquo;obtenir la signature de Florian Thauvin (Udinese).\u00a0<\/p>\n","protected":false},"author":1,"featured_media":600108,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,14093,1889],"class_list":["post-600107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-mercato-football","tag-om"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Florian Thauvin proche de signer \u00e0 Lens<\/title>\n<meta name=\"description\" content=\"TRANSFERTS - Selon L&#039;\u00c9quipe, le RC Lens serait proche d&#039;obtenir la signature de Florian Thauvin (Udinese).\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Florian Thauvin proche de signer \u00e0 Lens\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS - Selon L&#039;\u00c9quipe, le RC Lens serait proche d&#039;obtenir la signature de Florian Thauvin (Udinese).\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-03T11:54:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T11:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"TRANSFERTS - Le Paris Saint-Germain garde un \u0153il sur Lucas Chevalier alors que la situation de Gianluigi Donnarumma reste floue.\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Florian Thauvin proche de signer \u00e0 Lens\",\"datePublished\":\"2025-08-03T11:54:42+00:00\",\"dateModified\":\"2025-08-06T11:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\"},\"wordCount\":346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png\",\"keywords\":[\"br\u00e8ve\",\"Mercato football\",\"OM\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\",\"name\":\"Transferts : Florian Thauvin proche de signer \u00e0 Lens\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png\",\"datePublished\":\"2025-08-03T11:54:42+00:00\",\"dateModified\":\"2025-08-06T11:03:21+00:00\",\"description\":\"TRANSFERTS - Selon L'\u00c9quipe, le RC Lens serait proche d'obtenir la signature de Florian Thauvin (Udinese).\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Florian Thauvin proche de signer \u00e0 Lens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Florian Thauvin proche de signer \u00e0 Lens","description":"TRANSFERTS - Selon L'\u00c9quipe, le RC Lens serait proche d'obtenir la signature de Florian Thauvin (Udinese).\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Florian Thauvin proche de signer \u00e0 Lens","og_description":"TRANSFERTS - Selon L'\u00c9quipe, le RC Lens serait proche d'obtenir la signature de Florian Thauvin (Udinese).\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-08-03T11:54:42+00:00","article_modified_time":"2025-08-06T11:03:21+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_description":"TRANSFERTS - Le Paris Saint-Germain garde un \u0153il sur Lucas Chevalier alors que la situation de Gianluigi Donnarumma reste floue.","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Florian Thauvin proche de signer \u00e0 Lens","datePublished":"2025-08-03T11:54:42+00:00","dateModified":"2025-08-06T11:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png","keywords":["br\u00e8ve","Mercato football","OM"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/","name":"Transferts : Florian Thauvin proche de signer \u00e0 Lens","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png","datePublished":"2025-08-03T11:54:42+00:00","dateModified":"2025-08-06T11:03:21+00:00","description":"TRANSFERTS - Selon L'\u00c9quipe, le RC Lens serait proche d'obtenir la signature de Florian Thauvin (Udinese).\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-Florian-Thauvin-proche-de-signer-a-Lens.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-florian-thauvin-proche-de-signer-a-lens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Florian Thauvin proche de signer \u00e0 Lens"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/600107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=600107"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/600107\/revisions"}],"predecessor-version":[{"id":600118,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/600107\/revisions\/600118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/600108"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=600107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=600107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=600107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}