{"id":602946,"date":"2025-08-15T11:29:10","date_gmt":"2025-08-15T09:29:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=602946&#038;preview=true&#038;preview_id=602946"},"modified":"2025-08-15T11:36:44","modified_gmt":"2025-08-15T09:36:44","slug":"transferts-psg-denouement-dans-le-dossier-randal-kolo-muani","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/","title":{"rendered":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS PSG &#8211; Le PSG va se d\u00e9barrasser de l&rsquo;un de ses ind\u00e9sirables. Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato estival.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-willem-geubbels-tout-proche-de-signer-au-paris-fc\/\">Transferts : Willem Geubbels tout proche de signer au Paris FC<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le d\u00e9graissage s&rsquo;acc\u00e9l\u00e8re du c\u00f4t\u00e9 du Paris Saint-Germain. Alors qu&rsquo;un <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-psg-gianluigi-donnarumma-annonce-son-depart\/\">d\u00e9part de Gianluigi Donnarumma<\/a> devrait \u00eatre boucl\u00e9 avant la fin du mercato, un autre international pouss\u00e9 vers la sortie a trouv\u00e9 une nouvelle terre d&rsquo;accueil. Pr\u00eat\u00e9 \u00e0 la Juventus la saison derni\u00e8re, <strong>Randal Kolo Muani<\/strong> n&rsquo;aura fait qu&rsquo;un bref retour dans la capitale cet \u00e9t\u00e9. Barr\u00e9 par la concurrence et n&rsquo;entrant plus dans les plans de <strong>Luis Enrique<\/strong>, l&rsquo;attaquant s&rsquo;appr\u00eate \u00e0 repartir en Italie la saison prochaine.<\/p>\n<h2 style=\"text-align: justify;\">Randal Kolo Muani retrouve la Juventus<\/h2>\n<p style=\"text-align: justify;\">En effet, selon le m\u00e9dia italien <a href=\"https:\/\/www.tuttosport.com\/news\/calcio\/serie-a\/juventus\/2025\/08\/15-142540313\/calciomercato_juve_kolo_muani_col_parma_le_cifre_messe_sul_tavolo_da_comolli_vlahovic_o_meno\"><em>Tuttosport<\/em><\/a>, la <strong>Juventus<\/strong> est parvenue \u00e0 trouver un accord avec le PSG pour se faire pr\u00eater le joueur une saison suppl\u00e9mentaire. Il faut dire que l&rsquo;attaquant de 26 ans a laiss\u00e9 un bon souvenir dans le Pi\u00e9mont en trouvant le chemin des filets \u00e0 10 reprises en 21 matchs, toutes comp\u00e9titions confondues.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-rennes-direction-la-premier-league-pour-arnaud-kalimuendo\/\">Transferts Rennes : Direction la Premier League pour Arnaud Kalimuendo<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">De belles performances qui ont pouss\u00e9 la Vieille Dame \u00e0 faire un bel effort pour l&rsquo;attirer. En effet, les deux clubs se sont entendus sur un <strong>pr\u00eat payant d&rsquo;un an \u00e0 hauteur de 10 M\u20ac<\/strong>, le tout agr\u00e9ment\u00e9 d&rsquo;une <strong>option d&rsquo;achat de 45 M\u20ac<\/strong>. En additionnant les 5 M\u20ac d\u00e9j\u00e0 r\u00e9cup\u00e9r\u00e9s lors du premier pr\u00eat, le PSG pourrait donc \u00e0 terme r\u00e9cup\u00e9rer une somme totale de 60 M\u20ac pour <strong>Kolo Muani<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Par ailleurs, <em>Tuttosport<\/em> pr\u00e9cise que la Juve est d\u00e9termin\u00e9e \u00e0 boucler rapidement le dossier afin de permettre \u00e0 <strong>Igor Tudor<\/strong> d&rsquo;aligner sa nouvelle recrue d\u00e8s la 1\u00e8re journ\u00e9e de S\u00e9rie A \u00e0 Parme, le dimanche 24 ao\u00fbt.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udea8 Accord trouv\u00e9 entre la Juventus et le PSG pour Kolo Muani ! \ud83e\udd1d\ud83c\uddeb\ud83c\uddf7<\/p>\n<p>Pr\u00eat payant se 10M\u20ac avec une obligation d\u2019achat \u00e0 45M\u20ac ! \ud83e\udd11<\/p>\n<p>\ud83d\uddde\ufe0f <a href=\"https:\/\/twitter.com\/tuttosport?ref_src=twsrc%5Etfw\">@tuttosport<\/a> <a href=\"https:\/\/t.co\/HdSfO5St5K\">pic.twitter.com\/HdSfO5St5K<\/a><\/p>\n<p>\u2014 La Minute Foot (@La_Minute_Foot) <a href=\"https:\/\/twitter.com\/La_Minute_Foot\/status\/1956276431031292365?ref_src=twsrc%5Etfw\">August 15, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-psg-2025-2026-le-tableau-complet-des-transferts-arrivees-et-departs\/\" class=\"vlp-link\" title=\"Mercato PSG 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mercato PSG 2025-2026 Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/05\/Mercato-PSG-2025-2026-Le-tableau-complet-des-transferts-arrivees-et-departs-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mercato PSG 2025-2026 : Le tableau complet des transferts, arriv\u00e9es et d\u00e9parts<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS PSG - Retrouvez tous les mouvements du Paris Saint-Germain pour l'intersaison 2025 en Ligue 1. Arriv\u00e9es, d\u00e9part, pr\u00eats, transferts d\u00e9finitifs, ne ratez rien du mercato estival.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS PSG &#8211; Le PSG va se d\u00e9barrasser de l&rsquo;un de ses ind\u00e9sirables. Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato estival.<\/p>\n","protected":false},"author":55,"featured_media":602947,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,1554,910,2832],"class_list":["post-602946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-ligue-1","tag-psg","tag-transferts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani<\/title>\n<meta name=\"description\" content=\"TRANSFERTS PSG - Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS PSG - Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T09:29:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T09:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani\",\"datePublished\":\"2025-08-15T09:29:10+00:00\",\"dateModified\":\"2025-08-15T09:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\"},\"wordCount\":470,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png\",\"keywords\":[\"br\u00e8ve\",\"Ligue 1\",\"PSG\",\"transferts\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\",\"name\":\"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png\",\"datePublished\":\"2025-08-15T09:29:10+00:00\",\"dateModified\":\"2025-08-15T09:36:44+00:00\",\"description\":\"TRANSFERTS PSG - Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani","description":"TRANSFERTS PSG - Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani","og_description":"TRANSFERTS PSG - Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-08-15T09:29:10+00:00","article_modified_time":"2025-08-15T09:36:44+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani","datePublished":"2025-08-15T09:29:10+00:00","dateModified":"2025-08-15T09:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/"},"wordCount":470,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png","keywords":["br\u00e8ve","Ligue 1","PSG","transferts"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/","name":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png","datePublished":"2025-08-15T09:29:10+00:00","dateModified":"2025-08-15T09:36:44+00:00","description":"TRANSFERTS PSG - Plac\u00e9 dans le loft, Randal Kolo Muani a trouv\u00e9 une porte de sortie \u00e0 une quinzaine de jours de la fermeture du mercato.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Transferts-PSG-Denouement-dans-le-dossier-Randal-Kolo-Muani.png","width":1200,"height":674,"caption":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-psg-denouement-dans-le-dossier-randal-kolo-muani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts PSG : D\u00e9nouement dans le dossier Randal Kolo Muani"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/602946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=602946"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/602946\/revisions"}],"predecessor-version":[{"id":602953,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/602946\/revisions\/602953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/602947"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=602946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=602946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=602946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}