{"id":602963,"date":"2025-08-15T14:16:12","date_gmt":"2025-08-15T12:16:12","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=602963&#038;preview=true&#038;preview_id=602963"},"modified":"2025-08-15T14:49:26","modified_gmt":"2025-08-15T12:49:26","slug":"tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/","title":{"rendered":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&rsquo;exclusion de 5 \u00e9quipes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOUR DE ROMANDIE FEMMES 2025 &#8211; Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e de 4,4km, \u00e0 Villars-sur-Ollon. Un r\u00e9sultat qui est pass\u00e9 au second plan puisque 5 \u00e9quipes majeures n&rsquo;ont pas pris le d\u00e9part en raison d&rsquo;un d\u00e9saccord avec l&rsquo;UCI.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Tout simplement ubuesque. Le terme colle parfaitement \u00e0 la situation v\u00e9cue en ouverture du <strong>Tour de Romandie<\/strong> <strong>F<\/strong><b>emmes <\/b>ce vendredi. Une dizaine de jours apr\u00e8s le succ\u00e8s total du Tour de France, le calendrier World Tour reprenait ses droits en terres suisses avec 16 \u00e9quipes, dont 15 ayant pris part \u00e0 la Grande Boucle.<\/p>\n<h2 style=\"text-align: justify;\">Cinq \u00e9quipes exclues avant le d\u00e9part<\/h2>\n<p style=\"text-align: justify;\">Mais avant le d\u00e9part, un v\u00e9ritable coup de tonnerre s&rsquo;est abattu \u00e0 <strong>Hu\u00e9moz<\/strong> : 6 \u00e9quipes ont \u00e9t\u00e9 exclues \u00e0 moins de 2 heures du d\u00e9but du prologue de 4,4km menant \u00e0 <strong>Villars-sur-Ollon<\/strong> ! La raison ? Une bisbille entre ces m\u00eames \u00e9quipes et l&rsquo;UCI en raison d&rsquo;un nouveau capteur GPS qui devait \u00eatre mis en place sur les coureuses en vue des championnats du monde. Si les deux camps n&rsquo;ont toujours pas trouv\u00e9 un accord quant au GPS \u00e0 utiliser, l&rsquo;UCI souhaitait qu&rsquo;une seule coureuse de chaque \u00e9quipe soit \u00e9quip\u00e9e pour ce Tour de Romandie. Par ailleurs, l&rsquo;instance aurait impos\u00e9 le syst\u00e8me sans l&rsquo;installer ni assurer son suivi, laissant la responsabilit\u00e9 aux \u00e9quipes. Ce qui n&rsquo;a pas \u00e9t\u00e9 accept\u00e9 par ces derni\u00e8res. Un probl\u00e8me de fond qui a des r\u00e9percussions d\u00e9sastreuses sur la course suisse.<\/p>\n<p style=\"text-align: justify;\">Si l&rsquo;AG Insurance-Soudal a finalement pris le d\u00e9part, la <strong>Lidl-Trek<\/strong>, la <strong>Canyon\/\/SRAM<\/strong>, la <strong>Visma Lease a Bike<\/strong>, <strong>EF Education-Oatly<\/strong> et la <strong>Picnic PostNL<\/strong> n&rsquo;ont pas pris le d\u00e9part ! Ce sont donc<strong> 30 des 93 coureuses<\/strong> inscrites sur la startlist qui ne participeront pas \u00e0 l&rsquo;\u00e9preuve. Parmi elles, <strong>Katarzyna Niewiadoma<\/strong>, <strong>Elisa Balsamo<\/strong>, <strong>No\u00e9mie R\u00fcegg<\/strong> ou encore <strong>Niamh Fisher-Black<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Regarding Tour Romandie Feminin. The 5 teams that were disqualified by UCI were disqualified NOT for refusing the mandated(not agreed upon) GPS, but for not nominating which rider should carry the device and asking the UCI to nominate the rider. Difficult to understand? I agree.<\/p>\n<p>\u2014 Jonathan Vaughters (@Vaughters) <a href=\"https:\/\/twitter.com\/Vaughters\/status\/1956310946961322005?ref_src=twsrc%5Etfw\">August 15, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Paula Blasi cartonne le chrono, Juliette Labous sur la bo\u00eete<\/h2>\n<p style=\"text-align: justify;\">Suite \u00e0 cet imbroglio, le d\u00e9part a \u00e9t\u00e9 donn\u00e9 sur la rampe dans ce contexte particulier. Avec 2,2km d&rsquo;ascension \u00e0 8,7%, ce premier prologue a permis d&rsquo;\u00e9tablir une premi\u00e8re hi\u00e9rarchie. \u00c0 mi-parcours, <strong>Alena Ivanchenko<\/strong> (UAE Team ADQ) tenait la meilleure marque, mais la Russe a finalement \u00e9t\u00e9 battue par la sp\u00e9cialiste de l&rsquo;effort solitaire, la Suissesse <strong>Steffi H\u00e4berlin<\/strong> (SD Worx-ProTime). Seulement quelques minutes plus tard, <strong>Erica Magnaldi<\/strong> (UAE Team ADQ) s&rsquo;est arrach\u00e9e pour redonner la 1\u00e8re place \u00e0 son \u00e9quipe pour moins de 2 petites secondes.<\/p>\n<p style=\"text-align: justify;\">Toutefois, cela ne serait pas suffisant pour rafler la mise, les meilleures grimpeuses n&rsquo;\u00e9tant pas encore parties. <strong>Ur\u0161ka \u017digart\u00a0<\/strong>(AG Insurance-Soudal) a ainsi repouss\u00e9 une premi\u00e8re fois le meilleur chrono de 11 secondes, avant que l&rsquo;Espagnole <strong>Paula Blasi<\/strong> (UAE Team ADQ) franchisse un cap en bouclant les 4,4km en 11&rsquo;17\u00a0\u00bb, soit 17 secondes de moins que \u017digart. Un temps d\u00e9tonnant, d&rsquo;autant plus que les premi\u00e8res favorites du jour n&rsquo;ont pas r\u00e9ussi \u00e0 s&rsquo;approcher. <strong>Yara Kastelijn<\/strong> (Fenix-Deceuninck) a \u00e9chou\u00e9 \u00e0 25 secondes, tandis que <strong>Silvia Persico<\/strong> (UAE Team ADQ) ou <strong>Mavi Garcia<\/strong> (Jayco-AlUla) ont fini loin du Top 10. Derni\u00e8re \u00e0 s&rsquo;\u00e9lancer, <strong>Juliette Labous<\/strong> (FDJ-Suez) a d\u00fb \u00e9galement se r\u00e9soudre \u00e0 rendre les armes, mais elle s&#8217;empare d&rsquo;une belle 3\u00e8me place, \u00e0 19 secondes de la t\u00eate.<\/p>\n<p style=\"text-align: justify;\">Du haut de ses 22 ans, <strong>Paula Blasi<\/strong> ouvre son compteur de victoires en World Tour avec la mani\u00e8re, et confirme une excellente ann\u00e9e 2025, marqu\u00e9e par des victoires en France (Pointe du Raz Ladies Classic, La P\u00e9rigord Ladies). Demain, elle portera la tunique de leader au sein d&rsquo;un peloton qui sera, h\u00e9las, amput\u00e9 d&rsquo;un tiers de son effectif initial&#8230;<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Victoire de Paula Blasi ! Enorme r\u00e9sultat pour la jeune espagnole, qui signe sa 1\u00e8re victoire en World Tour et sa 4\u00e8me de la saison pour sa premi\u00e8re saison pro ! <a href=\"https:\/\/twitter.com\/hashtag\/TDRF2025?src=hash&amp;ref_src=twsrc%5Etfw\">#TDRF2025<\/a><\/p>\n<p>\u2014 Elise (@elise_caley) <a href=\"https:\/\/twitter.com\/elise_caley\/status\/1956328565651198357?ref_src=twsrc%5Etfw\">August 15, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE ROMANDIE FEMMES 2025 &#8211; Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e de 4,4km, \u00e0 Villars-sur-Ollon. Un r\u00e9sultat qui est pass\u00e9 au second plan puisque 5 \u00e9quipes majeures n&rsquo;ont pas pris le d\u00e9part en raison d&rsquo;un d\u00e9saccord avec l&rsquo;UCI.<\/p>\n","protected":false},"author":55,"featured_media":602993,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[16878,574,11197,7747],"class_list":["post-602963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-tour-de-romandie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&#039;exclusion de 5 \u00e9quipes<\/title>\n<meta name=\"description\" content=\"TOUR DE ROMANDIE FEMMES 2025 - Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e \u00e0 Villars-sur-Ollon.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&#039;exclusion de 5 \u00e9quipes\" \/>\n<meta property=\"og:description\" content=\"TOUR DE ROMANDIE FEMMES 2025 - Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e \u00e0 Villars-sur-Ollon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T12:16:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T12:49:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&#039;exclusion de 5 \u00e9quipes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&rsquo;exclusion de 5 \u00e9quipes\",\"datePublished\":\"2025-08-15T12:16:12+00:00\",\"dateModified\":\"2025-08-15T12:49:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\"},\"wordCount\":721,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png\",\"keywords\":[\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Tour de Romandie\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\",\"name\":\"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png\",\"datePublished\":\"2025-08-15T12:16:12+00:00\",\"dateModified\":\"2025-08-15T12:49:26+00:00\",\"description\":\"TOUR DE ROMANDIE FEMMES 2025 - Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e \u00e0 Villars-sur-Ollon.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&rsquo;exclusion de 5 \u00e9quipes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes","description":"TOUR DE ROMANDIE FEMMES 2025 - Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e \u00e0 Villars-sur-Ollon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes","og_description":"TOUR DE ROMANDIE FEMMES 2025 - Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e \u00e0 Villars-sur-Ollon.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-08-15T12:16:12+00:00","article_modified_time":"2025-08-15T12:49:26+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&rsquo;exclusion de 5 \u00e9quipes","datePublished":"2025-08-15T12:16:12+00:00","dateModified":"2025-08-15T12:49:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/"},"wordCount":721,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png","keywords":["br\u00e8ve","Cyclisme","Cyclisme sur route","Tour de Romandie"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/","name":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png","datePublished":"2025-08-15T12:16:12+00:00","dateModified":"2025-08-15T12:49:26+00:00","description":"TOUR DE ROMANDIE FEMMES 2025 - Paula Blasi (UAE Team ADQ) a remport\u00e9 la 1\u00e8re \u00e9tape, un contre-la-montre en mont\u00e9e \u00e0 Villars-sur-Ollon.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Tour-de-Romandie-Femmes-2025-Paula-Blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes.png","width":1200,"height":674,"caption":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l'exclusion de 5 \u00e9quipes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-femmes-2025-paula-blasi-remporte-une-1ere-etape-ubuesque-marquee-par-lexclusion-de-5-equipes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de Romandie Femmes 2025 : Paula Blasi remporte une 1\u00e8re \u00e9tape ubuesque, marqu\u00e9e par l&rsquo;exclusion de 5 \u00e9quipes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/602963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=602963"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/602963\/revisions"}],"predecessor-version":[{"id":603006,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/602963\/revisions\/603006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/602993"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=602963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=602963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=602963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}