{"id":603444,"date":"2025-08-17T11:04:10","date_gmt":"2025-08-17T09:04:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=603444&#038;preview=true&#038;preview_id=603444"},"modified":"2025-08-27T09:57:43","modified_gmt":"2025-08-27T07:57:43","slug":"eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/","title":{"rendered":"EuroBasket 2025 (H) : La liste des 12 joueurs de l&rsquo;\u00e9quipe de France pour la comp\u00e9tition"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EUROBASKET 2025 &#8211; Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Hier, <strong>l&rsquo;\u00e9quipe de France hommes<\/strong> a poursuivi son sans-faute dans sa pr\u00e9paration pour l&rsquo;EuroBasket, qui aura lieu du 27 ao\u00fbt au 14 septembre prochain dans plusieurs pays. Les Bleus se sont relev\u00e9s d&rsquo;une premi\u00e8re p\u00e9riode rat\u00e9e pour vaincre l&rsquo;Espagne pour la deuxi\u00e8me fois en trois jours. De tr\u00e8s bon augure pour la suite. Mais apr\u00e8s la victoire, venait le temps des choix.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/preparation-eurobasket-2025-h-menes-de-16-points-les-bleus-renversent-lespagne\/\" class=\"vlp-link\" title=\"Pr\u00e9paration EuroBasket 2025 (H) : Men\u00e9s de 16 points, les Bleus renversent l&#039;Espagne\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Preparation-EuroBasket-2025-H-Menes-de-16-points-les-Bleus-renversent-lEspagne.png\" class=\"attachment-800x445 size-800x445\" alt=\"Un mauvais passage rapidement oubli\u00e9 d\u00e8s le retour du facteur X Sylvain Francisco. Suite \u00e0 un shoot ext\u00e9rieur de Yabusele, le meneur a enfil\u00e9 un drive avant de provoquer deux pertes de balle par sa d\u00e9fense intense. Si le money time est encore loin, l&#039;\u00e9tau s&#039;est resserr\u00e9 en d\u00e9fense de part et d&#039;autres. Le jeu est cantonn\u00e9 sur demi-terrain, et les Bleus se montrant plus \u00e0 l&#039;aise dans cette configuration. Suite \u00e0 un dunk de Jaiteh pour \u00e9galiser, Jaylen Hoard s&#039;est charg\u00e9 de faire la bascule avec des lancers et un nouveau dunk (71-67) ! En t\u00eate durant 35 minutes, l&#039;Espagne a pris un coup fatal sur le casque. D\u00e9sormais sans solution, cette derni\u00e8re ne reviendra pas, subissant un assassinat en r\u00e8gle \u00e0 3 points d&#039;un coutumier du fait, Matthew Strazel, \u00e0 30 secondes du buzzer ! Devant un public chauff\u00e9 \u00e0 blanc par ce sc\u00e9nario renversant, la France boucle sa double confrontation face \u00e0 l&#039;Espagne par deux victoires. Deux matchs qui vont permettre \u00e0 Fr\u00e9d\u00e9ric Fauthoux de d\u00e9finitivement coucher une liste finale de 12 noms pour la comp\u00e9tition.\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Preparation-EuroBasket-2025-H-Menes-de-16-points-les-Bleus-renversent-lEspagne.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Preparation-EuroBasket-2025-H-Menes-de-16-points-les-Bleus-renversent-lEspagne-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Preparation-EuroBasket-2025-H-Menes-de-16-points-les-Bleus-renversent-lEspagne-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Preparation-EuroBasket-2025-H-Menes-de-16-points-les-Bleus-renversent-lEspagne-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Pr\u00e9paration EuroBasket 2025 (H) : Men\u00e9s de 16 points, les Bleus renversent l'Espagne<\/div><div class=\"vlp-block-1 vlp-link-summary\">PR\u00c9PARATION EUROBASKET 2025 - Ce samedi, l'\u00e9quipe de France a de nouveau battu l'Espagne, 78-73. Men\u00e9s toute la partie et rel\u00e9gu\u00e9s \u00e0 -16 \u00e0 la pause, les Tricolores ont rebondi en entamant la seconde p\u00e9riode tambour battant, avant de faire la diff\u00e9rence dans le money time.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">En conf\u00e9rence de presse d&rsquo;apr\u00e8s-match, le s\u00e9lectionneur <strong>Fr\u00e9d\u00e9ric Fauthoux<\/strong>, pour qui ce sera la premi\u00e8re grande comp\u00e9tition \u00e0 la t\u00eate de l&rsquo;\u00e9quipe de France, a assur\u00e9 ne plus vouloir \u201c<i>jouer avec les nerfs des joueurs<\/i>\u201d. Il a tenu parole et r\u00e9v\u00e9l\u00e9 ce matin la liste des 12 qui iront \u00e0 l&rsquo;EuroBasket.<\/p>\n<p style=\"text-align: justify;\">Puisque<strong> Vincent Poirier<\/strong> a d\u00e9clar\u00e9 forfait sur blessure, il ne restait plus qu&rsquo;un joueur \u00e0 couper. Le choix s&rsquo;est port\u00e9 sur <strong>Nadir Hifi<\/strong>, en balance depuis le d\u00e9but de la pr\u00e9paration, et moins en vue sur les derniers matchs, mais ce dernier sera tout de m\u00eame de la partie apr\u00e8s le forfait de <strong>Matthew Strazel<\/strong>. <strong>Sylvain Francisco<\/strong> sauve sa t\u00eate, alors qu&rsquo;aucun pivot n&rsquo;a \u00e9t\u00e9 rappel\u00e9, <strong>Moussa Diabat\u00e9<\/strong>, coup\u00e9 au d\u00e9but de la pr\u00e9paration, a d\u00e9clin\u00e9 une offre de retour selon le s\u00e9lectionneur.<\/p>\n<h2 style=\"text-align: justify;\">La liste des 12<\/h2>\n<p style=\"text-align: justify;\"><strong>Guards : Sylvain Francisco<\/strong> (Zalgiris) &#8211;\u00a0 <strong>Th\u00e9o Maledon<\/strong> (Real Madrid) &#8211; <del><strong>Matthew Strazel<\/strong> (Monaco)<\/del> FORFAIT, remplac\u00e9 par <strong>Nadir Hifi<\/strong> (Paris Basket) &#8211; <strong>\u00c9lie Okobo<\/strong> (Monaco) &#8211;<strong> Isa\u00efa Cordinier<\/strong> (Anadolu)<\/p>\n<p style=\"text-align: justify;\"><strong>Forwards : Bilal Coulibaly<\/strong> (Washington Wizards) &#8211; <strong>Zaccharie Risacher<\/strong> (Atlanta Hawks) &#8211; <strong>Timoth\u00e9 Luwawu-Cabarrot<\/strong> (Baskonia) &#8211; <strong>Guerschon Yabusele<\/strong> (New York Knicks, capitaine) &#8211; <strong>Jaylen Hoard<\/strong>\u00a0(Maccabi Tel-Aviv)<\/p>\n<p style=\"text-align: justify;\"><strong> Pivots : Mouhammadou Jaiteh<\/strong> (BC Duba\u00ef) &#8211; <strong>Alexandre Sarr<\/strong> (Washington Wizards)<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udea8 Les 12 bleus pour l&rsquo;Eurobasket !<\/p>\n<p>On connait les 12 qui disputeront l&rsquo;Euro, puisque Freddy Fauthoux a d\u00e9cid\u00e9 de couper Nadir Hifi.<\/p>\n<p>Isaia Cordinier<br \/>\nBilal Coulibaly<br \/>\nSylvain Francisco<br \/>\nJaylen Hoard<br \/>\nMam&rsquo; Jaiteh<br \/>\nTimoth\u00e9 Luwawu-Cabarrot<br \/>\nTh\u00e9o Maledon<br \/>\nElie Okobo<br \/>\nZaccharie Risacher\u2026 <a href=\"https:\/\/t.co\/HY6G4jcZCC\">pic.twitter.com\/HY6G4jcZCC<\/a><\/p>\n<p>\u2014 Basket-Infos (@Basket_Infos) <a href=\"https:\/\/twitter.com\/Basket_Infos\/status\/1957005602137219194?ref_src=twsrc%5Etfw\">August 17, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROBASKET 2025 &#8211; Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.<\/p>\n","protected":false},"author":59,"featured_media":603445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47000],"tags":[16878,359,1782,30],"class_list":["post-603444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eurobasket","tag-breve","tag-espagne","tag-eurobasket","tag-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroBasket 2025 (H) : La liste des 12 joueurs de l&#039;\u00e9quipe de France pour la comp\u00e9tition<\/title>\n<meta name=\"description\" content=\"EUROBASKET 2025 - Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroBasket 2025 (H) : La liste des 12 joueurs de l&#039;\u00e9quipe de France pour la comp\u00e9tition\" \/>\n<meta property=\"og:description\" content=\"EUROBASKET 2025 - Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-17T09:04:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T07:57:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroBasket 2025 (H) : La liste des 12 joueurs de l&#039;\u00e9quipe de France pour la comp\u00e9tition\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"EuroBasket 2025 (H) : La liste des 12 joueurs de l&rsquo;\u00e9quipe de France pour la comp\u00e9tition\",\"datePublished\":\"2025-08-17T09:04:10+00:00\",\"dateModified\":\"2025-08-27T07:57:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png\",\"keywords\":[\"br\u00e8ve\",\"Espagne\",\"eurobasket\",\"France\"],\"articleSection\":[\"EuroBasket\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\",\"name\":\"EuroBasket 2025 (H) : La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png\",\"datePublished\":\"2025-08-17T09:04:10+00:00\",\"dateModified\":\"2025-08-27T07:57:43+00:00\",\"description\":\"EUROBASKET 2025 - Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png\",\"width\":1200,\"height\":674,\"caption\":\"EuroBasket 2025 (H) La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroBasket 2025 (H) : La liste des 12 joueurs de l&rsquo;\u00e9quipe de France pour la comp\u00e9tition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroBasket 2025 (H) : La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition","description":"EUROBASKET 2025 - Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroBasket 2025 (H) : La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition","og_description":"EUROBASKET 2025 - Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.","og_url":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-08-17T09:04:10+00:00","article_modified_time":"2025-08-27T07:57:43+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"EuroBasket 2025 (H) : La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"EuroBasket 2025 (H) : La liste des 12 joueurs de l&rsquo;\u00e9quipe de France pour la comp\u00e9tition","datePublished":"2025-08-17T09:04:10+00:00","dateModified":"2025-08-27T07:57:43+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png","keywords":["br\u00e8ve","Espagne","eurobasket","France"],"articleSection":["EuroBasket"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/","url":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/","name":"EuroBasket 2025 (H) : La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png","datePublished":"2025-08-17T09:04:10+00:00","dateModified":"2025-08-27T07:57:43+00:00","description":"EUROBASKET 2025 - Le suspense est termin\u00e9, puisque Fr\u00e9d\u00e9ric Fauthoux a d\u00e9livr\u00e9 la liste des 12 joueurs qui porteront le maillot bleu pour la comp\u00e9tition.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/EuroBasket-2025-H-La-liste-des-12-joueurs-de-lequipe-de-France-pour-la-competition.png","width":1200,"height":674,"caption":"EuroBasket 2025 (H) La liste des 12 joueurs de l'\u00e9quipe de France pour la comp\u00e9tition"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-2025-h-la-liste-des-12-joueurs-de-lequipe-de-france-pour-la-competition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroBasket 2025 (H) : La liste des 12 joueurs de l&rsquo;\u00e9quipe de France pour la comp\u00e9tition"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/603444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=603444"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/603444\/revisions"}],"predecessor-version":[{"id":605806,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/603444\/revisions\/605806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/603445"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=603444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=603444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=603444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}