{"id":607579,"date":"2025-09-01T16:00:57","date_gmt":"2025-09-01T14:00:57","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=607579&#038;preview=true&#038;preview_id=607579"},"modified":"2025-09-01T14:19:43","modified_gmt":"2025-09-01T12:19:43","slug":"ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/","title":{"rendered":"Ligue 1 2025\/2026 : L&rsquo;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Ligue 1 2025\/2026 &#8211; Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Tops<\/h2>\n<p style=\"text-align: justify;\"><strong>Le Paris-Saint-Germain et Jo\u00e3o Neves relancent enfin la machine<\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s deux succ\u00e8s sur le plus petit des scores (1-0), face \u00e0 <strong>Nantes<\/strong> et <strong>Angers<\/strong>, le <strong>Paris-Saint-Germain <\/strong>a paraph\u00e9 une grosse victoire, <strong>6 \u00e0<\/strong> <strong>3<\/strong>, sur la pelouse de <strong>Toulouse<\/strong>. Le champion de France a notamment \u00e9t\u00e9 port\u00e9 par le spectaculaire tripl\u00e9 de <strong>Jo\u00e3o<\/strong> <strong>Neves<\/strong>. Le milieu de terrain portugais a tout d\u2019abord ouvert le score avec un retourn\u00e9 acrobatique \u00e0 la 7\u00e8me minute de jeu, \u00e0 bout portant. Apr\u00e8s le but du break de <strong>Bradley<\/strong> <strong>Barcola<\/strong> (9\u2019), <strong>Neves<\/strong> s\u2019est offert un second joyau, encore une fois sur un retourn\u00e9 acrobatique pour porter le score \u00e0 3-0.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s le doubl\u00e9 sur penalty de <strong>Demb\u00e9l\u00e9<\/strong>, l\u2019ancien joueur de Benfica a achev\u00e9 son chef-d&rsquo;\u0153uvre d\u2019une frappe de l\u2019ext\u00e9rieur de la surface, en pleine lucarne pour le 6 \u00e0 1 (78\u2019). Le succ\u00e8s parisien a \u00e9galement \u00e9t\u00e9 marqu\u00e9 par le double arr\u00eat sur penalty de <strong>Lucas<\/strong> <strong>Chevalier<\/strong>. Sur un penalty tir\u00e9 deux fois, l\u2019ancien lillois s\u2019est interpos\u00e9, face \u00e0 <strong>Magri<\/strong> puis face \u00e0 <strong>C\u00e1sseres Jr<\/strong>. Malgr\u00e9 un l\u00e9ger rel\u00e2chement en fin de match et deux buts encaiss\u00e9s, les <strong>Parisiens<\/strong> prennent la t\u00eate du championnat avec l\u2019<strong>OL<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Po\u00e9sie en mouvement. \ud83c\udfb6 <a href=\"https:\/\/t.co\/QASLXI5jE4\">pic.twitter.com\/QASLXI5jE4<\/a><\/p>\n<p>\u2014 Ligue 1 McDonald&rsquo;s (@Ligue1) <a href=\"https:\/\/twitter.com\/Ligue1\/status\/1962276713121145142?ref_src=twsrc%5Etfw\">August 31, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<strong>L\u2019OL seul rival du Paris-Saint-Germain en t\u00eate<\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s trois journ\u00e9es, seulement trois \u00e9quipes ont gagn\u00e9 leurs trois matchs, le <strong>Paris Saint-Germain<\/strong> et <strong>l\u2019Olympique Lyonnais<\/strong>, vainqueur de <strong>l\u2019Olympique de Marseille<\/strong> en cl\u00f4ture du week-end. Dans un match facilit\u00e9 par le carton rouge <strong>d\u2019Egan-Riley<\/strong> \u00e0 la 29\u00e8me minute, <strong>l\u2019OL<\/strong> a ma\u00eetris\u00e9 sa rencontre du d\u00e9but \u00e0 la fin malgr\u00e9 des difficult\u00e9s dans les derniers m\u00e8tres. Une victoire finalement arrach\u00e9e dans les derniers instants sur un but contre son camp de <strong>Leo<\/strong> <strong>Balerdi<\/strong> (<strong>1-0, 88\u2019<\/strong>).<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-j3-avec-solidite-patience-et-opportunisme-lol-a-fini-par-dominer-lom\/\" class=\"vlp-link\" title=\"Ligue 1 2025\/2026 (J3) : Avec solidit\u00e9, patience et opportunisme, l\u2019OL a fini par dominer l\u2019OM\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-1-20252026-J3-Avec-solidite-patience-et-opportunisme-lOL-a-fini-par-dominer-lOM-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Ligue 1 20252026 (J3) Avec solidit\u00e9, patience et opportunisme, l\u2019OL a fini par dominer l\u2019OM\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-1-20252026-J3-Avec-solidite-patience-et-opportunisme-lOL-a-fini-par-dominer-lOM-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-1-20252026-J3-Avec-solidite-patience-et-opportunisme-lOL-a-fini-par-dominer-lOM-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-1-20252026-J3-Avec-solidite-patience-et-opportunisme-lOL-a-fini-par-dominer-lOM-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-1-20252026-J3-Avec-solidite-patience-et-opportunisme-lOL-a-fini-par-dominer-lOM-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Ligue 1 2025\/2026 (J3) : Avec solidit\u00e9, patience et opportunisme, l\u2019OL a fini par dominer l\u2019OM<\/div><div class=\"vlp-block-1 vlp-link-summary\">LIGUE 1 2025-2026 - L\u2019Olympique Lyonnais s\u2019impose dans le premier Olympico de la saison. R\u00e9duit \u00e0 dix, l\u2019OM c\u00e8de 1-0 et laisse l\u2019OL reprendre la t\u00eate de la Ligue 1.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">Au-del\u00e0 d\u2019un jeu convaincant, les <strong>Rhodaniens<\/strong> ont montr\u00e9 un esprit combatif et collectif, int\u00e9ressant en vue du d\u00e9but de la campagne europ\u00e9enne apr\u00e8s la tr\u00eave internationale. Alors qu\u2019au vu de la situation financi\u00e8re du club, la saison s\u2019annon\u00e7ait compliqu\u00e9e pour l\u2019OL, le mois d\u2019ao\u00fbt montre plut\u00f4t le visage d\u2019une \u00e9quipe candidate aux places en Ligue des champions.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">LA FOLIEEE \ud83d\ude31 <a href=\"https:\/\/t.co\/JCsvtNyqIj\">pic.twitter.com\/JCsvtNyqIj<\/a><\/p>\n<p>\u2014 Ligue 1 McDonald&rsquo;s (@Ligue1) <a href=\"https:\/\/twitter.com\/Ligue1\/status\/1962274769933365754?ref_src=twsrc%5Etfw\">August 31, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<strong>Le festival offensif du LOSC<\/strong><\/p>\n<p style=\"text-align: justify;\">Face au promu lorientais, le <strong>LOSC<\/strong> a attendu la seconde mi-temps pour d\u00e9rouler son jeu puisque les deux \u00e9quipes sont rentr\u00e9es aux vestiaires sur un score de 0-0. Mais d\u00e8s le d\u00e9but de la seconde p\u00e9riode, <strong>Perraud<\/strong> a inscrit sous ses nouvelles couleurs pour ouvrir le score (46\u2019, 1-1). Quelques minutes apr\u00e8s, <strong>Fernandez-Pardo<\/strong> a doubl\u00e9 la mise pour le <strong>LOSC<\/strong>. Les <strong>Merlus<\/strong> ont ensuite r\u00e9duit l\u2019\u00e9cart malgr\u00e9 le penalty manqu\u00e9 de <strong>Soumano<\/strong> (<strong>64\u2019<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s ce but des bretons, les Lillois ont d\u00e9roul\u00e9 avec le doubl\u00e9 inscrit par <strong>Fernandez-Prado<\/strong>. La nouvelle recrue de vendredi, <strong>Hamza<\/strong> <strong>Igamane<\/strong> en est \u00e9galement all\u00e9 de son doubl\u00e9 pour son premier match avec <strong>Lille<\/strong>. <strong>Haraldsson<\/strong> et <strong>Sahraoui<\/strong> sont les derniers buteurs lillois de la partie. Malgr\u00e9 l\u2019absence d\u2019<strong>Olivier<\/strong> <strong>Giroud<\/strong>, buteurs sur les deux matchs pr\u00e9c\u00e9dents, le <strong>LOSC<\/strong> a d\u00e9roul\u00e9 avec cette victoire <strong>7 \u00e0 1<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>La premi\u00e8re victoire du Paris FC en ligue 1 depuis 46 ans<\/strong><\/p>\n<p style=\"text-align: justify;\">Pour son premier match \u00e0 domicile au stade Jean Bouin, le <strong>Paris FC<\/strong> a remport\u00e9 une victoire importante face au <strong>FC Metz<\/strong>. Dans ce duel, entre promus, les deux \u00e9quipes \u00e9taient en besoin de points apr\u00e8s deux d\u00e9faites en deux journ\u00e9es. Un match qui est mal parti pour les <strong>Parisiens<\/strong> avec l\u2019ouverture du score messine. Sur un corner tir\u00e9 au second poteau, <strong>Sadibou<\/strong> <strong>San\u00e9<\/strong> reprend le ballon avec une vol\u00e9e acrobatique qui termine sous la barre de la cage de <strong>Kevin<\/strong> <strong>Trapp<\/strong> (0-1, 22\u2019). Mais juste avant le retour au vestiaire, les Parisiens ont \u00e9galis\u00e9 gr\u00e2ce au penalty provoqu\u00e9 puis transform\u00e9 par <strong>Ilan<\/strong> <strong>Kebbal<\/strong> (1-1, 45+3\u2019).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Un but synonyme de victoire historique \ud83d\ude4c <a href=\"https:\/\/t.co\/kJ19O90rWs\">pic.twitter.com\/kJ19O90rWs<\/a><\/p>\n<p>\u2014 Ligue 1 McDonald&rsquo;s (@Ligue1) <a href=\"https:\/\/twitter.com\/Ligue1\/status\/1962425194103947582?ref_src=twsrc%5Etfw\">September 1, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Et au retour des vestiaires, c\u2019est encore une fois le milieu offensif alg\u00e9rien qui marque et qui permet au\u00a0<strong>PFC<\/strong>\u00a0de prendre l\u2019avantage pour la premi\u00e8re fois cette saison. Mais les Parisiens vont permettre aux Messins d\u2019\u00e9galiser, apr\u00e8s une perte de balle de\u00a0<strong>Maxime<\/strong>\u00a0<strong>Lopez<\/strong>\u00a0au milieu de terrain,\u00a0<strong>Gauthier<\/strong>\u00a0<strong>Hein<\/strong>\u00a0va remettre son \u00e9quipe \u00e0 \u00e9galit\u00e9. C\u2019est alors que le\u00a0<strong>PFC<\/strong>\u00a0va inscrire le but d\u00e9cisif par l\u2019interm\u00e9diaire de\u00a0<strong>Moses<\/strong>\u00a0<strong>Simon<\/strong>\u00a0(<strong>3-2, 67\u2019<\/strong>). Premi\u00e8re victoire importante pour le\u00a0<strong>Paris<\/strong>\u00a0<strong>FC<\/strong>\u00a0qui bat un concurrent direct au maintien, pour le moment.<\/p>\n<p style=\"text-align: justify;\"><strong>La bonne op\u00e9ration du Havre face \u00e0 Nice<\/strong><\/p>\n<p style=\"text-align: justify;\">Dans la course au maintien, <strong>Le<\/strong> <strong>Havre<\/strong> a fait une tr\u00e8s belle op\u00e9ration gr\u00e2ce \u00e0 sa victoire 3-1 face \u00e0 Nice \u00e0 domicile. Apr\u00e8s deux d\u00e9faites lors des deux premi\u00e8res journ\u00e9es, les <strong>Havrais<\/strong> recevaient une \u00e9quipe de <strong>l\u2019OGC Nice<\/strong> en difficult\u00e9 depuis le d\u00e9but de saison et leurs d\u00e9faites en barrages de qualifications. Dans un 4-5-1 habituel, les hommes de <strong>Didier Digard<\/strong> ont parfaitement d\u00e9but\u00e9 leur rencontre avec l\u2019ouverture du score de <strong>Doucour\u00e9<\/strong>. Sur un centre de <strong>Soumar\u00e9<\/strong>, l\u2019ailier droit havrais conclut en une touche dans une position d\u2019avant-centre inhabituelle. Mais les <strong>Normands<\/strong> se font surprendre au retour des vestiaires avec l\u2019\u00e9galisation d\u2019<strong>Oppong<\/strong>. Apr\u00e8s un bon travail de <strong>Boudaoui<\/strong> sur le c\u00f4t\u00e9, gauche, le d\u00e9fenseur ghan\u00e9en coupe au premier poteau sur une reprise sans force, mais profite du manque de fermet\u00e9 dans les gants de <strong>Mory<\/strong> <strong>Diaw<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le <strong>HAC<\/strong> a ensuite repris la ma\u00eetrise en se cr\u00e9ant de bonnes occasions dans la surface ni\u00e7oise. Et reprend l\u2019avantage, sur un centre de <strong>Doucour\u00e9<\/strong> sur le c\u00f4t\u00e9 droit, <strong>Antoine<\/strong> <strong>Mendy<\/strong> rate son contr\u00f4le puis en d\u00e9gageant le ballon rebondit sur <strong>Rassoul<\/strong> <strong>Ndiaye<\/strong> qui envoie le ballon au fond des filets de <strong>Diouf<\/strong>. Dans les derni\u00e8res minutes, les <strong>Havrais<\/strong> ont profit\u00e9 de la pr\u00e9sence de <strong>Diouf<\/strong> dans leur surface pour porter une derni\u00e8re contre-attaque et inscrire le troisi\u00e8me but dans une cage vide (<strong>3-1, 90+5\u2019<\/strong>). Victoire tr\u00e8s importante du <strong>Havre<\/strong> dans la course au maintien qui passe devant leurs adversaires, au classement.<\/p>\n<h2 style=\"text-align: justify;\">Flops<\/h2>\n<p style=\"text-align: justify;\"><strong>L\u2019OM en difficult\u00e9, les Anglais pas au rendez-vous<\/strong><\/p>\n<p style=\"text-align: justify;\">Dans le choc de cette 3\u00e8me journ\u00e9e, <strong>l\u2019Olympique de Marseille<\/strong> s\u2019est montr\u00e9 en grande difficult\u00e9 autant avant, que apr\u00e8s l\u2019exclusion <strong>d\u2019Egan-Riley<\/strong>. Dans un premier temps, la d\u00e9fense \u00e0 trois de <strong>De Zerbi<\/strong> a eu \u00e9norm\u00e9ment de mal \u00e0 couvrir les appels en profondeur des attaquants lyonnais. Cela a \u00e9t\u00e9 prouv\u00e9 par le carton rouge <strong>d\u2019Egan-Riley<\/strong>, sur le d\u00e9part en profondeur de <strong>Malick<\/strong> <strong>Fofana<\/strong>, provoqu\u00e9 par une perte de balle de <strong>Balerdi<\/strong>. Mais l\u2019animation offensive marseillaise a \u00e9t\u00e9 tr\u00e8s compliqu\u00e9e \u00e9galement.<\/p>\n<p style=\"text-align: justify;\">L\u2019attaquant anglais <strong>Mason<\/strong> <strong>Greenwood<\/strong> a montr\u00e9 un tr\u00e8s mauvais visage, tr\u00e8s peu impactant dans les contre-attaques marseillaises, l\u00e0 o\u00f9 on aurait pu attendre de sa vitesse avec <strong>Aubameyang<\/strong> et <strong>Hamed<\/strong> <strong>Traor\u00e9<\/strong>. Performance d\u00e9cevante \u00e9galement de son compatriote, <strong>Angel<\/strong> <strong>Gomes<\/strong> qui a manqu\u00e9 son coup dans son r\u00f4le de meneur de jeu des attaques marseillaises. L\u2019<strong>OM<\/strong> va devoir rapidement se remettre dans le bon sens, avec la r\u00e9ception de <strong>Lorient<\/strong> dans deux semaines, avant le premier match de Ligue des champions face au <strong>Real<\/strong> <strong>Madrid<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Brest confirme un d\u00e9but de saison difficile, Majecki voit rouge<\/strong><\/p>\n<p style=\"text-align: justify;\">En ouverture de cette troisi\u00e8me journ\u00e9e, <strong>Brest<\/strong> se d\u00e9pla\u00e7ait \u00e0 Lens avec la pr\u00e9sence de nouvelles recrues comme <strong>Daouda<\/strong> <strong>Guindo<\/strong>, mais sans <strong>Lees-Melou<\/strong> transf\u00e9r\u00e9 au <strong>Paris<\/strong> <strong>FC<\/strong>, la veille. Apr\u00e8s un match nul face \u00e0 <strong>Lille<\/strong> lors de la premi\u00e8re journ\u00e9e et une d\u00e9faite \u00e0 <strong>Toulouse<\/strong> le week-end dernier, la formation d&rsquo;<strong>Eric<\/strong> <strong>Roy<\/strong> se d\u00e9pla\u00e7ait \u00e0 <strong>Bollaert<\/strong> avec un besoin de points urgent. Une mission rat\u00e9e par les <strong>Brestois<\/strong> avec une d\u00e9faite 3-1 face aux <strong>Nordistes<\/strong>. Pourtant, l\u2019affaire \u00e9tait bien embarqu\u00e9e avec l\u2019ouverture du score \u00e0 la 24\u00e8me minute de <strong>Mama<\/strong> <strong>Bald\u00e9<\/strong>, parfaitement servi par <strong>Kamory<\/strong> <strong>Doumbia<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Certes, <strong>Brest<\/strong> \u00e9tait domin\u00e9, mais \u00e9tait efficace. Tout se passait plut\u00f4t bien jusqu\u2019\u00e0 la 55\u00e8me minute et la sortie compl\u00e9tement rat\u00e9e de <strong>Radoslaw<\/strong> <strong>Majecki<\/strong>. Sur un ballon en profondeur d\u2019<strong>Aguilar<\/strong> pour <strong>Fofana<\/strong>, le gardien polonais fauche l\u2019attaquant lensois dans la surface. Le gardien pr\u00eat\u00e9 par Monaco a logiquement \u00e9t\u00e9 sanctionn\u00e9 d\u2019un carton rouge et d\u2019un penalty transform\u00e9 par <strong>Florian<\/strong> <strong>Thauvin<\/strong>. Et c\u2019est alors le d\u00e9but du calvaire pour les <strong>Brestois<\/strong>, qui vont conc\u00e9der 19 tirs en seconde p\u00e9riode pour une d\u00e9faite 3 buts \u00e0 1. \u00c7a fait donc seulement 1 point en trois matches pour <strong>Brest<\/strong> qui vit un d\u00e9but de saison tr\u00e8s compliqu\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>Calvaire d\u00e9fensif pour Lorient<\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s une premi\u00e8re p\u00e9riode plut\u00f4t r\u00e9ussie, la d\u00e9fense lorientaise s\u2019est compl\u00e9tement effondr\u00e9e en seconde p\u00e9riode. Face \u00e0 <strong>Lille<\/strong>, le promu lorientais a conc\u00e9d\u00e9 <strong>7 buts en seconde p\u00e9riode<\/strong>, un record dans l\u2019histoire de la Ligue 1. Alors que le d\u00e9but de saison avait \u00e9t\u00e9 rassur\u00e9 par la large victoire 4 buts \u00e0 0 face \u00e0 un <strong>Stade<\/strong> <strong>Rennais<\/strong> r\u00e9duit \u00e0 9, les <strong>Merlus<\/strong> sont vite revenus sur terre cette large d\u00e9fait 7 buts \u00e0 1 face au <strong>LOSC<\/strong>. La d\u00e9fense \u00e0 trois de Lorient a compl\u00e9tement \u00e9t\u00e9 d\u00e9pass\u00e9e par le jeu en profondeur des <strong>Lillois<\/strong> et par la vitesse de leurs attaquants. Les combinaisons \u00e0 trois entre <strong>Igamane<\/strong>, <strong>Correia<\/strong> et <strong>Fernandez-Pardo<\/strong> ont d\u00e9boussol\u00e9 les <strong>Merlus<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ligue 1 2025\/2026 &#8211; Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.<\/p>\n","protected":false},"author":110,"featured_media":607599,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,1554],"class_list":["post-607579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-ligue-1"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 1 2025\/2026 : L&#039;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"Ligue 1 2025\/2026 - Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 2025\/2026 : L&#039;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Ligue 1 2025\/2026 - Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-01T14:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Malo Clement\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue 1 2025\/2026 : L&#039;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\"},\"author\":{\"name\":\"Malo Clement\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce\"},\"headline\":\"Ligue 1 2025\/2026 : L&rsquo;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e\",\"datePublished\":\"2025-09-01T14:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\"},\"wordCount\":1766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png\",\"keywords\":[\"br\u00e8ve\",\"Ligue 1\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\",\"name\":\"Ligue 1 2025\/2026 : L'OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png\",\"datePublished\":\"2025-09-01T14:00:57+00:00\",\"description\":\"Ligue 1 2025\/2026 - Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png\",\"width\":1200,\"height\":674,\"caption\":\"Ligue 1 20252026 L'OL victorieux, Joao Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 2025\/2026 : L&rsquo;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce\",\"name\":\"Malo Clement\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png\",\"caption\":\"Malo Clement\"},\"description\":\"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue 1 2025\/2026 : L'OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e","description":"Ligue 1 2025\/2026 - Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 2025\/2026 : L'OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e","og_description":"Ligue 1 2025\/2026 - Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-09-01T14:00:57+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png","type":"image\/png"}],"author":"Malo Clement","twitter_card":"summary_large_image","twitter_title":"Ligue 1 2025\/2026 : L'OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/"},"author":{"name":"Malo Clement","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce"},"headline":"Ligue 1 2025\/2026 : L&rsquo;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e","datePublished":"2025-09-01T14:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/"},"wordCount":1766,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png","keywords":["br\u00e8ve","Ligue 1"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/","name":"Ligue 1 2025\/2026 : L'OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png","datePublished":"2025-09-01T14:00:57+00:00","description":"Ligue 1 2025\/2026 - Juste avant la tr\u00eave internationale, la Ligue 1 a \u00e9t\u00e9 agit\u00e9 avec 39 buts inscrits en 9 rencontres ce week-end. Voici les tops et flops de la 3\u00e8me journ\u00e9e de championnat.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-LOL-victorieux-Joao-Neves-acrobatique-Lorient-sombre-les-tops-et-flops-de-la-3eme-journee.png","width":1200,"height":674,"caption":"Ligue 1 20252026 L'OL victorieux, Joao Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-lol-victorieux-joao-neves-acrobatique-lorient-sombre-les-tops-et-flops-de-la-3eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 2025\/2026 : L&rsquo;OL victorieux, Jo\u00e3o Neves acrobatique, Lorient sombre, les tops et flops de la 3\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/c28883329a45cc92814310316945b3ce","name":"Malo Clement","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Malo-150x150.png","caption":"Malo Clement"},"description":"Fan de sport depuis mes 10 ans, mes premiers souvenirs de stade sont le Racing M\u00e9tro 92 \u00e0 Yves du Manoir, le XV de France et le PSG de Nen\u00ea. Celui d\u2019Ibra, Lucas, Cavani et Verratti m\u2019ont d\u00e9finitivement emport\u00e9 dans le football, au d\u00e9sarroi de ma famille. Entre les finales perdues de Champions Cup et les m\u00e9saventures en Ligue des Champions, j\u2019ai eu le nez fin. Au-del\u00e0 de mes clubs franciliens, je m\u2019int\u00e9resse au sport en g\u00e9n\u00e9ral et principalement \u00e0 la d\u00e9couverte de jeunes sportifs. Cela a commenc\u00e9 par Football Manager et j'ai repris \u00e7a avec les sports automobiles. Depuis 2020, mes dimanches apr\u00e8s-midi sont occup\u00e9s par Julien F\u00e9breau et la Formule 1. L\u2019endurance, la F2, la F3 et les autres championnats compl\u00e8tent mes week-ends. J\u2019ai rejoint Dicodusport en novembre 2024 et je suis ravi d\u2019\u00eatre le cadet de la r\u00e9daction.","url":"https:\/\/dicodusport.fr\/blog\/author\/clement-malo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/607579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=607579"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/607579\/revisions"}],"predecessor-version":[{"id":607611,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/607579\/revisions\/607611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/607599"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=607579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=607579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=607579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}