{"id":608105,"date":"2025-09-06T16:26:47","date_gmt":"2025-09-06T14:26:47","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=608105&#038;preview=true&#038;preview_id=608105"},"modified":"2025-09-06T16:26:26","modified_gmt":"2025-09-06T14:26:26","slug":"ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/","title":{"rendered":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/sports-de-combat\/mma\/\">MMA<\/a> UFC PARIS 4 &#8211; L&rsquo;UFC Paris se d\u00e9roule ce samedi 6 septembre \u00e0 l&rsquo;Accor Arena, avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis sur la carte principale. D\u00e9couvrez le programme TV.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"https:\/\/www.navymediasport.com\/go\/dicodusport-ufc\" class=\"su-button su-button-style-default\" style=\"color:#ffffff;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_self\" rel=\"nofollow\"><span style=\"color:#ffffff;padding:0px 24px;font-size:18px;line-height:36px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> <strong>Cliquez ici pour regarder l\u2019UFC en direct<\/strong><\/span><\/a><\/div>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-liste-des-combats-cartes-principale-et-preliminaire\/\">UFC Paris 4 : Liste des combats Cartes principale et pr\u00e9liminaire<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Apr\u00e8s <strong>Ciryl Gane<\/strong> en <a href=\"https:\/\/dicodusport.fr\/blog\/video-limpressionnant-ko-inflige-par-cyril-gane-a-tai-tuivasa\/\"><strong>2022<\/strong><\/a> et <a href=\"https:\/\/dicodusport.fr\/blog\/ufc-paris-2-ciryl-gane-renoue-avec-le-succes-en-surclassant-serghei-spivac\/\"><strong>2023<\/strong><\/a>, apr\u00e8s <strong>Beno\u00eet Saint Denis<\/strong> en <a href=\"https:\/\/dicodusport.fr\/blog\/ufc-paris-3-belle-soiree-pour-les-francais-malgre-la-defaite-de-benoit-saint-denis\/\"><strong>2024<\/strong><\/a>, c&rsquo;est <strong>Nassourdine Imavov<\/strong> qui combattra dans le <em>main event<\/em> de l&rsquo;UFC Paris, quatri\u00e8me \u00e9dition. Il affrontera <strong>Caio Borralho<\/strong>, et une victoire sur le Br\u00e9silien lui ouvrira peut-\u00eatre les portes d&rsquo;un match de championnat pour la ceinture des poids moyens.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/qui-sont-les-grands-oublies-de-lufc-paris-4\/\" class=\"vlp-link\" title=\"Qui sont les grands oubli\u00e9s de l\u2019UFC Paris 4 ?\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-grands-oublies-de-lUFC-Paris-4-.png\" class=\"attachment-800x445 size-800x445\" alt=\"Qui sont les grands oubli\u00e9s de l\u2019UFC Paris 4\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-grands-oublies-de-lUFC-Paris-4-.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-grands-oublies-de-lUFC-Paris-4--300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-grands-oublies-de-lUFC-Paris-4--1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-grands-oublies-de-lUFC-Paris-4--768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Qui sont les grands oubli\u00e9s de l\u2019UFC Paris 4 ?<\/div><div class=\"vlp-block-1 vlp-link-summary\">La carte de l\u2019UFC Paris 4 para\u00eet d\u00e9sormais compl\u00e8te, \u00e0 quelques jours de l\u2019\u00e9v\u00e9nement. Certaines t\u00eates d\u2019affiche du MMA fran\u00e7ais n\u2019en font pas partie, pour diverses raisons. Petit tour d\u2019horizon sur les combattants qui manqueront \u00e0 l\u2019appel<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\"><strong>BSD<\/strong> sera n\u00e9anmoins pr\u00e9sent, puisqu&rsquo;il combattra juste avant <strong>Maur\u00edcio Ruffy<\/strong>, pour tenter de la hi\u00e9rarchie des poids l\u00e9gers, lui qui est 13\u00e8me actuellement au ranking de sa cat\u00e9gorie. On comptera 5 Bleus, avec la pr\u00e9sence d&rsquo;<strong>Oumar Sy<\/strong>, <strong>William Gomis<\/strong> et <strong>Axel Sola<\/strong>. Frapp\u00e9 par un deuil familial, <strong>Far\u00e8s Ziam<\/strong> ne sera lui pas pr\u00e9sent, alors qu&rsquo;il aurait d\u00fb lui aussi combattre un Br\u00e9silien, <strong>Kau\u00ea Fernandes<\/strong>.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/un-ufc-numerote-en-france-cest-pour-quand\/\">Un UFC num\u00e9rot\u00e9 en France, c\u2019est pour quand ?<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">Carte principale UFC Paris 4 (21h00) :<\/h2>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\">\ud83c\uddeb\ud83c\uddf7 Nassourdine Imavov vs Caio Borralho \ud83c\udde7\ud83c\uddf7 (poids moyens)<\/li>\n<li>\ud83c\uddeb\ud83c\uddf7 Beno\u00eet Saint Denis vs Maur\u00edcio Ruffy \ud83c\udde7\ud83c\uddf7 (poids l\u00e9gers)<\/li>\n<li>\ud83c\uddf1\ud83c\uddf9 Modestas Bukauskas vs Paul Craig <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8797\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-300x180.png\" alt=\"\" width=\"16\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-392x272.png 392w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-130x90.png 130w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-800x445.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse.png 1000w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/> (poids mi-lourds)<\/li>\n<li>\ud83c\udde7\ud83c\uddea Bolaji Oki vs Mason Jones <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3749\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Pays-de-Galles-300x180.png\" alt=\"\" width=\"16\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Pays-de-Galles.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Pays-de-Galles-130x90.png 130w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/> (poids l\u00e9gers)<\/li>\n<li>\ud83c\uddeb\ud83c\uddf7 Axel Sola vs Rhys McKee \ud83c\uddee\ud83c\uddea (poids mi-moyens)<\/li>\n<li>\ud83c\uddeb\ud83c\uddf7 William Gomis vs Robert Rucha\u0142a \ud83c\uddf5\ud83c\uddf1 (poids plume)<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" align=\"justify\">Carte pr\u00e9liminaire UFC Paris 4 (18h00) :<\/h2>\n<ul style=\"text-align: justify;\">\n<li>\ud83c\uddeb\ud83c\uddf7 Oumar Sy vs Brendson Ribeiro \ud83c\udde7\ud83c\uddf7 (poids mi-lourds)<\/li>\n<li>\ud83c\uddf5\ud83c\uddf1 Marcin Tybura vs Ante Delija \ud83c\udded\ud83c\uddf7 (poids lourds)<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3761\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png\" alt=\"\" width=\"16\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-392x272.png 392w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-130x90.png 130w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png 800w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/> Harry Hardwick vs Kau\u00ea Fernandes \ud83c\udde7\ud83c\uddf7 (poids l\u00e9gers)<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3761\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png\" alt=\"\" width=\"16\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-392x272.png 392w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-130x90.png 130w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png 800w\" sizes=\"auto, (max-width: 16px) 100vw, 16px\" \/> Sam Patterson vs Trey Waters \ud83c\uddfa\ud83c\uddf8 (poids mi-moyens)<\/li>\n<li>\ud83c\uddfa\ud83c\uddf8 Brad Tavares vs Robert Bryczek \ud83c\uddf5\ud83c\uddf1\u00a0(poids moyens)<\/li>\n<li>\ud83c\uddf8\ud83c\uddea Andreas Gustafsson vs Rinat Fakhretdinov \ud83c\uddf7\ud83c\uddfa (poids mi-moyens)<\/li>\n<li>\ud83c\uddee\ud83c\uddea Shauna Bannon vs Sam Hughes \ud83c\uddfa\ud83c\uddf8 (poids paille)<\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/levolution-des-ufc-paris-depuis-la-premiere-carte-en-2022\/\" class=\"vlp-link\" title=\"L\u2019\u00e9volution des UFC Paris depuis la premi\u00e8re carte en 2022\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Levolution-des-UFC-Paris-depuis-la-premiere-carte-en-2022.png\" class=\"attachment-800x445 size-800x445\" alt=\"L\u2019\u00e9volution des UFC Paris depuis la premi\u00e8re carte en 2022\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Levolution-des-UFC-Paris-depuis-la-premiere-carte-en-2022.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Levolution-des-UFC-Paris-depuis-la-premiere-carte-en-2022-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Levolution-des-UFC-Paris-depuis-la-premiere-carte-en-2022-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Levolution-des-UFC-Paris-depuis-la-premiere-carte-en-2022-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">L\u2019\u00e9volution des UFC Paris depuis la premi\u00e8re carte en 2022<\/div><div class=\"vlp-block-1 vlp-link-summary\">Le 6 septembre marquera la quatri\u00e8me \u00e9dition de l\u2019UFC Paris. L\u2019occasion de retracer l\u2019\u00e9volution des cartes depuis le lancement de l\u2019\u00e9v\u00e9nement en 2022.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">UFC Paris 4 : Le Programme TV<\/h2>\n<h3 style=\"text-align: justify;\">Samedi 6 septembre<\/h3>\n<p style=\"text-align: justify;\"><strong>RMC SPORT<\/strong><\/p>\n<p style=\"text-align: justify;\">18h00 : D\u00e9but de la carte pr\u00e9liminaire UFC Paris 4 (<strong>sur la cha\u00eene Twitch RMC Sport<\/strong>)<\/p>\n<p style=\"text-align: justify;\">21h00 : D\u00e9but de la carte principale UFC Paris 4 (<strong>sur RMC Sport 1, prise d&rsquo;antenne \u00e0 20h30<\/strong>) &#8211; <a href=\"https:\/\/www.navymediasport.com\/go\/dicodusport-ufc\" target=\"_blank\" rel=\"noopener\"><strong>Cliquez ici pour voir la promotion RMC Sport<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Vers 23h00 : Beno\u00eet Saint Denis vs Mauricio Ruffy<br \/>\nPas avant 23h30 : Nassourdine Imavov vs Caio Borralho<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Nassourdine Imavov vs Caio Borralho<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 532px;\" colspan=\"2\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 6 septembre, 23h30<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 400px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Nassourdine Imavov<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61899386?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#013369;border-color:#012954;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4e7196;border-radius:5px;text-shadow:none\"> 2.00<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 400px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Caio Borralho<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61899386?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#013369;border-color:#012954;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4e7196;border-radius:5px;text-shadow:none\"> 1.80<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MMA UFC PARIS 4 &#8211; L&rsquo;UFC Paris se d\u00e9roule ce samedi 6 septembre \u00e0 l&rsquo;Accor Arena, avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis sur la carte principale. D\u00e9couvrez le programme TV.<\/p>\n","protected":false},"author":59,"featured_media":608109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,10666],"tags":[32399,16878,32065,8799,1224],"class_list":["post-608105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-mma","tag-benoit-saint-denis","tag-breve","tag-nassourdine-imavov","tag-programme-tv","tag-ufc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV<\/title>\n<meta name=\"description\" content=\"MMA UFC PARIS 4 - L&#039;UFC Paris se d\u00e9roule ce samedi 6 septembre avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis. D\u00e9couvrez le programme TV.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV\" \/>\n<meta property=\"og:description\" content=\"MMA UFC PARIS 4 - L&#039;UFC Paris se d\u00e9roule ce samedi 6 septembre avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis. D\u00e9couvrez le programme TV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-06T14:26:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV\",\"datePublished\":\"2025-09-06T14:26:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\"},\"wordCount\":663,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"keywords\":[\"Beno\u00eet Saint-Denis\",\"br\u00e8ve\",\"Nassourdine Imavov\",\"Programme TV\",\"UFC\"],\"articleSection\":[\"Cha\u00eene TV\",\"MMA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\",\"name\":\"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"datePublished\":\"2025-09-06T14:26:47+00:00\",\"description\":\"MMA UFC PARIS 4 - L'UFC Paris se d\u00e9roule ce samedi 6 septembre avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis. D\u00e9couvrez le programme TV.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"width\":1200,\"height\":674,\"caption\":\"UFC Paris 4 \u00c0 quelle heure et sur quelle cha\u00eene TV\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV","description":"MMA UFC PARIS 4 - L'UFC Paris se d\u00e9roule ce samedi 6 septembre avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis. D\u00e9couvrez le programme TV.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/","og_locale":"fr_FR","og_type":"article","og_title":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV","og_description":"MMA UFC PARIS 4 - L'UFC Paris se d\u00e9roule ce samedi 6 septembre avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis. D\u00e9couvrez le programme TV.","og_url":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-09-06T14:26:47+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV","datePublished":"2025-09-06T14:26:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/"},"wordCount":663,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png","keywords":["Beno\u00eet Saint-Denis","br\u00e8ve","Nassourdine Imavov","Programme TV","UFC"],"articleSection":["Cha\u00eene TV","MMA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/","url":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/","name":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png","datePublished":"2025-09-06T14:26:47+00:00","description":"MMA UFC PARIS 4 - L'UFC Paris se d\u00e9roule ce samedi 6 septembre avec notamment Nassourdine Imavov et Beno\u00eet Saint Denis. D\u00e9couvrez le programme TV.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/UFC-Paris-4-A-quelle-heure-et-sur-quelle-chaine-TV.png","width":1200,"height":674,"caption":"UFC Paris 4 \u00c0 quelle heure et sur quelle cha\u00eene TV"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ufc-paris-4-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"UFC Paris 4 : \u00c0 quelle heure et sur quelle cha\u00eene TV"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/608105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=608105"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/608105\/revisions"}],"predecessor-version":[{"id":608870,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/608105\/revisions\/608870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/608109"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=608105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=608105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=608105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}