{"id":612803,"date":"2025-09-20T16:34:22","date_gmt":"2025-09-20T14:34:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=612803&#038;preview=true&#038;preview_id=612803"},"modified":"2025-09-20T16:59:06","modified_gmt":"2025-09-20T14:59:06","slug":"4eme-etape-tour-de-slovaquie-2025-classement-et-resultats","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/","title":{"rendered":"4\u00e8me \u00e9tape Tour de Slovaquie 2025 &#8211; Classement et r\u00e9sultats"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s&rsquo;est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-slovaquie-2025-actualise\/\">Classement g\u00e9n\u00e9ral Tour de Slovaquie 2025 actualis\u00e9<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La <strong>quatri\u00e8me \u00e9tape du Tour de Slovaquie 2025<\/strong> se d\u00e9roule le <strong>samedi 20 septembre<\/strong>, entre <strong>Vr\u00e1ble<\/strong> et <strong>Sl\u00e1dkovi\u010dovo<\/strong>, sur une distance de<strong> 169,1 km<\/strong>. Avec un profil relativement plat et un d\u00e9nivel\u00e9 mod\u00e9r\u00e9, cette \u00e9tape s\u2019annonce id\u00e9ale pour les sprinteurs et les puncheurs, qui auront l\u2019occasion de briller lors des sprints interm\u00e9diaires et de l\u2019arriv\u00e9e.<\/p>\n<h2>Les coureurs \u00e0 suivre<\/h2>\n<p style=\"text-align: justify;\">Parmi les coureurs \u00e0 suivre figurent \u00e9videmment <strong>Paul Magnier<\/strong> (Soudal Quick-Step), vainqueur des trois premi\u00e8res \u00e9tapes sur l&rsquo;\u00e9preuve slovaque, ainsi que <strong>Milan Menten<\/strong> (Lotto) et <strong>Matthew Walls<\/strong> (Groupama-FDJ), qui disposent tous deux d\u2019une belle pointe de vitesse. Les locaux comme <strong>Luk\u00e1\u0161 Kubi\u0161<\/strong> (Unibet Tietema Rockets) pourraient \u00e9galement jouer un r\u00f4le cl\u00e9 dans le d\u00e9roulement de l\u2019\u00e9tape.<\/p>\n<p style=\"text-align: justify;\">Les \u00e9quipes devront rester vigilantes et contr\u00f4ler les \u00e9chapp\u00e9es pour pr\u00e9parer un sprint final, car l\u2019arriv\u00e9e \u00e0 <strong>Sl\u00e1dkovi\u010dovo<\/strong> pourrait \u00eatre d\u00e9cisive pour le classement g\u00e9n\u00e9ral et offrir une premi\u00e8re victoire d\u2019\u00e9tape aux sprinteurs du peloton.<\/p>\n<p style=\"text-align: justify;\"><strong>Arriv\u00e9e pr\u00e9vue sur les coups de 16h45. Retrouvez les r\u00e9sultats complets et le classement de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025 ci-dessous.<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/\">L&rsquo;actualit\u00e9 du cyclisme<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Classement 4\u00e8me \u00e9tape &#8211; Tour de Slovaquie 2025<\/h2>\n<p style=\"text-align: justify;\"><em><span style=\"font-size: 14px;\"><strong>Classement mis \u00e0 jour \u00e0 l&rsquo;issue de l&rsquo;\u00e9tape.<\/strong><\/span><\/em><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 PAUL MAGNIER<\/strong><br \/>\n<span style=\"font-size: 0.8em\">SOUDAL QUICK-STEP<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h30m16s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf8\ud83c\uddf0 LUK\u00c1\u0160 KUBI\u0160<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UNIBET TIETEMA ROCKETS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea MILAN MENTEN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">LOTTO<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde9\ud83c\uddea NIKLAS BEHRENS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM VISMA | LEASE A BIKE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 ANDREA PERON<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM NOVO NORDISK<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 NICOLO ARRIGHETTI<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BIESSE &#8211; CARRERA &#8211; PREMAC<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\uddff DOMINIK NEUMAN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ATT INVESTMENTS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddf1 TIMO DE JONG<\/strong><br \/>\n<span style=\"font-size: 0.8em\">VOLKERWESSELS CYCLING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\uddff ADAM BITTMAN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ELKOV &#8211; KASPER<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 FILIPPO RIDOLFO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM NOVO NORDISK<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea LIAM VAN BYLEN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">LOTTO<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddea JOPPE HEREMANS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">VOLKERWESSELS CYCLING TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 GABRIELE BESSEGA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BIESSE &#8211; CARRERA &#8211; PREMAC<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf3\ud83c\uddf1 MARVIN PETERS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">DIFTAR CONTINENTAL CYCLINGTEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 ALESSIO DELLE VEDOVE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">XDS ASTANA TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 TOMMASO BESSEGA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BIESSE &#8211; CARRERA &#8211; PREMAC<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\udde7 MATTHEW WALLS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">GROUPAMA &#8211; FDJ CONTI<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf0\ud83c\uddff RUSLAN YELYUBAYEV<\/strong><br \/>\n<span style=\"font-size: 0.8em\">XDS ASTANA DEVELOPMENT TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddf8\ud83c\uddee TILEN FINK\u0160T<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ADRIA MOBIL<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 ATTILIO VIVIANI<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM SOLUTION TECH &#8211; VINI FANTINI<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h3 style=\"text-align: justify;\">\u00c0 lire aussi<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/okolo-slovenska\/2025\/stage-4\/\"><strong>Le classement complet de la 4\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-mercato-2025-2026-le-tableau-des-transferts\/\" class=\"vlp-link\" title=\"Cyclisme Mercato 2025-2026 - Le tableau des transferts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts.png\" class=\"attachment-800x445 size-800x445\" alt=\"Cyclisme Mercato 2025-2026 - Le tableau des transferts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Cyclisme Mercato 2025-2026 - Le tableau des transferts<\/div><div class=\"vlp-block-1 vlp-link-summary\">MERCATO CYCLISME 2025-2026 - D\u00e9couvrez les transferts officiels et les rumeurs du mercato cycliste.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s&rsquo;est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).<\/p>\n","protected":false},"author":4,"featured_media":612806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[16878,574,11197,19213],"class_list":["post-612803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-tour-de-slovaquie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4\u00e8me \u00e9tape Tour de Slovaquie 2025 - Classement et r\u00e9sultats<\/title>\n<meta name=\"description\" content=\"Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s&#039;est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de Slovaquie 2025 : R\u00e9sultats et classement de la 4\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s&#039;est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-20T14:34:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-20T14:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de Slovaquie 2025 : R\u00e9sultats et classement de la 4\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"4\u00e8me \u00e9tape Tour de Slovaquie 2025 &#8211; Classement et r\u00e9sultats\",\"datePublished\":\"2025-09-20T14:34:22+00:00\",\"dateModified\":\"2025-09-20T14:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png\",\"keywords\":[\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"Tour de Slovaquie\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\",\"name\":\"4\u00e8me \u00e9tape Tour de Slovaquie 2025 - Classement et r\u00e9sultats\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png\",\"datePublished\":\"2025-09-20T14:34:22+00:00\",\"dateModified\":\"2025-09-20T14:59:06+00:00\",\"description\":\"Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s'est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png\",\"width\":1200,\"height\":674,\"caption\":\"4\u00e8me \u00e9tape Tour de Slovaquie 2025 - Classement et r\u00e9sultats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4\u00e8me \u00e9tape Tour de Slovaquie 2025 &#8211; Classement et r\u00e9sultats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4\u00e8me \u00e9tape Tour de Slovaquie 2025 - Classement et r\u00e9sultats","description":"Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s'est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de Slovaquie 2025 : R\u00e9sultats et classement de la 4\u00e8me \u00e9tape","og_description":"Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s'est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).","og_url":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-09-20T14:34:22+00:00","article_modified_time":"2025-09-20T14:59:06+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour de Slovaquie 2025 : R\u00e9sultats et classement de la 4\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"4\u00e8me \u00e9tape Tour de Slovaquie 2025 &#8211; Classement et r\u00e9sultats","datePublished":"2025-09-20T14:34:22+00:00","dateModified":"2025-09-20T14:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png","keywords":["br\u00e8ve","Cyclisme","Cyclisme sur route","Tour de Slovaquie"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/","url":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/","name":"4\u00e8me \u00e9tape Tour de Slovaquie 2025 - Classement et r\u00e9sultats","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png","datePublished":"2025-09-20T14:34:22+00:00","dateModified":"2025-09-20T14:59:06+00:00","description":"Retrouvez le classement et les r\u00e9sultats de la 4\u00e8me \u00e9tape du Tour de Slovaquie 2025, qui s'est d\u00e9roul\u00e9e ce vendredi 19 septembre entre Vr\u00e1ble et Sl\u00e1dkovi\u010dovo (169,1 km).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/4eme-etape-Tour-de-Slovaquie-2025-Classement-et-resultats.png","width":1200,"height":674,"caption":"4\u00e8me \u00e9tape Tour de Slovaquie 2025 - Classement et r\u00e9sultats"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/4eme-etape-tour-de-slovaquie-2025-classement-et-resultats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"4\u00e8me \u00e9tape Tour de Slovaquie 2025 &#8211; Classement et r\u00e9sultats"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/612803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=612803"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/612803\/revisions"}],"predecessor-version":[{"id":612961,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/612803\/revisions\/612961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/612806"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=612803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=612803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=612803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}