{"id":613182,"date":"2025-09-21T12:53:05","date_gmt":"2025-09-21T10:53:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=613182&#038;preview=true&#038;preview_id=613182"},"modified":"2025-09-21T13:00:35","modified_gmt":"2025-09-21T11:00:35","slug":"basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/","title":{"rendered":"Basket 3&#215;3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DU MONDE F\u00c9MININE DE BASKET 3&#215;3 U23 2025 &#8211; Derri\u00e8re durant l&rsquo;int\u00e9gralit\u00e9 de la rencontre, les Bleuettes, port\u00e9es par Vaciana Gomis, ont renvers\u00e9 l&rsquo;Espagne dans les derni\u00e8res secondes (17-18).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Et encore un match <strong>Espagne-France<\/strong> en basket 3&#215;3 ! Apr\u00e8s avoir arrach\u00e9 leur qualification aux prolongations, les Bleuettes retrouvaient les Espagnoles en demi-finale.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-calendrier-et-resultats-mis-a-jour\/\" target=\"_blank\" rel=\"noopener\">Basket 3\u00d73 Coupe du monde U23 2025 (F) : Calendrier et r\u00e9sultats mis \u00e0 jour<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Les Fran\u00e7aises domin\u00e9es par les Espagnoles<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s un premier <strong>block<\/strong> de l&rsquo;Espagne, les Bleues ont mal assur\u00e9 leur passe et perdu le ballon. Plusieurs <strong>erreurs techniques<\/strong> c\u00f4t\u00e9 fran\u00e7ais. Difficile de marquer des paniers de part et d&rsquo;autre, 3-1 pour l&rsquo;Espagne apr\u00e8s le premier temps mort publicitaire. Les Espagnoles font la course en t\u00eate et r\u00e9pondent \u00e0 chaque panier fran\u00e7ais : l&rsquo;\u00e9cart se stabilise autour de 2-3 points. Alors que les \u00e9checs \u00e0 2 points fran\u00e7ais se succ\u00e8dent, les Espagnoles enfilent les paniers et s&rsquo;envolent (8-3).<\/p>\n<p style=\"text-align: justify;\">Les Espagnoles poussent leurs adversaires fran\u00e7aises \u00e0 la faute et celles-ci doivent courir apr\u00e8s le score. Seule <strong>Louise Bussiere<\/strong> parvient \u00e0 inscrire un panier \u00e0 2 points pour tenter de recoller au score (11-7). \u00c0 3 minutes de la fin, les Fran\u00e7aises sont toujours men\u00e9es de 3 points et \u00e0 l&rsquo;int\u00e9rieur, <strong>Marta Garcia<\/strong> fait tr\u00e8s mal (15-11).<\/p>\n<h2 style=\"text-align: justify;\">Le come-back fran\u00e7ais !<\/h2>\n<p style=\"text-align: justify;\">La 7\u00e8me faute espagnole envoie <strong>Vaciana Gomis<\/strong> sur la ligne des lancers (17-15). Les Fran\u00e7aises d\u00e9fendent proprement et Gomis, meilleure joueuse fran\u00e7aise de cette demie, part seule au panier pour un nouveau lay-up (17-16). Malgr\u00e9 la taille des Espagnoles, celles-ci se crispent un peu et les Fran\u00e7aises par l&rsquo;interm\u00e9diaire de Gomis parviennent une nouvelle fois \u00e0 chiper un ballon. Et elle se retrouve m\u00eame sur la ligne des lancers. Malheureusement, elle rate le premier (17-17). Plus rien ne rentre pour l&rsquo;<strong>Espagne<\/strong>. Ainsi, aux lancers francs, <strong>Samantha Peytour<\/strong> permet aux Bleues de passer devant pour la premi\u00e8re fois dans les derni\u00e8res secondes (17-18). Les Bleuettes ont le ballon et font tourner la balle. Si Gomis rate son lancer, elle est \u00e0 la retomb\u00e9e : fin du match 17-18 !<\/p>\n<p style=\"text-align: justify;\">En finale, la <strong>France<\/strong> retrouvera les <strong>Pays-Bas<\/strong>, vice-champions du monde 2024.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">FRANCE \ud83c\uddeb\ud83c\uddf7 COME AWAY WITH THE WIN! \ud83e\udd2f<\/p>\n<p>They comeback to defeat Spain and book a spot in the <a href=\"https:\/\/twitter.com\/hashtag\/3x3U23?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3U23<\/a> FINAL! \ud83e\udd29 <a href=\"https:\/\/t.co\/QrWTCEA96G\">pic.twitter.com\/QrWTCEA96G<\/a><\/p>\n<p>\u2014 3&#215;3 Basketball | FIBA3x3 (@FIBA3x3) <a href=\"https:\/\/twitter.com\/FIBA3x3\/status\/1969714723655438433?ref_src=twsrc%5Etfw\">September 21, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE F\u00c9MININE DE BASKET 3&#215;3 U23 2025 &#8211; Derri\u00e8re durant l&rsquo;int\u00e9gralit\u00e9 de la rencontre, les Bleuettes, port\u00e9es par Vaciana Gomis, ont renvers\u00e9 l&rsquo;Espagne dans les derni\u00e8res secondes (17-18).<\/p>\n","protected":false},"author":12,"featured_media":613210,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[27116],"tags":[174,16878,47256],"class_list":["post-613182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-basket","tag-breve","tag-coupe-du-monde-3x3-u23"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE F\u00c9MININE DE BASKET 3x3 U23 2025 - Les Bleuettes ont renvers\u00e9 l&#039;Espagne dans les derni\u00e8res secondes (17-18).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE F\u00c9MININE DE BASKET 3x3 U23 2025 - Les Bleuettes ont renvers\u00e9 l&#039;Espagne dans les derni\u00e8res secondes (17-18).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-21T10:53:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-21T11:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Basket 3&#215;3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes\",\"datePublished\":\"2025-09-21T10:53:05+00:00\",\"dateModified\":\"2025-09-21T11:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\"},\"wordCount\":422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png\",\"keywords\":[\"basket\",\"br\u00e8ve\",\"Coupe du monde 3X3 U23\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\",\"name\":\"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png\",\"datePublished\":\"2025-09-21T10:53:05+00:00\",\"dateModified\":\"2025-09-21T11:00:35+00:00\",\"description\":\"COUPE DU MONDE F\u00c9MININE DE BASKET 3x3 U23 2025 - Les Bleuettes ont renvers\u00e9 l'Espagne dans les derni\u00e8res secondes (17-18).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png\",\"width\":1200,\"height\":674,\"caption\":\"Basket 3x3 Coupe du monde U23 2025 (F) Direction la finale pour les Bleuettes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Basket 3&#215;3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes","description":"COUPE DU MONDE F\u00c9MININE DE BASKET 3x3 U23 2025 - Les Bleuettes ont renvers\u00e9 l'Espagne dans les derni\u00e8res secondes (17-18).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/","og_locale":"fr_FR","og_type":"article","og_title":"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes","og_description":"COUPE DU MONDE F\u00c9MININE DE BASKET 3x3 U23 2025 - Les Bleuettes ont renvers\u00e9 l'Espagne dans les derni\u00e8res secondes (17-18).","og_url":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-09-21T10:53:05+00:00","article_modified_time":"2025-09-21T11:00:35+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Basket 3&#215;3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes","datePublished":"2025-09-21T10:53:05+00:00","dateModified":"2025-09-21T11:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png","keywords":["basket","br\u00e8ve","Coupe du monde 3X3 U23"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/","url":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/","name":"Basket 3x3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png","datePublished":"2025-09-21T10:53:05+00:00","dateModified":"2025-09-21T11:00:35+00:00","description":"COUPE DU MONDE F\u00c9MININE DE BASKET 3x3 U23 2025 - Les Bleuettes ont renvers\u00e9 l'Espagne dans les derni\u00e8res secondes (17-18).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Basket-3x3-Coupe-du-monde-U23-2025-F-Direction-la-finale-pour-les-Bleuettes.png","width":1200,"height":674,"caption":"Basket 3x3 Coupe du monde U23 2025 (F) Direction la finale pour les Bleuettes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/basket-3x3-coupe-du-monde-u23-2025-f-direction-la-finale-pour-les-bleuettes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Basket 3&#215;3 Coupe du monde U23 2025 (F) : Direction la finale pour les Bleuettes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=613182"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613182\/revisions"}],"predecessor-version":[{"id":613225,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613182\/revisions\/613225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/613210"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=613182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=613182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=613182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}