{"id":613670,"date":"2025-09-22T17:27:02","date_gmt":"2025-09-22T15:27:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=613670&#038;preview=true&#038;preview_id=613670"},"modified":"2025-09-22T17:27:02","modified_gmt":"2025-09-22T15:27:02","slug":"ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/","title":{"rendered":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE 2 2025-2026 &#8211; Cette 6\u00e8me journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure. Mais tout n\u2019a pas \u00e9t\u00e9 rose, Boulogne rechute et Dunkerque a pay\u00e9 cher le coup de sang de son capitaine. Revue des Tops et Flops de cette derni\u00e8re journ\u00e9e de Ligue 2 BKT.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-qui-sont-les-favoris-pour-la-montee-en-ligue-1\/\">Ligue 2 2025-2026 : Qui sont les favoris pour la mont\u00e9e en Ligue 1 ?<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span style=\"color: #339966;\">Les Tops<\/span><\/h2>\n<h2 style=\"text-align: justify;\">Stassin encha\u00eene<\/h2>\n<p style=\"text-align: justify;\">Cette fois, plus aucun doute, le poids du mercato est d\u00e9finitivement derri\u00e8re <strong>Lucas Stassin<\/strong>. \u00c9panoui \u00e0 <strong>Saint-\u00c9tienne<\/strong>, il le prouve \u00e0 nouveau sur le terrain. Titulaire face \u00e0 <strong>Reims<\/strong>, il n\u2019a eu besoin que de 45 minutes pour claquer un doubl\u00e9. Les Verts l\u2019emportent 3-2 et confortent leur fauteuil de leader de Ligue 2 BKT. <strong>Stassin<\/strong>, lui, s\u2019installe tranquillement dans la peau du facteur X de cette \u00e9quipe, un v\u00e9ritable Game Changer.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83e\udd29 La MERVEILLE de Lucas Stassin qui s&rsquo;offre un doubl\u00e9 et redonne l&rsquo;avantage \u00e0 Saint-\u00c9tienne face \u00e0 Reims ! <a href=\"https:\/\/t.co\/kPDzgtKB0g\">pic.twitter.com\/kPDzgtKB0g<\/a><\/p>\n<p>\u2014 beIN SPORTS (@beinsports_FR) <a href=\"https:\/\/twitter.com\/beinsports_FR\/status\/1969474326509375532?ref_src=twsrc%5Etfw\">September 20, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">L\u2019attaque de Troyes carbure plein pot<\/h2>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0 victorieux 3-0 de <strong>Nancy<\/strong> la semaine derni\u00e8re, les supporters du Stade de l\u2019Aube ont encore eu droit \u00e0 un nouveau festival offensif. Pourtant men\u00e9s d\u00e8s la 4\u00e8me minute par <strong>Guingamp<\/strong>, les hommes de <strong>St\u00e9phane Dumont<\/strong> ont r\u00e9pliqu\u00e9 avec panache : victoire 5-2. De quoi rester dans le sillage de l\u2019ASSE.<\/p>\n<p style=\"text-align: justify;\">En face, Guingamp continue de jouer les portes ouvertes, 14 buts encaiss\u00e9s en 6 matchs. Pour <strong>Sylvain Ripoll<\/strong>, la muraille bretonne ressemble plus \u00e0 une passoire qu\u2019\u00e0 un rempart solide.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">TOTAL R\u00c9GAL \ud83d\ude0d<a href=\"https:\/\/twitter.com\/hashtag\/ESTACEAG?src=hash&amp;ref_src=twsrc%5Etfw\">#ESTACEAG<\/a> <a href=\"https:\/\/t.co\/tCr9mzbSC3\">pic.twitter.com\/tCr9mzbSC3<\/a><\/p>\n<p>\u2014 Ligue 2 BKT (@Ligue2BKT) <a href=\"https:\/\/twitter.com\/Ligue2BKT\/status\/1969400539549941871?ref_src=twsrc%5Etfw\">September 20, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Montpellier se rassure<\/h2>\n<p style=\"text-align: justify;\">La d\u00e9faite de la semaine derni\u00e8re contre <strong>Guingamp<\/strong> avait laiss\u00e9 craindre un d\u00e9but de rechute. Mais <strong>Montpellier<\/strong> a remis les pendules \u00e0 l\u2019heure en s\u2019imposant 2-0 face \u00e0 <strong>Bastia<\/strong>, bon dernier et toujours en qu\u00eate d\u2019une premi\u00e8re victoire.<\/p>\n<p style=\"text-align: justify;\">Les buteurs du jour ? Les exp\u00e9riment\u00e9s <strong>Christopher Jullien<\/strong> et <strong>Alexandre Mendy<\/strong>, qui offrent aux H\u00e9raultais une 7\u00e8me place au classement. Ce n\u2019est pas encore la grande flamboyance, mais c\u2019est d\u00e9j\u00e0 une crise \u00e9vit\u00e9e et un grand ouf de soulagement pour <strong>Zoumana Camara<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Lib\u00e9r\u00e9, d\u00e9livr\u00e9 \ud83d\ude4c<\/p>\n<p>L&rsquo;attaquant restait sur 18 matchs sans trouver le chemin des filets, sa plus longue disette dans la division depuis ses d\u00e9buts en 2014\/15&#8230; <a href=\"https:\/\/t.co\/kFm9xY6HFj\">pic.twitter.com\/kFm9xY6HFj<\/a><\/p>\n<p>\u2014 Ligue 2 BKT (@Ligue2BKT) <a href=\"https:\/\/twitter.com\/Ligue2BKT\/status\/1970080643762495703?ref_src=twsrc%5Etfw\">September 22, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" data-start=\"122\" data-end=\"165\">Le Red Star accroch\u00e9 au wagon de t\u00eate<\/h2>\n<p style=\"text-align: justify;\" data-start=\"166\" data-end=\"540\">On le r\u00e9p\u00e9tait d\u00e9j\u00e0 ces derni\u00e8res semaines : <strong data-start=\"211\" data-end=\"270\">le Red Star <\/strong>est la belle surprise de ce d\u00e9but de saison, et il le prouve encore. Quatri\u00e8me victoire cons\u00e9cutive, cette fois 0-1 sur la pelouse de <strong data-start=\"339\" data-end=\"370\">Nancy<\/strong>. Les Audoniens restent ainsi dans le sillage du duo <strong data-start=\"423\" data-end=\"447\">Troyes &#8211; Saint-\u00c9tienne<\/strong> et confirment leur d\u00e9part canon. Un d\u00e9but de saison \u00e0 faire p\u00e2lir plus d\u2019un cador annonc\u00e9.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-2-2025-2026\/\">Classement Ligue 2 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Les Flops<\/span><\/h2>\n<h2 style=\"text-align: justify;\">Boulogne retombe dans ses travers<\/h2>\n<p style=\"text-align: justify;\">On croyait que la victoire en match en retard contre Bastia, synonyme de premiers points de la saison pour Boulogne, allait lancer la machine. Rat\u00e9. Face \u00e0 <strong>Pau<\/strong>, les Boulonnais sont compl\u00e8tement \u00e0 c\u00f4t\u00e9, 0-3 \u00e0 la mi-temps, un score qui ne bougera plus. \u00c0 domicile, qui plus est. Une soir\u00e9e \u00e0 vite classer dans la cat\u00e9gorie \u00ab\u00a0\u00e0 oublier\u00a0\u00bb, et un rappel que le retour en Ligue 2 ne sera pas une promenade sans emb\u00fbche.<\/p>\n<h2 style=\"text-align: justify;\">Sangante voit rouge et change le sc\u00e9nario<\/h2>\n<p style=\"text-align: justify;\">Un <strong>Dunkerque &#8211; Le<\/strong> <strong>Mans<\/strong> sans rebondissement ? Impossible. Menant 2-1 \u00e0 11 contre 10 avant l\u2019heure de jeu, <strong>Dunkerque<\/strong> avait pourtant le match en main. Mais son capitaine <strong>Opa Sangante<\/strong> a d\u00e9cid\u00e9 de relancer le suspense : rouge direct pour une grosse faute \u00e0 vingt minutes du terme. \u00c0 10 contre 10, les Manceaux n\u2019ont pas laiss\u00e9 passer l\u2019occasion et ont arrach\u00e9 l\u2019\u00e9galisation (2-2). R\u00e9sultat : troisi\u00e8me nul 2-2 de la saison pour <strong>Dunkerque<\/strong>, et une petite impression de d\u00e9j\u00e0-vu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 2 2025-2026 &#8211; Pendant que le Red Star, Troyes et Saint-\u00c9tienne s\u2019installent tranquillement en t\u00eate, Montpellier, lui, recommence \u00e0 donner des sueurs froides \u00e0 ses supporters. Sans oublier le retour en fanfare de Lucas Stassin, les rouges du Pau FC. Tops, flops et rebondissements : on vous raconte tout.<\/p>\n","protected":false},"author":111,"featured_media":613674,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301],"tags":[16878,75,12325],"class_list":["post-613670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-breve","tag-football","tag-ligue-2-bkt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"LIGUE 2 2025-2026 - Cette 6eme journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"LIGUE 2 2025-2026 - Cette 6eme journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T15:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Derambure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\"},\"author\":{\"name\":\"L\u00e9o Derambure\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\"},\"headline\":\"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e\",\"datePublished\":\"2025-09-22T15:27:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\"},\"wordCount\":697,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue 2 BKT\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\",\"name\":\"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png\",\"datePublished\":\"2025-09-22T15:27:02+00:00\",\"description\":\"LIGUE 2 2025-2026 - Cette 6eme journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png\",\"width\":1200,\"height\":674,\"caption\":\"Ligue 2 20252026 Troyes, Lucas Stassin, Montpellier, les tops et flops de la 6\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\",\"name\":\"L\u00e9o Derambure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"caption\":\"L\u00e9o Derambure\"},\"description\":\"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.\",\"worksFor\":\"L\u00e9o Derambure\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e","description":"LIGUE 2 2025-2026 - Cette 6eme journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e","og_description":"LIGUE 2 2025-2026 - Cette 6eme journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-09-22T15:27:02+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png","type":"image\/png"}],"author":"L\u00e9o Derambure","twitter_card":"summary_large_image","twitter_title":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/"},"author":{"name":"L\u00e9o Derambure","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295"},"headline":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e","datePublished":"2025-09-22T15:27:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/"},"wordCount":697,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png","keywords":["br\u00e8ve","Football","Ligue 2 BKT"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/","name":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png","datePublished":"2025-09-22T15:27:02+00:00","description":"LIGUE 2 2025-2026 - Cette 6eme journ\u00e9e de Ligue 2 a confirm\u00e9 quelques tendances fortes : Saint-\u00c9tienne consolide son fauteuil de leader, Troyes encha\u00eene les buts et Montpellier se rassure.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-2-20252026-Troyes-Lucas-Stassin-Montpellier-les-tops-et-flops-de-la-6eme-journee.png","width":1200,"height":674,"caption":"Ligue 2 20252026 Troyes, Lucas Stassin, Montpellier, les tops et flops de la 6\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-2025-2026-troyes-lucas-stassin-boulogne-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue 2 2025\/2026 : Troyes, Lucas Stassin, Boulogne, les tops et flops de la 6\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295","name":"L\u00e9o Derambure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","caption":"L\u00e9o Derambure"},"description":"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.","worksFor":"L\u00e9o Derambure","url":"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=613670"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613670\/revisions"}],"predecessor-version":[{"id":613675,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613670\/revisions\/613675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/613674"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=613670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=613670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=613670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}