{"id":613857,"date":"2025-09-24T12:05:42","date_gmt":"2025-09-24T10:05:42","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=613857&#038;preview=true&#038;preview_id=613857"},"modified":"2025-09-24T07:56:43","modified_gmt":"2025-09-24T05:56:43","slug":"strasbourg-marseille-compositions-chaine-tv-heure-et-cotes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/","title":{"rendered":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE 1 2025-2026 &#8211; <\/em><em>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes<\/em><em>.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Quatri\u00e8me de Ligue 1 apr\u00e8s cinq journ\u00e9es, <strong>Strasbourg<\/strong> r\u00e9alise un d\u00e9but de saison au presque parfait. Les Alsaciens ont remport\u00e9 quatre de leurs cinq premiers matchs. <strong>Metz<\/strong>, <strong>Nantes,<\/strong> <strong>Le<\/strong> <strong>Havre<\/strong> et le <strong>Paris<\/strong> <strong>FC<\/strong> sont tomb\u00e9s face au <strong>RCS<\/strong>. Seul Monaco a r\u00e9ussi \u00e0 arracher un succ\u00e8s en toute fin de partie pour infliger leur seule d\u00e9faite de ce d\u00e9but de saison aux <strong>Strasbourgeois<\/strong>.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2025-2026\/\">Classement Ligue 1 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Marseille veut confirmer apr\u00e8s sa victoire face au PSG<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Olympique<\/strong> <strong>de<\/strong> <strong>Marseille<\/strong> a enfin remport\u00e9 un Classique contre le <strong>Paris Saint-Germain<\/strong> apr\u00e8s le report du match \u00e0 cause des intemp\u00e9ries. Les <strong>Olympiens<\/strong> ont remport\u00e9 trois de leurs cinq premiers matchs de la saison et ils viennent d&rsquo;encha\u00eener deux succ\u00e8s de rang. Le <strong>Stade Rennais<\/strong> et l&rsquo;<strong>Olympique Lyonnais<\/strong> sont les deux \u00e9quipes \u00e0 avoir fait tomber l&rsquo;OM.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-j5-lolympique-de-marseille-vient-enfin-a-bout-du-paris-saint-germain\/\" class=\"vlp-link\" title=\"Ligue 1 2025\/2026 (J5) : L&#039;Olympique de Marseille vient enfin \u00e0 bout du Paris Saint-Germain\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J5-LOlympique-de-Marseille-vient-enfin-a-bout-du-Paris-Saint-Germain.png\" class=\"attachment-800x445 size-800x445\" alt=\"Ligue 1 20252026 (J5) L&#039;Olympique de Marseille vient enfin \u00e0 bout du Paris Saint-Germain\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J5-LOlympique-de-Marseille-vient-enfin-a-bout-du-Paris-Saint-Germain.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J5-LOlympique-de-Marseille-vient-enfin-a-bout-du-Paris-Saint-Germain-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J5-LOlympique-de-Marseille-vient-enfin-a-bout-du-Paris-Saint-Germain-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J5-LOlympique-de-Marseille-vient-enfin-a-bout-du-Paris-Saint-Germain-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Ligue 1 2025\/2026 (J5) : L'Olympique de Marseille vient enfin \u00e0 bout du Paris Saint-Germain<\/div><div class=\"vlp-block-1 vlp-link-summary\">LIGUE 1 2025\/2026 - Apr\u00e8s son report dimanche \u00e0 cause des pluies diluviennes qui se sont abattues sur les Bouches-du-Rh\u00f4ne, le Classique a profit\u00e9 \u00e0 l'OM, qui s'impose 1-0 contre le PSG sur la pelouse du V\u00e9lodrome.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">La saison pass\u00e9e, <strong>Strasbourg<\/strong> s&rsquo;est impos\u00e9 \u00e0 l&rsquo;aller et les deux \u00e9quipes ont fait match nul au retour. Chez les bookmakers, l&rsquo;<strong>OM<\/strong> est favori pour cette rencontre de la sixi\u00e8me journ\u00e9e de Ligue 1.<\/p>\n<h2 style=\"text-align: justify;\">Ligue 1 : Le programme TV de Strasbourg-Marseille<\/h2>\n<h3 style=\"text-align: justify;\">Vendredi 26 septembre 2025<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur Ligue 1+<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 20h45.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions officielles de Strasbourg-Marseille<\/h2>\n<h3 style=\"text-align: justify;\">La composition de Strasbourg<\/h3>\n<p style=\"text-align: justify;\">\u00c0 venir&#8230;<\/p>\n<h3 style=\"text-align: justify;\">La composition de Marseille<\/h3>\n<p style=\"text-align: justify;\">\u00c0 venir&#8230;<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Strasbourg-Marseille<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Vendredi 26 septembre, 20h45<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Strasbourg<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526064?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 3.40<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526064?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 3.65<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526064?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.96<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2025-2026 &#8211; \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/p>\n","protected":false},"author":1,"featured_media":613858,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,47045],"tags":[16878,75,1554,446,8799,1619],"class_list":["post-613857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-ligue-1","tag-breve","tag-football","tag-ligue-1","tag-marseille","tag-programme-tv","tag-strasbourg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2025-2026 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2025-2026 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T10:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes\",\"datePublished\":\"2025-09-24T10:05:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\"},\"wordCount\":448,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue 1\",\"Marseille\",\"Programme TV\",\"Strasbourg\"],\"articleSection\":[\"Cha\u00eene TV\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\",\"name\":\"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"datePublished\":\"2025-09-24T10:05:42+00:00\",\"description\":\"LIGUE 1 2025-2026 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes","description":"LIGUE 1 2025-2026 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/","og_locale":"fr_FR","og_type":"article","og_title":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes","og_description":"LIGUE 1 2025-2026 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","og_url":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-09-24T10:05:42+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes","datePublished":"2025-09-24T10:05:42+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/"},"wordCount":448,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png","keywords":["br\u00e8ve","Football","Ligue 1","Marseille","Programme TV","Strasbourg"],"articleSection":["Cha\u00eene TV","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/","url":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/","name":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png","datePublished":"2025-09-24T10:05:42+00:00","description":"LIGUE 1 2025-2026 - \u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre Strasbourg et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Strasbourg-Marseille-Compositions-Chaine-TV-Heure-et-Cotes.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/strasbourg-marseille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Strasbourg-Marseille : Compositions, Cha\u00eene TV, Heure et Cotes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=613857"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613857\/revisions"}],"predecessor-version":[{"id":613869,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/613857\/revisions\/613869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/613858"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=613857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=613857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=613857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}