{"id":615231,"date":"2025-09-29T16:00:47","date_gmt":"2025-09-29T14:00:47","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=615231&#038;preview=true&#038;preview_id=615231"},"modified":"2025-09-29T13:04:22","modified_gmt":"2025-09-29T11:04:22","slug":"ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/","title":{"rendered":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE 1 2025-2026 &#8211; Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l&rsquo;arrach\u00e9e. Tour d&rsquo;horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le championnat de France bat son plein depuis la reprise. Et toutes les \u00e9quipes continuent de nous offrir du spectacle. Les comp\u00e9titions europ\u00e9ennes ont \u00e9galement repris pour certaines \u00e9quipes de <strong>Ligue 1<\/strong>. Entre de nouveaux cartons rouges, des buts somptueux, des victoires surprises ou des batailles acharn\u00e9es, voyons ce que nous r\u00e9serve la 6\u00e8me journ\u00e9e de <strong>Ligue 1<\/strong>.<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2025-2026\/\">Classement Ligue 1 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Les Tops<\/h2>\n<p style=\"text-align: justify;\"><strong>Brest sort la t\u00eate de l&rsquo;eau<\/strong><\/p>\n<p style=\"text-align: justify;\">En difficult\u00e9 depuis le d\u00e9but du championnat, <strong>Brest<\/strong> sort enfin la t\u00eate de l&rsquo;eau. Si les <strong>Brestois<\/strong>, h\u00e9ro\u00efques en <b>Ligue des champions<\/b>\u00a0la saison derni\u00e8re, ont entam\u00e9 la saison par un match nul prolifique face \u00e0 <strong>Lille<\/strong> (3-3), la suite ne s&rsquo;est pas d\u00e9roul\u00e9e comme pr\u00e9vu. D\u00e9faits \u00e0 <strong>Toulouse<\/strong>, \u00e0 <strong>Lens<\/strong> et face au <strong>Paris FC<\/strong> \u00e0 domicile, les <strong>Brestois<\/strong> ont finalement pass\u00e9 la seconde et ram\u00e8nent leur 2\u00e8me victoire cons\u00e9cutive du <strong>Stade Raymond-Kopa<\/strong> (0-2) face \u00e0 <strong>Angers<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Pablo Pagis et Lorient en feu<\/strong><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est probablement le joueur du week-end en <strong>Ligue 1<\/strong>. <strong>Pablo Pagis<\/strong> a illumin\u00e9 la pelouse du <strong>Moustoir<\/strong> de son talent et de son football. Face \u00e0 un <strong>Monaco<\/strong> rapidement r\u00e9duit \u00e0 10 (<strong>Kehrer<\/strong> 38&prime;) et priv\u00e9 de toute inspiration, le num\u00e9ro 10 des <strong>Merlus<\/strong> \u00e0 fait le show. Entr\u00e9 en jeu \u00e0 la 72\u00e8me minute, il n&rsquo;aura fallu que 4 minutes au jeune milieu de terrain pour s&rsquo;illustrer. D&rsquo;abord par un slalom fou en pleine surface mon\u00e9gasque (76&prime;), puis par un but longue distance inscrit quelques minutes plus tard (82&prime;). Une victoire pleine de rage des <strong>Lorientais<\/strong>, port\u00e9 par un <strong>Pablo Pagis<\/strong> de gala, face \u00e0 un cador du championnat.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"pt\">Pablo Pagis, FC Lorient, olho nele \ud83d\udcab <a href=\"https:\/\/t.co\/5R7QMMatv2\">pic.twitter.com\/5R7QMMatv2<\/a><\/p>\n<p>\u2014 Ligue 1 Portugu\u00eas (@Ligue1_POR) <a href=\"https:\/\/twitter.com\/Ligue1_POR\/status\/1972429407685157297?ref_src=twsrc%5Etfw\">September 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>L&rsquo;OM continue sur sa lanc\u00e9e\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Forts <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-j5-lolympique-de-marseille-vient-enfin-a-bout-du-paris-saint-germain\/\">d&rsquo;une victoire au forceps face au <strong>PSG<\/strong><\/a> lors de la journ\u00e9e pr\u00e9c\u00e9dente, les joueurs de <strong>Roberto De Zerbi<\/strong> se d\u00e9pla\u00e7aient sur la pelouse <strong>La Meinau<\/strong>, face \u00e0 <strong>Strasbourg<\/strong>, autre \u00e9quipe europ\u00e9enne de <strong>Ligue 1<\/strong> engag\u00e9e en <strong>Ligue Europa Conf\u00e9rence<\/strong>. Dans un d\u00e9placement qui s&rsquo;annon\u00e7aient p\u00e9rilleux, les <strong>Marseillais<\/strong> se sont d&rsquo;abord faits peur avec l&rsquo;ouverture du score de <strong>Ouattara <\/strong>(49&prime;). Il aura fallu s&rsquo;en remettre \u00e0 <strong>Aubameyang <\/strong>(78&prime;) et \u00e0 un but d&rsquo;<strong>Amir Murillo<\/strong> dans les arr\u00eats de jeu (90+1&prime;) pour ramener les 3 points d&rsquo;<strong>Alsace<\/strong>. Une victoire pleine de caract\u00e8re et d&rsquo;envie pour les <strong>Phoc\u00e9ens<\/strong>, \u00e0 4 jours de leur d\u00e9placement \u00e0 l&rsquo;<strong>Ajax d&rsquo;Amsterdam<\/strong> en <b>Ligue des champions<\/b>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le sauveur Amir Murillo \ud83e\uddb8 <a href=\"https:\/\/t.co\/MT3ddjvrnW\">pic.twitter.com\/MT3ddjvrnW<\/a><\/p>\n<p>\u2014 Ligue 1 McDonald&rsquo;s (@Ligue1) <a href=\"https:\/\/twitter.com\/Ligue1\/status\/1972426089239863647?ref_src=twsrc%5Etfw\">September 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-compositions-chaine-tv-cotes-et-heure\/\">Marseille-Ajax : Compositions, Cha\u00eene TV, Cotes et Heure<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Krasso maintien le Paris FC<\/strong><\/p>\n<p style=\"text-align: justify;\">Si le <strong>Paris FC<\/strong> est un des promus de <strong>Ligue 1<\/strong> cette ann\u00e9e, ce n&rsquo;est pas pour autant qu&rsquo;il souhaite s&rsquo;enliser dans les derni\u00e8res places du championnat. Au fil des week-ends, on parle du <strong>PFC<\/strong> comme du petit poucet du milieu de tableau qui vient se faire une place parmi les \u00e9curies plus exp\u00e9riment\u00e9es. Ce dimanche encore, les hommes de <strong>St\u00e9phane Gilli<\/strong> en d\u00e9placement sur la C\u00f4te d&rsquo;Azur, se sont d\u00e9pass\u00e9s pour ramener le point du nul de <strong>Nice<\/strong> gr\u00e2ce \u00e0 un p\u00e9nalty de <strong>Jean-Philippe Krasso<\/strong> en fin de match. Encore tr\u00e8s important lors de sa rentr\u00e9e pour les <strong>Parisiens<\/strong>, l&rsquo;attaquant ivoirien permet au club de la capitale de s&rsquo;installer \u00e0 la 11\u00e8me place.<\/p>\n<h2 style=\"text-align: justify;\">Les Flops<\/h2>\n<p style=\"text-align: justify;\"><strong>Jonathan Gradit saborde Lens<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lens<\/strong> avait l&rsquo;occasion de faire un coup ce week-end face \u00e0 <strong>Rennes<\/strong>. En d\u00e9placement chez les <strong>Rennais<\/strong> avec qui ils se battent pour une place dans le <strong>Top 6,<\/strong> les <strong>Lensois<\/strong> esp\u00e9raient surfer sur la derni\u00e8re r\u00e9ception compliqu\u00e9e des <strong>Bretons<\/strong> (2-2 face \u00e0 <strong>Nantes<\/strong>) pour grappiller quelques points au classement. Mais l\u00e0-bas aussi, tout ne s&rsquo;est pas pass\u00e9 comme pr\u00e9vu. D\u00e8s la premi\u00e8re minute de jeu, le match a \u00e0 peine commenc\u00e9 et <strong>Jonathan Gradit<\/strong> se rend coupable d&rsquo;une tr\u00e8s vilaine faute. \u00c7a ne fait aucun doute pour l&rsquo;arbitre de la rencontre qui le renvoie aux vestiaires. <strong>Lens<\/strong> a tenu bon tout le match et valide un bien maigre r\u00e9sultat, 0-0.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">5 | Rennes 0-0 Lens<\/p>\n<p>Jonathan Gradit&rsquo;s game lasted only 54 seconds. This is far from being the record for the fastest sending off in Ligue 1, which belongs to Jean-Clair Todibo.<a href=\"https:\/\/t.co\/PKZdOkhV7M\">pic.twitter.com\/PKZdOkhV7M<\/a><\/p>\n<p>\u2014 Get French Football News (@GFFN) <a href=\"https:\/\/twitter.com\/GFFN\/status\/1972374116054487270?ref_src=twsrc%5Etfw\">September 28, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<strong>Monaco coule \u00e0 Lorient<\/strong><\/p>\n<p style=\"text-align: justify;\">Mais que se passe-t-il \u00e0 <strong>Monaco<\/strong> ? Un coup de moins bien ? L&rsquo;ombre sournoise et invisible d&rsquo;un marabout ? En tout cas, touch\u00e9s au plus profond par une d\u00e9faite critique sur le terrain du <strong>Club Bruges<\/strong> en <b>Ligue des champions<\/b>, les <strong>Mon\u00e9gasques<\/strong> ne parviennent pas \u00e0 s&rsquo;en sortir. Face \u00e0 <strong>Lorient<\/strong>, club qui n&rsquo;est pourtant pas abonn\u00e9 au titre de bourreau des grosses \u00e9curies, le club du <strong>Rocher<\/strong> a litt\u00e9ralement coul\u00e9. Trois buts conc\u00e9d\u00e9s, la faute \u00e0 des largesses d\u00e9fensives rares \u00e0 <strong>Monaco<\/strong>. Et un seul petit but marqu\u00e9, bien loin au-del\u00e0 du temps r\u00e8glementaire, et sur p\u00e9nalty de surcroit. L&rsquo;heure est au r\u00e9veil dans la principaut\u00e9, alors que c&rsquo;est <strong>Manchester City<\/strong> qui s&rsquo;avance en <b>Ligue des champions<\/b>\u00a0ce mardi sur la pelouse du <strong>Louis-II<\/strong>.<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/monaco-manchester-city-compositions-chaine-tv-heure-et-cotes-ligue-des-champions-2025-2026\/\">Monaco-Manchester City : Compositions, Cha\u00eene TV, Heure et Cotes<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Bruno Genesio d\u00e9goupille\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lille<\/strong> n&rsquo;avait certainement pas besoin de \u00e7a. Port\u00e9 par son stade <strong>Pierre-Mauroy<\/strong> et fort <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-2025-2026-j1-lille-sen-remet-a-olivier-giroud-pour-simposer-face-a-brann\/\">d&rsquo;une victoire en <strong>Ligue Europa<\/strong><\/a> quelques jours auparavant, le <strong>LOSC<\/strong> s&rsquo;avan\u00e7ait confiant face aux <strong>Lyonnais<\/strong>. Un match qui promettait sur le papier, tendu jusqu&rsquo;au bout sur le terrain. <strong>Tyler Morton<\/strong> a ouvert le score tr\u00e8s t\u00f4t pour l&rsquo;<strong>OL<\/strong> (13&prime;). <strong>Lille<\/strong> a tent\u00e9 de revenir tout le match, domin\u00e9 son adversaire pendant plus de 70 minutes (1.47 XG contre 0.44) mais les <strong>Dogues<\/strong> ont manqu\u00e9 de r\u00e9alisme. <strong>Bruno Genesio<\/strong>, furieux que son \u00e9quipe ne convertisse pas ses occasions et v\u00e9h\u00e9ment envers l&rsquo;arbitre, est sanctionn\u00e9 d&rsquo;un carton rouge. Dommage pour le <strong>LOSC<\/strong> qui s&rsquo;incline \u00e0 domicile 0-1 face \u00e0 l&rsquo;<strong>OL<\/strong>.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-j6-lyon-fait-le-coup-parfait-a-lille-et-rejoint-le-psg-en-tete\/\" class=\"vlp-link\" title=\"Ligue 1 2025\/2026 (J6) : Lyon fait le coup parfait \u00e0 Lille et rejoint le PSG en t\u00eate\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J6-Lyon-fait-le-coup-parfait-a-Lille-et-rejoint-le-PSG-en-tete.png\" class=\"attachment-800x445 size-800x445\" alt=\"Ligue 1 20252026 (J6) Lyon fait le coup parfait \u00e0 Lille et rejoint le PSG en t\u00eate\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J6-Lyon-fait-le-coup-parfait-a-Lille-et-rejoint-le-PSG-en-tete.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J6-Lyon-fait-le-coup-parfait-a-Lille-et-rejoint-le-PSG-en-tete-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J6-Lyon-fait-le-coup-parfait-a-Lille-et-rejoint-le-PSG-en-tete-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-J6-Lyon-fait-le-coup-parfait-a-Lille-et-rejoint-le-PSG-en-tete-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Ligue 1 2025\/2026 (J6) : Lyon fait le coup parfait \u00e0 Lille et rejoint le PSG en t\u00eate<\/div><div class=\"vlp-block-1 vlp-link-summary\">LIGUE 1 2025\/2026 - Un but pr\u00e9coce de Tyler Morton aura suffi \u00e0 Lyon pour rafler sa cinqui\u00e8me victoire en six matchs. Battu pour la deuxi\u00e8me fois d'affil\u00e9e en Ligue 1, Lille marque le pas.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\"><strong>Match plat entre Metz et Le Havre<\/strong><\/p>\n<p style=\"text-align: justify;\">Et pour finir ces Tops et Flops anim\u00e9s, quoi de mieux qu&rsquo;une petite sieste. \u00c0 <strong>Metz<\/strong>, les supporters qui avaient pris place dans les trav\u00e9es du stade <strong>Saint-Symphorien<\/strong> ont sans doute ferm\u00e9 les yeux pendant un moment. Les <strong>Messins<\/strong>, lanternes rouges, recevaient <strong>Le Havre<\/strong>, aux portes de la zone rel\u00e9gable, dans un match totalement \u00e0 leur port\u00e9e. Deux tirs cadr\u00e9s dans tout le match, les deux \u00e9quipes confondues et un match bien plat conclu par un score \u00e0 son image : 0-0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2025-2026 &#8211; Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l&rsquo;arrach\u00e9e. Tour d&rsquo;horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.<\/p>\n","protected":false},"author":119,"featured_media":615258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,75,1554,7842],"class_list":["post-615231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-football","tag-ligue-1","tag-tops-et-flops"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2025-2026 - Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l&#039;arrach\u00e9e. Tour d&#039;horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2025-2026 - Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l&#039;arrach\u00e9e. Tour d&#039;horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T14:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Aur\u00e9lien Torreilles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\"},\"author\":{\"name\":\"Aur\u00e9lien Torreilles\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d42c64fd3f03197157c71106ec84f28a\"},\"headline\":\"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e\",\"datePublished\":\"2025-09-29T14:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\"},\"wordCount\":1246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue 1\",\"Tops et flops\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\",\"name\":\"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png\",\"datePublished\":\"2025-09-29T14:00:47+00:00\",\"description\":\"LIGUE 1 2025-2026 - Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l'arrach\u00e9e. Tour d'horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png\",\"width\":1200,\"height\":674,\"caption\":\"Ligue 1 20252026 Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d42c64fd3f03197157c71106ec84f28a\",\"name\":\"Aur\u00e9lien Torreilles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Aurelien-Torreilles-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Aurelien-Torreilles-150x150.jpg\",\"caption\":\"Aur\u00e9lien Torreilles\"},\"description\":\"Encore apprenti journaliste, je d\u00e9couvre d\u00e8s mon plus jeune \u00e2ge les joies, les \u00e9motions et les frissons du monde du sport. Tr\u00e8s vite, j'en suis convaincu, je parlerai de sport toute ma vie, et promis pas que de rugby. Apr\u00e8s 3 ann\u00e9es de droit franco-espagnol, j'ai vite bifurqu\u00e9 vers l'\u00e9cole de journalisme de Toulouse pour en apprendre encore plus quant \u00e0 ce monde qui me passionne et parfaire mes tr\u00e8s jeunes et modestes connaissances. Je rejoins Dicodusport en juin 2025 apr\u00e8s 3 ann\u00e9es pass\u00e9es sur Treize Mondial. Faire vivre l'actualit\u00e9, transmettre l'information et transmettre des \u00e9motions sont mes seuls objectifs. Bien \u00e9videmment, tout \u00e7a dans la bonne humeur transpirante de l'\u00e9quipe de Dicodusport !\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/aurelien\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e","description":"LIGUE 1 2025-2026 - Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l'arrach\u00e9e. Tour d'horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e","og_description":"LIGUE 1 2025-2026 - Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l'arrach\u00e9e. Tour d'horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-09-29T14:00:47+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png","type":"image\/png"}],"author":"Aur\u00e9lien Torreilles","twitter_card":"summary_large_image","twitter_title":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/"},"author":{"name":"Aur\u00e9lien Torreilles","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d42c64fd3f03197157c71106ec84f28a"},"headline":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e","datePublished":"2025-09-29T14:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/"},"wordCount":1246,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png","keywords":["br\u00e8ve","Football","Ligue 1","Tops et flops"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/","name":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png","datePublished":"2025-09-29T14:00:47+00:00","description":"LIGUE 1 2025-2026 - Des buts, de nouveaux cartons rouges, mais aussi des surprises et des victoires \u00e0 l'arrach\u00e9e. Tour d'horizons des meilleures et des pires choses que nous a offertes la 6\u00e8me journ\u00e9e de Ligue 1.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Ligue-1-20252026-Jonathan-Gradit-Marseille-Monaco-les-tops-et-flops-de-la-6eme-journee.png","width":1200,"height":674,"caption":"Ligue 1 20252026 Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-2025-2026-jonathan-gradit-marseille-monaco-les-tops-et-flops-de-la-6eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 2025\/2026 : Jonathan Gradit, Marseille, Monaco, les tops et flops de la 6\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d42c64fd3f03197157c71106ec84f28a","name":"Aur\u00e9lien Torreilles","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Aurelien-Torreilles-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Aurelien-Torreilles-150x150.jpg","caption":"Aur\u00e9lien Torreilles"},"description":"Encore apprenti journaliste, je d\u00e9couvre d\u00e8s mon plus jeune \u00e2ge les joies, les \u00e9motions et les frissons du monde du sport. Tr\u00e8s vite, j'en suis convaincu, je parlerai de sport toute ma vie, et promis pas que de rugby. Apr\u00e8s 3 ann\u00e9es de droit franco-espagnol, j'ai vite bifurqu\u00e9 vers l'\u00e9cole de journalisme de Toulouse pour en apprendre encore plus quant \u00e0 ce monde qui me passionne et parfaire mes tr\u00e8s jeunes et modestes connaissances. Je rejoins Dicodusport en juin 2025 apr\u00e8s 3 ann\u00e9es pass\u00e9es sur Treize Mondial. Faire vivre l'actualit\u00e9, transmettre l'information et transmettre des \u00e9motions sont mes seuls objectifs. Bien \u00e9videmment, tout \u00e7a dans la bonne humeur transpirante de l'\u00e9quipe de Dicodusport !","url":"https:\/\/dicodusport.fr\/blog\/author\/aurelien\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/119"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=615231"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615231\/revisions"}],"predecessor-version":[{"id":615259,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615231\/revisions\/615259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/615258"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=615231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=615231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=615231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}