{"id":615342,"date":"2025-09-30T07:55:17","date_gmt":"2025-09-30T05:55:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=615342&#038;preview=true&#038;preview_id=615342"},"modified":"2025-09-30T07:51:40","modified_gmt":"2025-09-30T05:51:40","slug":"marseille-ajax-les-compositions-probables","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/","title":{"rendered":"Marseille-Ajax : Les compositions probables"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>LIGUE DES CHAMPIONS &#8211; Selon L&rsquo;\u00c9quipe, voici les compositions probables du match entre Marseille et l&rsquo;Ajax pr\u00e9vu ce mardi.<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-compositions-chaine-tv-cotes-et-heure\/\" target=\"_blank\" rel=\"noopener\">Marseille-Ajax : Compositions, Cha\u00eene TV, Cotes et Heure<\/a><\/strong><strong><br \/>\n<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Olympique de Marseille<\/strong> s&rsquo;avance en favori pour ce deuxi\u00e8me match en <b>Ligue des champions<\/b>\u00a0de la saison. Au V\u00e9lodrome, les <strong>Olympiens<\/strong> pourront compter sur un stade \u00e0 guichets ferm\u00e9s pour marquer leurs premiers points dans cette comp\u00e9tition, apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-2025-2026-j1-porte-par-mbappe-le-real-madrid-vient-a-bout-de-lom\/\">la d\u00e9faite inaugurale sur la pelouse du Real Madrid<\/a>.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-2025-2026-dates-matchs-et-calendrier-de-marseille\/\" class=\"vlp-link\" title=\"Ligue des Champions 2025-2026 : Dates, matchs et calendrier de Marseille\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-des-Champions-2025-2026-Dates-matchs-et-calendrier-de-Marseille.png\" class=\"attachment-800x445 size-800x445\" alt=\"Ligue des Champions 2025-2026 Dates, matchs et calendrier de Marseille\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-des-Champions-2025-2026-Dates-matchs-et-calendrier-de-Marseille.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-des-Champions-2025-2026-Dates-matchs-et-calendrier-de-Marseille-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-des-Champions-2025-2026-Dates-matchs-et-calendrier-de-Marseille-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/08\/Ligue-des-Champions-2025-2026-Dates-matchs-et-calendrier-de-Marseille-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Ligue des Champions 2025-2026 : Dates, matchs et calendrier de Marseille<\/div><div class=\"vlp-block-1 vlp-link-summary\">LIGUE DES CHAMPIONS - Apr\u00e8s le tirage au sort, place au calendrier : voici les dates des 8 rencontres de l'Olympique de Marseille pour la phase de championnat.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Leonardo Balerdi incertain<\/h2>\n<p style=\"text-align: justify;\"><strong>Roberto De Zerbi<\/strong> pourrait \u00eatre contraint \u00e0 jouer sans <strong>Leonardo<\/strong> <strong>Balerdi<\/strong>, incertain pour cette rencontre. En cas de forfait, <strong>Facundo<\/strong> <strong>Medina<\/strong> serait titularis\u00e9 dans l&rsquo;axe. Au milieu de terrain, <strong>Matt<\/strong> <strong>O&rsquo;Riley<\/strong> devrait d\u00e9buter, tout comme <strong>Angel<\/strong> <strong>Gomes<\/strong>. Rempla\u00e7ants face \u00e0 Strasbourg, <strong>Mason<\/strong> <strong>Greenwood<\/strong> et <strong>Pierre-Emerick<\/strong> <strong>Aubameyang<\/strong> sont attendus dans le onze de d\u00e9part.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Ajax Amsterdam<\/strong> est de son c\u00f4t\u00e9 priv\u00e9 de deux joueurs offensifs majeurs pour cette rencontre. <strong>Wout<\/strong> <strong>Weghorst<\/strong> et <strong>Kasper<\/strong> <strong>Dolberg<\/strong> sont forfaits pour ce choc face \u00e0 l&rsquo;Olympique de Marseille. <strong>Branco<\/strong> <strong>van<\/strong> <strong>den<\/strong> <strong>Boomen<\/strong>, pass\u00e9 par le Toulouse FC, est lui aussi absent pour une blessure.<\/p>\n<h2 style=\"text-align: justify;\">La composition probable de Marseille<\/h2>\n<p style=\"text-align: justify;\"><span class=\"css-1jxf684 r-bcqeeo r-1ttztb7 r-qvutc0 r-poiln3\">Rulli &#8211; Pavard, Aguerd, Medina, Emerson &#8211; O&rsquo;Riley, Hojbjerg &#8211; Gomes, Weah, Greenwood &#8211; Aubameyang<\/span><\/p>\n<h2 style=\"text-align: justify;\">La composition probable de l&rsquo;Ajax<\/h2>\n<p style=\"text-align: justify;\">Jaros &#8211; Gaaei, Itakura, Baas, Wijndal &#8211; Berghuis, Klaassen, Taylor &#8211; Moro, Gloukh, Godts<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Marseille-Ajax<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Mardi 30 septembre, 21h00<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/63369745?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.50<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/63369745?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 4.50<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Ajax<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/63369745?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 5.50<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS &#8211; Selon L&rsquo;\u00c9quipe, voici les compositions probables du match entre Marseille et l&rsquo;Ajax pr\u00e9vu ce mardi.<\/p>\n","protected":false},"author":1,"featured_media":615343,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47250],"tags":[7823,16878,75,419,446],"class_list":["post-615342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-ajax","tag-breve","tag-football","tag-ligue-des-champions","tag-marseille"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marseille-Ajax : Les compositions probables<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS - Selon L&#039;\u00c9quipe, voici les compositions probables du match entre Marseille et l&#039;Ajax pr\u00e9vu ce mardi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marseille-Ajax : Les compositions probables\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS - Selon L&#039;\u00c9quipe, voici les compositions probables du match entre Marseille et l&#039;Ajax pr\u00e9vu ce mardi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T05:55:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Marseille-Ajax : Les compositions probables\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Marseille-Ajax : Les compositions probables\",\"datePublished\":\"2025-09-30T05:55:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\"},\"wordCount\":422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png\",\"keywords\":[\"Ajax\",\"br\u00e8ve\",\"Football\",\"Ligue des champions\",\"Marseille\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\",\"name\":\"Marseille-Ajax : Les compositions probables\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png\",\"datePublished\":\"2025-09-30T05:55:17+00:00\",\"description\":\"LIGUE DES CHAMPIONS - Selon L'\u00c9quipe, voici les compositions probables du match entre Marseille et l'Ajax pr\u00e9vu ce mardi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marseille-Ajax : Les compositions probables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marseille-Ajax : Les compositions probables","description":"LIGUE DES CHAMPIONS - Selon L'\u00c9quipe, voici les compositions probables du match entre Marseille et l'Ajax pr\u00e9vu ce mardi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/","og_locale":"fr_FR","og_type":"article","og_title":"Marseille-Ajax : Les compositions probables","og_description":"LIGUE DES CHAMPIONS - Selon L'\u00c9quipe, voici les compositions probables du match entre Marseille et l'Ajax pr\u00e9vu ce mardi.","og_url":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-09-30T05:55:17+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Marseille-Ajax : Les compositions probables","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Marseille-Ajax : Les compositions probables","datePublished":"2025-09-30T05:55:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png","keywords":["Ajax","br\u00e8ve","Football","Ligue des champions","Marseille"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/","url":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/","name":"Marseille-Ajax : Les compositions probables","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png","datePublished":"2025-09-30T05:55:17+00:00","description":"LIGUE DES CHAMPIONS - Selon L'\u00c9quipe, voici les compositions probables du match entre Marseille et l'Ajax pr\u00e9vu ce mardi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Marseille-Ajax-Les-compositions-probables.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/marseille-ajax-les-compositions-probables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Marseille-Ajax : Les compositions probables"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=615342"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615342\/revisions"}],"predecessor-version":[{"id":615364,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615342\/revisions\/615364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/615343"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=615342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=615342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=615342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}