{"id":615371,"date":"2025-09-30T08:54:56","date_gmt":"2025-09-30T06:54:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=615371&#038;preview=true&#038;preview_id=615371"},"modified":"2025-09-30T16:11:12","modified_gmt":"2025-09-30T14:11:12","slug":"tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/","title":{"rendered":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&rsquo;offre le titre en double"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOURNOI ATP 500 DE TOKYO 2025 &#8211; Favori de la finale en compagnie d&rsquo;Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Figure du circuit de double et meilleur joueur fran\u00e7ais de la discipline, <strong>\u00c9douard Roger-Vasselin<\/strong> a pour partenaire depuis le d\u00e9but de la saison le Mon\u00e9gasque <strong>Hugo Nys<\/strong>. Une paire qui a atteint ensemble la finale \u00e0 Marrakech et \u00e0 Washington, mais leur premier titre se faisait attendre. Ils avaient toutefois l&rsquo;occasion de le rafler ce matin, en finale de l&rsquo;ATP 500 de Tokyo.<\/p>\n<h2 style=\"text-align: justify;\">Et de 29 pour Roger-Vasselin<\/h2>\n<p style=\"text-align: justify;\">Face \u00e0 eux, la l\u00e9gende indienne <strong>Rohan Bopanna<\/strong>, 45 ans, vainqueur de l&rsquo;Open d&rsquo;Australie en 2024, et le local <strong>Takeru Yuzuki<\/strong>. Une paire nouvellement form\u00e9e qui ne faisait pas peur \u00e0 l&rsquo;attelage franco-mon\u00e9gasque, qui breakait d&rsquo;entr\u00e9e avant de se faire rejoindre. N\u00e9anmoins, <strong>Roger-Vasselin<\/strong> et son comparse allaient d\u00e9montrer leur solidit\u00e9 sur les moments importants, faisant parler leur longue exp\u00e9rience. Deux fois, ils allaient mettre une pression monstre sur leurs rivaux quand ceux-ci servaient \u00e0 5-5, et deux fois, ils allaient breaker au meilleur moment.<\/p>\n<p style=\"text-align: justify;\">Quand ils servaient pour le set, ils sauvaient une balle de d\u00e9break et concluaient sur une vol\u00e9e gagnante. Et quand ils servaient pour le titre, le bras ne tremblait absolument pas, et ils concluaient en patrons sur un jeu blanc. <strong>7-5, 7-5<\/strong>, c&rsquo;est donc leur premier titre ensemble, mais surtout, c&rsquo;est le 29\u00e8me titre en carri\u00e8re en double messieurs pour <strong>\u00c9douard Roger-Vasselin<\/strong>, qui, \u00e0 41 ans, n&rsquo;en a clairement pas fini avec le tennis, puisqu&rsquo;il est toujours solidement ancr\u00e9 dans le Top 20 mondial (16\u00e8me) en double. Le tout gr\u00e2ce \u00e0 son premier titre depuis <a href=\"https:\/\/dicodusport.fr\/blog\/rolex-paris-masters-2023-santiago-gonzalez-et-edouard-roger-vasselin-remportent-leur-2e-masters-1000\/\">le Masters 1000 de Paris en 2023<\/a> (il avait n\u00e9anmoins remport\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2024-edouard-roger-vasselin-s-offre-le-double-mixte-aux-cotes-de-laura-siegemund\/\">Roland-Garros en 2024, mais en double mixte avec <strong>Laura Siegemund<\/strong><\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOURNOI ATP 500 DE TOKYO 2025 &#8211; Favori de la finale en compagnie d&rsquo;Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.<\/p>\n","protected":false},"author":59,"featured_media":615480,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2302],"tags":[16878,23367,6755],"class_list":["post-615371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-breve","tag-circuit-atp","tag-edouard-roger-vasselin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&#039;offre le titre en double<\/title>\n<meta name=\"description\" content=\"TOURNOI ATP 500 DE TOKYO 2025 - Favori de la finale en compagnie d&#039;Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&#039;offre le titre en double\" \/>\n<meta property=\"og:description\" content=\"TOURNOI ATP 500 DE TOKYO 2025 - Favori de la finale en compagnie d&#039;Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T06:54:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T14:11:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&#039;offre le titre en double\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&rsquo;offre le titre en double\",\"datePublished\":\"2025-09-30T06:54:56+00:00\",\"dateModified\":\"2025-09-30T14:11:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png\",\"keywords\":[\"br\u00e8ve\",\"circuit ATP\",\"Edouard Roger-Vasselin\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\",\"name\":\"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s'offre le titre en double\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png\",\"datePublished\":\"2025-09-30T06:54:56+00:00\",\"dateModified\":\"2025-09-30T14:11:12+00:00\",\"description\":\"TOURNOI ATP 500 DE TOKYO 2025 - Favori de la finale en compagnie d'Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Tennis ATP Tokyo 2025 \u00c9douard Roger-Vasselin s'offre le titre en double\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&rsquo;offre le titre en double\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s'offre le titre en double","description":"TOURNOI ATP 500 DE TOKYO 2025 - Favori de la finale en compagnie d'Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/","og_locale":"fr_FR","og_type":"article","og_title":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s'offre le titre en double","og_description":"TOURNOI ATP 500 DE TOKYO 2025 - Favori de la finale en compagnie d'Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.","og_url":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-09-30T06:54:56+00:00","article_modified_time":"2025-09-30T14:11:12+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s'offre le titre en double","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&rsquo;offre le titre en double","datePublished":"2025-09-30T06:54:56+00:00","dateModified":"2025-09-30T14:11:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png","keywords":["br\u00e8ve","circuit ATP","Edouard Roger-Vasselin"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/","url":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/","name":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s'offre le titre en double","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png","datePublished":"2025-09-30T06:54:56+00:00","dateModified":"2025-09-30T14:11:12+00:00","description":"TOURNOI ATP 500 DE TOKYO 2025 - Favori de la finale en compagnie d'Hugo Nys, \u00c9douard Roger-Vasselin a tenu son rang et rafle son 29\u00e8me titre en double messieurs.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Tennis-ATP-Tokyo-2025-Edouard-Roger-Vasselin-soffre-le-titre-en-double-1.png","width":1200,"height":674,"caption":"Tennis ATP Tokyo 2025 \u00c9douard Roger-Vasselin s'offre le titre en double"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tennis-atp-tokyo-2025-edouard-roger-vasselin-soffre-le-titre-en-double\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tennis ATP Tokyo 2025 : \u00c9douard Roger-Vasselin s&rsquo;offre le titre en double"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=615371"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615371\/revisions"}],"predecessor-version":[{"id":615374,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/615371\/revisions\/615374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/615480"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=615371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=615371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=615371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}