{"id":616209,"date":"2025-10-03T11:55:37","date_gmt":"2025-10-03T09:55:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=616209&#038;preview=true&#038;preview_id=616209"},"modified":"2025-10-03T12:04:15","modified_gmt":"2025-10-03T10:04:15","slug":"para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/","title":{"rendered":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 &#8211; Alexandra Nouchet d\u00e9croche l&rsquo;argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re. Elle a propuls\u00e9 son poids \u00e0 10.11 m<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est un bel exploit que vient de r\u00e9aliser<strong> Alexandra Nouchet<\/strong> aux Mondiaux de para athl\u00e9tisme \u00e0 New Delhi. La Fran\u00e7aise de 27 ans a d\u00e9croch\u00e9 la m\u00e9daille d&rsquo;argent au lancer de poids F64 (athl\u00e8tes appareill\u00e9s de membre(s) inf\u00e9rieur(s)). Un exploit, car la Fran\u00e7aise \u00e9tait la seule F63 engag\u00e9e dans le concours. Pour rappel, pour le deuxi\u00e8me chiffre est proche du 1, plus le handicap est lourd. La Tricolore concourrait avec des concurrentes ayant un handicap plus l\u00e9ger qu&rsquo;elle. Cela ne l&rsquo;a pas emp\u00each\u00e9 d&rsquo;aller chercher la 2\u00e8me place son concours. Avec un jet \u00e0 10.10 m, son meilleur de la saison.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-marie-ngoussou-ngouyi-en-bronze-sur-le-100-m-t47\/\" class=\"vlp-link\" title=\"Para athl\u00e9tisme Mondiaux 2025 : Marie Ngoussou Ngouyi en bronze sur le 100 m T47\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Para-athletisme-Mondiaux-2025-Marie-Ngoussou-Ngouyi-en-bronze-sur-le-100-m-T47.png\" class=\"attachment-800x445 size-800x445\" alt=\"Para athl\u00e9tisme Mondiaux 2025 - Marie Ngoussou Ngouyi en bronze sur le 100 m T47\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Para-athletisme-Mondiaux-2025-Marie-Ngoussou-Ngouyi-en-bronze-sur-le-100-m-T47.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Para-athletisme-Mondiaux-2025-Marie-Ngoussou-Ngouyi-en-bronze-sur-le-100-m-T47-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Para-athletisme-Mondiaux-2025-Marie-Ngoussou-Ngouyi-en-bronze-sur-le-100-m-T47-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Para-athletisme-Mondiaux-2025-Marie-Ngoussou-Ngouyi-en-bronze-sur-le-100-m-T47-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Para athl\u00e9tisme Mondiaux 2025 : Marie Ngoussou Ngouyi en bronze sur le 100 m T47<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025 &#8211; Au milli\u00e8me, Marie Ngoussou Ngouyi prend le bronze sur le 100 m T47 en 12.29. <\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Quatri\u00e8me m\u00e9daille pour les Bleus<\/h2>\n<p style=\"text-align: justify;\">Un jet certes \u00e0 distance respectable de son record (10.63 m, soit le record du monde dans la cat\u00e9gorie F63). Mais qui lui a permis de devancer l&rsquo;Am\u00e9ricaine <strong>Alexandra Guerrero<\/strong> de huit centim\u00e8tres, alors que la jeune Polonaise, <strong>Faustyna Kot\u0142owska,<\/strong> \u00e9tablit le record des championnats, avec un jet \u00e0 10.88 m. Mais l&rsquo;argent fait le bonheur de la Fran\u00e7aise, qui d\u00e9croche en Inde la toute premi\u00e8re m\u00e9daille mondiale de sa carri\u00e8re.<\/p>\n<p style=\"text-align: justify;\">La quatri\u00e8me pour le clan tricolore depuis le d\u00e9but des championnats du monde. Les Bleus se rapprochent \u00e0 une unit\u00e9 du total des Jeux Paralympiques de Paris 2024. D\u00e8s ce vendredi, d&rsquo;autres Fran\u00e7ais seront en lice pour tenter de d\u00e9crocher une breloque. Dont <strong>Pierre Fairbank<\/strong> sur le 800 m fauteuil. Mais aussi <strong>Dimitri Pavad\u00e9<\/strong>, dans une finale de la longueur T64 (la m\u00eame cat\u00e9gorie qu&rsquo;Alexandra Nouchet) report\u00e9e \u00e0 ce vendredi. Deux vraies chances de m\u00e9dailles pour le clan tricolore.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udc74\ud835\udc68\ud835\udc6e\ud835\udc70\ud835\udc7a\ud835\udc7b\ud835\udc79\ud835\udc68\ud835\udc73\ud835\udc6c<br \/>\nD\u00e8s son 2\u00e8me lancer, Alexandra Nouchet signe la 2\u00e8me meilleure performance du concours et est sacr\u00e9e Vice-Championne du Monde en lancer de poids F61\/62\/63\/64 !<\/p>\n<p>Quelle fiert\u00e9 pour notre athl\u00e8te du Team EDF \ud83e\udd79 <a href=\"https:\/\/t.co\/wlbI9x6hpF\">pic.twitter.com\/wlbI9x6hpF<\/a><\/p>\n<p>\u2014 EDF Sport (@EDF_Sport) <a href=\"https:\/\/twitter.com\/EDF_Sport\/status\/1974020387869540605?ref_src=twsrc%5Etfw\">October 3, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les m\u00e9dailles fran\u00e7aises<\/h2>\n<p style=\"text-align: justify;\">Or : \u2013<\/p>\n<p style=\"text-align: justify;\">Argent : Thibault Daurat (5.000 m T54), Tr\u00e9sor Makunda (400 m T11), Alexandra Nouchet (lancer du poids F64)<\/p>\n<p style=\"text-align: justify;\">Bronze : Marie Ngoussou Ngouyi (100 m T47)<\/p>\n<div class=\"nwVKo\">\n<div class=\"loJjTe\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 &#8211; Alexandra Nouchet d\u00e9croche l&rsquo;argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re. Elle a propuls\u00e9 son poids \u00e0 10.11 m<\/p>\n","protected":false},"author":83,"featured_media":616217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2308,5753],"tags":[16878,29208],"class_list":["post-616209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-handisport","tag-breve","tag-para-athletisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 - Alexandra Nouchet d\u00e9croche l&#039;argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 - Alexandra Nouchet d\u00e9croche l&#039;argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-03T09:55:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T10:04:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64\",\"datePublished\":\"2025-10-03T09:55:37+00:00\",\"dateModified\":\"2025-10-03T10:04:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\"},\"wordCount\":496,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png\",\"keywords\":[\"br\u00e8ve\",\"para athl\u00e9tisme\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Handisport\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\",\"name\":\"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png\",\"datePublished\":\"2025-10-03T09:55:37+00:00\",\"dateModified\":\"2025-10-03T10:04:15+00:00\",\"description\":\"CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 - Alexandra Nouchet d\u00e9croche l'argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png\",\"width\":1200,\"height\":674,\"caption\":\"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64","description":"CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 - Alexandra Nouchet d\u00e9croche l'argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/","og_locale":"fr_FR","og_type":"article","og_title":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64","og_description":"CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 - Alexandra Nouchet d\u00e9croche l'argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re.","og_url":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-10-03T09:55:37+00:00","article_modified_time":"2025-10-03T10:04:15+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64","datePublished":"2025-10-03T09:55:37+00:00","dateModified":"2025-10-03T10:04:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/"},"wordCount":496,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png","keywords":["br\u00e8ve","para athl\u00e9tisme"],"articleSection":["Athl\u00e9tisme","Handisport"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/","url":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/","name":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png","datePublished":"2025-10-03T09:55:37+00:00","dateModified":"2025-10-03T10:04:15+00:00","description":"CHAMPIONNATS DU MONDE DE PARA ATHL\u00c9TISME 2025\u00a0 - Alexandra Nouchet d\u00e9croche l'argent au lancer de poids F64, la premi\u00e8re de sa carri\u00e8re.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Para-athletisme-Mondiaux-2025-Alexandra-Nouchet-en-argent-au-poids.png","width":1200,"height":674,"caption":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/para-athletisme-mondiaux-2025-alexandra-nouchet-en-argent-au-poids-f64\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Para athl\u00e9tisme Mondiaux 2025 : Alexandra Nouchet en argent au poids F64"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/616209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=616209"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/616209\/revisions"}],"predecessor-version":[{"id":616229,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/616209\/revisions\/616229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/616217"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=616209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=616209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=616209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}