{"id":617105,"date":"2025-10-05T20:58:38","date_gmt":"2025-10-05T18:58:38","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=617105&#038;preview=true&#038;preview_id=617105"},"modified":"2025-10-05T21:00:07","modified_gmt":"2025-10-05T19:00:07","slug":"vtt-xco-lake-placid-2025-classement-course-femmes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/","title":{"rendered":"VTT XCO Lake Placid 2025 : Classement Course femmes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><i>D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre <\/i><\/strong><strong><i>2025.<\/i><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-vtt-cross-country-2025-calendrier-et-resultats-a-jour\/\">Coupe du monde VTT Cross-Country 2025 : Calendrier et R\u00e9sultats \u00e0 Jour<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le circuit de <strong>Lake Placid<\/strong>, dans l\u2019\u00c9tat de New York, accueille ce dimanche 5 octobre 2025 la manche f\u00e9minine de cross-country olympique (XCO) des <strong>UCI Mountain Bike World Series<\/strong>. Organis\u00e9e sur le site mythique de <strong>Mt Van Hoevenberg<\/strong>, cette neuvi\u00e8me \u00e9tape du calendrier mondial s\u2019annonce comme l\u2019une des plus exigeantes de la saison, \u00e0 la fois physique, technique et d\u00e9cisive pour le classement g\u00e9n\u00e9ral.<\/p>\n<p style=\"text-align: justify;\">Le parcours, trac\u00e9 au c\u0153ur des <strong>Adirondacks<\/strong>, alterne mont\u00e9es raides, portions roulantes et descentes pi\u00e9geuses sur un sol changeant, typique de la r\u00e9gion. Avec ses encha\u00eenements rapides et ses zones de relance, le circuit mettra \u00e0 rude \u00e9preuve la gestion d\u2019effort et la pr\u00e9cision des pilotes.<\/p>\n<p style=\"text-align: justify;\">Les meilleures sp\u00e9cialistes mondiales du <strong>XCO<\/strong> seront au rendez-vous pour tenter de s\u2019imposer sur cette manche am\u00e9ricaine, \u00e0 commencer par les leaders du classement g\u00e9n\u00e9ral, bien d\u00e9cid\u00e9es \u00e0 consolider leur avance avant la fin de la saison. Mais sur un trac\u00e9 aussi s\u00e9lectif, les outsiders auront aussi leur mot \u00e0 dire : une attaque bien plac\u00e9e ou une erreur minime peut tout faire basculer. <a href=\"https:\/\/dicodusport.fr\/blog\/vtt-lake-placid-2025-jenny-rissveds-rafle-la-mise-sur-le-xcc\/\">Laur\u00e9ate du XCC vendredi<\/a>, <strong>Jenny Rissveds<\/strong> tentera de faire le doubl\u00e9, sur un format dont elle est la championne du monde en titre.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-vtt-2025-classement-general-feminin-en-cross-country\/\"><strong>Coupe du monde VTT 2025 : Classement G\u00e9n\u00e9ral F\u00e9minin en Cross-country<\/strong><\/a><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">VTT Cross-country 2025 &#8211; Classement XCO femmes Lake Placid<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong><em>Classement officiel mis \u00e0 jour \u00e0 l&rsquo;issue de la course.<\/em><\/strong><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>CYCLISTES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\uddf8\ud83c\uddea\u00a0JENNY RISSVEDS<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">1h20m15s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\uddec\ud83c\udde7 EVIE RICHARDS<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 2m16s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\uddf3\ud83c\uddff SAMARA MAXWELL<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 2m31s<\/b><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\uddfa\ud83c\uddf8 SAVILIA BLUNK<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 2m36s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\udde8\ud83c\udded ALESSANDRA KELLER<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 3m35s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\uddff\ud83c\udde6 CANDICE LILL<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 3m45s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\udde8\ud83c\udded RONJA BL\u00d6CHLINGER<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 3m59s<\/b><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\udde8\ud83c\udded SINA FREI<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 4m17s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\uddee\ud83c\uddf9 MARTINA BERTA<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 4m17s<\/b><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>\ud83c\udde8\ud83c\udded GINIA CALUORI<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><b style=\"font-size: 14.4px\">\u00e0 4m26s<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h3 style=\"text-align: justify;\">\u00c0 ce sujet<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.ucimtbworldseries.com\/results\/2025\/lake-placid-2025\">Le classement complet de la course<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.<\/p>\n","protected":false},"author":4,"featured_media":617108,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10279],"tags":[16878,11873,692],"class_list":["post-617105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vtt","tag-breve","tag-coupe-du-monde-de-vtt","tag-vtt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VTT XCO Lake Placid 2025 : Classement Course femmes<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VTT XCO Lake Placid 2025 : Classement Course femmes\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-05T18:58:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-05T19:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"VTT XCO Lake Placid 2025 : Classement Course femmes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"VTT XCO Lake Placid 2025 : Classement Course femmes\",\"datePublished\":\"2025-10-05T18:58:38+00:00\",\"dateModified\":\"2025-10-05T19:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\"},\"wordCount\":359,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png\",\"keywords\":[\"br\u00e8ve\",\"Coupe du monde de VTT\",\"VTT\"],\"articleSection\":[\"VTT\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\",\"name\":\"VTT XCO Lake Placid 2025 : Classement Course femmes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png\",\"datePublished\":\"2025-10-05T18:58:38+00:00\",\"dateModified\":\"2025-10-05T19:00:07+00:00\",\"description\":\"D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png\",\"width\":1200,\"height\":674,\"caption\":\"VTT XCO Lake Placid 2025 Classement Course femmes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VTT XCO Lake Placid 2025 : Classement Course femmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VTT XCO Lake Placid 2025 : Classement Course femmes","description":"D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/","og_locale":"fr_FR","og_type":"article","og_title":"VTT XCO Lake Placid 2025 : Classement Course femmes","og_description":"D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-10-05T18:58:38+00:00","article_modified_time":"2025-10-05T19:00:07+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"VTT XCO Lake Placid 2025 : Classement Course femmes","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"VTT XCO Lake Placid 2025 : Classement Course femmes","datePublished":"2025-10-05T18:58:38+00:00","dateModified":"2025-10-05T19:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/"},"wordCount":359,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png","keywords":["br\u00e8ve","Coupe du monde de VTT","VTT"],"articleSection":["VTT"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/","url":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/","name":"VTT XCO Lake Placid 2025 : Classement Course femmes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png","datePublished":"2025-10-05T18:58:38+00:00","dateModified":"2025-10-05T19:00:07+00:00","description":"D\u00e9couvrez le classement de la XCO femmes de Lake Placid (USA), dans le cadre de la Coupe du monde de VTT Cross-country, qui a eu lieu ce dimanche 5 octobre 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/VTT-XCO-Lake-Placid-2025-Classement-Course-femmes.png","width":1200,"height":674,"caption":"VTT XCO Lake Placid 2025 Classement Course femmes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/vtt-xco-lake-placid-2025-classement-course-femmes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"VTT XCO Lake Placid 2025 : Classement Course femmes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=617105"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617105\/revisions"}],"predecessor-version":[{"id":617124,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617105\/revisions\/617124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/617108"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=617105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=617105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=617105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}