{"id":617465,"date":"2025-10-08T12:00:24","date_gmt":"2025-10-08T10:00:24","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=617465&#038;preview=true&#038;preview_id=617465"},"modified":"2025-10-08T12:03:28","modified_gmt":"2025-10-08T10:03:28","slug":"edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/","title":{"rendered":"\u00c9dito : Pourquoi la prolongation d&rsquo;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Dans un rugby moderne o\u00f9 <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/transferts-rugby\/\">les transferts<\/a> se n\u00e9gocient \u00e0 coups de z\u00e9ros, de promesses de titres, voire de contrats mirobolants, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c0 contre-courant d\u2019une \u00e9poque o\u00f9 la fid\u00e9lit\u00e9 devient presque na\u00efve, le jeune international fran\u00e7ais (10 s\u00e9lections) rappelle qu\u2019il existe encore de la place pour la loyaut\u00e9, la patience et la conviction.<\/p>\n<p style=\"text-align: justify;\">Oui, il aurait pu c\u00e9der aux sir\u00e8nes du <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-un-cador-de-top-14-proche-de-signer-tom-willis\/\">Stade Toulousain<\/a>, du <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/stade-rochelais\/\">Stade Rochelais<\/a> ou d\u2019un autre grand club fran\u00e7ais. Les opportunit\u00e9s ne manquaient pas, les garanties sportives (et financi\u00e8res) non plus. Mais <strong>Gailleton<\/strong> a pr\u00e9f\u00e9r\u00e9 grandir l\u00e0 o\u00f9 il s\u2019est construit, l\u00e0 o\u00f9 il est pass\u00e9 d\u2019un espoir prometteur \u00e0 un joueur de niveau international. L\u00e0 o\u00f9 son rugby s\u2019est affin\u00e9, et o\u00f9 il a trouv\u00e9 un environnement \u00e0 son image : travailleur, exigeant, discret.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-pau-la-duree-du-nouveau-contrat-demilien-gailleton-devoilee\/\" class=\"vlp-link\" title=\"Transferts Pau : La dur\u00e9e du nouveau contrat d&#039;\u00c9milien Gailleton d\u00e9voil\u00e9e\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Transferts-Pau-La-duree-du-nouveau-contrat-dEmilien-Gailleton-devoilee.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Transferts-Pau-La-duree-du-nouveau-contrat-dEmilien-Gailleton-devoilee.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Transferts-Pau-La-duree-du-nouveau-contrat-dEmilien-Gailleton-devoilee-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Transferts-Pau-La-duree-du-nouveau-contrat-dEmilien-Gailleton-devoilee-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Transferts-Pau-La-duree-du-nouveau-contrat-dEmilien-Gailleton-devoilee-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts Pau : La dur\u00e9e du nouveau contrat d'\u00c9milien Gailleton d\u00e9voil\u00e9e<\/div><div class=\"vlp-block-1 vlp-link-summary\">TRANSFERTS PAU - Selon le Midi Olympique, \u00c9milien Gailleton va prolonger sur le long terme avec la Section Paloise.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Tout sauf un hasard<\/h2>\n<p style=\"text-align: justify;\">Ce choix n\u2019est pas anodin. \u00c0 22 ans, <strong>\u00c9milien Gailleton<\/strong> n\u2019est plus seulement un espoir : il est un symbole. Celui d\u2019une g\u00e9n\u00e9ration qui croit encore au sens du mot <em>projet<\/em>. En restant \u00e0 Pau, il prouve qu\u2019on peut viser haut sans forc\u00e9ment partir loin. Qu\u2019un club, entre guillemets <em>moyen<\/em>, du Top 14, peut offrir un cadre de progression aussi riche et exigeant, que les g\u00e9ants du championnat. Sa d\u00e9cision, m\u00fbrie et assum\u00e9e, en dit long sur son \u00e9tat d\u2019esprit : la construction avant la conqu\u00eate, la stabilit\u00e9 avant la gloire.<\/p>\n<p style=\"text-align: justify;\">Pour la <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-section-paloise-2025-arrivees-departs-et-prolongations\/\"><strong>Section Paloise<\/strong><\/a>, cette prolongation est bien plus qu\u2019une bonne nouvelle. C\u2019est un acte fondateur. Conserver un talent pareil, c\u2019est plus qu\u2019un coup sportif, c\u2019est un manifeste. Un message clair envoy\u00e9 \u00e0 tout le Top 14 : <strong>Pau<\/strong> n\u2019est plus un tremplin, c\u2019est une destination. Un club qui fid\u00e9lise, qui construit, qui croit en ses jeunes. Et surtout, qui leur donne des raisons d\u2019y croire aussi. Avant l\u2019ancien Agenais, <strong>Th\u00e9o Attissogb\u00e9<\/strong> et, plus r\u00e9cemment, <strong>Aaron Grandidier<\/strong>, ont aussi fait ce choix fort. Tout sauf un hasard.<\/p>\n<p style=\"text-align: justify;\">Car, depuis plusieurs saisons, le club b\u00e9arnais travaille dans la continuit\u00e9. Il mise sur la formation, sur un jeu vivant, sur la mont\u00e9e en puissance de ses jeunes cadres. La prolongation de <strong>Gailleton<\/strong> s\u2019inscrit parfaitement dans cette ligne. Elle donne de la cr\u00e9dibilit\u00e9 au projet et de la coh\u00e9rence \u00e0 l\u2019ambition. En conservant son joyau, <strong>Pau<\/strong> affirme qu\u2019il veut grandir \u00e0 son rythme, mais avec ses valeurs.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\u270d\ufe0f \ud835\udc77\ud835\udc93\ud835\udc90\ud835\udc8d\ud835\udc90\ud835\udc8f\ud835\udc88\ud835\udc82\ud835\udc95\ud835\udc8a\ud835\udc90\ud835\udc8f<\/p>\n<p>\ud835\udc38\ud835\udc5a\ud835\udc56\ud835\udc59\ud835\udc56\ud835\udc52\ud835\udc5b \ud835\udc3a\ud835\udc4e\ud835\udc56\ud835\udc59\ud835\udc59\ud835\udc52\ud835\udc61\ud835\udc5c\ud835\udc5b I 2029<\/p>\n<p>\ud83d\udc49 <a href=\"https:\/\/t.co\/uqBtaQVkEb\">https:\/\/t.co\/uqBtaQVkEb<\/a> <a href=\"https:\/\/t.co\/LyrK9Tuc1U\">pic.twitter.com\/LyrK9Tuc1U<\/a><\/p>\n<p>\u2014 Section Paloise B\u00e9arn Pyr\u00e9n\u00e9es (@SectionPaloise) <a href=\"https:\/\/twitter.com\/SectionPaloise\/status\/1975610043161530678?ref_src=twsrc%5Etfw\">October 7, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Croire en un projet<\/h2>\n<p style=\"text-align: justify;\">Alors oui, tout reste \u00e0 faire. Il faudra transformer l\u2019essai, le potentiel en titres, faire grandir autour de lui une \u00e9quipe capable de viser plus haut, maintenir la constance dans la performance. Mais dans ce rugby de l\u2019instant, o\u00f9 la patience semble devenue un luxe, la d\u00e9cision d\u2019<strong>\u00c9milien Gailleton<\/strong> rappelle une v\u00e9rit\u00e9 simple : les projets solides se b\u00e2tissent avec des convictions, pas des ch\u00e8ques.<\/p>\n<p style=\"text-align: justify;\">Son choix est une le\u00e7on de lucidit\u00e9, mais aussi de courage. Parce qu\u2019il est toujours plus difficile de rester que de partir. Et parce qu\u2019il faut une certaine force pour refuser la facilit\u00e9, et croire que l\u2019on peut \u00e9crire une belle histoire l\u00e0 o\u00f9 tout a commenc\u00e9.<\/p>\n<p style=\"text-align: justify;\">Pau a son diamant. Et le diamant a choisi de briller l\u00e0 o\u00f9 il est n\u00e9, rugbystiquement parlant, \u00e0 haut niveau. Non pas par nostalgie, mais par ambition. Une ambition ancr\u00e9e, sinc\u00e8re, patiente. Et peut-\u00eatre, \u00e0 terme, la plus belle des ambitions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, de promesses de titres, voire de contrats mirobolants, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.<\/p>\n","protected":false},"author":4,"featured_media":617497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[4940,47050],"tags":[16878,20923,111,29105],"class_list":["post-617465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edito","category-top-14","tag-breve","tag-emilien-gailleton","tag-top-14","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9dito : Pourquoi la prolongation d&#039;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby<\/title>\n<meta name=\"description\" content=\"Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9dito : Pourquoi la prolongation d&#039;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby\" \/>\n<meta property=\"og:description\" content=\"Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-08T10:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T10:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9dito : Pourquoi la prolongation d&#039;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"\u00c9dito : Pourquoi la prolongation d&rsquo;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby\",\"datePublished\":\"2025-10-08T10:00:24+00:00\",\"dateModified\":\"2025-10-08T10:03:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\"},\"wordCount\":719,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png\",\"keywords\":[\"br\u00e8ve\",\"\u00c9milien Gailleton\",\"Top 14\",\"Transferts rugby\"],\"articleSection\":[\"Edito\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\",\"name\":\"\u00c9dito : Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png\",\"datePublished\":\"2025-10-08T10:00:24+00:00\",\"dateModified\":\"2025-10-08T10:03:28+00:00\",\"description\":\"Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png\",\"width\":1200,\"height\":674,\"caption\":\"\u00c9dito Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9dito : Pourquoi la prolongation d&rsquo;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9dito : Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby","description":"Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9dito : Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby","og_description":"Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.","og_url":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-10-08T10:00:24+00:00","article_modified_time":"2025-10-08T10:03:28+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"\u00c9dito : Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"\u00c9dito : Pourquoi la prolongation d&rsquo;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby","datePublished":"2025-10-08T10:00:24+00:00","dateModified":"2025-10-08T10:03:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/"},"wordCount":719,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png","keywords":["br\u00e8ve","\u00c9milien Gailleton","Top 14","Transferts rugby"],"articleSection":["Edito","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/","url":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/","name":"\u00c9dito : Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png","datePublished":"2025-10-08T10:00:24+00:00","dateModified":"2025-10-08T10:03:28+00:00","description":"Dans un rugby moderne o\u00f9 les transferts se n\u00e9gocient \u00e0 coups de z\u00e9ros, la d\u00e9cision d\u2019\u00c9milien Gailleton de prolonger \u00e0 Pau jusqu\u2019en 2029 a quelque chose de rafra\u00eechissant.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Edito-Pourquoi-la-prolongation-dEmilien-Gailleton-a-Pau-est-une-excellente-nouvelle-pour-le-rugby.png","width":1200,"height":674,"caption":"\u00c9dito Pourquoi la prolongation d'\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/edito-pourquoi-la-prolongation-demilien-gailleton-a-pau-est-une-excellente-nouvelle-pour-le-rugby\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9dito : Pourquoi la prolongation d&rsquo;\u00c9milien Gailleton \u00e0 Pau est une excellente nouvelle pour le rugby"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=617465"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617465\/revisions"}],"predecessor-version":[{"id":617543,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617465\/revisions\/617543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/617497"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=617465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=617465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=617465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}