{"id":617894,"date":"2025-10-10T07:59:06","date_gmt":"2025-10-10T05:59:06","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=617894&#038;preview=true&#038;preview_id=617894"},"modified":"2025-10-10T08:47:14","modified_gmt":"2025-10-10T06:47:14","slug":"thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/","title":{"rendered":"Thibaut Pinot : \u00ab\u00a0Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CYCLISME &#8211; Dans les colonnes de <a href=\"https:\/\/www.lequipe.fr\/Cyclisme-sur-route\/Article\/Thibaut-pinot-s-enthousiasme-pour-les-performances-de-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/1600355\">L&rsquo;\u00c9quipe<\/a>, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/quel-paul-seixas-verra-t-on-en-2026\/\" target=\"_blank\" rel=\"noopener\">Quel Paul Seixas verra-t-on en 2026 ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Troisi\u00e8me des championnats d&rsquo;Europe dimanche derri\u00e8re <b>Tadej Poga\u010dar<\/b>\u00a0et <strong>Remco Evenepoel<\/strong>, <strong>Paul<\/strong> <strong>Seixas<\/strong> a \u00e9bloui le grand public sur les routes fran\u00e7aises. D\u00e9j\u00e0 performance lors du championnat du monde au <strong>Rwanda<\/strong>, le <strong>Tricolore<\/strong> de 19 ans a donc r\u00e9ussi \u00e0 encha\u00eener deux courses de tr\u00e8s haut niveau en quelques jours, malgr\u00e9 son jeune \u00e2ge.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-2025-tadej-pogacar-rafle-lor-en-solitaire-paul-seixas-en-bronze\/\" class=\"vlp-link\" title=\"Championnats d&#039;Europe 2025 : Tadej Pogacar rafle l&#039;or en solitaire, Paul Seixas en bronze !\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Championnats-dEurope-2025-Tadej-Pogacar-rafle-lor-en-solitaire-Paul-Seixas-en-bronze-1-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Championnats d&#039;Europe 2025 Tadej Pogacar rafle l&#039;or en solitaire, Paul Seixas en bronze !\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Championnats-dEurope-2025-Tadej-Pogacar-rafle-lor-en-solitaire-Paul-Seixas-en-bronze-1-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Championnats-dEurope-2025-Tadej-Pogacar-rafle-lor-en-solitaire-Paul-Seixas-en-bronze-1-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Championnats-dEurope-2025-Tadej-Pogacar-rafle-lor-en-solitaire-Paul-Seixas-en-bronze-1-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Championnats-dEurope-2025-Tadej-Pogacar-rafle-lor-en-solitaire-Paul-Seixas-en-bronze-1-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Championnats d'Europe 2025 : Tadej Pogacar rafle l'or en solitaire, Paul Seixas en bronze !<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS D'EUROPE DE CYCLISME SUR ROUTE 2025 - Parti seul \u00e0 75 kilom\u00e8tres de l'arriv\u00e9e, Tadej Pogacar a d\u00e9croch\u00e9 son premier titre europ\u00e9en au terme d'un nouveau num\u00e9ro en solitaire. Remco Evenepoel et surtout Paul Seixas compl\u00e8tent le podium.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les \u00e9loges de Pinot<\/h2>\n<p style=\"text-align: justify;\">Sa maturit\u00e9 et sa pr\u00e9cocit\u00e9 permettent au cyclisme fran\u00e7ais de l&rsquo;imaginer en vainqueur de Grand Tour un jour, m\u00eame si le chemin est encore loin. Rare dans les m\u00e9dias, <strong>Thibaut<\/strong> <strong>Pinot<\/strong> a accept\u00e9 d&rsquo;\u00e9voquer <strong>Paul<\/strong> <strong>Seixas<\/strong> chez nos confr\u00e8res, et l&rsquo;ancien grimpeur ne tarit pas d&rsquo;\u00e9loges \u00e0 son sujet :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Pour moi, depuis Tadej Pogacar et Remco Evenepoel, on n&rsquo;a pas vu un tel ph\u00e9nom\u00e8ne. Sorti de juniors comme \u00e7a, largement&#8230; C&rsquo;est peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge. Lui n&rsquo;est pas pass\u00e9 pro tout de suite apr\u00e8s les juniors, et c&rsquo;est vrai que lors de sa premi\u00e8re saison, il fait troisi\u00e8me de la Vuelta et y gagne trois \u00e9tapes, mais il avait aussi deux ans de plus que Seixas (21 ans contre 19 au Fran\u00e7ais aujourd&rsquo;hui). \u00c7a montre presque que Seixas a de l&rsquo;avance. Autant Remco a gagn\u00e9 d\u00e8s ses premi\u00e8res courses pros, la Clasica San Sebastian notamment&#8230; Donc en gros, voil\u00e0, il est entre Remco et Pogacar au m\u00eame \u00e2ge.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Sauf retournement de situation, <strong>Paul<\/strong> <strong>Seixas<\/strong> devrait \u00eatre au d\u00e9part du prochain <strong>Tour<\/strong> <strong>de<\/strong> <strong>France<\/strong>. La question est plut\u00f4t de savoir avec quelles ambitions il sera au d\u00e9part de la plus grande course du monde. En attendant, il sera de nouveau confront\u00e9 \u00e0 <strong>Remco<\/strong> <strong>Evenepoel<\/strong> et <b>Tadej Poga\u010dar<\/b>\u00a0sur le Tour de Lombardie ce samedi.<\/p>\n<h3 style=\"text-align: justify;\">\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-mercato-2025-2026-le-tableau-des-transferts\/\" class=\"vlp-link\" title=\"Cyclisme Mercato 2025-2026 - Le tableau des transferts\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts.png\" class=\"attachment-800x445 size-800x445\" alt=\"Cyclisme Mercato 2025-2026 - Le tableau des transferts\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Cyclisme-Mercato-2025-2026-Le-tableau-des-transferts-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Cyclisme Mercato 2025-2026 - Le tableau des transferts<\/div><div class=\"vlp-block-1 vlp-link-summary\">MERCATO CYCLISME 2025-2026 - D\u00e9couvrez les transferts officiels et les rumeurs du mercato cycliste.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; Dans les colonnes de L&rsquo;\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":617895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46994],"tags":[16878,574,11197,39260],"class_list":["post-617894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-cyclisme","tag-cyclisme-sur-route","tag-paul-seixas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Thibaut Pinot : &quot;Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge&quot;<\/title>\n<meta name=\"description\" content=\"CYCLISME - Dans les colonnes de L&#039;\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thibaut Pinot : &quot;Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge&quot;\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - Dans les colonnes de L&#039;\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T05:59:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T06:47:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Thibaut Pinot : &quot;Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Thibaut Pinot : \u00ab\u00a0Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\u00a0\u00bb\",\"datePublished\":\"2025-10-10T05:59:06+00:00\",\"dateModified\":\"2025-10-10T06:47:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\"},\"wordCount\":549,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png\",\"keywords\":[\"br\u00e8ve\",\"Cyclisme\",\"Cyclisme sur route\",\"paul seixas\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\",\"name\":\"Thibaut Pinot : \\\"Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png\",\"datePublished\":\"2025-10-10T05:59:06+00:00\",\"dateModified\":\"2025-10-10T06:47:14+00:00\",\"description\":\"CYCLISME - Dans les colonnes de L'\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thibaut Pinot : \u00ab\u00a0Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Thibaut Pinot : \"Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\"","description":"CYCLISME - Dans les colonnes de L'\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/","og_locale":"fr_FR","og_type":"article","og_title":"Thibaut Pinot : \"Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\"","og_description":"CYCLISME - Dans les colonnes de L'\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-10-10T05:59:06+00:00","article_modified_time":"2025-10-10T06:47:14+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Thibaut Pinot : \"Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\"","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Thibaut Pinot : \u00ab\u00a0Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\u00a0\u00bb","datePublished":"2025-10-10T05:59:06+00:00","dateModified":"2025-10-10T06:47:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/"},"wordCount":549,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png","keywords":["br\u00e8ve","Cyclisme","Cyclisme sur route","paul seixas"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/","url":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/","name":"Thibaut Pinot : \"Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png","datePublished":"2025-10-10T05:59:06+00:00","dateModified":"2025-10-10T06:47:14+00:00","description":"CYCLISME - Dans les colonnes de L'\u00c9quipe, Thibaut Pinot a \u00e9voqu\u00e9 le nouveau ph\u00e9nom\u00e8ne du cyclisme fran\u00e7ais, Paux Seixas.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Thibaut-Pinot-Paul-Seixas-peut-etre-meme-plus-fort-que-Pogacar-a-son-age.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/thibaut-pinot-paul-seixas-peut-etre-meme-plus-fort-que-pogacar-a-son-age\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Thibaut Pinot : \u00ab\u00a0Paul Seixas peut-\u00eatre m\u00eame plus fort que Pogacar \u00e0 son \u00e2ge\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=617894"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617894\/revisions"}],"predecessor-version":[{"id":617903,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617894\/revisions\/617903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/617895"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=617894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=617894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=617894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}