{"id":617994,"date":"2025-10-10T19:54:00","date_gmt":"2025-10-10T17:54:00","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=617994&#038;preview=true&#038;preview_id=617994"},"modified":"2025-10-10T20:20:34","modified_gmt":"2025-10-10T18:20:34","slug":"qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/","title":{"rendered":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>QUALIFICATIONS EURO ESPOIRS 2027 &#8211; Les Bleuets ne pouvaient pas mieux d\u00e9marrer dans cette course au prochain Euro. Au terme d\u2019un match abouti et \u00e0 sens unique, l&rsquo;\u00e9quipe de France s&rsquo;impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Le lancement a \u00e9t\u00e9 quelque peu retard\u00e9 pour les Espoirs apr\u00e8s le report du match contre le Luxembourg. C\u2019est donc avec les \u00celes F\u00e9ro\u00e9 que les Bleuets avaient rendez-vous pour d\u00e9crocher leurs trois premiers points. Et c\u2019est sous la pluie et le vent qu\u2019ils attaquaient cette campagne de qualifications. Des conditions qui ne les ont pas emp\u00each\u00e9s de d\u00e9rouler.<\/p>\n<h2 style=\"text-align: justify;\">D\u00e9part canon pour la rel\u00e8ve fran\u00e7aise<\/h2>\n<p style=\"text-align: justify;\">Les Bleuets ont rapidement tu\u00e9 tout suspense dans ce match. Posant d\u00e8s le coup d\u2019envoi le pied sur le ballon, ils ont dict\u00e9 le rythme de bout en bout. Et les F\u00e9ro\u00efens ont craqu\u00e9 apr\u00e8s un peu plus de dix minutes. Id\u00e9alement servi, <strong>Wilson Odobert<\/strong> se muait en premier buteur et lan\u00e7ait la moisson tricolore. Quelques instants plus tard et pour sa premi\u00e8re avec les Espoirs, <strong>Methalie<\/strong> doublait la mise d\u2019un tir enroul\u00e9 \u00e0 l\u2019entr\u00e9e de la surface. Surmen\u00e9e, la d\u00e9fense f\u00e9ro\u00efenne tentait tant bien que mal de repousser les multiples centres venus de toute part pour rester \u00e0 flot.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"de\">Wilson Odobert\ud83d\udd25\ud83d\udd25\ud83d\udd25 <a href=\"https:\/\/t.co\/P8ZNQCIu3A\">pic.twitter.com\/P8ZNQCIu3A<\/a><\/p>\n<p>\u2014 The Pride Of North London (@PrideOfNorthLDN) <a href=\"https:\/\/twitter.com\/PrideOfNorthLDN\/status\/1976686617076310120?ref_src=twsrc%5Etfw\">October 10, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Puis, sur une rare incursion dans la surface fran\u00e7aise, les h\u00f4tes b\u00e9n\u00e9ficiaient d\u2019un penalty pour relancer le suspense. C\u2019\u00e9tait sans compter sur <strong>Guillaume Restes<\/strong>, auteur d\u2019une double parade pour conserver le clean sheet. L\u2019occasion manqu\u00e9e, les F\u00e9ro\u00efens se remettaient inlassablement \u00e0 d\u00e9fendre. La sentence tombait cette fois dans l\u2019autre sens. Sur penalty, <strong>Mathys Tel<\/strong> rendait justice \u00e0 <strong>Bahoya<\/strong> pour le 3-0. F\u00e9roces d\u2019efficacit\u00e9 avec 5 tirs tent\u00e9s \u00e0 la pause, les Bleuets ont poursuivi leur festival en deuxi\u00e8me p\u00e9riode.<\/p>\n<h2 style=\"text-align: justify;\">Bis repetita au retour des vestiaires<\/h2>\n<p style=\"text-align: justify;\">Il ne fallait pas attendre plus de cinq minutes dans cet acte pour voir la marque s\u2019alourdir. <strong>Wilson Odobert<\/strong> s\u2019infiltrait dans la surface et s\u2019offrait le doubl\u00e9 avec un brin de r\u00e9ussite. 4-0, puis 5-0 avant m\u00eame l\u2019heure de jeu. <strong>Dayann Methalie<\/strong>, lui aussi, marquait son deuxi\u00e8me but personnel dans la partie. Une frappe puissante \u00e0 ras de terre apr\u00e8s un contr\u00f4le soign\u00e9 qui laissait <strong>Armgrimsson<\/strong> impuissant. Les vagues bleues ont d\u00e9ferl\u00e9, encore et encore, sur les buts f\u00e9ro\u00efens, au plus grand bonheur des quelques supporters fran\u00e7ais venus donner de la voix malgr\u00e9 le froid pr\u00e9sent \u00e0 Klaksvik.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Dayann Methalie premi\u00e8re s\u00e9lection avec les Espoirs, doubl\u00e9. ET QUEL DOUBL\u00c9 \ud83e\udd75 <a href=\"https:\/\/t.co\/0FSCyWIU1N\">pic.twitter.com\/0FSCyWIU1N<\/a><\/p>\n<p>\u2014 M\u00e9dia Tolosa (@MediaTolosa) <a href=\"https:\/\/twitter.com\/MediaTolosa\/status\/1976705683505791389?ref_src=twsrc%5Etfw\">October 10, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Passeur sur l\u2019ouverture du score, <strong>Ayyoub Bouaddi<\/strong> \u00e9tait \u00e9galement r\u00e9compens\u00e9 de l\u2019effort collectif et des siens et se joignait \u00e0 la f\u00eate (6-0). Avec les m\u00eames intentions mais sans parvenir \u00e0 retrouver la faille lors des 20 derni\u00e8res minutes, les joueurs de <strong>G\u00e9rald Baticle <\/strong>n\u2019\u00e9taient pas non plus mis en difficult\u00e9. Dominatrice de son sujet, l\u2019\u00e9quipe de France, demi-finaliste de la derni\u00e8re \u00e9dition, s\u2019impose avec la mani\u00e8re et fait le plein de confiance avant d\u2019affronter l\u2019Estonie dans trois jours.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udddf\ud835\uddf2 \ud835\uddf0\ud835\uddee\ud835\uddff\ud835\ude01\ud835\uddfc\ud835\uddfb \ud835\uddf1\ud835\uddf2\ud835\ude00 \ud835\uddd8\ud835\ude00\ud835\uddfd\ud835\uddfc\ud835\uddf6\ud835\uddff\ud835\ude00 \ud83d\udd25<br \/>\nLes Bleuets d\u00e9marrent les qualifications \u00e0 l&rsquo;Euro 2027 de la meilleure des mani\u00e8res \ud83d\udcaa<\/p>\n<p>Victoire 6\u20e3\u00e0 0\u20e3 aux Iles F\u00e9ro\u00e9 ! <a href=\"https:\/\/t.co\/mwoj11UMR7\">pic.twitter.com\/mwoj11UMR7<\/a><\/p>\n<p>\u2014 Equipe de France \u2b50\u2b50 (@equipedefrance) <a href=\"https:\/\/twitter.com\/equipedefrance\/status\/1976708422344094111?ref_src=twsrc%5Etfw\">October 10, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au terme d\u2019un match abouti, l&rsquo;\u00e9quipe de France s&rsquo;impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).<\/p>\n","protected":false},"author":18,"featured_media":618015,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301],"tags":[16878,30,47130,47290],"class_list":["post-617994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-breve","tag-france","tag-iles-feroe","tag-qualifications-euro-espoirs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9<\/title>\n<meta name=\"description\" content=\"QUALIFICATIONS EURO ESPOIRS 2027 - Au terme d\u2019un match abouti, l&#039;\u00e9quipe de France s&#039;impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9\" \/>\n<meta property=\"og:description\" content=\"QUALIFICATIONS EURO ESPOIRS 2027 - Au terme d\u2019un match abouti, l&#039;\u00e9quipe de France s&#039;impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T17:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T18:20:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9\",\"datePublished\":\"2025-10-10T17:54:00+00:00\",\"dateModified\":\"2025-10-10T18:20:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\"},\"wordCount\":616,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png\",\"keywords\":[\"br\u00e8ve\",\"France\",\"\u00celes F\u00e9ro\u00e9\",\"Qualifications Euro Espoirs\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\",\"name\":\"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png\",\"datePublished\":\"2025-10-10T17:54:00+00:00\",\"dateModified\":\"2025-10-10T18:20:34+00:00\",\"description\":\"QUALIFICATIONS EURO ESPOIRS 2027 - Au terme d\u2019un match abouti, l'\u00e9quipe de France s'impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png\",\"width\":1200,\"height\":674,\"caption\":\"Qualifications Euro Espoirs Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9","description":"QUALIFICATIONS EURO ESPOIRS 2027 - Au terme d\u2019un match abouti, l'\u00e9quipe de France s'impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/","og_locale":"fr_FR","og_type":"article","og_title":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9","og_description":"QUALIFICATIONS EURO ESPOIRS 2027 - Au terme d\u2019un match abouti, l'\u00e9quipe de France s'impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).","og_url":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2025-10-10T17:54:00+00:00","article_modified_time":"2025-10-10T18:20:34+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9","datePublished":"2025-10-10T17:54:00+00:00","dateModified":"2025-10-10T18:20:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/"},"wordCount":616,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png","keywords":["br\u00e8ve","France","\u00celes F\u00e9ro\u00e9","Qualifications Euro Espoirs"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/","url":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/","name":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png","datePublished":"2025-10-10T17:54:00+00:00","dateModified":"2025-10-10T18:20:34+00:00","description":"QUALIFICATIONS EURO ESPOIRS 2027 - Au terme d\u2019un match abouti, l'\u00e9quipe de France s'impose avec la mani\u00e8re contre les \u00celes F\u00e9ro\u00e9 (6-0).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Qualifications-Euro-Espoirs-Une-premiere-tonitruante-pour-lequipe-de-France-contre-les-Iles-Feroe.png","width":1200,"height":674,"caption":"Qualifications Euro Espoirs Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-euro-espoirs-une-premiere-tonitruante-pour-lequipe-de-france-contre-les-iles-feroe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Qualifications Euro Espoirs : Une premi\u00e8re tonitruante pour l\u2019\u00e9quipe de France contre les \u00celes F\u00e9ro\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=617994"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617994\/revisions"}],"predecessor-version":[{"id":618026,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/617994\/revisions\/618026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/618015"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=617994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=617994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=617994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}