{"id":61810,"date":"2020-03-01T18:17:08","date_gmt":"2020-03-01T17:17:08","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=61810&#038;preview=true&#038;preview_id=61810"},"modified":"2020-03-01T20:01:17","modified_gmt":"2020-03-01T19:01:17","slug":"super-league-les-dragons-catalans-renversent-hull-fc","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/","title":{"rendered":"Super League : Les Dragons Catalans renversent Hull FC"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Les Anglais entraient mieux dans la partie et <strong>Fonua<\/strong> inscrivait le premier essai de la rencontre. Bonne r\u00e9action des Catalans qui marquaient par deux fois par deux joueurs fran\u00e7ais, d&rsquo;abord <strong>Jullien<\/strong> puis <strong>Yaha<\/strong> pour mener 10 \u00e0 4. Le doubl\u00e9 de Fonua permettait \u00e0 Hull FC de revenir \u00e0 hauteur puis la r\u00e9alisation de Tuimavave juste avant la pause donnait l&rsquo;avantage aux Anglais, <strong>16-10 \u00e0 la mi-temps<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Une fin de match folle<\/h2>\n<p style=\"text-align: justify;\">La deuxi\u00e8me p\u00e9riode commen\u00e7ait mal pour les Dracs qui encaissaient deux nouveaux essais par <strong>Shaul<\/strong> et <strong>Ma&rsquo;u<\/strong> et semblaient bien mal embarqu\u00e9s dans cette rencontre. Moment choisi par Sam Tomkins pour acc\u00e9l\u00e9rer et remettre son \u00e9quipe dans le bon sens. D\u00e9cisif trois fois, il permettait les essais de Jullien, Drinkwater et Langi : 28 partout. James Maloney ratait deux drops alors que Marc Sneyd ne se manquait pas et donnait l&rsquo;avantage aux Anglais. Alors que l&rsquo;on pensait le match perdu, <strong>James Maloney<\/strong> sortait de sa bo\u00eete pour marquer l&rsquo;essai de la victoire sur la sir\u00e8ne. Mal embarqu\u00e9s, les Dragons Catalans renversaient Hull FC et gagnaient <strong>34 \u00e0 29<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">QUELLE PERFORMANCE<\/p>\n<p>On revient avec les 2 points &#x1f525;&#x1f525;<\/p>\n<p><a href=\"https:\/\/twitter.com\/hashtag\/Dragons?src=hash&amp;ref_src=twsrc%5Etfw\">#Dragons<\/a> &#x1f409; <a href=\"https:\/\/t.co\/aZXrj7mErj\">pic.twitter.com\/aZXrj7mErj<\/a><\/p>\n<p>\u2014 Dragons Catalans (@DragonsOfficiel) <a href=\"https:\/\/twitter.com\/DragonsOfficiel\/status\/1234162532430077952?ref_src=twsrc%5Etfw\">March 1, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.<\/p>\n","protected":false},"author":1,"featured_media":61812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9128],"tags":[5690,2049],"class_list":["post-61810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xiii","tag-dragons","tag-dragons-catalans"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Super League : Les Dragons Catalans renversent Hull FC<\/title>\n<meta name=\"description\" content=\"Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Super League : Les Dragons Catalans renversent Hull FC\" \/>\n<meta property=\"og:description\" content=\"Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-01T17:17:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-01T19:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Dragons-Catalans-Hull-Fc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Super League : Les Dragons Catalans renversent Hull FC\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Super League : Les Dragons Catalans renversent Hull FC\",\"datePublished\":\"2020-03-01T17:17:08+00:00\",\"dateModified\":\"2020-03-01T19:01:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Dragons-Catalans-Hull-Fc.png\",\"keywords\":[\"Dragons\",\"Dragons Catalans\"],\"articleSection\":[\"Rugby \u00e0 XIII\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/\",\"name\":\"Super League : Les Dragons Catalans renversent Hull FC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Dragons-Catalans-Hull-Fc.png\",\"datePublished\":\"2020-03-01T17:17:08+00:00\",\"dateModified\":\"2020-03-01T19:01:17+00:00\",\"description\":\"Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Dragons-Catalans-Hull-Fc.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Dragons-Catalans-Hull-Fc.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/super-league-les-dragons-catalans-renversent-hull-fc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Super League : Les Dragons Catalans renversent Hull FC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Super League : Les Dragons Catalans renversent Hull FC","description":"Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/","og_locale":"fr_FR","og_type":"article","og_title":"Super League : Les Dragons Catalans renversent Hull FC","og_description":"Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.","og_url":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-03-01T17:17:08+00:00","article_modified_time":"2020-03-01T19:01:17+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Dragons-Catalans-Hull-Fc.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Super League : Les Dragons Catalans renversent Hull FC","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Super League : Les Dragons Catalans renversent Hull FC","datePublished":"2020-03-01T17:17:08+00:00","dateModified":"2020-03-01T19:01:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Dragons-Catalans-Hull-Fc.png","keywords":["Dragons","Dragons Catalans"],"articleSection":["Rugby \u00e0 XIII"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/","url":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/","name":"Super League : Les Dragons Catalans renversent Hull FC","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Dragons-Catalans-Hull-Fc.png","datePublished":"2020-03-01T17:17:08+00:00","dateModified":"2020-03-01T19:01:17+00:00","description":"Pour leur premier d\u00e9placement en Angleterre, les Dragons Catalans \u00e9taient oppos\u00e9s \u00e0 Hull FC.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Dragons-Catalans-Hull-Fc.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Dragons-Catalans-Hull-Fc.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/super-league-les-dragons-catalans-renversent-hull-fc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Super League : Les Dragons Catalans renversent Hull FC"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/61810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=61810"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/61810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/61812"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=61810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=61810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=61810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}