{"id":618620,"date":"2025-10-13T13:31:36","date_gmt":"2025-10-13T11:31:36","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=618620&#038;preview=true&#038;preview_id=618620"},"modified":"2025-10-13T13:40:00","modified_gmt":"2025-10-13T11:40:00","slug":"euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/","title":{"rendered":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&rsquo;Italie"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EURO BASKET FAUTEUIL 2025 (H) &#8211; Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l&rsquo;\u00c9quipe de France. Apr\u00e8s la Grande-Bretagne, les Bleus se sont \u00e9galement inclin\u00e9s face \u00e0 l&rsquo;Italie dans cette poule B de l&rsquo;Euro Basket Fauteuil, assez lourdement (81-64). Le dernier match de poule face \u00e0 la Suisse sera d\u00e9cisif.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la <a href=\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-un-de-chute-pour-les-bleus\/\">lourde d\u00e9faite face \u00e0 la Grande-Bretagne (63-96)<\/a>, l\u2019Equipe de France devait se reprendre face \u00e0 l\u2019Italie ce 13 octobre, dans le quatri\u00e8me match de la poule B.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\">L\u2019Italie domine puis prend le large<\/h2>\n<p style=\"text-align: justify;\">Dans un premier quart-temps disput\u00e9, l\u2019Italie a rapidement pris les commandes du match, menant 11-4, notamment gr\u00e2ce \u00e0 9 points d\u2019<b>Andrea Giaretti<\/b>. Les Fran\u00e7ais tentent de r\u00e9duire le score, mais les Transalpins conservent la main sur le match, et terminent le premier quart-temps sur le score de 19-14. La France a alors limit\u00e9 l\u2019\u00e9cart gr\u00e2ce aux 6 points de <b>Nicolas Jouanserre<\/b> et de <b>Christophe Carlier<\/b>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Toutefois, les Fran\u00e7ais n\u2019ont pas r\u00e9ussi \u00e0 combler les quelques points s\u00e9parant les deux \u00e9quipes pendant le deuxi\u00e8me quart-temps. L\u2019\u00e9cart se creuse m\u00eame \u00e0 l\u2019approche de la mi-temps, passant \u00e0 13 points (38-25) \u00e0 2.40min. <b>Filippo Carossino<\/b> brille sur ce deuxi\u00e8me quart, avec d\u00e9j\u00e0 12 points. En difficult\u00e9 au tir (47% sur la mi-temps, contre 64% pour les transalpins), les Fran\u00e7ais laissent s\u2019envoler leur adversaire. \u00c0 1min de la mi-temps, l\u2019Italie m\u00e8ne 42-27. Puis 44-29 alors qu\u2019est siffl\u00e9e la mi-temps. La France de <b>Clifford Fisher<\/b> est largement domin\u00e9, uniquement sauv\u00e9e par les 14 points de <b>Nicolas Jouanserre<\/b>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\">Un troisi\u00e8me quart d\u2019espoir pour la France, avant la chute<\/h2>\n<p style=\"text-align: justify;\">Le troisi\u00e8me quart-temps reste dans la lign\u00e9e des deux pr\u00e9c\u00e9dents. L\u2019Italie conserve sa quinzaine de points d\u2019avance, port\u00e9e par les points de <b>Carossino<\/b>. \u00c0 3 minutes de la fin du troisi\u00e8me quart-temps, l\u2019Italie m\u00e8ne 58-46. C\u2019est le moment choisi par la France pour tenter une remont\u00e9e fantastique. \u00c0 l\u2019entame des 10 derni\u00e8res minutes, la France n\u2019est plus men\u00e9e que de 10 points (60-50). <b>Christophe Carlier<\/b> a retrouv\u00e9 le chemin du panier, et c\u2019est toute l\u2019\u00e9quipe de France qui se met \u00e0 r\u00eaver d\u2019un retour au score.<\/p>\n<p style=\"text-align: justify;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Q66UAF7EO2Q?si=OeQvDekAXJmuDMVx\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Mais l\u2019Italie ne l\u2019entend pas de cette oreille. En 3 min, les Italiens reprennent de l\u2019avance. Beaucoup d\u2019avance. Ils m\u00e8nent de 21 points, le plus gros \u00e9cart du match. Il aura fallu attendre plus de 4 minutes dans le 4e quart-temps pour voir inscrit les premiers points fran\u00e7ais. La fin de match ne change rien. L\u2019Italie conserve ses 20 points d\u2019avance, dans un quart-temps o\u00f9 les Fran\u00e7ais n\u2019ont inscrit que 14 points. <strong>Filippo Carossino<\/strong> a termin\u00e9 meilleur marqueur du match, avec 22 points, mais aussi 10 rebonds et 8 passes. Du c\u00f4t\u00e9 fran\u00e7ais, c\u2019est <strong>Nicolas Jouanserre<\/strong>, comme souvent, qui a port\u00e9 son \u00e9quipe, avec 19 points. <strong>Louis Hardouin<\/strong> aura particuli\u00e8rement \u00e9t\u00e9 en difficult\u00e9 quand il \u00e9tait sur le terrain (2 \u00e0 1\/7 en 25min).<\/p>\n<p style=\"text-align: justify;\">La France est d\u00e9sormais avec un bilan \u00e0 50%, avec deux victoires et deux d\u00e9faites. Toutefois, il faudra trouver les solutions pour le prochain match, apr\u00e8s deux lourdes d\u00e9faites face \u00e0 la Grande-Bretagne et l\u2019Italie. Au risque, sinon, de se retrouver en difficult\u00e9 dans le groupe B. Les Bleus affronteront la Suisse demain dans un match o\u00f9 la victoire sera obligatoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EURO BASKET FAUTEUIL 2025 (H) &#8211; Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l&rsquo;\u00c9quipe de France. Apr\u00e8s la Grande-Bretagne, les Bleus se sont \u00e9galement inclin\u00e9s face \u00e0 l&rsquo;Italie dans cette poule B de l&rsquo;Euro Basket Fauteuil, assez lourdement (81-64). Le dernier match de poule face \u00e0 la Suisse sera d\u00e9cisif.<\/p>\n","protected":false},"author":88,"featured_media":618625,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2305],"tags":[47288,16878,47289],"class_list":["post-618620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basket-fauteuil","tag-breve","tag-euro-basket-fauteuil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&#039;Italie<\/title>\n<meta name=\"description\" content=\"EURO BASKET FAUTEUIL 2025 (H) - Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l&#039;\u00c9quipe de France face \u00e0 l&#039;Italie dans cette poule B de l&#039;Euro Basket Fauteuil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&#039;Italie\" \/>\n<meta property=\"og:description\" content=\"EURO BASKET FAUTEUIL 2025 (H) - Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l&#039;\u00c9quipe de France face \u00e0 l&#039;Italie dans cette poule B de l&#039;Euro Basket Fauteuil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T11:31:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T11:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Paul Lalevee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&#039;Italie\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\"},\"author\":{\"name\":\"Paul Lalevee\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd\"},\"headline\":\"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&rsquo;Italie\",\"datePublished\":\"2025-10-13T11:31:36+00:00\",\"dateModified\":\"2025-10-13T11:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\"},\"wordCount\":584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png\",\"keywords\":[\"basket fauteuil\",\"br\u00e8ve\",\"Euro Basket Fauteuil\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\",\"name\":\"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png\",\"datePublished\":\"2025-10-13T11:31:36+00:00\",\"dateModified\":\"2025-10-13T11:40:00+00:00\",\"description\":\"EURO BASKET FAUTEUIL 2025 (H) - Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l'\u00c9quipe de France face \u00e0 l'Italie dans cette poule B de l'Euro Basket Fauteuil.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png\",\"width\":1200,\"height\":674,\"caption\":\"Euro Basket Fauteuil 2025 (H) Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&rsquo;Italie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd\",\"name\":\"Paul Lalevee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg\",\"caption\":\"Paul Lalevee\"},\"description\":\"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie","description":"EURO BASKET FAUTEUIL 2025 (H) - Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l'\u00c9quipe de France face \u00e0 l'Italie dans cette poule B de l'Euro Basket Fauteuil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie","og_description":"EURO BASKET FAUTEUIL 2025 (H) - Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l'\u00c9quipe de France face \u00e0 l'Italie dans cette poule B de l'Euro Basket Fauteuil.","og_url":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-10-13T11:31:36+00:00","article_modified_time":"2025-10-13T11:40:00+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png","type":"image\/png"}],"author":"Paul Lalevee","twitter_card":"summary_large_image","twitter_title":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/"},"author":{"name":"Paul Lalevee","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd"},"headline":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&rsquo;Italie","datePublished":"2025-10-13T11:31:36+00:00","dateModified":"2025-10-13T11:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/"},"wordCount":584,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png","keywords":["basket fauteuil","br\u00e8ve","Euro Basket Fauteuil"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/","url":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/","name":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png","datePublished":"2025-10-13T11:31:36+00:00","dateModified":"2025-10-13T11:40:00+00:00","description":"EURO BASKET FAUTEUIL 2025 (H) - Une deuxi\u00e8me d\u00e9faite qui fait mal \u00e0 l'\u00c9quipe de France face \u00e0 l'Italie dans cette poule B de l'Euro Basket Fauteuil.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Euro-Basket-Fauteuil-2025-H-Deuxieme-defaite-consecutive-pour-la-France-battue-largement-par-lItalie.png","width":1200,"height":674,"caption":"Euro Basket Fauteuil 2025 (H) Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l'Italie"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-basket-fauteuil-2025-h-deuxieme-defaite-consecutive-pour-la-france-battue-largement-par-litalie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro Basket Fauteuil 2025 (H) : Deuxi\u00e8me d\u00e9faite cons\u00e9cutive pour la France, battue largement par l&rsquo;Italie"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/1eaa63dfac40b5e5c47f03a71920c1cd","name":"Paul Lalevee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/291154246_1690604071293245_3118259335115946499_n-150x150.jpg","caption":"Paul Lalevee"},"description":"La bulle Disney pendant le Covid, le Tour 2019, la Coupe du monde 2018. Ces trois \u00e9v\u00e9nements majeurs sont ancr\u00e9s dans ma t\u00eate de fan de sport, n\u00e9gativement ou positivement. Passionn\u00e9 de sport depuis l'enfance, j'ai d\u00e9cid\u00e9 de mettre ma passion de l'\u00e9criture au service de cette premi\u00e8re passion.","url":"https:\/\/dicodusport.fr\/blog\/author\/paul-lalevee\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/618620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=618620"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/618620\/revisions"}],"predecessor-version":[{"id":618628,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/618620\/revisions\/618628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/618625"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=618620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=618620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=618620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}