{"id":619344,"date":"2025-10-16T19:40:08","date_gmt":"2025-10-16T17:40:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=619344&#038;preview=true&#038;preview_id=619344"},"modified":"2025-10-16T20:08:03","modified_gmt":"2025-10-16T18:08:03","slug":"euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/","title":{"rendered":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>EUROLIGUE FEMMES 2025\/2026 &#8211; Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, les Berruy\u00e8res ont r\u00e9ussi \u00e0 se d\u00e9faire du VBW Gdynia en terres polonaises. Un succ\u00e8s 72-57 qui permet \u00e0 Bourges de se relancer dans ce groupe A.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Le TBB aura d\u00fb se montrer patient face \u00e0 Gdynia pour repartir de Pologne avec la victoire. En panne d\u2019adresse avant la pause, les Berruy\u00e8res ont retrouv\u00e9 des couleurs en attaque mais ont surtout verrouill\u00e9 la d\u00e9fense, poussant \u00e0 la faute leurs h\u00f4tes du jour. Bourges rebondit dans son groupe apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j1-bourges-subit-une-large-defaite-face-a-prague\/\">sa d\u00e9faite initiale face \u00e0 Prague<\/a>.<\/p>\n<h2 style=\"text-align: justify;\">Personne ne se d\u00e9tache en premi\u00e8re p\u00e9riode<\/h2>\n<p style=\"text-align: justify;\">Les deux \u00e9quipes avaient bien des difficult\u00e9s \u00e0 se d\u00e9partager dans le premier quart-temps. Surtout parce qu\u2019elles se rendaient temps forts et temps faibles. Lorsque le VBW Gdynia faisait ficelle, le TBB r\u00e9pondait. Mais lorsque les Polonaises restaient muettes face au cercle, les Berruy\u00e8res \u00e9galement. Compliqu\u00e9 alors pour les unes ou les autres de s\u2019\u00e9chapper. Ainsi, apr\u00e8s 10 minutes et pas mal de maladresse, le score n\u2019affichait que 14-12 en faveur des visiteuses. Mais 14 points inscrits par 7 joueuses diff\u00e9rentes, l\u00e0 o\u00f9 <strong>Ruth Hebard<\/strong> et <strong>Anna Jakubiuk <\/strong>avaient augment\u00e9 presque \u00e0 elles seules le compteur de Gdynia.<\/p>\n<p style=\"text-align: justify;\">Le suspense restait entier apr\u00e8s les dix minutes suivantes. Si les points augmentaient un peu plus rapidement, l\u2019\u00e9cart, lui, ne d\u00e9passait pas les trois unit\u00e9s d\u2019avance. Souvent \u00e0 la m\u00e8ne, le TBB ne parvenait cependant pas \u00e0 prendre ses distances. Dans l\u2019incapacit\u00e9 de bonifier les multiples s\u00e9quences de disette offensive polonaise, les Berruy\u00e8res restaient \u00e0 la port\u00e9e de leurs adversaires, qui trouvaient toujours une main chaude pour les faire douter.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">3\ufe0f\u20e3 points d\u2019avance pour nos Tango \u00e0 la pause ! <a href=\"https:\/\/twitter.com\/hashtag\/FierteTango?src=hash&amp;ref_src=twsrc%5Etfw\">#FierteTango<\/a> <a href=\"https:\/\/t.co\/NjUWpIIcp7\">pic.twitter.com\/NjUWpIIcp7<\/a><\/p>\n<p>\u2014 Tango Bourges Basket (@BourgesBasket) <a href=\"https:\/\/twitter.com\/BourgesBasket\/status\/1978864170410901848?ref_src=twsrc%5Etfw\">October 16, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Bourges acc\u00e9l\u00e8re apr\u00e8s la pause<\/h2>\n<p style=\"text-align: justify;\">Bourges commen\u00e7ait \u00e0 voir un peu le jour au retour des vestiaires. <strong>La\u00ebtitia Guapo<\/strong> interceptait et filait au panier avant que <strong>Maeva Djaldi Tabdi<\/strong> ne r\u00e9ponde longue distance \u00e0 <strong>Liliana Banaszak<\/strong>. Un panier qui faisait du bien au TBB, qui respirait dor\u00e9navant de 7 longueurs (37-44). Au combat sous le panier, <strong>\u00c9lodie Naigre<\/strong> donnait davantage d\u2019air aux siennes avant une r\u00e9alisation de <strong>Marie-Paule Dally<\/strong> qui leur permettait de d\u00e9passer les dix points d\u2019avance (39-51). Impuissant face aux nombreuses g\u00e2chettes fran\u00e7aises et incapable de se d\u00e9faire du scotch d\u00e9fensif du Tango, le VBW Gdynia n\u2019a inscrit que 9 points dans ce troisi\u00e8me quart-temps et devait en rattraper 14 dans le quatri\u00e8me.<\/p>\n<p style=\"text-align: justify;\">Il n\u2019en \u00e9tait rien, le TBB insistait. <strong>Tima Pouye<\/strong> (16 points) se faufilait, obtenait les lancers, augmentait la marge et for\u00e7ait le temps mort polonais \u00e0 quatre minutes de la fin du match (48-61). Pas de changement pour autant apr\u00e8s celui-ci, <strong>Marie-Paule Dally<\/strong> perforait la raquette avant d\u2019envoyer un tir prim\u00e9 qui scellait d\u00e9finitivement, si ce n\u2019\u00e9tait d\u00e9j\u00e0 fait, le sort de la rencontre. Apr\u00e8s une entame timide, la pause a \u00e9t\u00e9 b\u00e9n\u00e9fique \u00e0 Bourges, qui se relance dans son groupe gr\u00e2ce \u00e0 cette victoire.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83e\udde1 VICTOIRE ! Nos Tango s\u2019imposent \u00e0 Gdynia !<\/p>\n<p>Focus sur dimanche, \u00e0 Villeneuve d\u00e9sormais ! \u270a<a href=\"https:\/\/twitter.com\/hashtag\/FierteTango?src=hash&amp;ref_src=twsrc%5Etfw\">#FierteTango<\/a> <a href=\"https:\/\/t.co\/EvnXa83JZw\">pic.twitter.com\/EvnXa83JZw<\/a><\/p>\n<p>\u2014 Tango Bourges Basket (@BourgesBasket) <a href=\"https:\/\/twitter.com\/BourgesBasket\/status\/1978879746780840012?ref_src=twsrc%5Etfw\">October 16, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE FEMMES 2025\/2026 &#8211; Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).<\/p>\n","protected":false},"author":18,"featured_media":619361,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[16878,22243,47296,3067],"class_list":["post-619344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-breve","tag-euroligue-feminine","tag-gdynia","tag-tango-bourges-basket"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia<\/title>\n<meta name=\"description\" content=\"EUROLIGUE FEMMES 2025\/2026 - Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE FEMMES 2025\/2026 - Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T17:40:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T18:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia\",\"datePublished\":\"2025-10-16T17:40:08+00:00\",\"dateModified\":\"2025-10-16T18:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\"},\"wordCount\":558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png\",\"keywords\":[\"br\u00e8ve\",\"euroligue f\u00e9minine\",\"Gdynia\",\"tango bourges basket\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\",\"name\":\"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png\",\"datePublished\":\"2025-10-16T17:40:08+00:00\",\"dateModified\":\"2025-10-16T18:08:03+00:00\",\"description\":\"EUROLIGUE FEMMES 2025\/2026 - Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png\",\"width\":1200,\"height\":674,\"caption\":\"EuroLigue Femmes 20252026 (J2) Bourges rebondit contre le VBW Gdynia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia","description":"EUROLIGUE FEMMES 2025\/2026 - Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia","og_description":"EUROLIGUE FEMMES 2025\/2026 - Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2025-10-16T17:40:08+00:00","article_modified_time":"2025-10-16T18:08:03+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia","datePublished":"2025-10-16T17:40:08+00:00","dateModified":"2025-10-16T18:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/"},"wordCount":558,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png","keywords":["br\u00e8ve","euroligue f\u00e9minine","Gdynia","tango bourges basket"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/","name":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png","datePublished":"2025-10-16T17:40:08+00:00","dateModified":"2025-10-16T18:08:03+00:00","description":"EUROLIGUE FEMMES 2025\/2026 - Gr\u00e2ce \u00e0 un bon troisi\u00e8me quart-temps, Bourges se relance contre le VBW Gdynia (72-57).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/EuroLigue-Femmes-20252026-J2-Bourges-rebondit-contre-le-VBW-Gdynia.png","width":1200,"height":674,"caption":"EuroLigue Femmes 20252026 (J2) Bourges rebondit contre le VBW Gdynia"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-2025-2026-j2-bourges-rebondit-contre-le-vbw-gdynia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue Femmes 2025\/2026 (J2) : Bourges rebondit contre le VBW Gdynia"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/619344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=619344"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/619344\/revisions"}],"predecessor-version":[{"id":619373,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/619344\/revisions\/619373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/619361"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=619344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=619344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=619344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}