{"id":620023,"date":"2025-10-19T13:00:24","date_gmt":"2025-10-19T11:00:24","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=620023&#038;preview=true&#038;preview_id=620023"},"modified":"2025-10-19T13:43:28","modified_gmt":"2025-10-19T11:43:28","slug":"resultats-et-classement-marathon-des-villages-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/","title":{"rendered":"R\u00e9sultats et classement Marathon des Villages 2025"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le <strong>Marathon des Villages 2025<\/strong> se tiendra le<strong> dimanche 19 octobre 2025<\/strong> sur la presqu\u2019\u00eele de <strong>L\u00e8ge-Cap Ferret<\/strong>, en Gironde. Nich\u00e9 entre l\u2019oc\u00e9an Atlantique et le bassin d\u2019Arcachon, cet \u00e9v\u00e9nement embl\u00e9matique offre une exp\u00e9rience de course unique, m\u00ealant performance sportive, nature pr\u00e9serv\u00e9e et ambiance conviviale.<\/p>\n<h2 style=\"text-align: justify;\">Parcours et infos<\/h2>\n<p style=\"text-align: justify;\">Le parcours de <strong>42,195 km<\/strong>, r\u00e9alisable en solo ou en relais duo, traverse des paysages d\u2019une rare diversit\u00e9 : for\u00eats de pins, chemins sablonneux, pistes cyclables et ruelles pittoresques des villages ostr\u00e9icoles tels que <strong>Le Canon<\/strong>, <strong>Piraillan<\/strong>, <strong>Claouey<\/strong> ou <strong>L\u2019Herbe<\/strong>. Chaque kilom\u00e8tre d\u00e9voile une nouvelle facette de la presqu\u2019\u00eele, entre senteurs marines et horizon oc\u00e9anique.<\/p>\n<p style=\"text-align: justify;\">Accessible \u00e0 tous les passionn\u00e9s de course \u00e0 pied, le <strong>Marathon des Villages<\/strong> s\u00e9duit par son atmosph\u00e8re chaleureuse. Les b\u00e9n\u00e9voles, les habitants et les spectateurs transforment l\u2019\u00e9v\u00e9nement en une v\u00e9ritable f\u00eate du sport et du territoire, rythm\u00e9e par les ravitaillements gourmands et les encouragements sur le parcours.<\/p>\n<p style=\"text-align: justify;\">Plus qu\u2019une course, le <strong>Marathon des Villages<\/strong> est une immersion sensorielle et humaine au c\u0153ur du Sud-Ouest. Une aventure o\u00f9 chaque foul\u00e9e invite \u00e0 savourer la beaut\u00e9 naturelle du<strong> Cap Ferret<\/strong> et \u00e0 partager la joie simple de courir ensemble.<\/p>\n<p style=\"text-align: justify;\"><strong>Retrouvez les r\u00e9sultats complets du Marathon des Villages 2025.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Classement Marathon des Villages hommes 2025<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Classement officiel mis \u00e0 jour \u00e0 l&rsquo;issue de la course.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>ATHL\u00c8TES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 500px\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 MATHIEU RUPPEL<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h34m06s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-default\">2.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 PAUL RENAUDIE<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h35m45s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-important\">3.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 RAPHAEL BOUTON<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h38m43s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 FRANCIS INGLES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 220px\"><strong><span style=\"font-size: 0.9em\">2h41m43s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 CLEMENT PETER<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 220px\"><strong><span style=\"font-size: 0.9em\">2h43m33s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 VALENTIN REMAUD<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h44m47s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 ALEXANDRE JOUAN<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h45m15s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 COLIN KARCZEWSKI<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h46m20s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 REMY VITRAS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h47m59s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 SIEGFRIED VENOT<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">2h48m11s<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\"><\/div>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.protiming.fr\/Results\/runningR\/7491-Marathon-des-Villages\/365\">Le classement complet<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<hr \/>\n<h2 style=\"text-align: justify;\">Classement Marathon des Villages femmes 2025<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong><em>Classement officiel mis \u00e0 jour \u00e0 l&rsquo;issue de la course.<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>ATHL\u00c8TES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-warning\">1.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 500px\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 CONSTANCE DE LONGUEIL<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h12m35s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-default\">2.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 500px\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 DELPHINE DE LEPINAY<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h16m37s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><strong><span class=\"su-label su-label-type-important\">3.<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 500px\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 LEA VALLA<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h16m39s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 SANDRINE PEDRO<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 220px\"><strong><span style=\"font-size: 0.9em\">3h19m43s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 FANNY CASTELLANI<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h21m30s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 LUCILE RICHARD<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;vertical-align: middle;width: 220px\"><strong><span style=\"font-size: 0.9em\">3h21m33s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 ELODIE LEBOSSE<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h22m42s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 MARIE FUMEY<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h26m13s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 PAULINE GRASSET<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h28m36s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 ANNE CALVO<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h31m32s<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\"><\/div>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.protiming.fr\/Results\/runningR\/7491-Marathon-des-Villages\/365\">Le classement complet<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.<\/p>\n","protected":false},"author":4,"featured_media":620026,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2308],"tags":[143,16878],"class_list":["post-620023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","tag-athletisme","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9sultats et classement Marathon des Villages 2025<\/title>\n<meta name=\"description\" content=\"Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9sultats et classement Marathon des Villages 2025\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-19T11:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-19T11:43:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"R\u00e9sultats et classement Marathon des Villages 2025\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"R\u00e9sultats et classement Marathon des Villages 2025\",\"datePublished\":\"2025-10-19T11:00:24+00:00\",\"dateModified\":\"2025-10-19T11:43:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png\",\"keywords\":[\"Athl\u00e9tisme\",\"br\u00e8ve\"],\"articleSection\":[\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\",\"name\":\"R\u00e9sultats et classement Marathon des Villages 2025\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png\",\"datePublished\":\"2025-10-19T11:00:24+00:00\",\"dateModified\":\"2025-10-19T11:43:28+00:00\",\"description\":\"Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png\",\"width\":1200,\"height\":674,\"caption\":\"R\u00e9sultats et classement Marathon des Villages 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sultats et classement Marathon des Villages 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9sultats et classement Marathon des Villages 2025","description":"Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9sultats et classement Marathon des Villages 2025","og_description":"Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.","og_url":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2025-10-19T11:00:24+00:00","article_modified_time":"2025-10-19T11:43:28+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"R\u00e9sultats et classement Marathon des Villages 2025","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"R\u00e9sultats et classement Marathon des Villages 2025","datePublished":"2025-10-19T11:00:24+00:00","dateModified":"2025-10-19T11:43:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png","keywords":["Athl\u00e9tisme","br\u00e8ve"],"articleSection":["Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/","url":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/","name":"R\u00e9sultats et classement Marathon des Villages 2025","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png","datePublished":"2025-10-19T11:00:24+00:00","dateModified":"2025-10-19T11:43:28+00:00","description":"Retrouvez le classement et les r\u00e9sultats du Marathon des Villages 2025, qui se d\u00e9roule ce dimanche 19 octobre 2025. D\u00e9part donn\u00e9 \u00e0 9h30, heure fran\u00e7aise.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Resultats-et-classement-Marathon-des-Villages-2025.png","width":1200,"height":674,"caption":"R\u00e9sultats et classement Marathon des Villages 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/resultats-et-classement-marathon-des-villages-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sultats et classement Marathon des Villages 2025"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/620023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=620023"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/620023\/revisions"}],"predecessor-version":[{"id":620264,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/620023\/revisions\/620264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/620026"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=620023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=620023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=620023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}