{"id":620938,"date":"2025-10-22T22:56:41","date_gmt":"2025-10-22T20:56:41","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=620938&#038;preview=true&#038;preview_id=620938"},"modified":"2025-10-22T23:47:39","modified_gmt":"2025-10-22T21:47:39","slug":"coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/","title":{"rendered":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 Ce mercredi soir, l&rsquo;\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0) gr\u00e2ce \u00e0 un but d\u00e9cisif de Ma\u00efssa Fathallah.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Trois jours apr\u00e8s une <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-les-bleuettes-sen-sortent-avec-des-sueurs-froides-contre-les-samoa\/\">premi\u00e8re victoire \u00e9triqu\u00e9e face aux Samoa<\/a>, l&rsquo;<strong>\u00e9quipe de France<\/strong> f\u00e9minine disposait d\u00e9j\u00e0 de la possibilit\u00e9 de valider sa qualification en 8\u00e8mes de finale en cas de victoire face au <strong>Nigeria<\/strong>. Pour faire face \u00e0 la cadence inhabituelle des matchs \u00e0 cet \u00e2ge, le s\u00e9lectionneur <strong>Micka\u00ebl Ferreira<\/strong> avait largement chang\u00e9 son onze en int\u00e9grant sept nouvelles joueuses.<\/p>\n<h2 style=\"text-align: justify;\">Une premi\u00e8re mi-temps ferm\u00e9e \u00e0 double tour<\/h2>\n<p style=\"text-align: justify;\">Face \u00e0 un adversaire ayant plus de r\u00e9pondant technique et physique que les Samoa, les Bleuettes ont adopt\u00e9 un jeu tr\u00e8s direct \u00e0 la r\u00e9cup\u00e9ration de balle qui a entra\u00een\u00e9 beaucoup de d\u00e9chet. Si l&rsquo;arri\u00e8re-garde nig\u00e9riane a donn\u00e9 la sensation d&rsquo;\u00eatre friable, les Bleuettes ont eu toutes les peines du monde \u00e0 se montrer dangereuses. Il aura fallu attendre quasiment une demi-heure pour que <strong>L\u00e9a Morissaint<\/strong> dispose d&rsquo;une premi\u00e8re balle de but, mais sa reprise s&rsquo;est envol\u00e9e au-dessus de la barre.<\/p>\n<p style=\"text-align: justify;\">Ce fut alors l&rsquo;un des rares moments o\u00f9 les Fran\u00e7aises ont r\u00e9ussi \u00e0 ressortir proprement un ballon. Face au pressing nig\u00e9rian, elles ont m\u00eame progressivement recul\u00e9, laissant leurs rivales disposer de quelques situations aux abords de la surface. Si un r\u00e9veil en fin de p\u00e9riode a permis de se rapprocher des 30 derniers m\u00e8tres adverses, le manque de pr\u00e9sence dans la surface s&rsquo;est fait ressentir. Au final, il n&rsquo;y aura pas eu grand-chose \u00e0 se mettre sous la dent au bout de 45 premi\u00e8res minutes resserr\u00e9es.<\/p>\n<h2>Fathallah lib\u00e8re les Bleuettes<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, ce sont m\u00eame les Nig\u00e9rianes qui ont affich\u00e9 les meilleures intentions. Au point de se procurer la meilleure occasion du match sur coup de pied arr\u00eat\u00e9, l\u00e0 o\u00f9 les Bleuettes avaient d\u00e9j\u00e0 accord\u00e9 deux buts face aux Samoa. Heureusement, <strong>Lauryne Chevray<\/strong> est rest\u00e9e vigilante pour frustrer <strong>Chisom Nwachukwu<\/strong>. Cette frayeur a eu le m\u00e9rite de donner un coup de fouet aux Bleuettes bien aid\u00e9es par le sang frais inject\u00e9 sur le front de l&rsquo;attaque. Plus pr\u00e9cises dans les transmissions, elles ont enfin r\u00e9ussi \u00e0 combiner. Et sur une offensive rondement men\u00e9e depuis l&rsquo;aile droite, <strong>Luna Laboucarie<\/strong> pensait avoir fait le plus dur suite \u00e0 une sortie hasardeuse de la gardienne nig\u00e9riane. Mais sur sa ligne, une d\u00e9fenseure adverse a h\u00e9ro\u00efquement repouss\u00e9 la gonfle !<\/p>\n<p style=\"text-align: justify;\">Une longue interruption pour un arbitrage vid\u00e9o a ensuite coup\u00e9 le rythme au moment de lancer les vingt derni\u00e8res minutes. La fatigue se fait alors ressentir d&rsquo;un c\u00f4t\u00e9 comme de l&rsquo;autre, et il suffit d&rsquo;une simple erreur ou d&rsquo;un \u00e9clair pour d\u00e9bloquer une situation toujours aussi ind\u00e9cise. Cet \u00e9clair aurait pu venir du pied de <strong>No\u00e9mie Fatier<\/strong>, qui a effleur\u00e9 la lucarne droite du but nig\u00e9rian en d\u00e9cochant une frappe limpide de plus de 30 m\u00e8tres. Mais au bout de 81 minutes de jeu, <strong>Ma\u00efssa Fathallah<\/strong> a d\u00e9bloqu\u00e9 la situation suite \u00e0 une subtile d\u00e9viation de <strong>Luna Laboucarie<\/strong>. Ce but sera litt\u00e9ralement salvateur. Les Tricolores ont ensuite fait bloc devant leur but pour r\u00e9sister jusqu&rsquo;au bout aux derniers assauts des Nig\u00e9rianes.<\/p>\n<p style=\"text-align: justify;\">Avec ce succ\u00e8s<strong> 1-0<\/strong>, les Bleuettes ont d\u00e9j\u00e0 assur\u00e9 leur place en 8\u00e8mes de finale, et joueront samedi la 1\u00e8re place du groupe face \u00e0 un gros morceau, le <strong>Canada<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">What a finish to MD5! \ud83e\udd29<a href=\"https:\/\/twitter.com\/hashtag\/U17WWC?src=hash&amp;ref_src=twsrc%5Etfw\">#U17WWC<\/a><\/p>\n<p>\u2014 FIFA Women&rsquo;s World Cup (@FIFAWWC) <a href=\"https:\/\/twitter.com\/FIFAWWC\/status\/1981106498521747486?ref_src=twsrc%5Etfw\">October 22, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 Ce mercredi soir, l&rsquo;\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0) gr\u00e2ce \u00e0 un but d\u00e9cisif de Ma\u00efssa Fathallah.<\/p>\n","protected":false},"author":55,"featured_media":620979,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47043],"tags":[16878,40531,30,3356],"class_list":["post-620938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","tag-breve","tag-coupe-du-monde-u17-feminine","tag-france","tag-nigeria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 L&#039;\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 L&#039;\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-22T20:56:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T21:47:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes\",\"datePublished\":\"2025-10-22T20:56:41+00:00\",\"dateModified\":\"2025-10-22T21:47:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\"},\"wordCount\":647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png\",\"keywords\":[\"br\u00e8ve\",\"Coupe du monde U17 f\u00e9minine\",\"France\",\"Nigeria\"],\"articleSection\":[\"Coupe du monde de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\",\"name\":\"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png\",\"datePublished\":\"2025-10-22T20:56:41+00:00\",\"dateModified\":\"2025-10-22T21:47:39+00:00\",\"description\":\"COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 L'\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png\",\"width\":1200,\"height\":674,\"caption\":\"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes","description":"COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 L'\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes","og_description":"COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 L'\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0).","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-10-22T20:56:41+00:00","article_modified_time":"2025-10-22T21:47:39+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes","datePublished":"2025-10-22T20:56:41+00:00","dateModified":"2025-10-22T21:47:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/"},"wordCount":647,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png","keywords":["br\u00e8ve","Coupe du monde U17 f\u00e9minine","France","Nigeria"],"articleSection":["Coupe du monde de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/","name":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png","datePublished":"2025-10-22T20:56:41+00:00","dateModified":"2025-10-22T21:47:39+00:00","description":"COUPE DU MONDE F\u00c9MININE DE FOOTBALL U17 \u2013 L'\u00e9quipe de France a valid\u00e9 sa qualification pour les 8\u00e8mes de finale en battant le Nigeria (1-0).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Coupe-du-monde-U17-F-Laborieuses-les-Bleuettes-battent-difficilement-le-Nigeria-et-filent-en-8emes.png","width":1200,"height":674,"caption":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-u17-f-laborieuses-les-bleuettes-battent-difficilement-le-nigeria-et-filent-en-8emes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde U17 (F) : Laborieuses, les Bleuettes battent difficilement le Nigeria et filent en 8\u00e8mes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/620938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=620938"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/620938\/revisions"}],"predecessor-version":[{"id":621016,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/620938\/revisions\/621016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/620979"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=620938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=620938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=620938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}