{"id":622082,"date":"2025-10-26T21:05:36","date_gmt":"2025-10-26T20:05:36","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=622082&#038;preview=true&#038;preview_id=622082"},"modified":"2025-10-26T21:05:36","modified_gmt":"2025-10-26T20:05:36","slug":"betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/","title":{"rendered":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>BETCLIC \u00c9LITE 2025\/2026 &#8211; En d\u00e9placement \u00e0 Chalon-sur-Sa\u00f4ne, le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s&rsquo;imposant sur le score sans appel de 107-67. Face \u00e0 des Chalonnais impuissants, les Parisiens ont eu besoin d&rsquo;une seule mi-temps pour plier la partie.<\/em><\/strong><\/p>\n<ul>\n<li><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-basket-betclic-elite-2025-2026\/\">Classement Basket Betclic \u00c9lite 2025\/2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La 5\u00e8me journ\u00e9e de <strong>Betclic \u00c9lite<\/strong> prenait fin ce dimanche soir au Colis\u00e9e de<strong> Chalon-sur-Sa\u00f4ne<\/strong>. Auteur d&rsquo;un bon d\u00e9but de saison, l&rsquo;<strong>\u00c9lan<\/strong> faisait face \u00e0 un d\u00e9fi de taille en affrontant le champion de France en titre, le <strong>Paris Basketball<\/strong>. Pr\u00e9sentant seulement un bilan \u00e0 l&rsquo;\u00e9quilibre (2V-2D), le club de la capitale comptait bien s&rsquo;imposer en terres chalonnaises pour virer dans le positif.<\/p>\n<h2>Paris plie le match d\u00e8s la 1\u00e8re mi-temps<\/h2>\n<p>L&rsquo;intensit\u00e9 a \u00e9t\u00e9 de mise d&rsquo;entr\u00e9e de jeu, <strong>Allan Dokossi<\/strong> ouvrant le bal avec un \u00e9norme contre, avant de se faire post\u00e9riser violemment par <strong>Clarence Nadolny<\/strong>. Ce rythme convient alors parfaitement \u00e0 des Parisiens qui ont trouv\u00e9 la faille sur quasiment chaque offensive en s&rsquo;appuyant sur l&rsquo;axe 1-5 Dokossi &#8211;<strong> Nadir Hifi<\/strong>. Si les Chalonnais ont stopp\u00e9 la furia en imposant une belle \u00e9nergie d\u00e9fensive, un manque d&rsquo;adresse combin\u00e9 \u00e0 un net d\u00e9ficit au rebond a progressivement commenc\u00e9 \u00e0 peser. M\u00eame en laissant filer quelques munitions, Paris s&rsquo;est doucement d\u00e9tach\u00e9 en multipliant les stops d\u00e9fensifs spectaculaires, avant que deux fl\u00e8ches sign\u00e9es Hifi et Cavali\u00e8re creusent un \u00e9cart d\u00e9j\u00e0 s\u00e9rieux en moins de 8 minutes (10-23).<\/p>\n<p style=\"text-align: justify;\">Le cauchemar chalonnais s&rsquo;est prolong\u00e9 inlassablement, <strong>Derek Willis<\/strong> entamant le 2\u00e8me quart avec une nouvelle filoche pour porter l&rsquo;\u00e9cart \u00e0 +18 (12-30) ! Il faut dire qu&rsquo;avec un terrible 4\/16 au tir, l&rsquo;\u00c9lan est totalement asphyxi\u00e9 par la d\u00e9fense parisienne. M\u00eame lorsque Paris a d\u00e9jou\u00e9 durant quelques s\u00e9quences en conc\u00e9dant notamment deux fautes techniques, Chalon n&rsquo;en a pas profit\u00e9, et a subi un retour de b\u00e2ton terrible. En quelques secondes, un 8-0 a \u00e9t\u00e9 coll\u00e9 et Paris continue de s&rsquo;envoler avec d\u00e9j\u00e0 40 points en 14 minutes (17-40). Les fautes ont ensuite hach\u00e9 le match, sans que la marche en avant des visiteurs soit entrav\u00e9e. Face \u00e0 l&rsquo;adresse insolente de Parisiens en d\u00e9monstration (61% au global dont 53% \u00e0 3 points, 16\/17 aux lancers), avec un <strong>L\u00e9opold Cavali\u00e8re<\/strong> plus agressif que jamais (12 points \u00e0 la pause) les Chalonnais ont rendu les armes \u00e0 la pause (27-58).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Un excellent premier QT ! <a href=\"https:\/\/t.co\/8HADAq3tii\">pic.twitter.com\/8HADAq3tii<\/a><\/p>\n<p>\u2014 Paris Basketball (@ParisBasketball) <a href=\"https:\/\/twitter.com\/ParisBasketball\/status\/1982515196100055102?ref_src=twsrc%5Etfw\">October 26, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Les Parisiens en gestion, l&rsquo;\u00c9lan limite la casse<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, Paris n&rsquo;a pas ralenti le rythme, bien au contraire. En trois petites minutes, <strong>Nadir Hifi<\/strong> (21 points) et <strong>Derek Willis<\/strong> (13 points, 7 rebonds) ont trouv\u00e9 chacun la mire \u00e0 deux reprises pour coller un 12-0 qui a port\u00e9 l&rsquo;\u00e9cart \u00e0&#8230;+43 (27-70) ! L&rsquo;h\u00e9morragie a ensuite \u00e9t\u00e9 stopp\u00e9e par Zac Cuthbertson, qui a initi\u00e9 un premier vrai run pour adoucir provisoirement l&rsquo;ampleur des d\u00e9g\u00e2ts (35-71). Il faut dire que les Parisiens jouent naturellement avec plus de rel\u00e2chement, ce qui laisse enfin des espaces dans la d\u00e9fense. Mais Hifi s&rsquo;est charg\u00e9 de relancer une attaque mollassonne durant plusieurs minutes en claquant deux paniers successifs (40-80). En fin de 3\u00e8me quart, <strong>Yoann Choupas<\/strong> aura m\u00eame r\u00e9veill\u00e9 le Colis\u00e9e avec deux tirs ext\u00e9rieurs de rang (50-85).<\/p>\n<p style=\"text-align: justify;\">Dans le dernier quart, les locaux ont montr\u00e9 du caract\u00e8re en trouvant enfin de l&rsquo;adresse pour matcher avec le champion de France. N\u00e9anmoins, cela ne changera rien \u00e0 l&rsquo;affaire. Paris a cass\u00e9 la barre des 100 points bien avant la fin du match. Comme un symbole, c&rsquo;est un <strong>L\u00e9opold Cavali\u00e8re<\/strong> excellent qui l&rsquo;a atteint en ajoutant deux lancers francs pour signer son meilleur match offensif sous le maillot parisien (20 points), atteignant pour la premi\u00e8re fois en 18 mois la barre des 20 points. Au final, l&rsquo;addition reste lourde, et Paris sign\u00e9 d\u00e9j\u00e0 son deuxi\u00e8me succ\u00e8s de plus de 40 points de la saison : <strong>107-67<\/strong>. Un r\u00e9sultat convaincant, qui permet d&rsquo;aborder dans les meilleures dispositions une semaine \u00e9reintante avec deux rencontres d&rsquo;Euroligue (face \u00e0 l&rsquo;Anadolu Efes mardi, \u00e0 Milan jeudi).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La d\u00e9monstration continue ! <a href=\"https:\/\/t.co\/Q1yb5s4DLs\">pic.twitter.com\/Q1yb5s4DLs<\/a><\/p>\n<p>\u2014 Paris Basketball (@ParisBasketball) <a href=\"https:\/\/twitter.com\/ParisBasketball\/status\/1982533568053321740?ref_src=twsrc%5Etfw\">October 26, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BETCLIC \u00c9LITE 2025\/2026 &#8211; En d\u00e9placement \u00e0 Chalon-sur-Sa\u00f4ne, le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s&rsquo;imposant sur le score sans appel de 107-67.<\/p>\n","protected":false},"author":55,"featured_media":622132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46998],"tags":[17909,16878,8274,18992],"class_list":["post-622082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betclic-elite","tag-betclic-elite","tag-breve","tag-chalon-sur-saone","tag-paris-basketball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne<\/title>\n<meta name=\"description\" content=\"BETCLIC \u00c9LITE 2025\/2026 - Le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s&#039;imposant sur le score de 107-67 \u00e0 Chalon-sur-Sa\u00f4ne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne\" \/>\n<meta property=\"og:description\" content=\"BETCLIC \u00c9LITE 2025\/2026 - Le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s&#039;imposant sur le score de 107-67 \u00e0 Chalon-sur-Sa\u00f4ne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-26T20:05:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne\",\"datePublished\":\"2025-10-26T20:05:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\"},\"wordCount\":735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png\",\"keywords\":[\"Betclic Elite\",\"br\u00e8ve\",\"Chalon-sur-Sa\u00f4ne\",\"Paris Basketball\"],\"articleSection\":[\"Betclic \u00c9lite\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\",\"name\":\"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png\",\"datePublished\":\"2025-10-26T20:05:36+00:00\",\"description\":\"BETCLIC \u00c9LITE 2025\/2026 - Le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s'imposant sur le score de 107-67 \u00e0 Chalon-sur-Sa\u00f4ne.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png\",\"width\":1200,\"height\":674,\"caption\":\"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne","description":"BETCLIC \u00c9LITE 2025\/2026 - Le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s'imposant sur le score de 107-67 \u00e0 Chalon-sur-Sa\u00f4ne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/","og_locale":"fr_FR","og_type":"article","og_title":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne","og_description":"BETCLIC \u00c9LITE 2025\/2026 - Le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s'imposant sur le score de 107-67 \u00e0 Chalon-sur-Sa\u00f4ne.","og_url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-10-26T20:05:36+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne","datePublished":"2025-10-26T20:05:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/"},"wordCount":735,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png","keywords":["Betclic Elite","br\u00e8ve","Chalon-sur-Sa\u00f4ne","Paris Basketball"],"articleSection":["Betclic \u00c9lite"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/","url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/","name":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png","datePublished":"2025-10-26T20:05:36+00:00","description":"BETCLIC \u00c9LITE 2025\/2026 - Le Paris Basketball a d\u00e9livr\u00e9 un v\u00e9ritable r\u00e9cital en s'imposant sur le score de 107-67 \u00e0 Chalon-sur-Sa\u00f4ne.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Betclic-Elite-20252026-J5-Le-Paris-Basketball-fait-totalement-exploser-Chalon-sur-Saone.png","width":1200,"height":674,"caption":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-2025-2026-j5-le-paris-basketball-fait-totalement-exploser-chalon-sur-saone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Betclic \u00c9lite 2025\/2026 (J5) : Le Paris Basketball fait totalement exploser Chalon-sur-Sa\u00f4ne"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=622082"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622082\/revisions"}],"predecessor-version":[{"id":622144,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622082\/revisions\/622144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/622132"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=622082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=622082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=622082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}