{"id":622237,"date":"2025-10-27T10:10:55","date_gmt":"2025-10-27T09:10:55","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=622237&#038;preview=true&#038;preview_id=622237"},"modified":"2025-10-27T13:06:29","modified_gmt":"2025-10-27T12:06:29","slug":"bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/","title":{"rendered":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&rsquo;Europe des Champions"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE D&rsquo;EUROPE DES CHAMPIONS DE BOWLING 2025 &#8211; En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">En juin dernier, l&rsquo;\u00e9quipe de France avait ramen\u00e9 pas moins de 8 m\u00e9dailles des championnats d&rsquo;Europe. Et un certain<strong> Maxime Dubois<\/strong> avait largement contribu\u00e9 \u00e0 la r\u00e9ussite tricolore, avec ses trois m\u00e9dailles d&rsquo;argent. Pour la Coupe d&rsquo;Europe des champions, il esp\u00e9rait bien changer cet argent en or et se pr\u00e9sentait parmi les leaders de la d\u00e9l\u00e9gation fran\u00e7aise.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/bowling-pas-dor-mais-8-medailles-pour-les-bleus-aux-championnats-deurope\/\" class=\"vlp-link\" title=\"Bowling : Pas d&#039;or mais 8 m\u00e9dailles pour les Bleus aux Championnats d&#039;Europe\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Bowling-Pas-dor-mais-8-medailles-pour-les-Bleus-aux-Championnats-dEurope.png\" class=\"attachment-800x445 size-800x445\" alt=\"Bowling Pas d&#039;or mais 8 m\u00e9dailles pour les Bleus aux Championnats d&#039;Europe\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Bowling-Pas-dor-mais-8-medailles-pour-les-Bleus-aux-Championnats-dEurope.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Bowling-Pas-dor-mais-8-medailles-pour-les-Bleus-aux-Championnats-dEurope-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Bowling-Pas-dor-mais-8-medailles-pour-les-Bleus-aux-Championnats-dEurope-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/06\/Bowling-Pas-dor-mais-8-medailles-pour-les-Bleus-aux-Championnats-dEurope-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Bowling : Pas d'or mais 8 m\u00e9dailles pour les Bleus aux Championnats d'Europe<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS D'EUROPE DE BOWLING 2025 - Si les Bleus ont \u00e9chou\u00e9 dans leur qu\u00eate d'or, ils ont livr\u00e9 une magnifique comp\u00e9tition au Danemark pour rentrer les valises pleines de 8 m\u00e9dailles.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">De l&rsquo;or, enfin<\/h2>\n<p style=\"text-align: justify;\">Et cet or, il l&rsquo;a obtenu en doublettes mixtes avec <strong>Sol\u00e8ne Goron<\/strong>. Sur une \u00e9preuve r\u00e9cente, puisque rajout\u00e9e au programme en 2023, les Bleus ont \u00e9t\u00e9 absolument intouchables. D\u00e8s la premi\u00e8re des 8 parties, ils se sont install\u00e9s en t\u00eate avec <strong>527 points<\/strong>, alors qu&rsquo;aucune autre paire n&rsquo;avait d\u00e9pass\u00e9 les 500 ! Une mani\u00e8re d&rsquo;annoncer ce qu&rsquo;allait \u00eatre la suite de la comp\u00e9tition : une d\u00e9monstration. Dubois allait carr\u00e9ment signer un 299 sur la troisi\u00e8me manche, et terminer avec un incroyable 256.8 de moyenne. R\u00e9sultat : <strong>3812 points<\/strong>, 70 de mieux que la concurrence, et une m\u00e9daille d&rsquo;or bien m\u00e9rit\u00e9e : les Bleus ont survol\u00e9 la comp\u00e9tition.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\uddd6\ud835\udddb\ud835\uddd4\ud835\udde0\ud835\udde3\ud835\udddc\ud835\udde2\ud835\udde1\ud835\udde6 \ud835\uddd7&rsquo;\ud835\uddd8\ud835\udde8\ud835\udde5\ud835\udde2\ud835\udde3\ud835\uddd8 ! \ud83e\udd47<\/p>\n<p>Stratosph\u00e9riques ! Maxime et Sol\u00e8ne remportent l&rsquo;or en doublettes mixtes \u00e0 l&rsquo;issue de huit magnifiques parties, avec un score de 3812 \ud83d\udc4f\ud83d\udc4f<\/p>\n<p>Une fois encore, nos Bleus ont \u00e9t\u00e9 incroyables aujourd&rsquo;hui. On a vibr\u00e9 avec vous, un grand bravo ! <a href=\"https:\/\/t.co\/IDSSIJj8fS\">pic.twitter.com\/IDSSIJj8fS<\/a><\/p>\n<p>\u2014 FF Bowling et Sport de Quilles (@FFBSQ) <a href=\"https:\/\/twitter.com\/FFBSQ\/status\/1981405887848992774?ref_src=twsrc%5Etfw\">October 23, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Et au vu de sa forme, <strong>Maxime Dubois<\/strong> pouvait viser le doubl\u00e9 sur l&rsquo;\u00e9preuve individuelle, d&rsquo;autant qu&rsquo;il \u00e9tait tout simplement le tenant du titre. Bien plus r\u00e9gulier que ses adversaires, il a travers\u00e9 les qualifications puis les quarts de finale, l\u00e0 o\u00f9 s&rsquo;est arr\u00eat\u00e9 <strong>Ga\u00ebtan Mouveroux<\/strong>, malgr\u00e9 un <strong>300<\/strong>. <strong>Dubois<\/strong> a ensuite ma\u00eetris\u00e9 <strong>Teodor Samuelsson<\/strong>, mais a fini par craquer en finale contre <strong>Luk\u00e1\u0161 Jel\u00ednek<\/strong>, notamment \u00e0 cause d&rsquo;une deuxi\u00e8me manche rat\u00e9e \u00e0 188. M\u00e9daille d&rsquo;argent donc, pendant que <strong>Sol\u00e8ne Goron<\/strong> avait \u00e9chou\u00e9 aux portes des demi-finales. Mais avec deux podiums en trois \u00e9preuves, aucun doute, les Bleus du bowling n&rsquo;ont pas fait le voyage pour rien en Autriche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE D&rsquo;EUROPE DES CHAMPIONS DE BOWLING 2025 &#8211; En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.<\/p>\n","protected":false},"author":59,"featured_media":622239,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47068],"tags":[16878,47063],"class_list":["post-622237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bowling","tag-breve","tag-championnats-deurope-de-bowling"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&#039;Europe des Champions<\/title>\n<meta name=\"description\" content=\"COUPE D&#039;EUROPE DES CHAMPIONS DE BOWLING 2025 - En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&#039;Europe des Champions\" \/>\n<meta property=\"og:description\" content=\"COUPE D&#039;EUROPE DES CHAMPIONS DE BOWLING 2025 - En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T09:10:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T12:06:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&#039;Europe des Champions\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&rsquo;Europe des Champions\",\"datePublished\":\"2025-10-27T09:10:55+00:00\",\"dateModified\":\"2025-10-27T12:06:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/\"},\"wordCount\":484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png\",\"keywords\":[\"br\u00e8ve\",\"Championnats d'Europe de bowling\"],\"articleSection\":[\"Bowling\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/\",\"name\":\"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png\",\"datePublished\":\"2025-10-27T09:10:55+00:00\",\"dateModified\":\"2025-10-27T12:06:29+00:00\",\"description\":\"COUPE D'EUROPE DES CHAMPIONS DE BOWLING 2025 - En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png\",\"width\":1200,\"height\":674,\"caption\":\"Bowling Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&rsquo;Europe des Champions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions","description":"COUPE D'EUROPE DES CHAMPIONS DE BOWLING 2025 - En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/","og_locale":"fr_FR","og_type":"article","og_title":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions","og_description":"COUPE D'EUROPE DES CHAMPIONS DE BOWLING 2025 - En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.","og_url":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-10-27T09:10:55+00:00","article_modified_time":"2025-10-27T12:06:29+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&rsquo;Europe des Champions","datePublished":"2025-10-27T09:10:55+00:00","dateModified":"2025-10-27T12:06:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/"},"wordCount":484,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png","keywords":["br\u00e8ve","Championnats d'Europe de bowling"],"articleSection":["Bowling"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/","url":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/","name":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png","datePublished":"2025-10-27T09:10:55+00:00","dateModified":"2025-10-27T12:06:29+00:00","description":"COUPE D'EUROPE DES CHAMPIONS DE BOWLING 2025 - En argent en simple, Maxime Dubois, associ\u00e9 \u00e0 Sol\u00e8ne Goron, a triomph\u00e9 sur les doublettes mixtes en Autriche.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Bowling-Solene-Goron-et-Maxime-Dubois-remportent-la-Coupe-dEurope-des-Champions.png","width":1200,"height":674,"caption":"Bowling Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d'Europe des Champions"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/bowling-solene-goron-et-maxime-dubois-remportent-la-coupe-deurope-des-champions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Bowling : Sol\u00e8ne Goron et Maxime Dubois remportent la Coupe d&rsquo;Europe des Champions"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=622237"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622237\/revisions"}],"predecessor-version":[{"id":622284,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622237\/revisions\/622284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/622239"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=622237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=622237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=622237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}