{"id":622340,"date":"2025-10-27T21:17:02","date_gmt":"2025-10-27T20:17:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=622340&#038;preview=true&#038;preview_id=622340"},"modified":"2025-10-27T21:17:02","modified_gmt":"2025-10-27T20:17:02","slug":"nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/","title":{"rendered":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>NBA 2025\/2026 &#8211; Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l&rsquo;Ouest.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Qui dit lundi en <strong>NBA<\/strong>, dit remise des r\u00e9compenses de la semaine \u00e9coul\u00e9e ! Alors que la saison a repris ses droits mardi dernier, la ligue a d\u00e9cern\u00e9 les titres de<strong> joueurs de la semaine<\/strong> au sein des deux Conf\u00e9rences. Comme cela pouvait \u00eatre attendu, <strong>Victor Wembanyama<\/strong> a rafl\u00e9 la mise dans la Conf\u00e9rence Ouest.<\/p>\n<h2>Victor Wembanyama r\u00e9compens\u00e9 pour la 2\u00e8me fois de sa carri\u00e8re<\/h2>\n<p style=\"text-align: justify;\">Pourtant, la concurrence \u00e9tait bien pr\u00e9sente entre un<strong> Stephen Curry<\/strong> chaud comme la braise, ou un <strong>Shai Gilgeous-Alexander<\/strong> qui a repris sur des bases similaires \u00e0 sa saison de MVP sortant. Malgr\u00e9 tout, le ph\u00e9nom\u00e8ne tricolore leur a dam\u00e9 le pion en fournissant une premi\u00e8re semaine tonitruante. D\u00e8s le match d&rsquo;ouverture face aux Pelicans, il est pass\u00e9 proche d&rsquo;un incroyable triple double en claquant 9 contres en plus de ses 29 points et 11 rebonds. Puis, il a cartonn\u00e9 les Mavs en culminant \u00e0 40 unit\u00e9s, avant de finir en beaut\u00e9 avec <a href=\"https:\/\/dicodusport.fr\/blog\/nba-2025-2026-les-spurs-viennent-a-bout-des-nets-victor-wembanyama-repond-encore-present\/\">31 points et 14 rebonds face aux Nets dimanche soir<\/a>. Cerise sur le g\u00e2teau, les <strong>Spurs<\/strong> ont r\u00e9alis\u00e9 un sans-faute en remportant ces trois parties.<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/statistiques-victor-wembanyama-record-de-points-rebonds-assists-et-blocks-en-nba\/\">Statistiques Victor Wembanyama : Record de points, rebonds, assists et blocks en NBA<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En trois matchs, le Fran\u00e7ais a donc affol\u00e9 les statistiques en tournant \u00e0 <strong>33,3 points, 13,3 rebonds et 6 contres<\/strong> par match ! C&rsquo;est donc tout naturellement qu&rsquo;il d\u00e9croche son 2\u00e8me titre de meilleur joueur de la semaine en carri\u00e8re. Un total qui pourrait exploser au fil des mois si le gar\u00e7on continue \u00e0 rouler sur la ligue \u00e0 ce rythme.<\/p>\n<p style=\"text-align: justify;\">Dans la Conf\u00e9rence Est, c&rsquo;est <strong>Giannis Antetokounmpo<\/strong> qui a rafl\u00e9 la mise en alignant des chiffres encore plus gargantuesques : <strong>36 points, 16 rebonds et 7 passes<\/strong> ! Si les <strong>Bucks<\/strong> ont conc\u00e9d\u00e9 une d\u00e9faite dimanche \u00e0 Cleveland, la domination du Grec \u00e0 l&rsquo;int\u00e9rieur a \u00e9t\u00e9 totale, et la r\u00e9compense est donc amplement m\u00e9rit\u00e9e. Habitu\u00e9 de cet honneur, il est \u00e9lu pour la 28\u00e8me fois de sa carri\u00e8re joueur de la Conf\u00e9rence Est.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">San Antonio Spurs forward-center Victor Wembanyama and Milwaukee Bucks forward Giannis Antetokounmpo have been named the NBA Western and Eastern Conference Players of the Week, respectively, for Week 1 of the 2025-26 season (Oct. 21-26). <a href=\"https:\/\/t.co\/OKTkuUjIAv\">pic.twitter.com\/OKTkuUjIAv<\/a><\/p>\n<p>\u2014 NBA Communications (@NBAPR) <a href=\"https:\/\/twitter.com\/NBAPR\/status\/1982892658684244143?ref_src=twsrc%5Etfw\">October 27, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/nba-2025-2026-sans-lebron-james-ni-luka-doncic-austin-reaves-entre-dans-la-zone-51\/\" class=\"vlp-link\" title=\"NBA 2025\/2026 : Sans LeBron James ni Luka Don\u010di\u0107, Austin Reaves entre dans la zone 51\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-20252026-Sans-LeBron-James-ni-Luka-Doncic-Austin-Reaves-entre-dans-la-zone-51.png\" class=\"attachment-800x445 size-800x445\" alt=\"NBA 20252026 Sans LeBron James ni Luka Doncic, Austin Reaves entre dans la zone 51\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-20252026-Sans-LeBron-James-ni-Luka-Doncic-Austin-Reaves-entre-dans-la-zone-51.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-20252026-Sans-LeBron-James-ni-Luka-Doncic-Austin-Reaves-entre-dans-la-zone-51-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-20252026-Sans-LeBron-James-ni-Luka-Doncic-Austin-Reaves-entre-dans-la-zone-51-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-20252026-Sans-LeBron-James-ni-Luka-Doncic-Austin-Reaves-entre-dans-la-zone-51-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">NBA 2025\/2026 : Sans LeBron James ni Luka Don\u010di\u0107, Austin Reaves entre dans la zone 51<\/div><div class=\"vlp-block-1 vlp-link-summary\">NBA 2025-2026 - En l'absence de Luka Don\u010di\u0107 et de LeBron James, Austin Reaves a pris les commandes du jeu des Lakers face \u00e0 Sacramento dans la nuit de dimanche \u00e0 lundi. R\u00e9sultat, 51 points, 11 rebonds et 9 passes. Mais l'arri\u00e8re, non draft\u00e9, finira-t-il la saison \u00e0 Los Angeles ?\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>NBA 2025\/2026 &#8211; Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l&rsquo;Ouest.<\/p>\n","protected":false},"author":55,"featured_media":622341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[10533],"tags":[16878,179,16921],"class_list":["post-622340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-breve","tag-nba","tag-victor-wembanyama"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest<\/title>\n<meta name=\"description\" content=\"NBA 2025\/2026 - Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l&#039;Ouest.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest\" \/>\n<meta property=\"og:description\" content=\"NBA 2025\/2026 - Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l&#039;Ouest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T20:17:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest\",\"datePublished\":\"2025-10-27T20:17:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png\",\"keywords\":[\"br\u00e8ve\",\"NBA\",\"Victor Wembanyama\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/\",\"name\":\"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png\",\"datePublished\":\"2025-10-27T20:17:02+00:00\",\"description\":\"NBA 2025\\\/2026 - Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l'Ouest.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png\",\"width\":1200,\"height\":674,\"caption\":\"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest","description":"NBA 2025\/2026 - Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l'Ouest.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/","og_locale":"fr_FR","og_type":"article","og_title":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest","og_description":"NBA 2025\/2026 - Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l'Ouest.","og_url":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-10-27T20:17:02+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest","datePublished":"2025-10-27T20:17:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png","keywords":["br\u00e8ve","NBA","Victor Wembanyama"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/","url":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/","name":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png","datePublished":"2025-10-27T20:17:02+00:00","description":"NBA 2025\/2026 - Auteur de trois premiers matchs impressionnants, Victor Wembanyama a \u00e9t\u00e9 r\u00e9compens\u00e9 en cons\u00e9quence en \u00e9tant \u00e9lu joueur de la semaine \u00e0 l'Ouest.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/NBA-Victor-Wembanyama-elu-joueur-de-la-semaine-de-la-Conference-Ouest.png","width":1200,"height":674,"caption":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nba-victor-wembanyama-elu-joueur-de-la-semaine-de-la-conference-ouest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"NBA : Victor Wembanyama \u00e9lu joueur de la semaine de la Conf\u00e9rence Ouest"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=622340"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622340\/revisions"}],"predecessor-version":[{"id":622348,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/622340\/revisions\/622348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/622341"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=622340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=622340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=622340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}