{"id":624468,"date":"2025-11-08T11:53:34","date_gmt":"2025-11-08T10:53:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=624468&#038;preview=true&#038;preview_id=624468"},"modified":"2025-11-08T11:53:34","modified_gmt":"2025-11-08T10:53:34","slug":"mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/","title":{"rendered":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 &#8211; Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">En 2024, les Bleus du VTT Trials avaient fait une belle moisson de trois m\u00e9dailles lors des Championnats du monde de cyclisme urbain, avec en point d&rsquo;orgue le sacre de <strong>Roman Salaun<\/strong> chez les juniors. Difficile de faire mieux cette ann\u00e9e, mais la d\u00e9l\u00e9gation fran\u00e7aise n&rsquo;est pas repartie bredouille.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2024-roman-salaun-champion-du-monde-juniors-de-trials-guillaume-camus-en-argent\/\" class=\"vlp-link\" title=\"Mondiaux cyclisme urbain 2024 : Roman Salaun champion du monde juniors de Trials, Guillaume Camus en argent !\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-cyclisme-urbain-2024-Roman-Salaun-champion-du-monde-juniors-de-Trials-Guillaume-Camus-en-argent-1-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Mondiaux cyclisme urbain 2024 Roman Salaun champion du monde juniors de Trials, Guillaume Camus en argent !\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-cyclisme-urbain-2024-Roman-Salaun-champion-du-monde-juniors-de-Trials-Guillaume-Camus-en-argent-1-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-cyclisme-urbain-2024-Roman-Salaun-champion-du-monde-juniors-de-Trials-Guillaume-Camus-en-argent-1-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-cyclisme-urbain-2024-Roman-Salaun-champion-du-monde-juniors-de-Trials-Guillaume-Camus-en-argent-1-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/12\/Mondiaux-cyclisme-urbain-2024-Roman-Salaun-champion-du-monde-juniors-de-Trials-Guillaume-Camus-en-argent-1-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Mondiaux cyclisme urbain 2024 : Roman Salaun champion du monde juniors de Trials, Guillaume Camus en argent !<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2024 - Roman Salaun a d\u00e9fi\u00e9 les pronostics pour aller rafler le titre mondial juniors de trials en v\u00e9lo 26 pouces \u00e0 Abu Dhabi, alors qu'en 20 pouces, Guillaume Camus s'est par\u00e9 d'argent.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les Bleus en bronze<\/h2>\n<p style=\"text-align: justify;\">La premi\u00e8re m\u00e9daille \u00e9tait pour <strong>Louis Chasseuil<\/strong>, en cat\u00e9gorie juniors, sur l&rsquo;\u00e9preuve en VTT 20 pouces. La prolongation d&rsquo;une belle tradition, puisque c&rsquo;est la quatri\u00e8me \u00e9dition d&rsquo;affil\u00e9e qu&rsquo;un Bleuet monte sur le podium de cette \u00e9preuve, apr\u00e8s <strong>Robin Berchiatti<\/strong>, en or en 2022 et en argent en 2023, et <strong>Guillaume Camus<\/strong>, vice-champion du monde l&rsquo;an dernier. S&rsquo;il n&rsquo;a r\u00e9alis\u00e9 aucun score maximal et qu&rsquo;il n&rsquo;a pu contester les deux leaders, il a r\u00e9ussi \u00e0 sauver le bronze, sa premi\u00e8re m\u00e9daille internationale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"ca\"><a href=\"https:\/\/twitter.com\/hashtag\/Riyadh2025?src=hash&amp;ref_src=twsrc%5Etfw\">#Riyadh2025<\/a> Podiums \ud83c\udfc6<\/p>\n<p>Women Junior<br \/>\n\ud83e\udd47 Andrea Perez \ud83c\uddea\ud83c\uddf8<br \/>\n\ud83e\udd48 Yun Vilajosana \ud83c\uddea\ud83c\uddf8<br \/>\n\ud83e\udd49 Emilia Keikus \ud83c\udde9\ud83c\uddea<\/p>\n<p>Men Junior 26\u201d<br \/>\n\ud83e\udd47 Ferran Perez \ud83c\uddea\ud83c\uddf8<br \/>\n\ud83e\udd48 Carl Christ \ud83c\udde9\ud83c\uddea<br \/>\n\ud83e\udd49 Ian Martinez \ud83c\uddea\ud83c\uddf8<\/p>\n<p>Men Junior 20&Prime;<br \/>\n\ud83e\udd47 Travis Asenjo \ud83c\uddea\ud83c\uddf8<br \/>\n\ud83e\udd48 Ugo Theunissen \ud83c\udde7\ud83c\uddea<br \/>\n\ud83e\udd49 Louis Chasseuil \ud83c\uddeb\ud83c\uddf7<\/p>\n<p>\ud83d\udcf8 <a href=\"https:\/\/twitter.com\/ZubikoPhoto?ref_src=twsrc%5Etfw\">@ZubikoPhoto<\/a> <a href=\"https:\/\/t.co\/Dpnz59RCdK\">pic.twitter.com\/Dpnz59RCdK<\/a><\/p>\n<p>\u2014 UCI Trials (@UCI_Trials) <a href=\"https:\/\/twitter.com\/UCI_Trials\/status\/1986899432265167170?ref_src=twsrc%5Etfw\">November 7, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nLe bronze, c&rsquo;est \u00e9galement ce qui attend <strong>Nina Vabre<\/strong>. Une m\u00e9daille qui lui permet enfin de toucher au but. Quatri\u00e8me en 2023, cinqui\u00e8me en 2024, elle grimpe enfin sur le podium. Certes, elle n&rsquo;a rien pu faire contre la nouvelle reine de la discipline, Alba Riera, qui conserve son titre. Mais avec un superbe dernier passage, elle a quitt\u00e9 la quatri\u00e8me place qui l&rsquo;attendait pour arracher le bronze, comme aux derniers championnats d&rsquo;Europe. Et prendre la rel\u00e8ve de <strong>Manon Basseville<\/strong>, trois fois m\u00e9daill\u00e9e entre 2018 et 2021. Deux m\u00e9dailles pour les Bleus du VTT Trials, en attendant les finales du BMX Park cet apr\u00e8s-midi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 &#8211; Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.<\/p>\n","protected":false},"author":59,"featured_media":624478,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10279],"tags":[16878,47238],"class_list":["post-624468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vtt","tag-breve","tag-vtt-trials"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 - Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 - Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-08T10:53:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials\",\"datePublished\":\"2025-11-08T10:53:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\"},\"wordCount\":449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png\",\"keywords\":[\"br\u00e8ve\",\"VTT Trials\"],\"articleSection\":[\"VTT\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\",\"name\":\"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png\",\"datePublished\":\"2025-11-08T10:53:34+00:00\",\"description\":\"CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 - Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png\",\"width\":1200,\"height\":674,\"caption\":\"Mondiaux cyclisme urbain 2025 Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials","description":"CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 - Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/","og_locale":"fr_FR","og_type":"article","og_title":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials","og_description":"CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 - Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.","og_url":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-11-08T10:53:34+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials","datePublished":"2025-11-08T10:53:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/"},"wordCount":449,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png","keywords":["br\u00e8ve","VTT Trials"],"articleSection":["VTT"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/","url":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/","name":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png","datePublished":"2025-11-08T10:53:34+00:00","description":"CHAMPIONNATS DU MONDE DE CYCLISME URBAIN 2025 - Les \u00e9preuves de VTT Trials ont permis aux Bleus de ramener deux m\u00e9dailles de bronze, gr\u00e2ce \u00e0 Louis Chasseuil et Nina Vabre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Mondiaux-cyclisme-urbain-2025-Nina-Vabre-et-Louis-Chasseuil-medailles-en-Trials.png","width":1200,"height":674,"caption":"Mondiaux cyclisme urbain 2025 Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-cyclisme-urbain-2025-nina-vabre-et-louis-chasseuil-medailles-en-trials\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mondiaux cyclisme urbain 2025 : Nina Vabre et Louis Chasseuil m\u00e9daill\u00e9s en Trials"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/624468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=624468"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/624468\/revisions"}],"predecessor-version":[{"id":624479,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/624468\/revisions\/624479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/624478"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=624468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=624468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=624468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}