{"id":625024,"date":"2025-11-10T10:56:44","date_gmt":"2025-11-10T09:56:44","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=625024&#038;preview=true&#038;preview_id=625024"},"modified":"2025-11-10T10:56:44","modified_gmt":"2025-11-10T09:56:44","slug":"billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/","title":{"rendered":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&rsquo;argent"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>BILLIE JEAN KING CUP JUNIORS 2025 &#8211; Convaincantes jusqu&rsquo;en finale, les Bleuettes n&rsquo;ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d&rsquo;argent.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Voil\u00e0 20 ans que l&rsquo;\u00e9quipe de France juniors filles de tennis de n&rsquo;avait plus atteint la finale Billie Jean King Cup (ex Fed Cup). \u00c0 l&rsquo;\u00e9poque, <strong>Estelle Guisard<\/strong>,<strong> No\u00e9mie Scharle<\/strong> et une certaine <strong>Aliz\u00e9 Cornet<\/strong> avaient \u00e9chou\u00e9 contre les Polonaises, men\u00e9es par <strong>Agnieszka Radwa\u0144ska<\/strong>. 20 ans plus tard, <strong>N\u00e9hira Sanon<\/strong>, <strong>Cindy Langlais<\/strong> et <strong>Ksenia Efremova<\/strong> ont fait aussi bien \u00e0 Santiago du Chili.<\/p>\n<h2 style=\"text-align: justify;\">Argent content<\/h2>\n<p style=\"text-align: justify;\">Les Bleuettes ont en effet trac\u00e9 leur route sans r\u00e9el souci. La Grande-Bretagne, puis le Taipei Chinois sont pass\u00e9s \u00e0 la moulinette. En demi-finale, elles ont \u00e9trill\u00e9 les Polonaises, s&rsquo;imposant en deux matchs, deux victoires pour <strong>Sanon<\/strong> et <strong>Efremova<\/strong> qui n&rsquo;ont l\u00e2ch\u00e9 que 12 jeux en cumul\u00e9 ! Mais la finale, contre l&rsquo;ogre am\u00e9ricain, s&rsquo;annon\u00e7ait comme une derni\u00e8re marche trop haute.<\/p>\n<p style=\"text-align: justify;\"><strong>Kristina Penickova<\/strong>, finaliste de l&rsquo;Open d&rsquo;Australie juniors en janvier, a \u00e9t\u00e9 bien trop forte pour <strong>Cindy Langlais<\/strong>, qui n&rsquo;a pu inscrire que deux jeux. Tout reposait sur <strong>Ksenia Efremova<\/strong>, qui devait se mesurer \u00e0 la finaliste de Wimbledon juniors, <strong>Julieta Pareja<\/strong>. Malgr\u00e9 une belle partie, elle a d\u00fb rendre les armes 6-4, 6-3 et laisser le troph\u00e9e s&rsquo;envoler vers les \u00c9tats-Unis. 30 ans apr\u00e8s, le titre d\u00e9croch\u00e9 par <strong>Karolina Jagieniak<\/strong>, <strong>Am\u00e9lie Mauresmo<\/strong> et <strong>Kildine Chevalier<\/strong> reste l&rsquo;unique sacre fran\u00e7ais chez les filles. Mais cette performance au Chili reste le signe annonciateur d&rsquo;un rebond possible pour le tennis f\u00e9minin fran\u00e7ais.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Les Bleues s&rsquo;inclinent en finale de la Billie Jean King Cup face aux \u00c9tats-Unis \ud83e\udd1d<\/p>\n<p>Une tr\u00e8s belle m\u00e9daille d&rsquo;argent pour N\u00e9hira Sanon, Cindy Langlais, Ksenia Efremova et le capitaine Philippe Robin \ud83e\udd48\ud83c\uddeb\ud83c\uddf7 <a href=\"https:\/\/t.co\/IyZEVgFLXl\">pic.twitter.com\/IyZEVgFLXl<\/a><\/p>\n<p>\u2014 FFT (@FFTennis) <a href=\"https:\/\/twitter.com\/FFTennis\/status\/1987649006592278590?ref_src=twsrc%5Etfw\">November 9, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Chez les gar\u00e7ons, l&rsquo;affaire n&rsquo;a pas \u00e9t\u00e9 aussi belle. La derni\u00e8re victoire remonte \u00e0 2005, avec <strong>Kevin Botti<\/strong>, <strong>J\u00e9r\u00f4me Inzerillo<\/strong> et <strong>St\u00e9phane Piro<\/strong>, mais la succession devra attendre. <strong>Andrea Baudel<\/strong>, <strong>Amaury Abbas<\/strong> et <strong>Daniel Jade<\/strong> ont r\u00e9ussi \u00e0 se faufiler en quarts, mais ont craqu\u00e9 au double d\u00e9cisif contre l&rsquo;Allemagne. Dommage pour un trio qui avait l&rsquo;air solide, mais il en faudra plus pour renouer avec la victoire dans cette comp\u00e9tition.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BILLIE JEAN KING CUP JUNIORS 2025 &#8211; Convaincantes jusqu&rsquo;en finale, les Bleuettes n&rsquo;ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d&rsquo;argent.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":625025,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2302],"tags":[15987,16878],"class_list":["post-625024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-billie-jean-king-cup","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&#039;argent<\/title>\n<meta name=\"description\" content=\"BILLIE JEAN KING CUP JUNIORS 2025 - Convaincantes jusqu&#039;en finale, les Bleuettes n&#039;ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d&#039;argent.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&#039;argent\" \/>\n<meta property=\"og:description\" content=\"BILLIE JEAN KING CUP JUNIORS 2025 - Convaincantes jusqu&#039;en finale, les Bleuettes n&#039;ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d&#039;argent.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T09:56:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&#039;argent\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&rsquo;argent\",\"datePublished\":\"2025-11-10T09:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png\",\"keywords\":[\"Billie Jean King Cup\",\"br\u00e8ve\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\",\"name\":\"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d'argent\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png\",\"datePublished\":\"2025-11-10T09:56:44+00:00\",\"description\":\"BILLIE JEAN KING CUP JUNIORS 2025 - Convaincantes jusqu'en finale, les Bleuettes n'ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d'argent.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png\",\"width\":1200,\"height\":674,\"caption\":\"Billie Jean King Cup juniors 2025 Les Bleuettes \u00e9chouent en finale et se parent d'argent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&rsquo;argent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d'argent","description":"BILLIE JEAN KING CUP JUNIORS 2025 - Convaincantes jusqu'en finale, les Bleuettes n'ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d'argent.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/","og_locale":"fr_FR","og_type":"article","og_title":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d'argent","og_description":"BILLIE JEAN KING CUP JUNIORS 2025 - Convaincantes jusqu'en finale, les Bleuettes n'ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d'argent.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-11-10T09:56:44+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d'argent","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&rsquo;argent","datePublished":"2025-11-10T09:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png","keywords":["Billie Jean King Cup","br\u00e8ve"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/","url":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/","name":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d'argent","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png","datePublished":"2025-11-10T09:56:44+00:00","description":"BILLIE JEAN KING CUP JUNIORS 2025 - Convaincantes jusqu'en finale, les Bleuettes n'ont rien pu faire contre les Am\u00e9ricaines, mais d\u00e9crochent une belle m\u00e9daille d'argent.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Billie-Jean-King-Cup-juniors-2025-Les-Bleuettes-echouent-en-finale-et-se-parent-dargent.png","width":1200,"height":674,"caption":"Billie Jean King Cup juniors 2025 Les Bleuettes \u00e9chouent en finale et se parent d'argent"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/billie-jean-king-cup-juniors-2025-les-bleuettes-echouent-en-finale-et-se-parent-dargent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Billie Jean King Cup juniors 2025 : Les Bleuettes \u00e9chouent en finale et se parent d&rsquo;argent"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=625024"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625024\/revisions"}],"predecessor-version":[{"id":625026,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625024\/revisions\/625026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/625025"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=625024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=625024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=625024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}