{"id":625080,"date":"2025-11-11T09:30:22","date_gmt":"2025-11-11T08:30:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=625080&#038;preview=true&#038;preview_id=625080"},"modified":"2025-11-11T00:11:44","modified_gmt":"2025-11-10T23:11:44","slug":"arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/","title":{"rendered":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>ARKEMA PREMI\u00c8RE LIGUE 2025\/2026 &#8211; Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4. Dans le rouge en revanche, Lens ne voit pas la lumi\u00e8re alors que le danger guette pour les St\u00e9phanoises et les Marseillaises.<\/strong><\/em><\/p>\n<p>\u00c0 toi, \u00e0 moi, le Paris FC avait repris la deuxi\u00e8me place des mains du PSG en ouverture de la 7<sup>\u00e8me<\/sup> journ\u00e9e avant que les Parisiennes de <strong>Paulo C\u00e9sar<\/strong> ne la r\u00e9cup\u00e8re le lendemain. Dans cette lutte aux playoffs, la course est aussi de mise pour la 4<sup>\u00e8me<\/sup> place avec Nantes qui revient sur Fleury. Loin de ces pr\u00e9occupations, Lens a surtout des difficult\u00e9s \u00e0 sauver sa peau.<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-arkema-premiere-ligue-2025-2026\/\">Classement Arkema Premi\u00e8re Ligue 2025\/2026<\/a><\/strong><\/li>\n<\/ul>\n<h2>Tops\u00a0: Nantes grapille, Lyon sur un nuage<\/h2>\n<p>Les Nantaises ne devaient pas flancher lors de la r\u00e9ception du Havre, sous peine de voir les visiteuses leur chiper la 5<sup>\u00e8me<\/sup> place. C\u2019\u00e9tait bien mal embarqu\u00e9 cependant avec le but pr\u00e9coce de <strong>Madeline Roth<\/strong>. Domin\u00e9es dans la premi\u00e8re p\u00e9riode, les Canaries ont r\u00e9cup\u00e9r\u00e9 le momentum au retour des vestiaires. Sur penalty, <strong>L\u00e9a<\/strong> <strong>Khelifi<\/strong> les a replac\u00e9es sur un m\u00eame pied d\u2019\u00e9galit\u00e9 avant que <strong>Mariam Toloba <\/strong>ne leur donne l\u2019avantage (72<sup>\u00e8me<\/sup>). H\u00e9ro\u00efques d\u00e9fensivement pour \u00e9viter le nul, les Jaunes et Vertes ont pris 4 longueurs d\u2019avance sur les Havraises au classement. Toujours 5<sup>\u00e8me<\/sup>, Nantes revient \u00e0 une longueur de Fleury, battu lourdement par le PSG.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Premier but sous les couleurs Nantaises pour Mariam Toloba \ud83d\udfe1\ud83d\udfe2 <a href=\"https:\/\/twitter.com\/hashtag\/ArkemaPL?src=hash&amp;ref_src=twsrc%5Etfw\">#ArkemaPL<\/a> <a href=\"https:\/\/t.co\/hv1kRaZOff\">pic.twitter.com\/hv1kRaZOff<\/a><\/p>\n<p>\u2014 Arkema Premi\u00e8re Ligue (@ArkemaPL) <a href=\"https:\/\/twitter.com\/ArkemaPL\/status\/1987214144043372548?ref_src=twsrc%5Etfw\">November 8, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Si le Paris Saint-Germain a d\u00e9roul\u00e9 en sup\u00e9riorit\u00e9 num\u00e9rique contre Fleury, les Lyonnaises n\u2019ont pas eu besoin de \u00e7a pour venir \u00e0 bout de Montpellier. Et facilement. Pas vraiment surprenant, mais au-del\u00e0 de la victoire, le score r\u00e9v\u00e8le un peu plus la supr\u00e9matie rhodanienne en Arkema Premi\u00e8re Ligue. Encore 5 buts inscrits, l\u00e0 ou Nantes et le PSG en avaient d\u00e9j\u00e0 encaiss\u00e9 6 chacun et m\u00eame 8 du c\u00f4t\u00e9 des promues lensoises. \u00c0 se demander qui pourra bien faire redescendre l\u2019OL Lyonnes de son nuage. Peut-\u00eatre Wolfsburg en Ligue des Champions mais l\u00e0 encore, les Lyonnaises sont invaincues lors des deux premi\u00e8res journ\u00e9es.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-feminine-2024-2025-j2-lol-lyonnes-double-la-mise-contre-sankt-polten\/\" class=\"vlp-link\" title=\"Ligue des Champions f\u00e9minine 2025\/2026 (J2) : L&#039;OL Lyonnes double la mise contre Sankt P\u00f6lten\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Ligue-des-Champions-feminine-20242025-J2-LOL-Lyonnes-double-la-mise-contre-Sankt-Polten.png\" class=\"attachment-800x445 size-800x445\" alt=\"Ligue des Champions f\u00e9minine 20242025 (J2) L&#039;OL Lyonnes double la mise contre Sankt P\u00f6lten\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Ligue-des-Champions-feminine-20242025-J2-LOL-Lyonnes-double-la-mise-contre-Sankt-Polten.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Ligue-des-Champions-feminine-20242025-J2-LOL-Lyonnes-double-la-mise-contre-Sankt-Polten-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Ligue-des-Champions-feminine-20242025-J2-LOL-Lyonnes-double-la-mise-contre-Sankt-Polten-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/10\/Ligue-des-Champions-feminine-20242025-J2-LOL-Lyonnes-double-la-mise-contre-Sankt-Polten-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Ligue des Champions f\u00e9minine 2025\/2026 (J2) : L'OL Lyonnes double la mise contre Sankt P\u00f6lten<\/div><div class=\"vlp-block-1 vlp-link-summary\">L'OL Lyonnes s\u2019impose 3-0 contre Sankt P\u00f6lten lors de la 2\u00e8me journ\u00e9e.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2>Flops\u00a0: Une action de trop pour Marseille, le brouillard g\u00e2che la f\u00eate pour Strasbourg<\/h2>\n<p>En dehors de Lens, qui y a cru un temps avant de craquer en 2<sup>\u00e8me<\/sup> p\u00e9riode contre le Paris FC, les Marseillaises ont, elles, eu la victoire en main bien plus longtemps. Sur un coup franc de <strong>Laura Bourgouin<\/strong> venu nettoyer la lucarne, elles ont surpris les Dijonnaises, pourtant directrices des d\u00e9bats. Les joueuses de <strong>Maxime Di Liberto<\/strong> ne se sont pas d\u00e9moralis\u00e9es et ont continu\u00e9 de pousser. En vain\u2026 jusqu\u2019\u00e0 la derni\u00e8re minute du temps additionnel, la derni\u00e8re action du match. <strong>Kopinska<\/strong> a ainsi permis \u00e0 Dijon de rester dans le ventre mou du championnat tandis que l\u2019OM a perdu une belle opportunit\u00e9 de s\u2019\u00e9loigner de la zone de rel\u00e9gation. En attendant le duel entre Strasbourg et Saint-Etienne.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udc0b\ud835\udc14\ud835\udc02\ud835\udc00\ud835\udc11\ud835\udc0d\ud835\udc04 \ud835\udc0d\ud835\udc04\ud835\udc13\ud835\udc13\ud835\udc0e\ud835\udc18\ud835\udc04\u0301\ud835\udc04 \u2705<\/p>\n<p>Pr\u00e9cision et audace : \ud835\udc0b\ud835\udc1a\ud835\udc2e\ud835\udc2b\ud835\udc1a \ud835\udc1d\ud835\udc1e\u0301\ud835\udc1b\ud835\udc25\ud835\udc28\ud835\udc2a\ud835\udc2e\ud835\udc1e \ud835\udc2c\ud835\udc28\ud835\udc27 \ud835\udc1c\ud835\udc28\ud835\udc26\ud835\udc29\ud835\udc2d\ud835\udc1e\ud835\udc2e\ud835\udc2b \ud835\udc1b\ud835\udc2e\ud835\udc2d \ud835\udfd0\ud835\udfd3-\ud835\udfd0\ud835\udfd4 d\u2019une magnifique barre rentrante imparable \ud83d\ude0d\ud83d\udd25 <a href=\"https:\/\/t.co\/pt41MhV89x\">pic.twitter.com\/pt41MhV89x<\/a><\/p>\n<p>\u2014 Les Marseillaises (@OMfeminines) <a href=\"https:\/\/twitter.com\/OMfeminines\/status\/1987205043313918409?ref_src=twsrc%5Etfw\">November 8, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Dans le rouge actuellement, on ne d\u00e9loge plus Lens. Mais juste devant, Saint-Etienne n\u2019est pas \u00e0 l\u2019abri non plus. \u00c0 la seule diff\u00e9rence pr\u00e8s que l\u2019ASSE n\u2019a pas \u00e9t\u00e9 en mesure de finir son match \u00e0 Molsheim lors de cette 7<sup>\u00e8me<\/sup> journ\u00e9e. Peut-\u00eatre un mal pour un bien pour les Vertes. \u00c0 moins que ce ne soit pour Strasbourg. En t\u00eate d\u00e8s la 5<sup>\u00e8me<\/sup> minute, les Alsaciennes ont commenc\u00e9 \u00e0 d\u00e9chanter peu apr\u00e8s la demi-heure de jeu avec l\u2019exclusion de <strong>Nogueira<\/strong>. Elles ont souffert d\u00e9fensivement et ont logiquement subi les assauts verts. Puis le brouillard, trop pr\u00e9sent, est lui aussi venu jouer les trouble-f\u00eates. Dans l\u2019impossibilit\u00e9 de poursuivre le match, celui-ci a \u00e9t\u00e9 arr\u00eat\u00e9 et doit \u00eatre reprogramm\u00e9.<\/p>\n<div id=\"attachment_625084\" style=\"width: 2570px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-625084\" class=\"wp-image-625084 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-scaled.jpg\" alt=\"Le brouillard a eu raison du match entre Strasbourg et Saint-Etienne\" width=\"2560\" height=\"1706\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-scaled.jpg 2560w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-300x200.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-1024x683.jpg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-768x512.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-1536x1024.jpg 1536w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Le-brouillard-a-eu-raison-du-match-entre-Strasbourg-et-Saint-Etienne-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><p id=\"caption-attachment-625084\" class=\"wp-caption-text\">Le brouillard a eu raison du match entre Strasbourg et Saint-Etienne &#8211; Photo Icon Sport<\/p><\/div>\n<h2>Tous les r\u00e9sultats de la 7<sup>\u00e8me<\/sup> journ\u00e9e<\/h2>\n<p>Lens 1 \u2013 2 <strong>Paris FC<\/strong><\/p>\n<p>Montpellier 1 \u2013 5 <strong>Lyon<\/strong><\/p>\n<p>Dijon 1 \u2013 1 Marseille<\/p>\n<p><strong>Nantes<\/strong> 2 \u2013 1 Le Havre<\/p>\n<p><strong>Strasbourg<\/strong> 1 \u2013 0 Saint-Etienne (arr\u00eat\u00e9 \u00e0 la 35<sup>\u00e8me<\/sup>)<\/p>\n<p><strong>PSG<\/strong> 4 \u2013 0 Fleury<\/p>\n<p style=\"text-align: justify;\"><em>Plus d&rsquo;infos \u00e0 venir<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.<\/p>\n","protected":false},"author":18,"featured_media":625083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[41832,16878,457,1619],"class_list":["post-625080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-arkema-premiere-ligue","tag-breve","tag-saint-etienne","tag-strasbourg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"ARKEMA PREMI\u00c8RE LIGUE 2025\/2026 - Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"ARKEMA PREMI\u00c8RE LIGUE 2025\/2026 - Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T08:30:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Arkema Premi\u00e8re Ligue 2025\\\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e\",\"datePublished\":\"2025-11-11T08:30:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/\"},\"wordCount\":831,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png\",\"keywords\":[\"Arkema Premi\u00e8re Ligue\",\"br\u00e8ve\",\"Saint-Etienne\",\"Strasbourg\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/\",\"name\":\"Arkema Premi\u00e8re Ligue 2025\\\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png\",\"datePublished\":\"2025-11-11T08:30:22+00:00\",\"description\":\"ARKEMA PREMI\u00c8RE LIGUE 2025\\\/2026 - Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png\",\"width\":1200,\"height\":674,\"caption\":\"Arkema Premi\u00e8re Ligue 20252026 Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arkema Premi\u00e8re Ligue 2025\\\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e","description":"ARKEMA PREMI\u00c8RE LIGUE 2025\/2026 - Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e","og_description":"ARKEMA PREMI\u00c8RE LIGUE 2025\/2026 - Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.","og_url":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2025-11-11T08:30:22+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e","datePublished":"2025-11-11T08:30:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/"},"wordCount":831,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png","keywords":["Arkema Premi\u00e8re Ligue","br\u00e8ve","Saint-Etienne","Strasbourg"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/","name":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png","datePublished":"2025-11-11T08:30:22+00:00","description":"ARKEMA PREMI\u00c8RE LIGUE 2025\/2026 - Tandis que le PSG et le Paris FC luttent pour la deuxi\u00e8me place, Nantes se rapproche du top 4.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Arkema-Premiere-Ligue-20252026-Lyon-sur-un-nuage-le-brouillard-simpose-en-Alsace-les-tops-et-flops-de-la-7eme-journee.png","width":1200,"height":674,"caption":"Arkema Premi\u00e8re Ligue 20252026 Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/arkema-premiere-ligue-2025-2026-lyon-sur-un-nuage-le-brouillard-simpose-en-alsace-les-tops-et-flops-de-la-7eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Arkema Premi\u00e8re Ligue 2025\/2026 : Lyon sur un nuage, le brouillard s\u2019impose en Alsace, les tops et flops de la 7\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=625080"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625080\/revisions"}],"predecessor-version":[{"id":625088,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625080\/revisions\/625088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/625083"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=625080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=625080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=625080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}