{"id":625559,"date":"2026-06-05T09:35:21","date_gmt":"2026-06-05T07:35:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=625559&#038;preview=true&#038;preview_id=625559"},"modified":"2026-06-05T09:36:44","modified_gmt":"2026-06-05T07:36:44","slug":"transferts-rc-toulon-2026-recrues-departs-et-prolongations","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/","title":{"rendered":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TRANSFERTS RC TOULON &#8211; Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon pour la saison 2026-2027.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2014\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-top-14-2025-2026-mis-a-jour\/\">Classement Top 14 2025-2026 mis \u00e0 jour<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le principal dossier de Toulon en mati\u00e8re de transferts, c&rsquo;\u00e9tait la prolongation de son ma\u00eetre \u00e0 jouer, <strong>Baptiste Serin<\/strong>. On n&rsquo;imaginait pas le demi de m\u00eal\u00e9e international quitter la Rade, et il a confirm\u00e9 cet \u00e9tat de fait en prolongeant son contrat, tout comme sa doublure <strong>Ben White<\/strong>. Une bonne chose de faite pour le RCT.<\/p>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 arriv\u00e9es, <strong>Tom\u00e1s Albornoz<\/strong>, ouvreur international argentin, a d\u00e9j\u00e0 pris ses quartiers. Mais ce n&rsquo;est sans doute que le d\u00e9but, puisque apr\u00e8s avoir \u00e9chou\u00e9 dans le dossier <strong>Tommaso Menoncello<\/strong>, le RCT a ramen\u00e9<strong> Ga\u00ebl Fickou<\/strong> et <strong>Rabah Slimani<\/strong>, avec en prime l&rsquo;international \u00e9cossais <strong>Huw Jones<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le <strong>RC Toulon<\/strong> pr\u00e9pare activement la saison 2026-2027 avec un mercato qui promet d\u2019\u00eatre anim\u00e9 sur la Rade. Entre pistes \u00e9tudi\u00e9es pour renforcer l\u2019effectif, d\u00e9parts \u00e0 anticiper et prolongations majeures, le club varois travaille \u00e0 b\u00e2tir une \u00e9quipe ambitieuse. <strong>Retrouvez toutes les infos transferts du RCT<\/strong> : noms \u00e9voqu\u00e9s dans les coulisses, annonces officielles et rumeurs cr\u00e9dibles autour du club. Suivez \u00e9galement les joueurs susceptibles de prolonger leur aventure toulonnaise. Pour rester inform\u00e9 des mouvements du <strong>RC Toulon<\/strong> et ne manquer aucune actualit\u00e9 mercato, consultez notre mise \u00e0 jour d\u00e9di\u00e9e.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong>En gras : Officiel ou Certain<\/strong><\/span><br \/>\n<span style=\"font-size: 14px;\">En \u00e9criture normale : Rumeur ou Attendu<\/span><\/p>\n<p style=\"text-align: justify;\"><div class=\"su-table su-table-alternate\">\n<table style=\"height: x;width: 100%;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 840px;border-color: #e8e8e8;text-align: center;vertical-align: middle\" colspan=\"3\"><span style=\"font-size: 0.9em\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/cdn.lnr.fr\/club\/toulon\/photo\/logo.7d87d88b4bd187d9dd04023242f5ce1872dc43a1\" alt=\"RC Toulon\" width=\"100\" height=\"100\" \/><br \/>\nTOULON<br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 22px\">\n<td style=\"height: 23px;border-color: #e8e8e8;text-align: center;vertical-align: middle;width: 280px\"><span style=\"font-size: 0.9em\"><span style=\"color: #000000\"><strong><span style=\"color: #008000\">\u25bc<\/span><\/strong><\/span><strong><span style=\"color: #000000\">ARRIV\u00c9ES<\/span><\/strong><\/span><\/td>\n<td style=\"height: 23px;border-color: #e8e8e8;text-align: center;vertical-align: middle;width: 280px\"><span style=\"font-size: 0.9em\"><span style=\"color: #000000\"><strong><span style=\"color: #ff0000\">\u25b2<\/span><\/strong><\/span><strong><span style=\"color: #000000\">D\u00c9PARTS<\/span><\/strong><\/span><\/td>\n<td style=\"height: 23px;border-color: #e8e8e8;text-align: center;vertical-align: middle;width: 280px\"><span style=\"color: #000000;font-size: 0.9em\"><strong>\ud83d\udcddPROLONG. <\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 22px\">\n<td style=\"border-color: #e8e8e8;text-align: left;vertical-align: middle;height: 60px;width: 280px\"><span style=\"font-size: 0.9em\"><strong>&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-linternational-argentin-tomas-albornoz-signe-en-top-14\/\">Tom\u00e1s Albornoz<\/a> (Benetton)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/judicael-cancoriet-sen-va-le-troisieme-ligne-international-rejoint-un-cador-de-top-14\/\">Judica\u00ebl Cancoriet<\/a> (La Rochelle)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/le-centre-ecossais-huw-jones-signe-chez-un-cador-de-top-14\/\">Huw Jones<\/a> (Glasgow)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/surprise-rabah-slimani-va-faire-son-retour-chez-un-cador-de-top-14\/\">Rabah Slimani<\/a> (Leinster)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/surprise-junior-kpoku-change-de-club-avec-effet-immediat-en-top-14\/\">Junior Kpoku<\/a> (Racing, pr\u00eat, janvier 2026)<br \/>\n<\/strong><\/span><span style=\"font-size: 0.9em\"><strong>&#8211; <a title=\"C\u2019est officiel, la p\u00e9pite Luka Keletaona signe chez un cador de Top 14\" href=\"https:\/\/dicodusport.fr\/blog\/cest-officiel-la-pepite-luka-keletaona-signe-chez-un-cador-de-top-14\/\" rel=\"\">Luka Keletaona<\/a> (Brive)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tana-keletaona-rejoint-son-frere-chez-un-cador-du-top-14\/\">Tana Keleteona<\/a> (Brive)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/surprise-gael-fickou-signe-dans-lun-de-ses-anciens-clubs\/\">Ga\u00ebl Fickou<\/a> (Racing 92)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/le-talentueux-fidjien-apete-narogo-signe-en-top-14\/\">Apete Narogo<\/a> (Fidji, rugby \u00e0 7)<\/strong><\/span><\/td>\n<td style=\"border-color: #e8e8e8;text-align: left;vertical-align: middle;height: 60px;width: 280px\"><span style=\"font-size: 0.9em\"><strong>&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/brian-alainuuese-a-tranche-pour-son-avenir-le-2eme-ligne-de-toulon-va-rejoindre-un-cador-de-top-14\/\">Brian Alainu&rsquo;uese<\/a> (Bayonne)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-enzo-herve-quitte-toulon-pour-un-autre-club-de-top-14\/\">Enzo Herv\u00e9<\/a> (Castres, septembre 2025)<br \/>\n&#8211; Daniel Brennan (Montauban)<br \/>\n&#8211; Giorgi Javakhia (SA XV)<br \/>\n&#8211; Ma&rsquo;a Nonu (retraite)<br \/>\n<\/strong>&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/le-futur-de-paolo-garbisi-en-question-a-toulon\/\">Paolo Garbisi<\/a> (Montpellier, Perpignan)<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/gabin-villiere-cible-par-un-cador-du-top-14-le-dossier-saccelere\/\">Gabin Villi\u00e8re<\/a> (La Rochelle)<br \/>\n<\/span><\/td>\n<td style=\"text-align: left;border-color: #e8e8e8;vertical-align: middle;height: 60px;width: 280px\"><strong><span style=\"font-size: 0.9em\">&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-toulon-a-tranche-pour-lavenir-de-baptiste-serin-et-ben-white\/\">Baptiste Serin<\/a> \u2192 2028<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-toulon-a-tranche-pour-lavenir-de-baptiste-serin-et-ben-white\/\">Ben White<\/a> \u2192 2028<br \/>\n&#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tout-juste-de-retour-sur-les-terrains-gianmarco-lucchesi-a-tranche-pour-son-avenir\/\">Gianmarco Lucchesi<\/a> \u2192 2028<br \/>\n&#8211; Corentin Mezou \u2192 2028<br \/>\n&#8211; Junior Kpoku \u2192 2028<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify\"><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>PS : Si certains transferts et\/ou certaines prolongations sont oubli\u00e9s dans ce tableau, n&rsquo;h\u00e9sitez pas \u00e0 nous les signaler, merci !<\/strong><\/em><\/span><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/qui-sont-les-joueurs-les-mieux-payes-du-top-14-decouvrez-les-salaires-des-stars-du-championnat\/\" class=\"vlp-link\" title=\"Qui sont les joueurs les mieux pay\u00e9s du Top 14 ? D\u00e9couvrez les salaires des stars du championnat\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-joueurs-les-mieux-payes-du-Top-14-Decouvrez-les-salaires-des-stars-du-championnat.png\" class=\"attachment-800x445 size-800x445\" alt=\"Qui sont les joueurs les mieux pay\u00e9s du Top 14 D\u00e9couvrez les salaires des stars du championnat\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-joueurs-les-mieux-payes-du-Top-14-Decouvrez-les-salaires-des-stars-du-championnat.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-joueurs-les-mieux-payes-du-Top-14-Decouvrez-les-salaires-des-stars-du-championnat-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-joueurs-les-mieux-payes-du-Top-14-Decouvrez-les-salaires-des-stars-du-championnat-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/09\/Qui-sont-les-joueurs-les-mieux-payes-du-Top-14-Decouvrez-les-salaires-des-stars-du-championnat-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Qui sont les joueurs les mieux pay\u00e9s du Top 14 ? D\u00e9couvrez les salaires des stars du championnat<\/div><div class=\"vlp-block-1 vlp-link-summary\">On fait le point sur les joueurs les mieux pay\u00e9s du championnat.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arriv\u00e9es, d\u00e9parts et prolongations au RC Toulon.<\/p>\n","protected":false},"author":59,"featured_media":626608,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[7974,3078,111,30870,29105,7945],"class_list":["post-625559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-mercato-top-14","tag-rc-toulon","tag-top-14","tag-transferts-rc-toulon","tag-transferts-rugby","tag-transferts-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RC TOULON - Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RC TOULON - Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-05T07:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T07:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations\",\"datePublished\":\"2026-06-05T07:35:21+00:00\",\"dateModified\":\"2026-06-05T07:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/\"},\"wordCount\":476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png\",\"keywords\":[\"Mercato Top 14\",\"RC Toulon\",\"Top 14\",\"Transferts RC Toulon\",\"Transferts rugby\",\"Transferts Top 14\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/\",\"name\":\"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png\",\"datePublished\":\"2026-06-05T07:35:21+00:00\",\"dateModified\":\"2026-06-05T07:36:44+00:00\",\"description\":\"TRANSFERTS RC TOULON - Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts RC Toulon 2026 Recrues, d\u00e9parts et prolongations\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations","description":"TRANSFERTS RC TOULON - Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations","og_description":"TRANSFERTS RC TOULON - Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-06-05T07:35:21+00:00","article_modified_time":"2026-06-05T07:36:44+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations","datePublished":"2026-06-05T07:35:21+00:00","dateModified":"2026-06-05T07:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/"},"wordCount":476,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png","keywords":["Mercato Top 14","RC Toulon","Top 14","Transferts RC Toulon","Transferts rugby","Transferts Top 14"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/","name":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png","datePublished":"2026-06-05T07:35:21+00:00","dateModified":"2026-06-05T07:36:44+00:00","description":"TRANSFERTS RC TOULON - Arriv\u00e9es, d\u00e9parts, prolongations, rumeurs : retrouvez toutes les informations transferts du RC Toulon.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Transferts-RC-Toulon-2026-Recrues-departs-et-prolongations.png","width":1200,"height":674,"caption":"Transferts RC Toulon 2026 Recrues, d\u00e9parts et prolongations"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rc-toulon-2026-recrues-departs-et-prolongations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts RC Toulon 2026 : Recrues, d\u00e9parts et prolongations"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=625559"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625559\/revisions"}],"predecessor-version":[{"id":676054,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/625559\/revisions\/676054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/626608"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=625559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=625559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=625559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}