{"id":626330,"date":"2025-11-23T10:55:23","date_gmt":"2025-11-23T09:55:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=626330&#038;preview=true&#038;preview_id=626330"},"modified":"2025-11-23T14:43:13","modified_gmt":"2025-11-23T13:43:13","slug":"f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/","title":{"rendered":"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Le Grand Prix de Las Vegas 2025 de Formule 1 se d\u00e9roulera du 21 au 23 novembre sur le circuit urbain du m\u00eame nom. Vingt-deuxi\u00e8me manche du championnat du monde de F1 2025, il intervient apr\u00e8s vingt-et-une courses d\u00e9j\u00e0 disput\u00e9es, ayant vu quatre vainqueurs diff\u00e9rents et r\u00e9cidivistes cette saison. Le classement reste ind\u00e9cis, notamment pour la premi\u00e8re place, tr\u00e8s disput\u00e9e entre les deux pilotes McLaren et Max Verstappen.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Retrouvez ici toutes les informations essentielles : programme complet, horaires des s\u00e9ances, diffusion TV, r\u00e9sultats en direct, ainsi qu\u2019un retour sur l\u2019histoire et les enjeux de cette course inscrite au calendrier 2025, saison qui touche bient\u00f4t \u00e0 sa fin.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/f1-2025-le-calendrier-complet\/\" target=\"_blank\" rel=\"noopener\">F1 2025 : le calendrier complet<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Histoire du Grand Prix de Las Vegas de Formule 1<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Grand Prix de Las Vegas<\/strong> est inscrit au calendrier pour la troisi\u00e8me fois avec ce trac\u00e9. Il avait fait deux apparitions dans le championnat de F1 en 1981 et 1982. Cette ann\u00e9e encore, un large show est organis\u00e9 autour de cette manche, l\u2019un des trois rendez-vous se d\u00e9roulant aux \u00c9tats-Unis durant la saison. Lors de la premi\u00e8re \u00e9dition moderne, c\u2019est <strong>Max Verstappen<\/strong> qui s\u2019\u00e9tait impos\u00e9, tandis que l\u2019\u00e9dition 2024 avait \u00e9t\u00e9 le th\u00e9\u00e2tre de son sacre mondial officiel malgr\u00e9 une 5e place. C\u2019est le Britannique <strong>George Russell<\/strong> (Mercedes) qui avait remport\u00e9 la course.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2024-max-verstappen-champion-du-monde-pour-la-quatrieme-fois-consecutive\/\" class=\"vlp-link\" title=\"F1 GP de Las Vegas 2024 : Max Verstappen champion du monde pour la quatri\u00e8me fois cons\u00e9cutive\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/F1-GP-de-Las-Vegas-2024-Max-Verstappen-champion-du-monde-pour-la-quatrieme-fois-consecutive-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"F1 GP de Las Vegas 2024 Max Verstappen champion du monde pour la quatri\u00e8me fois cons\u00e9cutive (1)\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/F1-GP-de-Las-Vegas-2024-Max-Verstappen-champion-du-monde-pour-la-quatrieme-fois-consecutive-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/F1-GP-de-Las-Vegas-2024-Max-Verstappen-champion-du-monde-pour-la-quatrieme-fois-consecutive-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/F1-GP-de-Las-Vegas-2024-Max-Verstappen-champion-du-monde-pour-la-quatrieme-fois-consecutive-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/11\/F1-GP-de-Las-Vegas-2024-Max-Verstappen-champion-du-monde-pour-la-quatrieme-fois-consecutive-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">F1 GP de Las Vegas 2024 : Max Verstappen champion du monde pour la quatri\u00e8me fois cons\u00e9cutive<\/div><div class=\"vlp-block-1 vlp-link-summary\">F1 GRAND PRIX DE LAS VEGAS 2024 \u2014 En terminant cinqui\u00e8me, Max Verstappen (Red Bull) remporte son quatri\u00e8me titre de champion du monde de F1.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les sp\u00e9cificit\u00e9s du circuit de Las Vegas<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Grand Prix de Las Vegas<\/strong> se d\u00e9roule sur un circuit urbain rapide, traversant des lieux embl\u00e9matiques tels que le Caesars Palace, le Bellagio ou encore le Venetian. Long de 6,201 km et compos\u00e9 de 17 virages, il comporte \u00e9galement deux zones de DRS. La course comptera 50 tours, soit environ 310 km. Une affluence massive est une nouvelle fois attendue dans les rues de Las Vegas.<\/p>\n<div id=\"attachment_437530\" style=\"width: 1004px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-437530\" class=\"wp-image-437530 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Capture-decran-2023-11-16-000340.png\" alt=\"F1 - Circuit de Las Vegas\" width=\"994\" height=\"592\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Capture-decran-2023-11-16-000340.png 994w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Capture-decran-2023-11-16-000340-300x179.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Capture-decran-2023-11-16-000340-768x457.png 768w\" sizes=\"auto, (max-width: 994px) 100vw, 994px\" \/><p id=\"caption-attachment-437530\" class=\"wp-caption-text\">F1 &#8211; Circuit de Las Vegas<\/p><\/div>\n<h2 style=\"text-align: justify;\">Pneus et m\u00e9t\u00e9o du Grand Prix de Las Vegas 2025<\/h2>\n<p style=\"text-align: justify;\">Pour le <strong>Grand Prix de Las Vegas 2025<\/strong>, l\u2019\u00e9quipementier <strong>Pirelli<\/strong> a d\u00e9voil\u00e9 une s\u00e9lection de gommes tendres avec les compos\u00e9s <strong>C5<\/strong>, <strong>C4<\/strong> et <strong>C3<\/strong> (du plus tendre au plus dur). En conditions s\u00e8ches, ces pneus offriront un bon compromis entre performance et durabilit\u00e9. En cas de pluie, les \u00e9quipes disposeront des pneumatiques <strong>interm\u00e9diaires<\/strong> (verts) et <strong>pluie extr\u00eame<\/strong> (bleus), indispensables sur piste d\u00e9tremp\u00e9e.<\/p>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 m\u00e9t\u00e9o, les pr\u00e9visions annoncent un week-end perturb\u00e9 \u00e0 <strong>Las Vegas<\/strong> : froid, nuages et pluie sont attendus, \u00e0 l\u2019exception du dimanche. Les temp\u00e9ratures oscilleront entre 10 et 16 \u00b0C.<\/p>\n<p style=\"text-align: justify;\">Autant dire que la gestion des pneumatiques et l\u2019adaptation aux conditions climatiques seront d\u00e9terminantes dans ce <strong>Grand Prix de Las Vegas 2025<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Horaires et programme TV du Grand Prix de Las Vegas 2025 de F1<\/h2>\n<table style=\"width: 100%; border-collapse: collapse;\">\n<tbody>\n<tr>\n<td style=\"background-color: #c80502; width: 840px; text-align: center; vertical-align: middle;\" colspan=\"5\"><span style=\"color: #ffffff;\"><strong>VENDREDI 21 NOVEMBRE 2025<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Horaire<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%; background-color: #000000;\"><span style=\"color: #ffffff;\"><span style=\"font-size: 0.9em;\"><b>\u00c9preuve<\/b><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Meilleur temps<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Deuxi\u00e8me temps<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Troisi\u00e8me temps<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><strong>1H30 &#8211; 2H30<br \/>\n<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%;\"><strong>Essais libres 1<br \/>\n<a href=\"https:\/\/www.formula1.com\/en\/results\/2025\/races\/1274\/las-vegas\/practice\/1\"><span style=\"font-size: 12.8px;\"><i>R\u00e9sultats<\/i><\/span><\/a><\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/ferrari.png\" alt=\"Ferrari\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddf2\ud83c\udde8 CHARLES LECLERC<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">FERRARI<br \/>\n<strong><em>1:34.802<\/em><\/strong><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/williams.png\" alt=\"Williams\" width=\"101\" height=\"30\" \/><br \/>\n\ud83c\uddf9\ud83c\udded ALEXANDER ALBON<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">WILLIAMS<br \/>\n<strong><em>+0.166<\/em><\/strong><br \/>\n<\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/red-bull-racing.png\" alt=\"Red Bull Racing\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddef\ud83c\uddf5 YUKI TSUNODA<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">RED BULL<br \/>\n<strong><em>+0.269<\/em><\/strong><br \/>\n<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><strong>5h30 &#8211; 6h30<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%;\"><strong>Essais libres 2<br \/>\n<a href=\"https:\/\/www.formula1.com\/en\/results\/2025\/races\/1274\/las-vegas\/practice\/2\"><span style=\"font-size: 12.8px;\"><i>R\u00e9sultats<\/i><\/span><\/a><\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/mclaren.png\" alt=\"McLaren\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddec\ud83c\udde7 LANDO NORRIS<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">MCLAREN<br \/>\n<strong><em>1:33.602<\/em><\/strong><br \/>\n<\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/mercedes.png\" alt=\"Mercedes\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddee\ud83c\uddf9 KIMI ANTONELLI<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">MERCEDES<br \/>\n<strong><em>+0.029<\/em><\/strong><br \/>\n<\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/ferrari.png\" alt=\"Ferrari\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddf2\ud83c\udde8 CHARLES LECLERC<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">FERRARI<br \/>\n<strong><em>+0.161<\/em><\/strong><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #c80502; width: 100.018%; vertical-align: middle; text-align: center;\" colspan=\"5\"><span style=\"color: #ffffff;\"><strong>SAMEDI 22 NOVEMBRE 2025<\/strong><\/span><span style=\"color: #ffffff;\"><strong><br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"text-align: justify;\">\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Horaire<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%; background-color: #000000;\"><span style=\"color: #ffffff;\"><span style=\"font-size: 0.9em;\"><b>\u00c9preuve<\/b><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Meilleur temps<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Deuxi\u00e8me temps<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Troisi\u00e8me temps<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"text-align: justify;\">\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><strong>1H30 &#8211; 2h30<br \/>\n<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%;\"><strong>Essais libres 3<br \/>\n<a href=\"https:\/\/www.formula1.com\/en\/results\/2025\/races\/1274\/las-vegas\/practice\/3\"><span style=\"font-size: 12.8px;\"><i>R\u00e9sultats<\/i><\/span><\/a><br \/>\n<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/mercedes.png\" alt=\"Mercedes\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddec\ud83c\udde7 GEORGE RUSSELL<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">MERCEDES<br \/>\n<strong><em>1:34.054<\/em><\/strong><br \/>\n<\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/red-bull-racing.png\" alt=\"Red Bull Racing\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddf3\ud83c\uddf1 MAX VERSTAPPEN<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">RED BULL<br \/>\n<strong><em>+0.227<\/em><\/strong><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/williams.png\" alt=\"Williams\" width=\"101\" height=\"30\" \/><br \/>\n\ud83c\uddf9\ud83c\udded ALEXANDER ALBON<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">WILLIAMS<br \/>\n<strong><em>+0.821<\/em><\/strong><\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><strong>5H00 &#8211; 6H00<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%;\"><strong>Qualifications<br \/>\n<span style=\"font-size: 12.8px;\"><i><a href=\"https:\/\/dicodusport.fr\/blog\/lando-norris-chante-sous-la-pluie-la-pole-position-pour-le-britannique-a-las-vegas\/\">R\u00e9sum\u00e9<\/a> &#8211; <a href=\"https:\/\/www.formula1.com\/en\/results\/2025\/races\/1274\/las-vegas\/qualifying\">R\u00e9sultats<\/a><\/i><\/span><br \/>\n<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/mclaren.png\" alt=\"McLaren\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddec\ud83c\udde7 LANDO NORRIS<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">MCLAREN<br \/>\n<strong><em>1:47.934<\/em><\/strong><br \/>\n<\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/red-bull-racing.png\" alt=\"Red Bull Racing\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddf3\ud83c\uddf1 MAX VERSTAPPEN<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">RED BULL<br \/>\n<strong><em>+0.323<\/em><\/strong><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/williams.png\" alt=\"Williams\" width=\"101\" height=\"30\" \/><br \/>\n<span style=\"font-size: 1.0em;\">\ud83c\uddea\ud83c\uddf8<\/span> CARLOS SAINZ JR.<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">WILLIAMS<br \/>\n<strong><em>+0.362<\/em><\/strong><\/span><\/span><\/td>\n<\/tr>\n<tr style=\"text-align: justify;\">\n<td style=\"background-color: #c80502; width: 100.018%; text-align: center; vertical-align: middle;\" colspan=\"5\"><span style=\"color: #ffffff;\"><strong>DIMANCHE 23 NOVEMBRE 2025<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"text-align: justify;\">\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Horaire<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%; background-color: #000000;\"><span style=\"color: #ffffff;\"><span style=\"font-size: 0.9em;\"><b>\u00c9preuve<\/b><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Premier<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Deuxi\u00e8me<\/strong><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%; background-color: #000000;\"><span style=\"color: #ffffff; font-size: 0.9em;\"><strong>Troisi\u00e8me<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"text-align: justify;\">\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><strong>5H00<br \/>\n<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20.0176%;\"><strong>Course<br \/>\n<span style=\"font-size: 12.8px;\"><i><a href=\"https:\/\/dicodusport.fr\/blog\/max-verstappen-maintient-le-suspense-le-neerlandais-devance-lando-norris-a-las-vegas\/\">R\u00e9sum\u00e9<\/a> &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/f1-classement-et-resultats-du-grand-prix-de-las-vegas-2025\/\">Classement<\/a><\/i><\/span><br \/>\n<\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/red-bull-racing.png\" alt=\"Red Bull Racing\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddf3\ud83c\uddf1 MAX VERSTAPPEN<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">RED BULL<br \/>\n<strong><em>1:21:08.429<\/em><\/strong><\/span><\/span><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/mercedes.png\" alt=\"Mercedes\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddec\ud83c\udde7 GEORGE RUSSELL<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">MERCEDES<br \/>\n<\/span><\/span><strong style=\"font-size: 0.8em; font-family: inherit;\"><em>+23.546<\/em><\/strong><\/td>\n<td style=\"text-align: center; vertical-align: middle; width: 20%;\"><span style=\"font-size: 0.9em;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.formula1.com\/d_team_car_fallback_image.png\/content\/dam\/fom-website\/teams\/2025\/mercedes.png\" alt=\"Mercedes\" width=\"100\" height=\"30\" \/><br \/>\n\ud83c\uddee\ud83c\uddf9 KIMI ANTONELLI<br \/>\n<\/strong><span style=\"font-size: 0.8em;\">MERCEDES<br \/>\n<strong><em>+30.488<\/em><\/strong><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\">La course au titre<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Grand Prix de Las Vegas 2025<\/strong> constitue la vingt-deuxi\u00e8me manche du <strong>Championnat du monde de Formule 1<\/strong>. Cette saison, le quadruple champion en titre <strong>Max Verstappen<\/strong> conna\u00eet davantage de difficult\u00e9s que par le pass\u00e9, bien qu\u2019il ait d\u00e9j\u00e0 remport\u00e9 cinq Grands Prix, dont le dernier \u00e0 Austin. Il reste toutefois proche du duo de t\u00eate au classement, avec 49 points de retard sur le leader et 25 sur le deuxi\u00e8me.<\/p>\n<p style=\"text-align: justify;\">La v\u00e9ritable surprise de l\u2019ann\u00e9e vient de <strong>McLaren<\/strong>, revenue au premier plan gr\u00e2ce \u00e0 son duo impressionnant. <strong>Oscar Piastri<\/strong>, pour sa troisi\u00e8me saison en Formule 1, compte d\u00e9j\u00e0 sept victoires. Son co\u00e9quipier <strong>Lando Norris<\/strong> affiche le m\u00eame total de succ\u00e8s, dont le dernier au Br\u00e9sil. Les deux pilotes en orange dominent le championnat, s\u00e9par\u00e9s par seulement 24 points, \u00e0 l\u2019avantage du Britannique. Apr\u00e8s Las Vegas, il ne restera plus que deux manches pour faire la diff\u00e9rence.<\/p>\n<h2 style=\"text-align: justify;\">Les autres enjeux du Grand Prix de Las Vegas<\/h2>\n<p style=\"text-align: justify;\">Derri\u00e8re ce duel <strong>McLaren<\/strong> \u2013 <strong>Red Bull<\/strong>, <strong>Mercedes<\/strong> et <strong>Ferrari<\/strong> tentent de bousculer la hi\u00e9rarchie. Les deux \u00e9quipes montent r\u00e9guli\u00e8rement sur le podium, mais peinent \u00e0 transformer leurs performances en victoires. Le <em>midfield<\/em> reste tr\u00e8s anim\u00e9 avec <strong>Williams<\/strong>, <strong>Aston Martin<\/strong>, <strong>Kick Sauber<\/strong> et <strong>Racing Bulls<\/strong>. Au classement pilotes, seulement 15 points s\u00e9parent <strong>Nico H\u00fclkenberg<\/strong> (Kick Sauber), 9<sup>e<\/sup>, de <strong>Yuki Tsunoda<\/strong> (Red Bull), 17<sup>e<\/sup>. Autrement dit, il est possible de grimper rapidement en marquant seulement quelques points.<\/p>\n<p style=\"text-align: justify;\">Le rookie fran\u00e7ais <strong>Isack Hadjar<\/strong> a impressionn\u00e9 cette ann\u00e9e, en marquant r\u00e9guli\u00e8rement et m\u00eame en d\u00e9crochant un podium \u00e0 Zandvoort. <strong>Esteban Ocon<\/strong> se bat avec <strong>Haas<\/strong>, qu\u2019il a rejoint cette saison, tandis que <strong>Carlos Sainz Jr.<\/strong> se relance chez <strong>Williams<\/strong> et que <strong>Lewis Hamilton<\/strong> poursuit son aventure chez <strong>Ferrari<\/strong> dans une campagne marqu\u00e9e par de nombreux mouvements.<\/p>\n<p style=\"text-align: justify;\">La France est d\u2019ailleurs bien repr\u00e9sent\u00e9e avec trois Tricolores en piste : <strong>Isack Hadjar<\/strong>, <strong>Esteban Ocon<\/strong> et <strong>Pierre Gasly<\/strong> chez <strong>Alpine<\/strong>. En toile de fond, la <em>Silly Season 2025<\/em> a anim\u00e9 le march\u00e9 des transferts : on conna\u00eet d\u00e9sormais la plupart des pilotes engag\u00e9s pour 2026, notamment avec <a href=\"https:\/\/dicodusport.fr\/blog\/f1-lequipe-cadillac-peut-elle-briller-des-2026\/\" target=\"_blank\" rel=\"noopener\">l\u2019arriv\u00e9e tr\u00e8s attendue de <strong>Cadillac<\/strong> en Formule 1<\/a>. Il ne manque plus qu\u2019une d\u00e9cision d\u2019importance : celle du futur co\u00e9quipier de <strong>Max Verstappen<\/strong> chez <strong>Red Bull<\/strong>\u2026<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/championnat-du-monde-f1-2025-classement-des-pilotes-mis-a-jour\/\">F1 2025 \u2013 Classement Championnat du monde des pilotes<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/championnat-du-monde-f1-2025-classement-des-constructeurs\/\">F1 2025 \u2013 Classement Championnat du monde des constructeurs<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.<\/p>\n","protected":false},"author":54,"featured_media":626523,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44295,8653],"tags":[16878,3166,35919,2065,35920],"class_list":["post-626330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-formule-1","tag-breve","tag-f1","tag-f1-las-vegas","tag-formule-1","tag-grand-prix-de-las-vegas-f1"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets<\/title>\n<meta name=\"description\" content=\"Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/roxane.lecacher\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-23T09:55:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-23T13:43:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roxane Lecacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/\"},\"author\":{\"name\":\"Roxane Lecacher\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/819fb2545dd2715bd7c0580d6d4b411a\"},\"headline\":\"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets\",\"datePublished\":\"2025-11-23T09:55:23+00:00\",\"dateModified\":\"2025-11-23T13:43:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/\"},\"wordCount\":1103,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png\",\"keywords\":[\"br\u00e8ve\",\"F1\",\"F1 Las Vegas\",\"Formule 1\",\"Grand Prix de Las Vegas F1\"],\"articleSection\":[\"Cha\u00eene TV\",\"Formule 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/\",\"name\":\"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png\",\"datePublished\":\"2025-11-23T09:55:23+00:00\",\"dateModified\":\"2025-11-23T13:43:13+00:00\",\"description\":\"Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png\",\"width\":1200,\"height\":674,\"caption\":\"F1 GP de Las Vegas 2025 Horaires, Programme TV et R\u00e9sultats \u00e0 jour\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/819fb2545dd2715bd7c0580d6d4b411a\",\"name\":\"Roxane Lecacher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Roxane-Lecacher-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Roxane-Lecacher-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Roxane-Lecacher-150x150.jpg\",\"caption\":\"Roxane Lecacher\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/roxane.lecacher\",\"https:\\\/\\\/fr.linkedin.com\\\/in\\\/roxane-lecacher-23368313b\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/roxanel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets","description":"Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/","og_locale":"fr_FR","og_type":"article","og_title":"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets","og_description":"Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.","og_url":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/roxane.lecacher","article_published_time":"2025-11-23T09:55:23+00:00","article_modified_time":"2025-11-23T13:43:13+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png","type":"image\/png"}],"author":"Roxane Lecacher","twitter_card":"summary_large_image","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/"},"author":{"name":"Roxane Lecacher","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a"},"headline":"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets","datePublished":"2025-11-23T09:55:23+00:00","dateModified":"2025-11-23T13:43:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/"},"wordCount":1103,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png","keywords":["br\u00e8ve","F1","F1 Las Vegas","Formule 1","Grand Prix de Las Vegas F1"],"articleSection":["Cha\u00eene TV","Formule 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/","url":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/","name":"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png","datePublished":"2025-11-23T09:55:23+00:00","dateModified":"2025-11-23T13:43:13+00:00","description":"Retrouvez le programme, les informations sur la diffusion TV, les horaires et les r\u00e9sultats du Grand Prix de Las Vegas 2025 de F1.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/F1-GP-de-Las-Vegas-2025-Horaires-Programme-TV-et-Resultats-a-jour.png","width":1200,"height":674,"caption":"F1 GP de Las Vegas 2025 Horaires, Programme TV et R\u00e9sultats \u00e0 jour"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/f1-gp-de-las-vegas-2025-horaires-programme-tv-et-resultats-a-jour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"F1 GP de Las Vegas 2025 : Les r\u00e9sultats complets"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a","name":"Roxane Lecacher","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","caption":"Roxane Lecacher"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.","sameAs":["https:\/\/www.facebook.com\/roxane.lecacher","https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b"],"url":"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/626330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=626330"}],"version-history":[{"count":7,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/626330\/revisions"}],"predecessor-version":[{"id":627510,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/626330\/revisions\/627510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/626523"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=626330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=626330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=626330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}