{"id":626533,"date":"2025-11-19T22:08:02","date_gmt":"2025-11-19T21:08:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=626533&#038;preview=true&#038;preview_id=626533"},"modified":"2025-11-19T22:14:24","modified_gmt":"2025-11-19T21:14:24","slug":"euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/","title":{"rendered":"EuroLigue 2025\/2026 (J12) : Monaco s&rsquo;impose face \u00e0 l\u2019ASVEL dans un match sans saveur"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-euroligue-masculine-2025-2026\/\">Calendrier et r\u00e9sultats EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Match 100 % fran\u00e7ais ce soir \u00e0 l\u2019Astroballe, o\u00f9 <strong>l\u2019ASVEL<\/strong> recevait la Roca Team de <strong>Monaco<\/strong> pour le compte de la 12<sup>e<\/sup> journ\u00e9e d\u2019<strong>EuroLigue<\/strong>. Une affiche tricolore entre deux \u00e9quipes qui n&rsquo;ont pas les m\u00eames objectifs.<\/p>\n<h2 style=\"text-align: justify;\">Une adresse catastrophique des deux c\u00f4t\u00e9s<\/h2>\n<p style=\"text-align: justify;\" data-start=\"188\" data-end=\"639\">Le premier quart-temps est terrible offensivement pour les deux \u00e9quipes. L\u2019adresse, d\u00e9j\u00e0 fragile \u00e0 longue distance, est tout aussi compliqu\u00e9e \u00e0 mi-distance, et ce malgr\u00e9 des d\u00e9fenses qui ne se montrent pas particuli\u00e8rement agressives. <strong>L\u2019ASVEL<\/strong> prend les devants dans les premi\u00e8res minutes, mais <strong>Monaco<\/strong> finit par passer devant pour boucler ces dix premi\u00e8res minutes sur un maigre 14-11, t\u00e9moin d\u2019un d\u00e9but de match extr\u00eamement pauvre offensivement.<\/p>\n<p style=\"text-align: justify;\" data-start=\"641\" data-end=\"1090\">Le deuxi\u00e8me quart-temps est encore plus compliqu\u00e9 pour les <strong>Villeurbannais<\/strong> : 0\/9 \u00e0 trois points, \u00e0 peine 17,65 % de r\u00e9ussite globale, et aucune v\u00e9ritable \u00e9tincelle pour sortir de ce faux rythme. En face, <strong>Monaco<\/strong> n\u2019est pas beaucoup plus inspir\u00e9. Ni <strong>Mike James<\/strong>, ni <strong>Alpha Diallo<\/strong>, ni aucun autre joueur ne parvient \u00e0 r\u00e9ellement lancer la machine. Mais la Roca Team reste malgr\u00e9 tout plus propre et convertit suffisamment de tirs pour garder la main.<\/p>\n<p data-start=\"1092\" data-end=\"1288\">R\u00e9sultat \u00e0 la mi-temps : un score fam\u00e9lique de <strong data-start=\"1137\" data-end=\"1158\">31-24 pour Monaco<\/strong>, dans une rencontre o\u00f9 l\u2019on esp\u00e8re voir les deux \u00e9quipes ressortir des vestiaires avec davantage d\u2019id\u00e9es, et surtout d\u2019adresse.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-euroligue-masculine-2025-2026\/\">Classement actualis\u00e9 EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\" data-start=\"1092\" data-end=\"1288\">Une seconde mi-temps \u00e0 sens unique en faveur de Monaco<\/h2>\n<p style=\"text-align: justify;\" data-start=\"202\" data-end=\"596\">La Roca Team revient des vestiaires avec beaucoup plus d\u2019agressivit\u00e9. Sans prendre \u00e9norm\u00e9ment de tirs, <strong>Monaco<\/strong> provoque davantage de contacts, obtient des fautes et impose enfin un rythme coh\u00e9rent offensivement. En face, l\u2019ASVEL reste totalement sans solution. L\u2019attaque villeurbannaise est toujours sans id\u00e9e, accumule les possessions st\u00e9riles et se heurte \u00e0 une d\u00e9fense mon\u00e9gasque solide.<\/p>\n<p style=\"text-align: justify;\" data-start=\"598\" data-end=\"935\">La statistique est terrible : dans un match pourtant loin d\u2019\u00eatre une d\u00e9monstration offensive, les cinq meilleurs marqueurs \u00e0 la fin du troisi\u00e8me quart-temps sont mon\u00e9gasques. Apr\u00e8s quatre minutes de jeu dans ce troisi\u00e8me acte, seulement neuf points ont \u00e9t\u00e9 inscrits, dont deux par <strong data-start=\"875\" data-end=\"895\">l\u2019ASVEL<\/strong>. \u00c0 domicile, difficile de faire pire. Le match se d\u00e9bloque l\u00e9g\u00e8rement en fin de quart-temps, les deux \u00e9quipes retrouvant un semblant d\u2019adresse. Statistique marquante : il faudra attendre la 18<sup>e<\/sup> tentative \u00e0 trois points pour voir enfin rentrer le premier tir longue distance de <strong>l\u2019ASVEL<\/strong>, instant c\u00e9l\u00e9br\u00e9 par un \u00ab Alleluia \u00bb comique lanc\u00e9 par la r\u00e9gie. 64-40 pour <strong data-start=\"1272\" data-end=\"1293\">Monaco<\/strong> avant les dix derni\u00e8res minutes.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1330\" data-end=\"1528\">Le dernier quart-temps reprend le fil du premier : une succession de tirs forc\u00e9s, un rythme inexistant, et une <strong>ASVEL<\/strong> totalement d\u00e9pass\u00e9e, tandis que le coach mon\u00e9gasque fait tourner son effectif. Au terme d\u2019un match pauvre offensivement et tr\u00e8s loin des standards de l\u2019EuroLigue, Monaco s\u2019impose 82-54, dans une rencontre qui ne fera clairement pas office de vitrine pour le basket fran\u00e7ais.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">A RECORD win for <a href=\"https:\/\/twitter.com\/ASMonaco_Basket?ref_src=twsrc%5Etfw\">@ASMonaco_Basket<\/a>, highest margin of victory in the league since they joined! <a href=\"https:\/\/twitter.com\/hashtag\/RivalrySeries?src=hash&amp;ref_src=twsrc%5Etfw\">#RivalrySeries<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/EveryGameMatters?src=hash&amp;ref_src=twsrc%5Etfw\">#EveryGameMatters<\/a> <a href=\"https:\/\/t.co\/cDRQiT0n9S\">pic.twitter.com\/cDRQiT0n9S<\/a><\/p>\n<p>\u2014 EuroLeague (@EuroLeague) <a href=\"https:\/\/twitter.com\/EuroLeague\/status\/1991250934266048898?ref_src=twsrc%5Etfw\">November 19, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.<\/p>\n","protected":false},"author":111,"featured_media":626663,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[16232,7864,16878,181,24],"class_list":["post-626533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-as-monaco-basket","tag-asvel","tag-breve","tag-euroligue","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroLigue 2025\/2026 (J12) : Monaco s&#039;impose face \u00e0 l\u2019ASVEL dans un match sans saveur<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue 2025\/2026 (J12) : Monaco s&#039;impose face \u00e0 l\u2019ASVEL dans un match sans saveur\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T21:08:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T21:14:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Derambure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue 2025\/2026 (J12) : Monaco s&#039;impose face \u00e0 l\u2019ASVEL dans un match sans saveur\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\"},\"author\":{\"name\":\"L\u00e9o Derambure\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\"},\"headline\":\"EuroLigue 2025\/2026 (J12) : Monaco s&rsquo;impose face \u00e0 l\u2019ASVEL dans un match sans saveur\",\"datePublished\":\"2025-11-19T21:08:02+00:00\",\"dateModified\":\"2025-11-19T21:14:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png\",\"keywords\":[\"as monaco basket\",\"ASVEL\",\"br\u00e8ve\",\"Euroligue\",\"sport\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\",\"name\":\"EuroLigue 2025\/2026 (J12) : Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png\",\"datePublished\":\"2025-11-19T21:08:02+00:00\",\"dateModified\":\"2025-11-19T21:14:24+00:00\",\"description\":\"EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png\",\"width\":1200,\"height\":674,\"caption\":\"EuroLigue 20252026 (J12) Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue 2025\/2026 (J12) : Monaco s&rsquo;impose face \u00e0 l\u2019ASVEL dans un match sans saveur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295\",\"name\":\"L\u00e9o Derambure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png\",\"caption\":\"L\u00e9o Derambure\"},\"description\":\"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.\",\"worksFor\":\"L\u00e9o Derambure\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue 2025\/2026 (J12) : Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur","description":"EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue 2025\/2026 (J12) : Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur","og_description":"EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-11-19T21:08:02+00:00","article_modified_time":"2025-11-19T21:14:24+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png","type":"image\/png"}],"author":"L\u00e9o Derambure","twitter_card":"summary_large_image","twitter_title":"EuroLigue 2025\/2026 (J12) : Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/"},"author":{"name":"L\u00e9o Derambure","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295"},"headline":"EuroLigue 2025\/2026 (J12) : Monaco s&rsquo;impose face \u00e0 l\u2019ASVEL dans un match sans saveur","datePublished":"2025-11-19T21:08:02+00:00","dateModified":"2025-11-19T21:14:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png","keywords":["as monaco basket","ASVEL","br\u00e8ve","Euroligue","sport"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/","name":"EuroLigue 2025\/2026 (J12) : Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png","datePublished":"2025-11-19T21:08:02+00:00","dateModified":"2025-11-19T21:14:24+00:00","description":"EUROLIGUE 2025-2026 \u2013 Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png","width":1200,"height":674,"caption":"EuroLigue 20252026 (J12) Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue 2025\/2026 (J12) : Monaco s&rsquo;impose face \u00e0 l\u2019ASVEL dans un match sans saveur"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/93f03e222ed8da203c940d17ef257295","name":"L\u00e9o Derambure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/02\/Maillot-Dicodusport-Lele-150x150.png","caption":"L\u00e9o Derambure"},"description":"Passionn\u00e9 de sport depuis l\u2019enfance, j\u2019ai grandi au rythme des grands \u00e9v\u00e9nements comme les Jeux Olympiques, les championnats du monde d\u2019athl\u00e9tisme et de natation, ou encore le Tour de France sur France T\u00e9l\u00e9visions. Abonn\u00e9 au RC Lens depuis 2008, cette ferveur m\u2019a \u00e9t\u00e9 transmise d\u00e8s l\u2019\u00e2ge de 5 ans par mon grand-p\u00e8re et mon p\u00e8re. Avec Rafael Nadal ou encore Aruna Dindane comme idole, j\u2019ai toujours ressenti l\u2019envie de partager cette passion \u00e0 travers l\u2019\u00e9criture. Apr\u00e8s les Jeux Olympiques de Paris 2024, j\u2019ai franchi le pas en rejoignant l\u2019\u00e9quipe de r\u00e9daction de Dicodusport. Aujourd\u2019hui, je couvre le biathlon, le ski alpin ainsi que les rencontres des clubs fran\u00e7ais en comp\u00e9titions europ\u00e9ennes, avec l'envie de faire vivre chaque instant sportif et de transmettre ces \u00e9motions au lecteur, comme s\u2019il \u00e9tait au c\u0153ur de l\u2019\u00e9v\u00e9nement.","worksFor":"L\u00e9o Derambure","url":"https:\/\/dicodusport.fr\/blog\/author\/leo-derambure\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/626533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=626533"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/626533\/revisions"}],"predecessor-version":[{"id":626670,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/626533\/revisions\/626670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/626663"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=626533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=626533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=626533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}