{"id":628053,"date":"2025-11-26T21:31:31","date_gmt":"2025-11-26T20:31:31","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=628053&#038;preview=true&#038;preview_id=628053"},"modified":"2025-11-26T21:31:31","modified_gmt":"2025-11-26T20:31:31","slug":"monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/","title":{"rendered":"Monaco facile contre l&rsquo;Anadolu : la Roca Team se replace en EuroLigue"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EUROLIGUE 2025-2026 &#8211; \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l&rsquo;Anadolu \u00e0 Gaston-M\u00e9decin.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-euroligue-masculine-2025-2026\/\">Calendrier et r\u00e9sultats EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\" data-start=\"1092\" data-end=\"1288\">La semaine derni\u00e8re, <strong>Monaco<\/strong> avait remport\u00e9 le choc franco-fran\u00e7ais d&rsquo;EuroLigue contre l&rsquo;ASVEL, se repla\u00e7ant au classement. Mais la Roca Team avait besoin de plus de victoires pour s&rsquo;installer pour de bon dans le haut du classement. \u00c0 commencer par ce soir, lors de la visite d&rsquo;un poids lourd, l&rsquo;Anadolu, \u00e0 Gaston-M\u00e9decin.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/euroligue-2025-2026-j12-monaco-simpose-face-a-lasvel-dans-un-match-sans-saveur\/\" class=\"vlp-link\" title=\"EuroLigue 2025\/2026 (J12) : Monaco s&#039;impose face \u00e0 l\u2019ASVEL dans un match sans saveur\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png\" class=\"attachment-800x445 size-800x445\" alt=\"EuroLigue 20252026 (J12) Monaco s&#039;impose face \u00e0 l\u2019ASVEL dans un match sans saveur\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/EuroLigue-20252026-J12-Monaco-simpose-face-a-lASVEL-dans-un-match-sans-saveur-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">EuroLigue 2025\/2026 (J12) : Monaco s'impose face \u00e0 l\u2019ASVEL dans un match sans saveur<\/div><div class=\"vlp-block-1 vlp-link-summary\">Dans une rencontre pauvre offensivement et disput\u00e9e sur un faux rythme, Monaco s\u2019impose largement face \u00e0 l\u2019ASVEL, 84-52.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\" data-start=\"1092\" data-end=\"1288\">Monaco bien sup\u00e9rieur<\/h2>\n<p style=\"text-align: justify;\" data-start=\"1092\" data-end=\"1288\">L&rsquo;entame de match \u00e9tait en faveur des Mon\u00e9gasques, port\u00e9s par un <strong>\u00c9lie Okobo<\/strong> pour une fois titulaire. N\u00e9anmoins, le match s&rsquo;\u00e9quilibrait rapidement, notamment parce que la formation turque exploitait la puissance de <strong>Rolands Smits<\/strong> dans la peinture. C&rsquo;est toutefois un superbe passage d&rsquo;<strong>Alpha Diallo<\/strong> permettait aux Mon\u00e9gasques de mener \u00e0 la fin du premier quart. Mais rien n&rsquo;\u00e9tait facile, et l&rsquo;Anadolu \u00e9tait clairement venu pour faire un coup, notamment un certain <strong>Isa\u00efa Cordinier<\/strong>, qui encha\u00eenait les paniers, et terminait la premi\u00e8re p\u00e9riode avec pas moins de 13 points. Pas assez pour emp\u00eacher Monaco de mener \u00e0 la pause (<strong>50-43<\/strong>), avec un <strong>Daniel Theis<\/strong> impeccable.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Alpha Diallo helping <a href=\"https:\/\/twitter.com\/ASMonaco_Basket?ref_src=twsrc%5Etfw\">@ASMonaco_Basket<\/a> extend their lead! \ud83e\udd85<a href=\"https:\/\/twitter.com\/hashtag\/MotorolaMagicMoment?src=hash&amp;ref_src=twsrc%5Etfw\">#MotorolaMagicMoment<\/a> | <a href=\"https:\/\/twitter.com\/Moto?ref_src=twsrc%5Etfw\">@Moto<\/a> <a href=\"https:\/\/t.co\/5SDZloUIUv\">pic.twitter.com\/5SDZloUIUv<\/a><\/p>\n<p>\u2014 EuroLeague (@EuroLeague) <a href=\"https:\/\/twitter.com\/EuroLeague\/status\/1993770790429532543?ref_src=twsrc%5Etfw\">November 26, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\" data-start=\"1092\" data-end=\"1288\">D\u00e9termin\u00e9s \u00e0 ne pas se faire peur, les Mon\u00e9gasques pla\u00e7aient un coup d&rsquo;acc\u00e9l\u00e9rateur au retour des vestiaires, et l&rsquo;\u00e9cart franchissait la dizaine. Monaco dominait totalement \u00e0 l&rsquo;int\u00e9rieur, mais c&rsquo;est surtout d\u00e9fensivement que la Roca Team \u00e9tait impressionnante, n&rsquo;encaissant que 10 points dans le troisi\u00e8me quart ! L&rsquo;impact de <strong>Kevarrius Hayes<\/strong> \u00e9tait notamment \u00e0 saluer, et quand l&rsquo;avance mon\u00e9gasque atteignait 20 points, l&rsquo;Anadolu rendait les armes et sombrait totalement au score. Du bon travail pour Monaco, port\u00e9 par les <strong>17 points \u00e0 100% au tir de Daniel Theis<\/strong>, et qui s&rsquo;impose <strong>102-66<\/strong> sans trembler apr\u00e8s avoir eu le luxe de faire tourner durant le dernier quart. De quoi rester dans le peloton de t\u00eate au classement.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-euroligue-masculine-2025-2026\/\">Classement actualis\u00e9 EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2025-2026 &#8211; \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l&rsquo;Anadolu \u00e0 Gaston-M\u00e9decin.<\/p>\n","protected":false},"author":59,"featured_media":628099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[16232,16878,181,24],"class_list":["post-628053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-as-monaco-basket","tag-breve","tag-euroligue","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monaco facile contre l&#039;Anadolu : la Roca Team se replace en EuroLigue<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2025-2026 - \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l&#039;Anadolu \u00e0 Gaston-M\u00e9decin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monaco facile contre l&#039;Anadolu : la Roca Team se replace en EuroLigue\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2025-2026 - \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l&#039;Anadolu \u00e0 Gaston-M\u00e9decin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T20:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Monaco facile contre l&#039;Anadolu : la Roca Team se replace en EuroLigue\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Monaco facile contre l&rsquo;Anadolu : la Roca Team se replace en EuroLigue\",\"datePublished\":\"2025-11-26T20:31:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png\",\"keywords\":[\"as monaco basket\",\"br\u00e8ve\",\"Euroligue\",\"sport\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\",\"name\":\"Monaco facile contre l'Anadolu : la Roca Team se replace en EuroLigue\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png\",\"datePublished\":\"2025-11-26T20:31:31+00:00\",\"description\":\"EUROLIGUE 2025-2026 - \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l'Anadolu \u00e0 Gaston-M\u00e9decin.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png\",\"width\":1200,\"height\":674,\"caption\":\"Monaco facile contre l'Anadolu la Roca Team se replace en EuroLigue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monaco facile contre l&rsquo;Anadolu : la Roca Team se replace en EuroLigue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Monaco facile contre l'Anadolu : la Roca Team se replace en EuroLigue","description":"EUROLIGUE 2025-2026 - \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l'Anadolu \u00e0 Gaston-M\u00e9decin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/","og_locale":"fr_FR","og_type":"article","og_title":"Monaco facile contre l'Anadolu : la Roca Team se replace en EuroLigue","og_description":"EUROLIGUE 2025-2026 - \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l'Anadolu \u00e0 Gaston-M\u00e9decin.","og_url":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2025-11-26T20:31:31+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Monaco facile contre l'Anadolu : la Roca Team se replace en EuroLigue","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Monaco facile contre l&rsquo;Anadolu : la Roca Team se replace en EuroLigue","datePublished":"2025-11-26T20:31:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png","keywords":["as monaco basket","br\u00e8ve","Euroligue","sport"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/","url":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/","name":"Monaco facile contre l'Anadolu : la Roca Team se replace en EuroLigue","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png","datePublished":"2025-11-26T20:31:31+00:00","description":"EUROLIGUE 2025-2026 - \u00c0 sa main, Monaco a acc\u00e9l\u00e9r\u00e9 au retour des vestiaires, et domin\u00e9 sans coup f\u00e9rir l'Anadolu \u00e0 Gaston-M\u00e9decin.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/11\/Monaco-facile-contre-lAnadolu-la-Roca-Team-se-replace-en-EuroLigue.png","width":1200,"height":674,"caption":"Monaco facile contre l'Anadolu la Roca Team se replace en EuroLigue"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/monaco-facile-contre-lanadolu-la-roca-team-se-replace-en-euroligue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Monaco facile contre l&rsquo;Anadolu : la Roca Team se replace en EuroLigue"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/628053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=628053"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/628053\/revisions"}],"predecessor-version":[{"id":628104,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/628053\/revisions\/628104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/628099"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=628053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=628053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=628053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}