{"id":629717,"date":"2025-12-03T10:35:25","date_gmt":"2025-12-03T09:35:25","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=629717&#038;preview=true&#038;preview_id=629717"},"modified":"2025-12-03T11:44:50","modified_gmt":"2025-12-03T10:44:50","slug":"quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/","title":{"rendered":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des six poules d\u2019un Mondial au format in\u00e9dit.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le <a href=\"https:\/\/dicodusport.fr\/blog\/direct-le-tirage-au-sort-de-la-coupe-du-monde-de-rugby-2027\/\"><strong>tirage au sort de la Coupe du monde 2027 de rugby<\/strong><\/a> s&rsquo;est d\u00e9roul\u00e9 ce mercredi matin du c\u00f4t\u00e9 de <strong>Sydney<\/strong>. Du 1er octobre au 13 novembre 2027, l&rsquo;Australie accueillera une \u00e9dition historique puisque pour la premi\u00e8re fois, <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-2027-les-23-pays-deja-qualifies-dernier-billet-en-jeu-a-dubai\/\">24 nations sont sur la ligne de d\u00e9part<\/a>\u00a0pour tenter de mettre les mains sur le troph\u00e9e Webb-Ellis.<\/p>\n<h2 style=\"text-align: justify;\">Japon, \u00c9tats-Unis et Samoa pour les Bleus<\/h2>\n<p style=\"text-align: justify;\">Positionn\u00e9e dans le chapeau 1, le <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/xv-de-france\/\"><strong>XV de France<\/strong><\/a>\u00a0a naturellement \u00e9vit\u00e9 les plus grosses s\u00e9lections mondiales et h\u00e9rite d\u2019une poule plut\u00f4t abordable. En effet, les Bleus devront se mesurer \u00e0 des adversaires qu\u2019ils connaissent bien : un <strong>Japon<\/strong> toujours capable de coups d\u2019\u00e9clat, les <strong>\u00c9tats-Unis<\/strong> et les <a href=\"https:\/\/dicodusport.fr\/blog\/denouement-cruel-pour-la-belgique-face-aux-samoa-pas-de-coupe-du-monde-en-australie-pour-les-diables-noirs\/\"><strong>Samoa<\/strong><\/a>. Sur le papier, cela ne devrait pas poser de probl\u00e8mes aux troupes de <strong>Fabien Galthi\u00e9<\/strong>, qui devraient ais\u00e9ment assurer leur qualification pour le tour suivant. Rappelons que les deux premiers de chaque poule seront automatiquement qualifi\u00e9s pour d\u2019in\u00e9dits 8\u00e8mes de finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\uddef\ud83c\uddf5\ud83c\uddfa\ud83c\uddf8\ud83c\uddfc\ud83c\uddf8 On conna\u00eet \ud835\udc8f\ud835\udc90\ud835\udc94 \ud835\udc82\ud835\udc85\ud835\udc97\ud835\udc86\ud835\udc93\ud835\udc94\ud835\udc82\ud835\udc8a\ud835\udc93\ud835\udc86\ud835\udc94 pour la phase de poule de la prochaine Coupe du Monde !<\/p>\n<p>\ud83e\udee1\ud83c\uddeb\ud83c\uddf7 Rendez-vous en 2027 ! <a href=\"https:\/\/twitter.com\/hashtag\/RWC2027?src=hash&amp;ref_src=twsrc%5Etfw\">#RWC2027<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/XVdeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#XVdeFrance<\/a> <a href=\"https:\/\/t.co\/zZl6B8UpMU\">pic.twitter.com\/zZl6B8UpMU<\/a><\/p>\n<p>\u2014 France Rugby (@FranceRugby) <a href=\"https:\/\/twitter.com\/FranceRugby\/status\/1996151503870922840?ref_src=twsrc%5Etfw\">December 3, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Australie &#8211; Nouvelle-Z\u00e9lande d\u00e8s la phase de poules<\/h2>\n<p style=\"text-align: justify;\">Dans les autres poules, le pays h\u00f4te n\u2019a pas \u00e9t\u00e9 \u00e9pargn\u00e9 puisque l\u2019<strong>Australie<\/strong> affrontera la <strong>Nouvelle-Z\u00e9lande<\/strong> dans la poule A, tandis que le <strong>Chili<\/strong> et <strong>Hong Kong<\/strong> tenteront de faire de leur mieux face \u00e0 ces g\u00e9ants du rugby mondial. Championne du monde en titre, l\u2019<strong>Afrique du Sud<\/strong> d\u00e9fiera trois nations europ\u00e9ennes, dont l\u2019<strong>Italie<\/strong>, dans la poule B. De leur c\u00f4t\u00e9, l\u2019<strong>Argentine<\/strong> et les <strong>Fidji<\/strong> devraient se disputer la premi\u00e8re place d\u2019une poule qui comprend \u00e9galement l\u2019<strong>Espagne<\/strong> et le <strong>Canada<\/strong>. Enfin, deux chocs britanniques auront lieu d\u00e8s les poules : l\u2019<strong>Irlande<\/strong> et l\u2019<strong>\u00c9cosse<\/strong> dans la poule D, tandis que les <strong>Gallois<\/strong> et les <strong>Anglais<\/strong> s\u2019affronteront dans la poule F.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/les-adversaires-potentiels-du-xv-de-france-en-phase-finale-de-la-coupe-du-monde-2027\/\">Les adversaires potentiels du XV de France en phase finale de la Coupe du monde 2027<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">S\u2019il ne devrait pas y avoir d\u2019\u00e9normes surprises \u00e0 ce stade de la comp\u00e9tition, cette phase de poules s\u2019annonce particuli\u00e8rement int\u00e9ressante et exotique. Au-del\u00e0 de la pr\u00e9sence de <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-2027-qualification-historique-pour-hong-kong\/\"><strong>Hong Kong<\/strong><\/a>, les performances des revenants comme le <strong>Zimbabwe<\/strong> ou l\u2019<strong>Espagne<\/strong> seront \u00e0 observer de pr\u00e8s. En tout cas, les jeux sont faits : rendez-vous d\u00e9sormais le <strong>3 f\u00e9vrier<\/strong> pour le d\u00e9voilement du calendrier complet, et surtout dans 22 mois pour le grand lancement du tournoi !<\/p>\n<h2 style=\"text-align: justify;\">Les 6 poules pour la Coupe du monde de rugby 2027<\/h2>\n<table style=\"width: 800px; border-collapse: collapse;\">\n<tbody>\n<tr>\n<td style=\"width: 400px; background-color: #ff4600; text-align: center;\"><strong><span style=\"color: #ffffff;\">POULE A<\/span><\/strong><\/td>\n<td style=\"width: 400px; background-color: #ff4600; text-align: center;\"><strong><span style=\"color: #ffffff;\">POULE B<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddf3\ud83c\uddff NOUVELLE-Z\u00c9LANDE<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddff\ud83c\udde6 AFRIQUE DU SUD<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\udde6\ud83c\uddfa AUSTRALIE<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddee\ud83c\uddf9 ITALIE<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\udde8\ud83c\uddf1 CHILI<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddec\ud83c\uddea G\u00c9ORGIE<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\udded\ud83c\uddf0 HONG KONG<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 400px; background-color: #ff4600; text-align: center;\"><strong><span style=\"color: #ffffff;\">POULE C<\/span><\/strong><\/td>\n<td style=\"width: 400px; background-color: #ff4600; text-align: center;\"><strong><span style=\"color: #ffffff;\">POULE D<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\udde6\ud83c\uddf7 ARGENTINE<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b><em>\ud83c\uddee<\/em>\ud83c\uddea\u00a0IRLANDE<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddeb\ud83c\uddef FIDJI<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8797\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-300x180.png\" alt=\"\" width=\"17\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-390x205.png 390w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse-800x445.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Drapeau-Ecosse.png 1000w\" sizes=\"auto, (max-width: 17px) 100vw, 17px\" \/> \u00c9COSSE<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddfa\ud83c\uddfe URUGUAY<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\udde8\ud83c\udde6 CANADA<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddf5\ud83c\uddf9\u00a0PORTUGAL<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 400px; background-color: #ff4600; text-align: center;\"><strong><span style=\"color: #ffffff;\">POULE E<\/span><\/strong><\/td>\n<td style=\"width: 400px; background-color: #ff4600; text-align: center;\"><strong><span style=\"color: #ffffff;\">POULE F<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddeb\ud83c\uddf7 FRANCE<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3761\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png\" alt=\"\" width=\"17\" height=\"10\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-300x180.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-768x461.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre-390x205.png 390w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Angleterre.png 800w\" sizes=\"auto, (max-width: 17px) 100vw, 17px\" \/> ANGLETERRE<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddef\ud83c\uddf5 JAPON<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3749\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/Drapeau-Pays-de-Galles-300x180.png\" alt=\"\" width=\"17\" height=\"10\" \/> PAYS DE GALLES<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddfa\ud83c\uddf8 \u00c9TATS-UNIS<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddf9\ud83c\uddf4 TONGA<\/b><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddfc\ud83c\uddf8 SAMOA<\/b><\/span><\/td>\n<td style=\"text-align: center; width: 400px;\"><span style=\"font-size: 0.9em;\"><b>\ud83c\uddff\ud83c\uddfc ZIMBABWE<\/b><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des six poules d\u2019un Mondial au format in\u00e9dit.<\/p>\n","protected":false},"author":55,"featured_media":629721,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47049,19951],"tags":[32415,16878,1529,110,24,1638],"class_list":["post-629717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-rugby","category-xv-de-france","tag-actu","tag-breve","tag-coupe-du-monde-de-rugby","tag-rugby-a-xv","tag-sport","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des 6 poules.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des 6 poules.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-03T09:35:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T10:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien\",\"datePublished\":\"2025-12-03T09:35:25+00:00\",\"dateModified\":\"2025-12-03T10:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\"},\"wordCount\":527,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Coupe du monde de rugby\",\"Rugby \u00e0 XV\",\"sport\",\"XV de France\"],\"articleSection\":[\"Coupe du monde de rugby\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\",\"name\":\"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png\",\"datePublished\":\"2025-12-03T09:35:25+00:00\",\"dateModified\":\"2025-12-03T10:44:50+00:00\",\"description\":\"D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des 6 poules.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png\",\"width\":1200,\"height\":674,\"caption\":\"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 La composition des 6 poules du Mondial australien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien","description":"D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des 6 poules.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/","og_locale":"fr_FR","og_type":"article","og_title":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien","og_description":"D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des 6 poules.","og_url":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-12-03T09:35:25+00:00","article_modified_time":"2025-12-03T10:44:50+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien","datePublished":"2025-12-03T09:35:25+00:00","dateModified":"2025-12-03T10:44:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/"},"wordCount":527,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png","keywords":["actu","br\u00e8ve","Coupe du monde de rugby","Rugby \u00e0 XV","sport","XV de France"],"articleSection":["Coupe du monde de rugby","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/","url":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/","name":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png","datePublished":"2025-12-03T09:35:25+00:00","dateModified":"2025-12-03T10:44:50+00:00","description":"D\u00e9couvrez quels seront les adversaires possibles du XV de France \u00e0 la Coupe du monde 2027, ainsi que la composition des 6 poules.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Quels-adversaires-pour-le-XV-de-France-a-la-Coupe-du-monde-2027-La-composition-des-6-poules-du-Mondial-australien.png","width":1200,"height":674,"caption":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 La composition des 6 poules du Mondial australien"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/quels-adversaires-pour-le-xv-de-france-a-la-coupe-du-monde-2027-la-composition-des-6-poules-du-mondial-australien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Quels adversaires pour le XV de France \u00e0 la Coupe du monde 2027 ? La composition des 6 poules du Mondial australien"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/629717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=629717"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/629717\/revisions"}],"predecessor-version":[{"id":629751,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/629717\/revisions\/629751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/629721"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=629717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=629717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=629717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}