{"id":631131,"date":"2025-12-09T20:06:51","date_gmt":"2025-12-09T19:06:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=631131&#038;preview=true&#038;preview_id=631131"},"modified":"2025-12-09T20:08:01","modified_gmt":"2025-12-09T19:08:01","slug":"royale-union-sg-marseille-compositions-diffusion-heure-et-cotes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/","title":{"rendered":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-2025-2026-dates-matchs-et-calendrier-de-marseille\/\" target=\"_blank\" rel=\"noopener\">Ligue des champions 2025-2026 : Dates, matchs et calendrier de Marseille<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Union Sainte-Gilloise<\/strong> est en t\u00eate du championnat belge apr\u00e8s 17 journ\u00e9es, avec une marge de quatre points sur <strong>Saint-Trond<\/strong>. En <strong>Ligue des Champions<\/strong>, le club belge a remport\u00e9 deux matchs jusqu&rsquo;ici face \u00e0 <strong>Galatasaray<\/strong> et au <strong>PSV<\/strong> <strong>Eindhoven<\/strong>. La Royale Union s&rsquo;est inclin\u00e9e lors de ses trois autres rencontres face \u00e0 <strong>Newcastle<\/strong>, l&rsquo;Inter et l&rsquo;<strong>Atl\u00e9tico de Madrid<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Marseille sur sa lanc\u00e9e ?<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Olympique de Marseille<\/strong> s&rsquo;est relanc\u00e9 en <strong>Ligue des champions<\/strong> en s&rsquo;imposant face \u00e0 <strong>Newcastle<\/strong> lors de la derni\u00e8re journ\u00e9e. Les Olympiens \u00e9taient pourtant men\u00e9s, mais ont invers\u00e9 la tendance gr\u00e2ce \u00e0 un doubl\u00e9 de <strong>Pierre-Emerick Aubameyang<\/strong>. En <strong>Ligue<\/strong> <strong>1<\/strong>, l&rsquo;<strong>OM<\/strong> reste sur deux contre-performances, un nul face \u00e0 Toulouse puis une d\u00e9faite face \u00e0 <strong>Lille<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-des-champions-2025-2026-psg-marseille-et-monaco\/\">Classement Ligue des champions 2025-2026 (PSG, Marseille et Monaco)<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les deux \u00e9quipes ne se sont jamais affront\u00e9es, et ce sera donc une grande premi\u00e8re ce mardi soir. Chez les bookmakers, <strong>Marseille<\/strong> est l\u00e9g\u00e8rement favori pour cette rencontre.<\/p>\n<h2 style=\"text-align: justify;\">Ligue des champions : Le programme TV de Royale Union SG-Marseille<\/h2>\n<h3 style=\"text-align: justify;\">Mardi 9 d\u00e9cembre 2025<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur Canal+ Foot<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 21h00.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions officielles de Royale Union SG-Marseille<\/h2>\n<h3 style=\"text-align: justify;\">La composition de la Royale Union SG<\/h3>\n<p style=\"text-align: justify;\">Scherpen; Mac Allister, Burgess, Leysen, Khalaili; Zorgane, Van De Perre, Schoofs; Niang, Florucz; Rodr\u00edguez<\/p>\n<h3 style=\"text-align: justify;\">La composition de Marseille<\/h3>\n<div class=\"Article__paragraph Article__paragraph--textFocus Article__paragraph--isBeforeLinkParagraph\" data-v-0c628588=\"\">\n<div class=\"TextFocus Article__textFocus\" data-v-4b27739c=\"\" data-v-0c628588=\"\">\n<div class=\"TextFocus__block\" data-v-4b27739c=\"\">\n<div class=\"TextFocus__content\" data-v-4b27739c=\"\">Rulli; Weah, Murillo, Aguerd, Emerson; O&rsquo;Riley, Hojbjerg, Vermeeren; Greenwood, Aubameyang, Paix\u00e3o<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2 style=\"text-align: justify;\">Les cotes de Royale Union SG-Marseille<\/h2>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Mardi 9 d\u00e9cembre, 21h00<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Royale Union SG<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/63369911?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 2.90<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/63369911?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 3.60<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/63369911?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 2.25<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/p>\n","protected":false},"author":1,"featured_media":631133,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,47250],"tags":[16878,75,419,446,8799],"class_list":["post-631131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-ligue-des-champions-de-football","tag-breve","tag-football","tag-ligue-des-champions","tag-marseille","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes<\/title>\n<meta name=\"description\" content=\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes\" \/>\n<meta property=\"og:description\" content=\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T19:06:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T19:08:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes\",\"datePublished\":\"2025-12-09T19:06:51+00:00\",\"dateModified\":\"2025-12-09T19:08:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue des champions\",\"Marseille\",\"Programme TV\"],\"articleSection\":[\"Cha\u00eene TV\",\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\",\"name\":\"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png\",\"datePublished\":\"2025-12-09T19:06:51+00:00\",\"dateModified\":\"2025-12-09T19:08:01+00:00\",\"description\":\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes","description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/","og_locale":"fr_FR","og_type":"article","og_title":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes","og_description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","og_url":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-12-09T19:06:51+00:00","article_modified_time":"2025-12-09T19:08:01+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes","datePublished":"2025-12-09T19:06:51+00:00","dateModified":"2025-12-09T19:08:01+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png","keywords":["br\u00e8ve","Football","Ligue des champions","Marseille","Programme TV"],"articleSection":["Cha\u00eene TV","Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/","url":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/","name":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png","datePublished":"2025-12-09T19:06:51+00:00","dateModified":"2025-12-09T19:08:01+00:00","description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue des champions entre le Royale Union SG et Marseille ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Royale-Union-SG-Marseille-Compositions-Diffusion-Heure-et-Cotes.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/royale-union-sg-marseille-compositions-diffusion-heure-et-cotes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Royale Union SG-Marseille : Compositions, Diffusion, Heure et Cotes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/631131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=631131"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/631131\/revisions"}],"predecessor-version":[{"id":631306,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/631131\/revisions\/631306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/631133"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=631131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=631131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=631131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}