{"id":632824,"date":"2025-12-16T22:54:34","date_gmt":"2025-12-16T21:54:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=632824&#038;preview=true&#038;preview_id=632824"},"modified":"2025-12-16T23:10:22","modified_gmt":"2025-12-16T22:10:22","slug":"le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/","title":{"rendered":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EUROLIGUE 2025\/2026 \u2013 Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n\u2019a jamais \u00e9t\u00e9 en mesure d\u2019inqui\u00e9ter Barcelone et s\u2019incline logiquement 85-69.<\/em><\/strong><\/p>\n<ul>\n<li><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-euroligue-masculine-2025-2026\/\">Calendrier et r\u00e9sultats EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Englu\u00e9 dans une spirale n\u00e9gative en <strong>EuroLigue<\/strong> avec quatre d\u00e9faites cons\u00e9cutives, le <strong>Paris Basketball<\/strong> faisait face \u00e0 un d\u00e9fi de taille en accueillant le <strong>FC Barcelone<\/strong>. Solidement install\u00e9 \u00e0 la <strong>troisi\u00e8me place<\/strong> du classement, le club catalan restait sur trois victoires de rang, dont un succ\u00e8s de r\u00e9f\u00e9rence sur le parquet bouillant de l\u2019<strong>\u00c9toile Rouge<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Paris prend l\u2019eau d\u00e8s le premier quart<\/h2>\n<p style=\"text-align: justify;\">Dans une entame de match tr\u00e8s rythm\u00e9e, les visiteurs n\u2019ont pas tard\u00e9 \u00e0 imposer leur loi. Dominateurs au rebond face \u00e0 des Parisiens en grande difficult\u00e9 dans ce secteur, les Catalans sont mont\u00e9s en puissance au fil du premier quart-temps. <strong>Will Clyburn<\/strong> a d\u2019abord allum\u00e9 la m\u00e8che, avant que <strong>Kevin Punter<\/strong> ne mette le feu.<\/p>\n<p style=\"text-align: justify;\">L\u2019arri\u00e8re am\u00e9ricain a encha\u00een\u00e9 les tirs prim\u00e9s comme les p\u00e9n\u00e9trations pour atteindre la barre des <strong>13 points en sept minutes<\/strong>. Si <strong>Nadir Hifi<\/strong> (16 points) et <strong>Allan Dokossi<\/strong> (14 points, 9 rebonds) ont permis de limiter la casse en d\u00e9but de rencontre, le collectif parisien a rapidement implos\u00e9. Face \u00e0 un Bar\u00e7a en total contr\u00f4le, la sanction est tomb\u00e9e sans d\u00e9lai.<\/p>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0 rel\u00e9gu\u00e9 \u00e0 <strong>-17<\/strong> \u00e0 la fin du premier quart, Paris a continu\u00e9 de subir derri\u00e8re l\u2019arc, <strong>Dario Brizuela<\/strong> frappant \u00e0 deux reprises pour porter l\u2019\u00e9cart \u00e0 plus de vingt points en moins de onze minutes (13-34). Apr\u00e8s ce passage \u00e0 vide, les Parisiens ont timidement relev\u00e9 la t\u00eate, profitant d\u2019une baisse d\u2019adresse catalane. <strong>Hifi<\/strong>, <strong>Dokossi<\/strong> et <strong>Justin Robinson<\/strong> ont alors tent\u00e9 un l\u00e9ger rapproch\u00e9 (23-38).<\/p>\n<p style=\"text-align: justify;\">Mais Barcelone a remis un coup d\u2019acc\u00e9l\u00e9rateur avant la pause. Avec d\u00e9j\u00e0 plus de <strong>50 points encaiss\u00e9s<\/strong> et une adresse ext\u00e9rieure parisienne catastrophique (18 %), le score \u00e9tait sans appel \u00e0 la mi-temps : <strong>29-52<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">On est dans le dur. <a href=\"https:\/\/t.co\/VsNmS7ZUPE\">pic.twitter.com\/VsNmS7ZUPE<\/a><\/p>\n<p>\u2014 Paris Basketball (@ParisBasketball) <a href=\"https:\/\/twitter.com\/ParisBasketball\/status\/2001033466755125349?ref_src=twsrc%5Etfw\">December 16, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Barcelone en contr\u00f4le, des Parisiens inoffensifs<\/h2>\n<p style=\"text-align: justify;\">Au retour des vestiaires, Paris a pourtant tent\u00e9 d\u2019y croire. En difficult\u00e9 jusque-l\u00e0, <strong>Jared Rhoden<\/strong> a retrouv\u00e9 un peu de r\u00e9ussite, tandis que les Catalans tardaient \u00e0 remettre de la fluidit\u00e9 dans leur jeu offensif. Mais forts de leur avance et de l\u2019impact de leurs int\u00e9rieurs, les visiteurs ont parfaitement g\u00e9r\u00e9 ce temps faible sans jamais paniquer.<\/p>\n<p style=\"text-align: justify;\">\u00c0 l\u2019exp\u00e9rience, Barcelone a hach\u00e9 le jeu pour casser le rythme et maintenir un \u00e9cart d\u2019une quinzaine de points tout au long du troisi\u00e8me quart-temps (52-68).<\/p>\n<ul>\n<li><strong>\u00c0 lire aussi \u2013 <a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-euroligue-masculine-2025-2026\/\">Classement actualis\u00e9 EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Un tir \u00e0 mi-distance de <strong>Tomas Satoransky<\/strong> et une nouvelle filoche de l\u2019in\u00e9vitable <strong>Kevin Punter<\/strong> (21 points) ont d\u00e9finitivement tu\u00e9 tout suspense d\u00e8s l\u2019entame du dernier quart (54-73). D\u00e9sorganis\u00e9s en attaque et jamais r\u00e9ellement dans le match, les Parisiens ont travers\u00e9 la rencontre comme des fant\u00f4mes.<\/p>\n<p style=\"text-align: justify;\">Le <strong>Paris Basketball<\/strong> conc\u00e8de ainsi un inqui\u00e9tant <strong>cinqui\u00e8me revers cons\u00e9cutif<\/strong>, le neuvi\u00e8me lors de ses dix derni\u00e8res sorties europ\u00e9ennes. \u00c0 l\u2019issue d\u2019un blow-out interminable, le champion de France s\u2019incline logiquement sur le score de <strong>85-69<\/strong>, signant au passage son plus faible total de points de la saison.<\/p>\n<p style=\"text-align: justify;\">Avec d\u00e9sormais <strong>l\u2019un des pires bilans de l\u2019EuroLigue (5 victoires \u2013 11 d\u00e9faites)<\/strong>, Paris est dos au mur et devra imp\u00e9rativement r\u00e9agir rapidement pour ne pas voir la course aux playoffs se jouer sans lui.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"ca\">Final del tercer quart. Va, Bar\u00e7a! A rematar la feina. <a href=\"https:\/\/t.co\/kmfpsGBbBh\">pic.twitter.com\/kmfpsGBbBh<\/a><\/p>\n<p>\u2014 Bar\u00e7a Basket (@FCBbasket) <a href=\"https:\/\/twitter.com\/FCBbasket\/status\/2001043574201237796?ref_src=twsrc%5Etfw\">December 16, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2025\/2026 &#8211; Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n&rsquo;a jamais \u00e9t\u00e9 en mesure d&rsquo;inqui\u00e9ter Barcelone, et s&rsquo;incline\u00a085-69.<\/p>\n","protected":false},"author":55,"featured_media":632864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47001],"tags":[2101,16878,181,18992],"class_list":["post-632824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-barcelone","tag-breve","tag-euroligue","tag-paris-basketball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2025\/2026 - Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n&#039;a jamais \u00e9t\u00e9 en mesure d&#039;inqui\u00e9ter Barcelone, et s&#039;incline\u00a085-69.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2025\/2026 - Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n&#039;a jamais \u00e9t\u00e9 en mesure d&#039;inqui\u00e9ter Barcelone, et s&#039;incline\u00a085-69.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-16T21:54:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T22:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive\",\"datePublished\":\"2025-12-16T21:54:34+00:00\",\"dateModified\":\"2025-12-16T22:10:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\"},\"wordCount\":640,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png\",\"keywords\":[\"barcelone\",\"br\u00e8ve\",\"Euroligue\",\"Paris Basketball\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\",\"name\":\"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png\",\"datePublished\":\"2025-12-16T21:54:34+00:00\",\"dateModified\":\"2025-12-16T22:10:22+00:00\",\"description\":\"EUROLIGUE 2025\/2026 - Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n'a jamais \u00e9t\u00e9 en mesure d'inqui\u00e9ter Barcelone, et s'incline\u00a085-69.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png\",\"width\":1200,\"height\":674,\"caption\":\"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive","description":"EUROLIGUE 2025\/2026 - Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n'a jamais \u00e9t\u00e9 en mesure d'inqui\u00e9ter Barcelone, et s'incline\u00a085-69.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive","og_description":"EUROLIGUE 2025\/2026 - Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n'a jamais \u00e9t\u00e9 en mesure d'inqui\u00e9ter Barcelone, et s'incline\u00a085-69.","og_url":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-12-16T21:54:34+00:00","article_modified_time":"2025-12-16T22:10:22+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive","datePublished":"2025-12-16T21:54:34+00:00","dateModified":"2025-12-16T22:10:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/"},"wordCount":640,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png","keywords":["barcelone","br\u00e8ve","Euroligue","Paris Basketball"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/","url":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/","name":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png","datePublished":"2025-12-16T21:54:34+00:00","dateModified":"2025-12-16T22:10:22+00:00","description":"EUROLIGUE 2025\/2026 - Largu\u00e9 d\u00e8s le premier quart-temps, le Paris Basketball n'a jamais \u00e9t\u00e9 en mesure d'inqui\u00e9ter Barcelone, et s'incline\u00a085-69.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Le-Paris-Basketball-sombre-en-EuroLigue-Barcelone-inflige-aux-Parisiens-une-5eme-defaite-consecutive.png","width":1200,"height":674,"caption":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-paris-basketball-sombre-en-euroligue-barcelone-inflige-aux-parisiens-une-5eme-defaite-consecutive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Paris Basketball sombre en EuroLigue : Barcelone inflige aux Parisiens une 5\u00e8me d\u00e9faite cons\u00e9cutive"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/632824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=632824"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/632824\/revisions"}],"predecessor-version":[{"id":632871,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/632824\/revisions\/632871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/632864"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=632824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=632824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=632824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}