{"id":632980,"date":"2025-12-17T22:06:24","date_gmt":"2025-12-17T21:06:24","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=632980&#038;preview=true&#038;preview_id=632980"},"modified":"2025-12-17T22:30:37","modified_gmt":"2025-12-17T21:30:37","slug":"5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/","title":{"rendered":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&rsquo;ASVEL en EuroLigue"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>EUROLIGUE 2025\/2026 &#8211; <\/em><\/strong><strong><em>L&rsquo;ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-euroligue-masculine-2025-2026\/\">Calendrier et r\u00e9sultats EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Battue lors de ses quatre derniers matchs, l&rsquo;<strong>ASVEL<\/strong> disposait d&rsquo;une belle occasion de retrouver le chemin de la victoire en <strong>EuroLigue<\/strong>. Face \u00e0 un <strong>Bayern Munich<\/strong> en panne de r\u00e9sultats (6 d\u00e9faites de rang), il y avait un coup \u00e0 faire pour les hommes de <strong>Pierric Poupet<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;ASVEL fait d\u00e9jouer les Bavarois, Nando De Colo puissance 5 000<\/h2>\n<p style=\"text-align: justify;\">En d\u00e9but de match, <strong>Nando De Colo<\/strong> a tir\u00e9 la couverture en inscrivant rapidement quatre points pour devenir le 2\u00e8me joueur de l&rsquo;histoire \u00e0 franchir la barre des <strong>5 000 points en EuroLigue<\/strong>. Puis, le meneur tricolore a cr\u00e9\u00e9 un autre \u00e9v\u00e8nement en ratant son premier lancer franc de l&rsquo;ann\u00e9e apr\u00e8s&#8230; 55 r\u00e9ussites !<\/p>\n<p style=\"text-align: justify;\">Cela s&rsquo;est produit au sein d&rsquo;une entame plaisante et offensive, o\u00f9 les paniers ont plus des deux c\u00f4t\u00e9s. Mais une fois les premi\u00e8res rotations effectu\u00e9es, les Lyonnais ont subi en fin de premier quart. Dans le sillage des 8 points de l&rsquo;ancien Bressan <strong>Isiaha Mike<\/strong>, le Bayern a capitalis\u00e9 sur la p\u00e9nurie des Tricolores pour cr\u00e9er un premier \u00e9cart (13-20).<\/p>\n<p style=\"text-align: justify;\">Cependant, \u00e0 force de r\u00e9cup\u00e9rer des ballons, l&rsquo;ASVEL a compens\u00e9 son d\u00e9chet au tir par des points faciles en transition. Profitant de Bavarois hagards durant de longues minutes, ils sont parvenus \u00e0 totalement renverser la vapeur. Et sur un soyeux lay-up de <strong>Thomas Heurtel<\/strong>, ils sont parvenus \u00e0 valider un cinglant 11-2 (26-24).<\/p>\n<p style=\"text-align: justify;\">Dans la foul\u00e9e, l&rsquo;exp\u00e9riment\u00e9<strong> Johannes Voigtmann<\/strong> est sorti de sa bo\u00eete afin de coller sept points de rang. Mais \u00e0 l&rsquo;issue de ce premier acte ind\u00e9cis, l&rsquo;ASVEL a vir\u00e9 en t\u00eate gr\u00e2ce aux deux derniers shoots de <strong>Glynn Watson Jr<\/strong> avant le buzzer (42-38).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">NANDO TO THE 5K CLUB \ud83e\udd29 <a href=\"https:\/\/t.co\/x6WWem9y8s\">pic.twitter.com\/x6WWem9y8s<\/a><\/p>\n<p>\u2014 SKWEEK (@skweektv) <a href=\"https:\/\/twitter.com\/skweektv\/status\/2001373173246529695?ref_src=twsrc%5Etfw\">December 17, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>L&rsquo;ASVEL renverse tout dans le dernier quart<\/h2>\n<p style=\"text-align: justify;\">Entre ces deux \u00e9quipes fragiles, le combat \u00e9triqu\u00e9 s&rsquo;est prolong\u00e9 au retour des vestiaires. Suite \u00e0 une longue s\u00e9quence brouillonne de part et d&rsquo;autre, l&rsquo;adresse est revenue, comme l&rsquo;a prouv\u00e9 ce bel \u00e9change de banderilles entre <strong>Spencer Dinwiddie <\/strong>et <strong>Thomas Heurtel<\/strong>. N\u00e9anmoins, les Bavarois ont bris\u00e9 cette monotonie en l&rsquo;espace d&rsquo;une minute montre en main. Ces derniers ont inflig\u00e9 une \u00e9norme claque aux Lyonnais en collant un 11-0 dans ce laps de temps, gr\u00e2ce notamment \u00e0 une action \u00e0 quatre points d&rsquo;<strong>Andreas Obst<\/strong> (51-62) !<\/p>\n<p style=\"text-align: justify;\">Sonn\u00e9s, les Lyonnais ont travers\u00e9 la fin du troisi\u00e8me quart comme des fant\u00f4mes. N\u00e9anmoins, le Bayern n&rsquo;en a pas profit\u00e9 pour tuer d\u00e9finitivement le match. Progressivement, l&rsquo;ASVEL s&rsquo;est mis \u00e0 y croire de nouveau dans le sillage d&rsquo;un grand <strong>Glynn Watson Jr<\/strong>. L&rsquo;ancien gravelinois a tout d&rsquo;abord enfil\u00e9 deux gros tirs ext\u00e9rieurs pour combler la moiti\u00e9 de l&rsquo;\u00e9cart, avant de claquer une action \u00e0 trois points pour ramener le match \u00e0 une possession \u00e0 l&rsquo;entr\u00e9e du money time (69-72). Puis, une filoche d&rsquo;<strong>Armel Traor\u00e9<\/strong> a ramen\u00e9 les Lyonnais \u00e0 -1.<\/p>\n<ul>\n<li><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/classement-actualise-euroligue-masculine-2025-2026\/\">Classement actualis\u00e9 EuroLigue masculine 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Face \u00e0 ces Bavarois friables, incapables de scorer le moindre point, ils ont finalement r\u00e9alis\u00e9 l&rsquo;impensable gr\u00e2ce \u00e0 un magnifique shoot \u00e0 mi-distance de <strong>Thomas Heurtel<\/strong> \u00e0 24 secondes du buzzer en renversant d\u00e9finitivement la partie (75-74) ! Si le Bayern a dispos\u00e9 d&rsquo;une ultime munition pour renverser le match au buzzer, la tentative de Voigtmann n&rsquo;a pas fait mouche.<\/p>\n<p style=\"text-align: justify;\">Au bout d&rsquo;une remont\u00e9e lente et laborieuse, l&rsquo;ASVEL arrache une renversante et pr\u00e9cieuse victoire, <strong>76-74<\/strong>. De quoi mettre un terme \u00e0 une s\u00e9rie de quatre d\u00e9faites cons\u00e9cutives, tout en se rapprochant des \u00e9quipes positionn\u00e9es devant au classement. Seules les sorties sur blessure de <strong>Nando De Colo<\/strong> et<strong> Mbaye Ndiaye<\/strong>, viennent obscurcir un tableau globalement positif ce soir.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2025\/2026 &#8211; L&rsquo;ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.<\/p>\n","protected":false},"author":55,"featured_media":633038,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47001],"tags":[7864,4484,16878,181,24],"class_list":["post-632980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-asvel","tag-bayern-munich","tag-breve","tag-euroligue","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&#039;ASVEL en EuroLigue<\/title>\n<meta name=\"description\" content=\"EUROLIGUE 2025\/2026 - L&#039;ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&#039;ASVEL en EuroLigue\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE 2025\/2026 - L&#039;ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-17T21:06:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T21:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&#039;ASVEL en EuroLigue\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&rsquo;ASVEL en EuroLigue\",\"datePublished\":\"2025-12-17T21:06:24+00:00\",\"dateModified\":\"2025-12-17T21:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/\"},\"wordCount\":687,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png\",\"keywords\":[\"ASVEL\",\"Bayern Munich\",\"br\u00e8ve\",\"Euroligue\",\"sport\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/\",\"name\":\"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png\",\"datePublished\":\"2025-12-17T21:06:24+00:00\",\"dateModified\":\"2025-12-17T21:30:37+00:00\",\"description\":\"EUROLIGUE 2025\\\/2026 - L'ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png\",\"width\":1200,\"height\":674,\"caption\":\"5.000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&rsquo;ASVEL en EuroLigue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue","description":"EUROLIGUE 2025\/2026 - L'ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/","og_locale":"fr_FR","og_type":"article","og_title":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue","og_description":"EUROLIGUE 2025\/2026 - L'ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.","og_url":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-12-17T21:06:24+00:00","article_modified_time":"2025-12-17T21:30:37+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&rsquo;ASVEL en EuroLigue","datePublished":"2025-12-17T21:06:24+00:00","dateModified":"2025-12-17T21:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/"},"wordCount":687,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png","keywords":["ASVEL","Bayern Munich","br\u00e8ve","Euroligue","sport"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/","url":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/","name":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png","datePublished":"2025-12-17T21:06:24+00:00","dateModified":"2025-12-17T21:30:37+00:00","description":"EUROLIGUE 2025\/2026 - L'ASVEL a d\u00e9croch\u00e9 sa 4\u00e8me victoire de la saison en renversant le Bayern Munich dans la derni\u00e8re minute, 76-74.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/5.000-points-pour-Nando-De-Colo-et-la-victoire-enfin-une-belle-soiree-pour-lASVEL-en-EuroLigue.png","width":1200,"height":674,"caption":"5.000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l'ASVEL en EuroLigue"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/5-000-points-pour-nando-de-colo-et-la-victoire-enfin-une-belle-soiree-pour-lasvel-en-euroligue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"5 000 points pour Nando De Colo et la victoire : enfin une belle soir\u00e9e pour l&rsquo;ASVEL en EuroLigue"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/632980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=632980"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/632980\/revisions"}],"predecessor-version":[{"id":633047,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/632980\/revisions\/633047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/633038"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=632980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=632980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=632980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}