{"id":634243,"date":"2025-12-23T14:25:18","date_gmt":"2025-12-23T13:25:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=634243&#038;preview=true&#038;preview_id=634243"},"modified":"2026-02-03T09:43:48","modified_gmt":"2026-02-03T08:43:48","slug":"biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/","title":{"rendered":"Biathlon, ski, hockey&#8230; 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>JEUX OLYMPIQUES D&rsquo;HIVER 2026 &#8211; Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 voir \u00e9galement :\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/jo-dhiver-2026-modes-de-qualification-et-francais-qualifies-sport-par-sport\/\">JO d\u2019hiver 2026 : Modes de qualification et Fran\u00e7ais qualifi\u00e9s, sport par sport<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le CNOSF a d\u00e9voil\u00e9 ce mardi la premi\u00e8re des trois vagues de s\u00e9lection pour les <strong>Jeux Olympiques d&rsquo;Hiver de Milan-Cortina<\/strong> qui d\u00e9butent dans un mois et demi. En attendant les deux prochaines annonces qui interviendront les 20 et 23 janvier, la France est d\u00e9j\u00e0 assur\u00e9e de compter dans ses rangs les 73 athl\u00e8tes suivants dans 5 sports diff\u00e9rents.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[<a href=\"https:\/\/twitter.com\/hashtag\/MilanCortina2026?src=hash&amp;ref_src=twsrc%5Etfw\">#MilanCortina2026<\/a>]\n\u00c0 45 jours des Jeux Olympiques de Milan-Cortina 2026, le <a href=\"https:\/\/twitter.com\/hashtag\/CNOSF?src=hash&amp;ref_src=twsrc%5Etfw\">#CNOSF<\/a> a valid\u00e9 les 73 premiers athl\u00e8tes qui repr\u00e9senteront la d\u00e9l\u00e9gation fran\u00e7aise en biathlon, hockey sur glace, patinage artistique, patinage de vitesse et ski-alpinisme. \ud83c\uddeb\ud83c\uddf7<\/p>\n<p>D\u00e9couvrez la s\u00e9lection \u2b07\ufe0f\u2026 <a href=\"https:\/\/t.co\/I0C1lLznJx\">pic.twitter.com\/I0C1lLznJx<\/a><\/p>\n<p>\u2014 FranceOlympique (@FranceOlympique) <a href=\"https:\/\/twitter.com\/FranceOlympique\/status\/2003451939334320604?ref_src=twsrc%5Etfw\">December 23, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Biathlon :<\/h2>\n<p style=\"text-align: justify;\">Neuf noms ont \u00e9t\u00e9 officialis\u00e9s ce mardi. Pas de surprise dans la mesure o\u00f9 il s&rsquo;agit des six biathl\u00e8tes qui disposaient d\u00e9j\u00e0 d&rsquo;un statut d&rsquo;athl\u00e8tes prot\u00e9g\u00e9s par la FFS gr\u00e2ce aux r\u00e9sultats acquis jusqu&rsquo;\u00e0 pr\u00e9sent.\u00a0 S&rsquo;ajoutent \u00e0 cette liste <strong>Camille Bened, Oc\u00e9ane Michelon et Fabien Claude.<\/strong> Les Bleus iront \u00e0 Milan avec l&rsquo;\u00e9tiquette d&rsquo;une nation phare \u00e0 l&rsquo;image de la Norv\u00e8ge, capable de d\u00e9crocher un podium dans toutes les courses. C&rsquo;\u00e9tait le cas par exemple ce week-end, o\u00f9 l&rsquo;\u00e9quipe de France a d\u00e9croch\u00e9 au Grand-Bornand six podiums en autant de courses. Trois noms suppl\u00e9mentaires seront annonc\u00e9s en 2026.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/jeanmonnot-passera-noel-en-jaune-jacquelin-samuse-fillon-maillet-decoit-les-tops-et-flops-des-bleus-au-grand-bornand\/\">Jeanmonnot passera No\u00ebl en jaune, Jacquelin s\u2019amuse, Fillon Maillet d\u00e9\u00e7oit : les Tops et Flops des Bleus au Grand-Bornand<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Hommes :<\/strong> Quentin Fillon-Maillet, Emilien Jacquelin, Fabien Claude et Eric Perrot.<\/p>\n<p style=\"text-align: justify;\"><strong>Femmes : <\/strong>Camille Bened, Justine Braisaz-Bouchet, Julia Simon, Oc\u00e9ane Michelon et Lou Jeanmonnot.<\/p>\n<h2 style=\"text-align: justify;\">Hockey sur glace :<\/h2>\n<p style=\"text-align: justify;\">La France sera repr\u00e9sent\u00e9e aussi bien dans le tournoi masculin que dans le tournoi f\u00e9minin. Une premi\u00e8re dans l&rsquo;histoire dans la mesure o\u00f9 les femmes participeront pour la premi\u00e8re fois. Dans un cas comme dans l&rsquo;autre, cette qualification s&rsquo;est faite au d\u00e9triment de la Russie, dont la qualification n&rsquo;a pas \u00e9t\u00e9 valid\u00e9e par le CIO du fait de sa suspension par l&rsquo;IIHF. Les Bleus retrouveront donc la sc\u00e8ne olympique pour la premi\u00e8re fois depuis 2002.<\/p>\n<p style=\"text-align: justify;\"><strong>Hommes : <\/strong>Justin Addamo, Yohann Auvitu, Pierre-Edouard Bellemare, Charles Bertrand, Jules Boscq, Louis Boudon, Kevin Bozon, Enzo Cantagallo, Florian Chakiachvili, Pierre Crinon, St\u00e9phane Da Costa, Aur\u00e9lien Dair, Floran Douay, Dylan Fabre, Hugo Gallet, Enzo Guebey, Julian Junca, Antoine Keller, Martin Neckar, Jordann Perret, Anthony Rech, Nicolas Ritz, Thomas Thiry et Sacha Treille (un athl\u00e8te sera annonc\u00e9 en janvier 2026).<\/p>\n<p style=\"text-align: justify;\"><strong>Femmes : <\/strong>Chlo\u00e9 Aurard, Jade Barbirati, Lore Baudrit, L\u00e9a Berger, Cl\u00e9mence Boudin, Gabrielle De Serres, Estelle Duvin, Sehana Galbrun, Margot Huot-Marchand, Manon Le Scodan, Sophie Leclerc, Margaux Mameri, Julia Mesplede, Emma Nonnenmacher, Marie-Pierre P\u00e9lissou, Ana\u00efs Peyne-Dingival, Alice Philbert, Violette Pianel-Couriaut, Lucie Quarto, Clara Rozier, Ana\u00e9 Simon, L\u00e9a Villiot, Elina Zilliox.<\/p>\n<h2 style=\"text-align: justify;\">Patinage artistique :<\/h2>\n<p style=\"text-align: justify;\">Le couple <strong>Guillaume Cizeron<\/strong> &#8211; <strong>Laurence Fournier Beaudry, <\/strong>Canadienne r\u00e9cemment naturalis\u00e9e fran\u00e7aise, sera sans doute la plus grande attraction dans la d\u00e9l\u00e9gation tricolore. Les deux ont brill\u00e9 ces derni\u00e8res semaines en remportant le <a href=\"https:\/\/dicodusport.fr\/blog\/patinage-artistique-premiere-sortie-victorieuse-pour-guillaume-cizeron-et-laurence-fournier-beaudry-au-grand-prix-de-france\/\">Grand Prix de France<\/a> et celui de <a href=\"https:\/\/dicodusport.fr\/blog\/guillaume-cizeron-et-laurence-fournier-beaudry-patinent-vers-la-victoire-au-grand-prix-de-finlande\/\">Finlande<\/a> et en prenant la deuxi\u00e8me place de celui de Nagoya au Japon. On suivra \u00e9galement <strong>Adam Siao Him Fa<\/strong> et <strong>Kevin Aymoz<\/strong>, respectivement deuxi\u00e8me du Grand Prix de France et de Finlande et <a href=\"https:\/\/dicodusport.fr\/blog\/victoire-historique-pour-kevin-aymoz-au-skate-america-2025\/\">vainqueur du Skate America<\/a> il y a un mois.<\/p>\n<p style=\"text-align: justify;\"><strong>Hommes + Par \u00e9quipes :<\/strong> Adam Siao Him Fa, Kevin Aymoz<\/p>\n<p style=\"text-align: justify;\"><strong>Femmes + Par \u00e9quipes :<\/strong> Lorine Schild.<\/p>\n<p style=\"text-align: justify;\"><strong>Danse + Par \u00e9quipes :<\/strong> Guillaume Cizeron\/Laurence Fournier Beaudry et Evgeniia Lopareva\/Geoffrey Brissaud.<\/p>\n<p style=\"text-align: justify;\"><strong>Epreuve par \u00e9quipes : <\/strong>Camille Kovalev et Pavel Kovalev.<\/p>\n<h2 style=\"text-align: justify;\">Patinage de vitesse :<\/h2>\n<p style=\"text-align: justify;\">Les Bleus seront emmen\u00e9s par <strong>Timothy Loubineaud<\/strong>, qui repr\u00e9sentera une chance de m\u00e9daille cr\u00e9dible sur 5 000 m\u00e8tres, <a href=\"https:\/\/dicodusport.fr\/blog\/patinage-de-vitesse-vainqueur-a-salt-lake-city-thimothy-loubineaud-bat-le-record-du-monde-du-5000-metres\/\">\u00e9preuve dont il d\u00e9tient le record du monde<\/a>, mais aussi sur le 10 000 m\u00e8tres et la mass start. La poursuite masculine pourrait aussi avoir son mot \u00e0 dire quelques semaines apr\u00e8s un \u00e9patant <a href=\"https:\/\/dicodusport.fr\/blog\/le-patinage-de-vitesse-francais-en-grande-forme-le-relais-soffre-un-podium-en-coupe-du-monde\/\">podium en Coupe du monde \u00e0 Calgary<\/a>. Chez les femmes, <strong>Violette Braun<\/strong> tentera de cr\u00e9er la surprise, elle qui, \u00e0 19 ans, est davantage orient\u00e9e pour performer dans les Alpes fran\u00e7aises en 2030.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 voir \u00e9galement : <a href=\"https:\/\/dicodusport.fr\/blog\/qui-est-violette-braun-la-valeur-montante-du-patinage-de-vitesse-francais\/\">Qui est Violette Braun, la valeur montante du patinage de vitesse fran\u00e7ais ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Hommes :<\/strong> Timothy Loubineaud, Valentin Thiebault, Germain Deschamps, Giovanni Trebouta et Mathieu Belloir.<\/p>\n<p style=\"text-align: justify;\"><strong>Femmes :<\/strong> Violette Braun.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/%C3%89quipePolice?src=hash&amp;ref_src=twsrc%5Etfw\">#\u00c9quipePolice<\/a> | \u26f8\ufe0f Le policier Timothy Loubineaud signe un nouveau record du monde en patinage de vitesse du 5 000 m en patinage de vitesse avec un temps de 6\u201900\u2019\u201923.<br \/>\n\ud83c\udfaf \u00c0 quelques mois des Jeux de Milan-Cortina 2026, le Fran\u00e7ais s\u2019impose comme l\u2019un des hommes forts de la\u2026 <a href=\"https:\/\/t.co\/xOvyUAtxSj\">pic.twitter.com\/xOvyUAtxSj<\/a><\/p>\n<p>\u2014 Police nationale (@PoliceNationale) <a href=\"https:\/\/twitter.com\/PoliceNationale\/status\/1990043599346545002?ref_src=twsrc%5Etfw\">November 16, 2025<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Ski alpinisme :<\/h2>\n<p style=\"text-align: justify;\">La discipline fera ses d\u00e9buts sur la sc\u00e8ne olympique et la France entend bien truster les podiums. Il y aura une \u00e9preuve de sprint chez les hommes et chez les femmes, ainsi qu&rsquo;un relais mixte.<\/p>\n<p style=\"text-align: justify;\"><strong>Femmes :<\/strong> Emily Harrop.<\/p>\n<p style=\"text-align: justify;\"><strong>Hommes :<\/strong> Thibault Anselmet.<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>JEUX OLYMPIQUES D&rsquo;HIVER 2026 &#8211; Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.<\/p>\n","protected":false},"author":91,"featured_media":634252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2426,10575,44003,45757],"tags":[16878,46887,46888,47094,24],"class_list":["post-634243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biathlon","category-hockey-sur-glace","category-jo-hiver-2026","category-ski-alpinisme","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina<\/title>\n<meta name=\"description\" content=\"JEUX OLYMPIQUES D&#039;HIVER 2026 - Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina\" \/>\n<meta property=\"og:description\" content=\"JEUX OLYMPIQUES D&#039;HIVER 2026 - Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-23T13:25:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T08:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Victor Clot-Amiot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/VictorClotAmiot\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\"},\"author\":{\"name\":\"Victor Clot-Amiot\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/b623199cba9ba90fe84a3d16e9282360\"},\"headline\":\"Biathlon, ski, hockey&#8230; 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina\",\"datePublished\":\"2025-12-23T13:25:18+00:00\",\"dateModified\":\"2026-02-03T08:43:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\"},\"wordCount\":885,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png\",\"keywords\":[\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\",\"sport\"],\"articleSection\":[\"Biathlon\",\"Hockey sur glace\",\"JO d'hiver 2026\",\"Ski alpinisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\",\"name\":\"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png\",\"datePublished\":\"2025-12-23T13:25:18+00:00\",\"dateModified\":\"2026-02-03T08:43:48+00:00\",\"description\":\"JEUX OLYMPIQUES D'HIVER 2026 - Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png\",\"width\":1200,\"height\":674,\"caption\":\"Biathlon, ski, hockey 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biathlon, ski, hockey&#8230; 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/b623199cba9ba90fe84a3d16e9282360\",\"name\":\"Victor Clot-Amiot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg\",\"caption\":\"Victor Clot-Amiot\"},\"description\":\"Passionn\u00e9 de sport depuis toujours, un jour \u00e0 l'adolescence mes parents m'ont dit : \\\"quitte \u00e0 passer ton temps \u00e0 regarder du sport, au moins va le voir en vrai\\\" ! Depuis, cette remarque ne m'a plus quitt\u00e9 et je passe une grande partie de mon temps libre \u00e0 assister \u00e0 des comp\u00e9titions de tous sports. Je m\u00eale d'ailleurs mes deux passions, le sport et les voyages afin de faire une pierre deux coups ! Outre l'US Open ou l'Euro 2021 par exemple, j'ai assist\u00e9 cet \u00e9t\u00e9 aux Mondiaux d'athl\u00e9tisme \u00e0 Budapest. Mon plus gros coup dur est et restera les JO 2020-2021 pour lesquels j'avais r\u00e9serv\u00e9 17 \u00e9preuves. La suite, vous la connaissez...\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/x.com\/VictorClotAmiot\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/victor-clot-amiot\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina","description":"JEUX OLYMPIQUES D'HIVER 2026 - Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/","og_locale":"fr_FR","og_type":"article","og_title":"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina","og_description":"JEUX OLYMPIQUES D'HIVER 2026 - Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.","og_url":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2025-12-23T13:25:18+00:00","article_modified_time":"2026-02-03T08:43:48+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png","type":"image\/png"}],"author":"Victor Clot-Amiot","twitter_card":"summary_large_image","twitter_title":"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina","twitter_creator":"@https:\/\/x.com\/VictorClotAmiot","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/"},"author":{"name":"Victor Clot-Amiot","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/b623199cba9ba90fe84a3d16e9282360"},"headline":"Biathlon, ski, hockey&#8230; 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina","datePublished":"2025-12-23T13:25:18+00:00","dateModified":"2026-02-03T08:43:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/"},"wordCount":885,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png","keywords":["br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver","sport"],"articleSection":["Biathlon","Hockey sur glace","JO d'hiver 2026","Ski alpinisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/","url":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/","name":"Biathlon, ski, hockey... 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png","datePublished":"2025-12-23T13:25:18+00:00","dateModified":"2026-02-03T08:43:48+00:00","description":"JEUX OLYMPIQUES D'HIVER 2026 - Le CNOSF a valid\u00e9 ce mardi une premi\u00e8re liste de 73 athl\u00e8tes s\u00e9lectionn\u00e9s pour repr\u00e9senter la France.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2025\/12\/Biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-JO-2026-de-Milan-Cortina.png","width":1200,"height":674,"caption":"Biathlon, ski, hockey 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/biathlon-ski-hockey-73-premiers-athletes-annonces-pour-les-jo-2026-de-milan-cortina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Biathlon, ski, hockey&#8230; 73 premiers athl\u00e8tes annonc\u00e9s pour les JO 2026 de Milan-Cortina"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/b623199cba9ba90fe84a3d16e9282360","name":"Victor Clot-Amiot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg","caption":"Victor Clot-Amiot"},"description":"Passionn\u00e9 de sport depuis toujours, un jour \u00e0 l'adolescence mes parents m'ont dit : \"quitte \u00e0 passer ton temps \u00e0 regarder du sport, au moins va le voir en vrai\" ! Depuis, cette remarque ne m'a plus quitt\u00e9 et je passe une grande partie de mon temps libre \u00e0 assister \u00e0 des comp\u00e9titions de tous sports. Je m\u00eale d'ailleurs mes deux passions, le sport et les voyages afin de faire une pierre deux coups ! Outre l'US Open ou l'Euro 2021 par exemple, j'ai assist\u00e9 cet \u00e9t\u00e9 aux Mondiaux d'athl\u00e9tisme \u00e0 Budapest. Mon plus gros coup dur est et restera les JO 2020-2021 pour lesquels j'avais r\u00e9serv\u00e9 17 \u00e9preuves. La suite, vous la connaissez...","sameAs":["https:\/\/x.com\/https:\/\/x.com\/VictorClotAmiot"],"url":"https:\/\/dicodusport.fr\/blog\/author\/victor-clot-amiot\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/634243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=634243"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/634243\/revisions"}],"predecessor-version":[{"id":634265,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/634243\/revisions\/634265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/634252"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=634243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=634243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=634243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}