{"id":63512,"date":"2020-06-12T18:44:10","date_gmt":"2020-06-12T16:44:10","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=63512&#038;preview=true&#038;preview_id=63512"},"modified":"2020-07-10T20:19:59","modified_gmt":"2020-07-10T18:19:59","slug":"top-14-2020-2021-transferts-point-mercato-rc-toulon","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/","title":{"rendered":"Top 14 2020\/2021 &#8211; Transferts : le point sur le mercato du RC Toulon"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Top 14 2020\/2021 &#8211; La saison actuelle n&rsquo;est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur le mercato et les transferts au RC Toulon.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les arriv\u00e9es<\/h2>\n<p style=\"text-align: justify;\">Trois arriv\u00e9es sont pour le moment act\u00e9es. Le deuxi\u00e8me ligne de La Rochelle <strong>Thomas Jolm\u00e8s<\/strong>, 24 ans, rejoindra le RC Toulon la saison prochaine. Derri\u00e8re, le N\u00e9o-Z\u00e9landais <strong>Nehe Milner-Skudder<\/strong> (arri\u00e8re, 29 ans), ne viendra finalement pas garnir la ligne des trois-quarts varois. Le RCT est en bonne voie pour compenser ce faux-bond, avec la venue du Clermontois <strong>Isaia Toeava<\/strong>. Derni\u00e8re recrue en date, le pilier de Rennes, <strong>J\u00e9r\u00e9my Boyadjis<\/strong> (30 ans).<\/p>\n<h2 style=\"text-align: justify;\">Les d\u00e9parts<\/h2>\n<p style=\"text-align: justify;\">De nombreux joueurs sont d\u00e9j\u00e0 s\u00fbrs de ne pas \u00eatre conserv\u00e9s. Le pilier sud-africain <strong>Marcel Van der Merwe<\/strong> (29 ans) retourne au pays (Bulls). Le troisi\u00e8me ligne <strong>St\u00e9phane Onamb\u00e9l\u00e9<\/strong> (27 ans) filera \u00e0 Castres. Le deuxi\u00e8me ligne <strong>Corentin Vernet<\/strong> (23 ans) rejoint quant \u00e0 lui le SU Agen. Le troisi\u00e8me ligne n\u00e9o-z\u00e9landais <strong>Liam Messam<\/strong> (36 ans) va \u00e9galement quitter la Rade. L&rsquo;ailier et centre all-black <strong>Julian Savea<\/strong> (29 ans), d\u00e9cevant \u00e0 Toulon, va lui aussi quitter le RCT. Tout comme l&rsquo;arri\u00e8re <strong>Hugo Bonneval<\/strong> (29 ans), en partance pour Pau. L&rsquo;ouvreur espoir <strong>Mathieu Sma\u00efli<\/strong>, 20 ans, est lui pr\u00eat\u00e9 une saison \u00e0 Mont-de-Marsan.<\/p>\n<p style=\"text-align: justify;\">Quatre joueurs sont partis en cours de saison : le pilier sud-africain <strong>Wilco Louw<\/strong> (Stormers), les demis de m\u00eal\u00e9e <strong>Rhys Webb<\/strong> (Bath) et <strong>Louis Schreuder<\/strong> (Stormers) ainsi que le centre <strong>Ben Te&rsquo;o<\/strong> (Sunwolves).<\/p>\n<p style=\"text-align: justify;\">Enfin, la l\u00e9gende <strong>Mamuka Gorgodze<\/strong> (35 ans) met fin \u00e0 sa carri\u00e8re.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.allrugby.com\/dossiers\/transferts-rugby-club-toulonnais.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Tout ce qu&rsquo;il faut savoir sur l&rsquo;effectif du RC Toulon pour la saison 2020\/2021<\/strong><\/a><\/li>\n<\/ul>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Top 14 2020\/2021 &#8211; La saison actuelle n&rsquo;est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur le mercato et les transferts au RC Toulon.<\/p>\n","protected":false},"author":4,"featured_media":63522,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129],"tags":[7974,3078,216,111,7945],"class_list":["post-63512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-mercato-top-14","tag-rc-toulon","tag-rct","tag-top-14","tag-transferts-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon<\/title>\n<meta name=\"description\" content=\"Top 14 2020\/2021 - La saison actuelle n&#039;est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur les transferts au RC Toulon.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon\" \/>\n<meta property=\"og:description\" content=\"Top 14 2020\/2021 - La saison actuelle n&#039;est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur les transferts au RC Toulon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-12T16:44:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-10T18:19:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Top 14 2020\/2021 &#8211; Transferts : le point sur le mercato du RC Toulon\",\"datePublished\":\"2020-06-12T16:44:10+00:00\",\"dateModified\":\"2020-07-10T18:19:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\"},\"wordCount\":298,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png\",\"keywords\":[\"Mercato Top 14\",\"RC Toulon\",\"RCT\",\"Top 14\",\"Transferts Top 14\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\",\"name\":\"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png\",\"datePublished\":\"2020-06-12T16:44:10+00:00\",\"dateModified\":\"2020-07-10T18:19:59+00:00\",\"description\":\"Top 14 2020\/2021 - La saison actuelle n'est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur les transferts au RC Toulon.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 2020\/2021 &#8211; Transferts : le point sur le mercato du RC Toulon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon","description":"Top 14 2020\/2021 - La saison actuelle n'est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur les transferts au RC Toulon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon","og_description":"Top 14 2020\/2021 - La saison actuelle n'est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur les transferts au RC Toulon.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-06-12T16:44:10+00:00","article_modified_time":"2020-07-10T18:19:59+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Top 14 2020\/2021 &#8211; Transferts : le point sur le mercato du RC Toulon","datePublished":"2020-06-12T16:44:10+00:00","dateModified":"2020-07-10T18:19:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/"},"wordCount":298,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png","keywords":["Mercato Top 14","RC Toulon","RCT","Top 14","Transferts Top 14"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/","name":"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png","datePublished":"2020-06-12T16:44:10+00:00","dateModified":"2020-07-10T18:19:59+00:00","description":"Top 14 2020\/2021 - La saison actuelle n'est pas encore termin\u00e9e, que la prochaine est d\u00e9j\u00e0 dans les esprits. Le point sur les transferts au RC Toulon.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Top-14-2020_2021-Transferts-Le-point-sur-le-mercato-du-RC-Toulon.png","width":800,"height":445,"caption":"Top 14 2020\/2021 - Transferts : le point sur le mercato du RC Toulon"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-2020-2021-transferts-point-mercato-rc-toulon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 2020\/2021 &#8211; Transferts : le point sur le mercato du RC Toulon"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/63512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=63512"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/63512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/63522"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=63512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=63512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=63512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}