{"id":63570,"date":"2020-03-20T16:25:17","date_gmt":"2020-03-20T15:25:17","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=63570&#038;preview=true&#038;preview_id=63570"},"modified":"2020-04-07T18:52:22","modified_gmt":"2020-04-07T16:52:22","slug":"histoire-quand-skicross-francais-volait-jo-sotchi","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/","title":{"rendered":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>SKICROSS &#8211; On s&rsquo;en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/jean-frederic-chapuis\/\" target=\"_blank\" rel=\"noopener noreferrer\">Jean-Fr\u00e9d\u00e9ric Chapuis<\/a>, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient un tripl\u00e9 invraisemblable \u00e0 Sotchi. Ou quand le sport fran\u00e7ais est capable de r\u00e9aliser un \u00e9norme exploit.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Une grande, et immense premi\u00e8re. Le 20 f\u00e9vrier 2014, le sport tricolore a atteint des sommets dans la performance. Lors de l&rsquo;\u00e9preuve de <strong>skicross<\/strong> masculine, trois Frenchies allaient crever l&rsquo;\u00e9cran. Et de quelle mani\u00e8re. D\u00e9j\u00e0, un premier exploit, celui de caler trois skieurs fran\u00e7ais en finale, avec la certitude de d\u00e9crocher, au minimum, deux breloques. Ce jour-l\u00e0, <strong>Jean-Fred Chapuis<\/strong>, <strong>Arnaud Bovolenta<\/strong> et <strong>Jonathan Midol<\/strong>, les trois mousquetaires, \u00e9taient en route pour la course de toute une vie. Face \u00e0 eux, le Canadien <strong>Brady Leman<\/strong>, quatri\u00e8me et dernier qualifi\u00e9 pour la finale, allait se sentir bien seul.<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 l&rsquo;or fran\u00e7aise<\/h2>\n<p style=\"text-align: justify;\"><strong>Chapuis<\/strong>, <strong>Bovolenta<\/strong>, <strong>Midol<\/strong>, une meute bleue lanc\u00e9e pour une chasse \u00e0 l&rsquo;or. Le d\u00e9part \u00e9tait \u00e0 l&rsquo;avantage du duo <strong>Bovolenta-Chapuis<\/strong>, qui se tirait la bourre en t\u00eate de la course. Derri\u00e8re, juste derri\u00e8re, <strong>Jonathan Midol<\/strong> bataillait dur face \u00e0 <strong>Brady Leman<\/strong>. <strong>Bovolenta<\/strong>, <strong>Chapuis<\/strong>, <strong>Chapuis<\/strong>, <strong>Bovolenta<\/strong>, un mano a mano franco-fran\u00e7ais devant une guerre franco-canadienne.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est dans un dernier virage de folie que l&rsquo;impensable, le tripl\u00e9 r\u00eav\u00e9, se dessinait pour de bon. <strong>Brady Leman<\/strong> au sol, la France du ski pouvait exulter. Le natif de Bourg-Saint-Maurice <strong>Jean-Fr\u00e9d\u00e9ric Chapuis<\/strong> enlevait le titre olympique, devant le skieur originaire d&rsquo;Albertville <strong>Arnaud Bovolenta<\/strong> et le troisi\u00e8me larron, l&rsquo;Ann\u00e9cien <strong>Jonathan Midol<\/strong>. Pour la premi\u00e8re fois de l&rsquo;histoire des <strong>Jeux Olympiques d&rsquo;hiver<\/strong>, la France r\u00e9alisait un tripl\u00e9. Sotchi \u00e9tait pass\u00e9e \u00e0 l&rsquo;heure fran\u00e7aise. Ou \u00e0 l&rsquo;or fran\u00e7aise, c&rsquo;est vous qui voyez.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=u5kWtGsyljk<\/p>\n<h2 style=\"text-align: justify;\">La suite ?<\/h2>\n<p style=\"text-align: justify;\">Fortunes diverses pour les trois h\u00e9ros tricolores. <strong>Jean-Fr\u00e9d\u00e9ric Chapuis<\/strong> a rafl\u00e9 le globe de cristal en skicross en 2015, 2016 et 2017, en plus du titre de vice-champion du monde en 2015, apr\u00e8s avoir remport\u00e9 l&rsquo;or en 2013. <strong>Arnaud Bovolenta<\/strong> n&rsquo;est pas parvenu \u00e0 confirmer sa m\u00e9daille d&rsquo;argent. Pas \u00e9pargn\u00e9 par les blessures, il vient de mettre un terme \u00e0 sa carri\u00e8re \u00e0 31 ans. De son c\u00f4t\u00e9, <strong>Jonathan Midol<\/strong> a remport\u00e9 une Coupe du monde, fin 2018.<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SKICROSS &#8211; On s&rsquo;en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient un tripl\u00e9 invraisemblable \u00e0 Sotchi. Ou quand le sport fran\u00e7ais est capable de r\u00e9aliser un \u00e9norme exploit.<\/p>\n","protected":false},"author":4,"featured_media":63575,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8,9217],"tags":[2947],"class_list":["post-63570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-ski","tag-skicross"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi<\/title>\n<meta name=\"description\" content=\"SKICROSS - On s&#039;en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient le tripl\u00e9 \u00e0 Sotchi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi\" \/>\n<meta property=\"og:description\" content=\"SKICROSS - On s&#039;en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient le tripl\u00e9 \u00e0 Sotchi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T15:25:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-07T16:52:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi\",\"datePublished\":\"2020-03-20T15:25:17+00:00\",\"dateModified\":\"2020-04-07T16:52:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/\"},\"wordCount\":404,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png\",\"keywords\":[\"skicross\"],\"articleSection\":[\"Histoire\",\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/\",\"name\":\"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png\",\"datePublished\":\"2020-03-20T15:25:17+00:00\",\"dateModified\":\"2020-04-07T16:52:22+00:00\",\"description\":\"SKICROSS - On s'en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient le tripl\u00e9 \u00e0 Sotchi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png\",\"width\":800,\"height\":445,\"caption\":\"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/histoire-quand-skicross-francais-volait-jo-sotchi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi","description":"SKICROSS - On s'en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient le tripl\u00e9 \u00e0 Sotchi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/","og_locale":"fr_FR","og_type":"article","og_title":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi","og_description":"SKICROSS - On s'en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient le tripl\u00e9 \u00e0 Sotchi.","og_url":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-03-20T15:25:17+00:00","article_modified_time":"2020-04-07T16:52:22+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi","datePublished":"2020-03-20T15:25:17+00:00","dateModified":"2020-04-07T16:52:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/"},"wordCount":404,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png","keywords":["skicross"],"articleSection":["Histoire","Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/","url":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/","name":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png","datePublished":"2020-03-20T15:25:17+00:00","dateModified":"2020-04-07T16:52:22+00:00","description":"SKICROSS - On s'en souviendra, tr\u00e8s longtemps. Le 20 f\u00e9vrier 2014, Jean-Fr\u00e9d\u00e9ric Chapuis, Arnaud Bovolenta et Jonathan Midol r\u00e9alisaient le tripl\u00e9 \u00e0 Sotchi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/03\/Histoire-Quand-le-skicross-fran\u00e7ais-volait-sur-les-JO-de-Sotchi.png","width":800,"height":445,"caption":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/histoire-quand-skicross-francais-volait-jo-sotchi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Histoire] Quand le skicross fran\u00e7ais volait sur les JO de Sotchi"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/63570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=63570"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/63570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/63575"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=63570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=63570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=63570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}