{"id":635748,"date":"2026-01-04T13:00:15","date_gmt":"2026-01-04T12:00:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=635748&#038;preview=true&#038;preview_id=635748"},"modified":"2026-01-04T13:09:53","modified_gmt":"2026-01-04T12:09:53","slug":"guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/","title":{"rendered":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>DAKAR 2026 &#8211; L&rsquo;\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s&rsquo;est offert la victoire sur la 1\u00e8re \u00e9tape.<\/em><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/chaine-tv-dakar-2026-ou-suivre-les-etapes-en-direct\/\">Cha\u00eene TV Dakar 2026 : O\u00f9 suivre les \u00e9tapes en direct ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le d\u00e9but de ce <strong>Dakar 2026<\/strong> est garni de surprises ! En cat\u00e9gorie motos, le jeune Edgar Canet ne cesse de faire preuve d&rsquo;une pr\u00e9cocit\u00e9 historique, et r\u00e8gne en ma\u00eetre. Du c\u00f4t\u00e9 des autos, la 1\u00e8re \u00e9tape disput\u00e9e ce dimanche matin a \u00e9galement connu son lot de surprises.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/ross-branch-penalise-edgar-canet-double-la-mise-sur-la-1ere-etape-du-dakar\/\" class=\"vlp-link\" title=\"Ross Branch p\u00e9nalis\u00e9, Edgar Canet double la mise sur la 1\u00e8re \u00e9tape du Dakar\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ross-Branch-penalise-Edgar-Canet-double-la-mise-sur-la-1ere-etape-du-Dakar.png\" class=\"attachment-800x445 size-800x445\" alt=\"Ross Branch p\u00e9nalis\u00e9, Edgar Canet double la mise sur la 1\u00e8re \u00e9tape du Dakar\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ross-Branch-penalise-Edgar-Canet-double-la-mise-sur-la-1ere-etape-du-Dakar.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ross-Branch-penalise-Edgar-Canet-double-la-mise-sur-la-1ere-etape-du-Dakar-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ross-Branch-penalise-Edgar-Canet-double-la-mise-sur-la-1ere-etape-du-Dakar-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ross-Branch-penalise-Edgar-Canet-double-la-mise-sur-la-1ere-etape-du-Dakar-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Ross Branch p\u00e9nalis\u00e9, Edgar Canet double la mise sur la 1\u00e8re \u00e9tape du Dakar<\/div><div class=\"vlp-block-1 vlp-link-summary\">DAKAR 2026 - Le pilote espagnol Edgar Canet a remport\u00e9 la 1\u00e8re \u00e9tape en cat\u00e9gorie motos en profitant de la p\u00e9nalit\u00e9 inflig\u00e9e \u00e0 Ross Branch.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Les Ford marquent leur territoire, Loeb se positionne<\/h2>\n<p style=\"text-align: justify;\">Dans une \u00e9tape qui ne rev\u00eatait pas de pi\u00e8ge majeur en termes de topographie comme de navigation, les principaux favoris \u00e0 la victoire finale avaient avant tout pour but de passer une journ\u00e9e sans encombre, tout en \u00e9vitant de se retrouver trop haut dans le classement afin de ne pas ouvrir la route sur une 2\u00e8me \u00e9tape qui sera bien plus d\u00e9licate. Ainsi, les pilotes <strong>Ford<\/strong> ont montr\u00e9 que leur v\u00e9hicule marchait fort en caracolant longtemps en t\u00eate du rallye.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2026-autos-classement-et-resultats-1ere-etape\/\">Dakar 2026 Autos \u2013 Classement et r\u00e9sultats 1\u00e8re \u00e9tape<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Mais \u00e0 l&rsquo;image d&rsquo;un <strong>Mattias Ekstr\u00f6m<\/strong> qui a franchi tous les interm\u00e9diaires en t\u00eate, avant de r\u00e9trograder au 4\u00e8me rang \u00e0 l&rsquo;arriv\u00e9e, les \u00e9quipages de l&rsquo;\u00e9curie am\u00e9ricaine ont fait le choix de l\u00e2cher du lest, comme le prouvent \u00e9galement les places finales de <strong>Carlos Sainz<\/strong> (6\u00e8me), <strong>Nani Roma<\/strong> (8\u00e8me) et <strong>Mitch Guthrie<\/strong> (9\u00e8me).<\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e9bastien Loeb<\/strong> (Dacia Sandriders) est aussi rest\u00e9 au chaud aujourd&rsquo;hui en terminant plus ou moins l\u00e0 o\u00f9 il le souhaitait, en 10\u00e8me position. Au contraire, <strong>Nasser Al-Attiyah <\/strong>\u00e9tait en qu\u00eate de victoire, mais le Qatari a d\u00fb s&rsquo;incliner face \u00e0 l&rsquo;\u00e9quipage de ce d\u00e9but de Dakar : <strong>Guillaume De M\u00e9vius <\/strong>et <strong>Mathieu Baumel<\/strong> (X-Raid Team).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u00ab Aujourd&rsquo;hui je savais qu&rsquo;il ne fallait surtout pas gagner la sp\u00e9ciale. Je pr\u00e9f\u00e8re \u00eatre 9e que de l&rsquo;avoir gagn\u00e9e \u00bb, r\u00e9agit S\u00e9bastien Loeb \u00e0 l&rsquo;arriv\u00e9e de l&rsquo;\u00e9tape 1 du Dakar<br \/>\nToutes les r\u00e9actions sur la chaine L\u2019Equipe \u27a1\ufe0f <a href=\"https:\/\/t.co\/bZzATUPkNL\">https:\/\/t.co\/bZzATUPkNL<\/a> <a href=\"https:\/\/t.co\/Us1cJbaTxS\">pic.twitter.com\/Us1cJbaTxS<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/2007777245142646855?ref_src=twsrc%5Etfw\">January 4, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La belle histoire de Guillaume De M\u00e9vius et Mathieu Baumel<\/h2>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0 3\u00e8mes du prologue, le Belge et le Fran\u00e7ais ont atteint leur objectif en d\u00e9crochant une magnifique victoire d&rsquo;\u00e9tape. Une victoire qui rev\u00eat forc\u00e9ment une saveur particuli\u00e8re pour <strong>Mathieu Baumel<\/strong>. Onze mois apr\u00e8s avoir vu la mort en face dans un accident qui l&rsquo;a conduit \u00e0 \u00eatre amput\u00e9 \u00e0 la jambe droite, l&rsquo;ancien quadruple vainqueur de l&rsquo;\u00e9preuve continue d&rsquo;impressionner ses pairs et tous les suiveurs de l&rsquo;\u00e9preuve par son abn\u00e9gation.<\/p>\n<p style=\"text-align: justify;\">Demain, le duo franco-belge va donc ouvrir la route, sans pression. Une t\u00e2che ardue dans une journ\u00e9e qui s&rsquo;annonce d\u00e9j\u00e0 importante pour le classement g\u00e9n\u00e9ral.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2026-autos-classement-general-actualise\/\">Dakar 2026 Autos \u2013 Classement g\u00e9n\u00e9ral actualis\u00e9<\/a><\/strong><\/li>\n<\/ul>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">De Mevius et Baumel remportent l&rsquo;\u00e9tape 1 du Dakar ! <a href=\"https:\/\/twitter.com\/hashtag\/lequipeAUTO?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeAUTO<\/a><\/p>\n<p>Mathieu Baumel, amput\u00e9 de la jambe droite il y a onze mois, signe un retour triomphal et \u00e9mouvant sur la course <a href=\"https:\/\/t.co\/9pA8dLzJVv\">pic.twitter.com\/9pA8dLzJVv<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/2007780412119032043?ref_src=twsrc%5Etfw\">January 4, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-align: justify;\">Derri\u00e8re <strong>De M\u00e9vius<\/strong> et <strong>Al-Attiyah<\/strong>,\u00a0<\/span><strong style=\"text-align: justify;\">Martin Prokop<\/strong><span style=\"text-align: justify;\">\u00a0a lui r\u00e9alis\u00e9 une magnifique performance en compl\u00e9tant le podium du jour malgr\u00e9 son statut de pilote priv\u00e9. \u00c0 noter que les \u00e9carts sont infimes, une quinzaine de pilotes se tenant pour le moment en moins de trois minutes.<\/span><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DAKAR 2026 &#8211; L&rsquo;\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s&rsquo;est offert la victoire sur la 1\u00e8re \u00e9tape.<\/p>\n","protected":false},"author":55,"featured_media":635755,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9493],"tags":[16878,2736],"class_list":["post-635748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dakar","tag-breve","tag-dakar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos<\/title>\n<meta name=\"description\" content=\"DAKAR 2026 - L&#039;\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s&#039;est offert la victoire sur la 1\u00e8re \u00e9tape.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos\" \/>\n<meta property=\"og:description\" content=\"DAKAR 2026 - L&#039;\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s&#039;est offert la victoire sur la 1\u00e8re \u00e9tape.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-04T12:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-04T12:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos\",\"datePublished\":\"2026-01-04T12:00:15+00:00\",\"dateModified\":\"2026-01-04T12:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\"},\"wordCount\":705,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png\",\"keywords\":[\"br\u00e8ve\",\"dakar\"],\"articleSection\":[\"Dakar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\",\"name\":\"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png\",\"datePublished\":\"2026-01-04T12:00:15+00:00\",\"dateModified\":\"2026-01-04T12:09:53+00:00\",\"description\":\"DAKAR 2026 - L'\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s'est offert la victoire sur la 1\u00e8re \u00e9tape.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png\",\"width\":1200,\"height\":674,\"caption\":\"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos","description":"DAKAR 2026 - L'\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s'est offert la victoire sur la 1\u00e8re \u00e9tape.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/","og_locale":"fr_FR","og_type":"article","og_title":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos","og_description":"DAKAR 2026 - L'\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s'est offert la victoire sur la 1\u00e8re \u00e9tape.","og_url":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-01-04T12:00:15+00:00","article_modified_time":"2026-01-04T12:09:53+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos","datePublished":"2026-01-04T12:00:15+00:00","dateModified":"2026-01-04T12:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/"},"wordCount":705,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png","keywords":["br\u00e8ve","dakar"],"articleSection":["Dakar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/","url":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/","name":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png","datePublished":"2026-01-04T12:00:15+00:00","dateModified":"2026-01-04T12:09:53+00:00","description":"DAKAR 2026 - L'\u00e9quipage compos\u00e9 de Guillaume De M\u00e9vius et Mathieu Baumel s'est offert la victoire sur la 1\u00e8re \u00e9tape.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Guillaume-De-Mevius-et-Mathieu-Baumel-frappent-deja-sur-la-1ere-etape-du-Dakar-en-categorie-autos.png","width":1200,"height":674,"caption":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/guillaume-de-mevius-et-mathieu-baumel-frappent-deja-sur-la-1ere-etape-du-dakar-en-categorie-autos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Guillaume De M\u00e9vius et Mathieu Baumel frappent d\u00e9j\u00e0 sur la 1\u00e8re \u00e9tape du Dakar en cat\u00e9gorie autos"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/635748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=635748"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/635748\/revisions"}],"predecessor-version":[{"id":635759,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/635748\/revisions\/635759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/635755"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=635748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=635748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=635748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}