{"id":638137,"date":"2026-01-16T20:35:34","date_gmt":"2026-01-16T19:35:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=638137&#038;preview=true&#038;preview_id=638137"},"modified":"2026-01-16T20:37:47","modified_gmt":"2026-01-16T19:37:47","slug":"psg-lille-compositions-chaine-tv-heure-et-cotes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/","title":{"rendered":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes<\/em><em>.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La rencontre entre le <strong>Paris Saint-Germain<\/strong> et le <strong>Lille OSC<\/strong>, comptant pour la 18\u00e8me journ\u00e9e de Ligue 1 2025\/2026, aura lieu vendredi 16 janvier 2026 \u00e0 21h00, au Parc des Princes, \u00e0 Paris.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2025-2026\/\">Classement Ligue 1 2025-2026<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Paris en danger ?<\/h2>\n<p style=\"text-align: justify;\">Le <strong>Paris Saint-Germain<\/strong> a profit\u00e9 des derni\u00e8res semaines pour garnir encore plus son armoire \u00e0 troph\u00e9es. Fin d\u00e9cembre, les champions de France ont rafl\u00e9 aux tirs au but la <a href=\"https:\/\/dicodusport.fr\/blog\/un-dernier-trophee-pour-le-psg-matvei-safonov-offre-la-coupe-intercontinentale-a-paris-aux-tirs-au-but\/\">Coupe Intercontinentale<\/a>, avant d&rsquo;aller chercher de la m\u00eame mani\u00e8re le Troph\u00e9e des Champions contre l&rsquo;Olympique de Marseille. Mais les Parisiens ont subi un coup d&rsquo;arr\u00eat via une \u00e9limination en Coupe de France contre le Paris FC. Reste \u00e0 savoir \u00e0 quel point cela affectera leur saison.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/lucas-chevalier-decisif-le-psg-eteint-lom-aux-tirs-au-but-et-conserve-son-trophee-des-champions\/\" class=\"vlp-link\" title=\"Lucas Chevalier d\u00e9cisif : le PSG \u00e9teint l\u2019OM aux tirs au but et conserve son Troph\u00e9e des Champions\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Lucas-Chevalier-decisif-le-PSG-eteint-lOM-aux-tirs-au-but-et-conserve-son-Trophee-des-Champions-1.png\" class=\"attachment-800x445 size-800x445\" alt=\"Lucas Chevalier d\u00e9cisif le PSG \u00e9teint l\u2019OM aux tirs au but et conserve son Troph\u00e9e des Champions\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Lucas-Chevalier-decisif-le-PSG-eteint-lOM-aux-tirs-au-but-et-conserve-son-Trophee-des-Champions-1.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Lucas-Chevalier-decisif-le-PSG-eteint-lOM-aux-tirs-au-but-et-conserve-son-Trophee-des-Champions-1-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Lucas-Chevalier-decisif-le-PSG-eteint-lOM-aux-tirs-au-but-et-conserve-son-Trophee-des-Champions-1-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Lucas-Chevalier-decisif-le-PSG-eteint-lOM-aux-tirs-au-but-et-conserve-son-Trophee-des-Champions-1-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Lucas Chevalier d\u00e9cisif : le PSG \u00e9teint l\u2019OM aux tirs au but et conserve son Troph\u00e9e des Champions<\/div><div class=\"vlp-block-1 vlp-link-summary\">L\u2019OM y a cru mais le PSG conserve son titre au terme de la s\u00e9ance de tirs au but (2-2, 4-1 TAB).<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<p style=\"text-align: justify;\"><strong>Lille<\/strong> a \u00e9galement quitt\u00e9 la Coupe de France en 16\u00e8me de finale, logiquement battu \u00e0 Lyon. Mais en Ligue 1, les Dogues sont troisi\u00e8me ex\u00e6quo \u00e0 mi-parcours, et donc parfaitement en course pour une qualification en Ligue des champions. N\u00e9anmoins, ils restent sur une triste d\u00e9faite 0-2 \u00e0 domicile contre Rennes, et s&rsquo;ils s&rsquo;inclinaient ce vendredi soir, ce serait la premi\u00e8re fois de la saison qu&rsquo;ils perdraient trois matchs d&rsquo;affil\u00e9e.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/www.youtube.com\/watch?v=7nupFXI0-gU&amp;pp=ygUJbGlsbGUgUFNH\" class=\"vlp-link\" title=\"Lille 1-1 PSG\" rel=\"nofollow\" target=\"_blank\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/7nupFXI0-gU\/sddefault.jpg\" style=\"max-width: 800px; max-height: 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Lille 1-1 PSG<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">www.youtube.com<\/div><\/div><\/div>\n<p style=\"text-align: justify;\">Au match aller, les deux \u00e9quipes s&rsquo;\u00e9taient quitt\u00e9es sur un nul <strong>1-1<\/strong>. Mais chez les bookmakers, le PSG est logiquement favori de ce choc de la 18\u00e8me journ\u00e9e de Ligue 1.<\/p>\n<h2 style=\"text-align: justify;\">Ligue 1 : Le programme TV de PSG &#8211; Lille<\/h2>\n<h3 style=\"text-align: justify;\">Vendredi 16 janvier 2026<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur beIN SPORTS 1<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 21h00.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les compositions officielles de PSG &#8211; Lille<\/h2>\n<h3 style=\"text-align: justify;\">La composition du PSG<\/h3>\n<p style=\"text-align: justify;\">Chevalier \u2013 Za\u00efre-Emery, Marquinhos, Pacho, Mendes \u2013 Mayulu, Vitinha, Ruiz \u2013 Dou\u00e9, Demb\u00e9l\u00e9, Kvaratskhelia.<\/p>\n<h3 style=\"text-align: justify;\">La composition de Lille<\/h3>\n<p style=\"text-align: justify;\">\u00d6zer &#8211; Tiago Santos, Mandi, Ngoy, Perraud &#8211; Bouaddi, Mukau, Bentaleb &#8211; E.Mbapp\u00e9, Giroud, Haraldsson<\/p>\n<table style=\"width: 840px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; width: 840px; text-align: left;\" colspan=\"3\"><strong><span style=\"font-size: 12px; color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-512842\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png\" alt=\"\" width=\"14\" height=\"13\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax.png 290w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Logo-Winamax-80x80.png 80w\" sizes=\"auto, (max-width: 14px) 100vw, 14px\" \/> Vendredi 16 janvier 2026 21h00<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>PSG<br \/>\n<\/strong><\/span><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526306?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 1.39<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526306?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 4.80<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Paris FC<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/61526306?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#0860ff;border-color:#074dcc;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5390ff;border-radius:5px;text-shadow:none\"> 6.25<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.<\/p>\n","protected":false},"author":59,"featured_media":638164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[44295,47045],"tags":[16878,75,1554,19345,1230,8799],"class_list":["post-638137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaine-tv","category-ligue-1","tag-breve","tag-football","tag-ligue-1","tag-lille-osc","tag-paris-saint-germain","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes<\/title>\n<meta name=\"description\" content=\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes\" \/>\n<meta property=\"og:description\" content=\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T19:35:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T19:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes\",\"datePublished\":\"2026-01-16T19:35:34+00:00\",\"dateModified\":\"2026-01-16T19:37:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\"},\"wordCount\":552,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue 1\",\"Lille OSC\",\"Paris Saint-Germain\",\"Programme TV\"],\"articleSection\":[\"Cha\u00eene TV\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\",\"name\":\"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"datePublished\":\"2026-01-16T19:35:34+00:00\",\"dateModified\":\"2026-01-16T19:37:47+00:00\",\"description\":\"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png\",\"width\":1200,\"height\":674,\"caption\":\"PSG-Lille Compositions, Cha\u00eene TV, Heure et Cotes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes","description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/","og_locale":"fr_FR","og_type":"article","og_title":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes","og_description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","og_url":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-01-16T19:35:34+00:00","article_modified_time":"2026-01-16T19:37:47+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes","datePublished":"2026-01-16T19:35:34+00:00","dateModified":"2026-01-16T19:37:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/"},"wordCount":552,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png","keywords":["br\u00e8ve","Football","Ligue 1","Lille OSC","Paris Saint-Germain","Programme TV"],"articleSection":["Cha\u00eene TV","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/","url":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/","name":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png","datePublished":"2026-01-16T19:35:34+00:00","dateModified":"2026-01-16T19:37:47+00:00","description":"\u00c0 quelle heure et sur quelle cha\u00eene TV suivre le match de Ligue 1 entre le Paris Saint-Germain et le Lille OSC ? Retrouvez \u00e9galement les compositions des deux \u00e9quipes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/PSG-Lille-Compositions-Chaine-TV-Heure-et-Cotes.png","width":1200,"height":674,"caption":"PSG-Lille Compositions, Cha\u00eene TV, Heure et Cotes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/psg-lille-compositions-chaine-tv-heure-et-cotes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"PSG-Lille : Compositions, Cha\u00eene TV, Heure et Cotes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/638137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=638137"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/638137\/revisions"}],"predecessor-version":[{"id":638866,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/638137\/revisions\/638866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/638164"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=638137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=638137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=638137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}