{"id":639983,"date":"2026-01-20T16:23:43","date_gmt":"2026-01-20T15:23:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=639983&#038;preview=true&#038;preview_id=639983"},"modified":"2026-01-21T15:28:52","modified_gmt":"2026-01-21T14:28:52","slug":"penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/","title":{"rendered":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOURNOI DES 6 NATIONS 2026 &#8211; Selon L&rsquo;\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/six-nations-2026-decouvrez-les-42-joueurs-appeles-avec-le-xv-de-france\/\">Six Nations 2026 : d\u00e9couvrez les 42 joueurs appel\u00e9s avec le XV de France<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le Tournoi des 6 Nations 2026 d\u00e9butera le jeudi 5 f\u00e9vrier prochain avec un affrontement entre le <strong>XV de France<\/strong> et l&rsquo;Irlande. Demain matin, la liste des 42 joueurs pour pr\u00e9parer ce premier choc sera annonc\u00e9e par le staff, une \u00e9tape toujours importante pour lancer la mont\u00e9e en puissance. Mais selon <em><a href=\"https:\/\/www.lequipe.fr\/Rugby\/Actualites\/Penaud-et-fickou-pas-retenus-dans-la-liste-des-42-du-xv-de-france-pour-le-tournoi-des-six-nations\/1635103\">L&rsquo;\u00c9quipe<\/a><\/em>, il y aura deux absents de marque pour cette liste.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">INFO L&rsquo;\u00c9QUIPE. Damian Penaud (29 ans, 59 s\u00e9lections) et Ga\u00ebl Fickou (31 ans, 98 s\u00e9lections) ne figureront pas dans le groupe des 42 d\u00e9voil\u00e9 par le s\u00e9lectionneur Fabien Galthi\u00e9 mercredi pour pr\u00e9parer le Tournoi des Six Nations. <a href=\"https:\/\/t.co\/2Hrnmeped9\">https:\/\/t.co\/2Hrnmeped9<\/a> <a href=\"https:\/\/t.co\/5Br150rY10\">pic.twitter.com\/5Br150rY10<\/a><\/p>\n<p>\u2014 L&rsquo;\u00c9quipe (@lequipe) <a href=\"https:\/\/twitter.com\/lequipe\/status\/2013630416276623787?ref_src=twsrc%5Etfw\">January 20, 2026<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Fickou et Penaud sur le carreau<\/h2>\n<p style=\"text-align: justify;\">Le premier d&rsquo;entre eux n&rsquo;est autre que <strong>Damian Penaud<\/strong>. Homme de base du XV de France, il en est tout simplement le meilleur marqueur de son histoire. De plus, il avait inscrit un doubl\u00e9 contre l&rsquo;Afrique du Sud en novembre dernier, \u00e9tant titulaire lors des trois matchs de la Tourn\u00e9e d&rsquo;Automne, et reste de mani\u00e8re g\u00e9n\u00e9rale un finisseur haut de gamme.<\/p>\n<p style=\"text-align: justify;\">Il a cependant d\u00e9j\u00e0 \u00e9t\u00e9 positionn\u00e9 en rempla\u00e7ant, ou m\u00eame hors des 23, mais ne pas le voir dans une liste des 42 interpelle au plus haut point : simple test ou malaise plus profond ? Une certaine incompr\u00e9hension flotte dans l&rsquo;air, m\u00eame s&rsquo;il existe un certain r\u00e9servoir \u00e0 son poste, avec des joueurs comme <strong>Th\u00e9o Attissogbe<\/strong> par exemple.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-top-10-des-meilleurs-marqueurs-dessais-de-lhistoire\/\">XV de France : Top 10 des meilleurs marqueurs d\u2019essais de l\u2019histoire<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Tout comme au sujet de l&rsquo;autre absent de marque : <strong>Ga\u00ebl Fickou<\/strong>. Le cas avait d\u00e9j\u00e0 fait parler \u00e0 l&rsquo;automne. Titulaire et capitaine contre les Springboks, il avait purement et simplement disparu des 23 contre les Fidji, avant de revenir dans le XV de d\u00e9part face \u00e0 l&rsquo;Australie, mais sans le brassard. Lui aussi est un homme fort du syst\u00e8me <strong>Galthi\u00e9<\/strong>, qui l&rsquo;a souvent maintenu comme titulaire malgr\u00e9 des critiques et une forte concurrence au centre.<\/p>\n<p style=\"text-align: justify;\">Le laisser aux portes des 42 envoie donc un message curieux. Rendez-vous demain matin pour avoir la liste officielle, mais deux absences de ce calibre ne vont clairement pas manquer de faire parler, alors que les Bleus seront d\u00e9j\u00e0 priv\u00e9s de certains cadres comme <strong>Romain Ntamack, <a href=\"https:\/\/dicodusport.fr\/blog\/coup-dur-pour-maxime-lucu-tournoi-des-6-nations-compromis-pour-le-demi-de-melee-de-lubb\/\">Maxime Lucu<\/a><\/strong> ou<strong> Nolann Le Garrec<\/strong>, ainsi que de <strong>Gr\u00e9gory Alldritt<\/strong>&#8230;<\/p>\n<h3 style=\"text-align: justify;\">\u00c0 lire aussi<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/un-cadre-du-xv-de-france-de-plus-sur-la-touche-gregory-alldritt-lui-aussi-hors-de-la-liste-pour-le-6-nations\/\" class=\"vlp-link\" title=\"Un cadre du XV de France de plus sur la touche : Gr\u00e9gory Alldritt lui aussi hors de la liste pour le 6 Nations\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-cadre-du-XV-de-France-de-plus-sur-la-touche-Gregory-Alldritt-lui-aussi-hors-de-la-liste-pour-le-6-Nations.png\" class=\"attachment-800x445 size-800x445\" alt=\"Un cadre du XV de France de plus sur la touche : Gr\u00e9gory Alldritt lui aussi hors de la liste pour le 6 Nations\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-cadre-du-XV-de-France-de-plus-sur-la-touche-Gregory-Alldritt-lui-aussi-hors-de-la-liste-pour-le-6-Nations.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-cadre-du-XV-de-France-de-plus-sur-la-touche-Gregory-Alldritt-lui-aussi-hors-de-la-liste-pour-le-6-Nations-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-cadre-du-XV-de-France-de-plus-sur-la-touche-Gregory-Alldritt-lui-aussi-hors-de-la-liste-pour-le-6-Nations-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-cadre-du-XV-de-France-de-plus-sur-la-touche-Gregory-Alldritt-lui-aussi-hors-de-la-liste-pour-le-6-Nations-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Un cadre du XV de France de plus sur la touche : Gr\u00e9gory Alldritt lui aussi hors de la liste pour le 6 Nations<\/div><div class=\"vlp-block-1 vlp-link-summary\">TOURNOI DES 6 NATIONS 2026 \u2013 Selon Sud Ouest, Gr\u00e9gory Alldritt ne sera pas dans la liste du XV de France annonc\u00e9e demain.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TOURNOI DES 6 NATIONS 2026 &#8211; Selon L&rsquo;\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":639984,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47048,19951],"tags":[16878,7689,6704,9734,1638],"class_list":["post-639983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tournoi-des-6-nations","category-xv-de-france","tag-breve","tag-damian-penaud","tag-gael-fickou","tag-tournoi-des-6-nations","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !<\/title>\n<meta name=\"description\" content=\"TOURNOI DES 6 NATIONS 2026 - Selon L&#039;\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !\" \/>\n<meta property=\"og:description\" content=\"TOURNOI DES 6 NATIONS 2026 - Selon L&#039;\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T15:23:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T14:28:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !\",\"datePublished\":\"2026-01-20T15:23:43+00:00\",\"dateModified\":\"2026-01-21T14:28:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\"},\"wordCount\":571,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png\",\"keywords\":[\"br\u00e8ve\",\"Damian Penaud\",\"Ga\u00ebl Fickou\",\"Tournoi des 6 Nations\",\"XV de France\"],\"articleSection\":[\"Tournoi des 6 Nations\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\",\"name\":\"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png\",\"datePublished\":\"2026-01-20T15:23:43+00:00\",\"dateModified\":\"2026-01-21T14:28:52+00:00\",\"description\":\"TOURNOI DES 6 NATIONS 2026 - Selon L'\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png\",\"width\":1200,\"height\":674,\"caption\":\"Penaud et Fickou \u00e9cart\u00e9s la liste du XV de France pour le 6 Nations va faire parler !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !","description":"TOURNOI DES 6 NATIONS 2026 - Selon L'\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/","og_locale":"fr_FR","og_type":"article","og_title":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !","og_description":"TOURNOI DES 6 NATIONS 2026 - Selon L'\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2026-01-20T15:23:43+00:00","article_modified_time":"2026-01-21T14:28:52+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !","datePublished":"2026-01-20T15:23:43+00:00","dateModified":"2026-01-21T14:28:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/"},"wordCount":571,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png","keywords":["br\u00e8ve","Damian Penaud","Ga\u00ebl Fickou","Tournoi des 6 Nations","XV de France"],"articleSection":["Tournoi des 6 Nations","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/","url":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/","name":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png","datePublished":"2026-01-20T15:23:43+00:00","dateModified":"2026-01-21T14:28:52+00:00","description":"TOURNOI DES 6 NATIONS 2026 - Selon L'\u00c9quipe, Damian Penaud et Ga\u00ebl Fickou ne feront pas partie de la liste du XV de France annonc\u00e9e demain.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Penaud-et-Fickou-ecartes-la-liste-du-XV-de-France-pour-le-6-Nations-va-faire-parler-.png","width":1200,"height":674,"caption":"Penaud et Fickou \u00e9cart\u00e9s la liste du XV de France pour le 6 Nations va faire parler !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/penaud-et-fickou-ecartes-la-liste-du-xv-de-france-pour-le-6-nations-va-faire-parler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Penaud et Fickou \u00e9cart\u00e9s : la liste du XV de France pour le 6 Nations va faire parler !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/639983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=639983"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/639983\/revisions"}],"predecessor-version":[{"id":640219,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/639983\/revisions\/640219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/639984"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=639983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=639983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=639983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}