{"id":640192,"date":"2026-01-21T21:20:26","date_gmt":"2026-01-21T20:20:26","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=640192&#038;preview=true&#038;preview_id=640192"},"modified":"2026-01-28T21:03:10","modified_gmt":"2026-01-28T20:03:10","slug":"les-flammes-carolo-soffrent-bourges-en-euroligue","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/","title":{"rendered":"Les Flammes Carolo s&rsquo;offrent Bourges en EuroLigue"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>EUROLIGUE FEMMES 2025\/2026 &#8211; Devant de bout en bout, les Flammes Carolo n&rsquo;ont pas laiss\u00e9 de chance \u00e0 Bourges et s&rsquo;imposent 65-59.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s leur d\u00e9faite \u00e0 Prague, les <strong>Flammes Carolo\u00a0<\/strong>ont encha\u00een\u00e9 avec une d\u00e9faite rageante en quarts de finale de la Coupe de France face \u00e0 Basket Landes. D\u00e9j\u00e0 \u00e9limin\u00e9es de la comp\u00e9tition, les joueuses de Romuald Yernaux ont tout de m\u00eame encore 3 matchs \u00e0 jouer. Et le premier face \u00e0 Bourges, qui les avait battues il y a 10 jours en championnat. Pour le\u00a0<strong>Tango Bourges Basket<\/strong>, l&rsquo;enjeu est tout autre puisque le club \u00e9tait 3\u00e8me avant la rencontre et avait pour objectif de se qualifier pour le Final 6.<\/p>\n<h2 style=\"text-align: justify;\">Prague assomme les Flammes \u00e0 3 points<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s un d\u00e9but de match qui a vu les joueuses \u00eatre maladroites de part et d&rsquo;autre,\u00a0<strong>Prague<\/strong>, men\u00e9 par la Fran\u00e7aise <strong>Val\u00e9riane Ayayi<\/strong>, s&rsquo;est cr\u00e9\u00e9 un petit \u00e9cart. Les locales d\u00e9montraient d\u00e9j\u00e0 leur agilit\u00e9 \u00e0 3 points. En revanche, pas de r\u00e9ussite pour les visiteuses longue distance et elles \u00e9taient bien d\u00e9fendues sous le panier. Si on ajoute \u00e0 cela des rat\u00e9s sur la ligne des lancers francs, l&rsquo;addition devient sal\u00e9e. Prague peut asseoir sa domination sur le match et poursuivre son festival \u00e0 3 points.<\/p>\n<p style=\"text-align: justify;\">Malgr\u00e9 deux points inscrits en sortie de temps mort, les Flammes sont rest\u00e9es bloqu\u00e9es \u00e0 6 points pendant 4 minutes. Un tir en d\u00e9s\u00e9quilibre au buzzer de <strong>Lucile J\u00e9r\u00f4me<\/strong> va leur permettre d&rsquo;inscrire 3 points suppl\u00e9mentaire (29-9). Apr\u00e8s ce premier quart-temps, Prague peut se vanter d&rsquo;un \u00e9norme <strong>8\/11 (72%) \u00e0 3 points<\/strong> contre 1\/8 (12%).<\/p>\n<h2 style=\"text-align: justify;\">Pas de r\u00e9action des Flammes<\/h2>\n<p style=\"text-align: justify;\">Malheureusement, le d\u00e9but de deuxi\u00e8me quart-temps sera du m\u00eame acabit. Malgr\u00e9 les \u00e9checs sur la ligne des lancers francs et les quelques paniers laiss\u00e9s en route, Prague continue de d\u00e9rouler. \u00c0 cela se rajoutent des fautes qui offrent des munitions aux locales : 54-21 \u00e0 la mi-temps. La diff\u00e9rence \u00e9tait faite et les Flammes Carolo n&rsquo;ont pu que constater leur impuissance lors des 20 minutes suivantes. En manque de r\u00e9ussite au tir, les Flammes Carolo auront vu leurs adversaires \u00eatre \u00e9tincelantes (64%), notamment \u00e0 3 points (61% \u00e0 17\/28). La Fran\u00e7aise\u00a0<strong>Janelle Sala\u00fcn\u00a0<\/strong>(21 points) aura bien \u00e9paul\u00e9\u00a0<strong>Bridget Carleton\u00a0<\/strong>qui a \u00e9tabli un nouveau record dans la comp\u00e9tition en inscrivant 9 paniers \u00e0 3 points !<\/p>\n<p style=\"text-align: justify;\">Prochain rencontre face \u00e0 <strong>Bourges\u00a0<\/strong>la semaine prochaine.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">REWRITING HISTORY \u270d\ufe0f<\/p>\n<p>Bridget Carleton set a new <a href=\"https:\/\/twitter.com\/hashtag\/EuroLeagueWomen?src=hash&amp;ref_src=twsrc%5Etfw\">#EuroLeagueWomen<\/a> record with 9 three-pointers tonight \ud83e\udd2f\ud83d\udcda <a href=\"https:\/\/t.co\/Yh2si5VRuu\">pic.twitter.com\/Yh2si5VRuu<\/a><\/p>\n<p>\u2014 EuroLeague Women (@EuroLeagueWomen) <a href=\"https:\/\/twitter.com\/EuroLeagueWomen\/status\/2011528240884834731?ref_src=twsrc%5Etfw\">January 14, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE FEMMES 2025\/2026 &#8211; Devant de bout en bout, les Flammes Carolo n&rsquo;ont pas laiss\u00e9 de chance \u00e0 Bourges et s&rsquo;imposent 65-59.<\/p>\n","protected":false},"author":12,"featured_media":640290,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47001],"tags":[16878,28850,38116,22243,27824,28729],"class_list":["post-640192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-breve","tag-euroleague-femmes","tag-euroleague-women","tag-euroligue-feminine","tag-euroligue-femmes","tag-flammes-carolo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Flammes Carolo s&#039;offrent Bourges en EuroLigue<\/title>\n<meta name=\"description\" content=\"EUROLIGUE FEMMES 2025\/2026 - Devant de bout en bout, les Flammes Carolo n&#039;ont pas laiss\u00e9 de chance \u00e0 Bourges et s&#039;imposent 65-59.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Flammes Carolo s&#039;offrent Bourges en EuroLigue\" \/>\n<meta property=\"og:description\" content=\"EUROLIGUE FEMMES 2025\/2026 - Devant de bout en bout, les Flammes Carolo n&#039;ont pas laiss\u00e9 de chance \u00e0 Bourges et s&#039;imposent 65-59.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T20:20:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T20:03:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Les Flammes Carolo s&rsquo;offrent Bourges en EuroLigue\",\"datePublished\":\"2026-01-21T20:20:26+00:00\",\"dateModified\":\"2026-01-28T20:03:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png\",\"keywords\":[\"br\u00e8ve\",\"Euroleague Femmes\",\"Euroleague women\",\"euroligue f\u00e9minine\",\"EuroLigue Femmes\",\"Flammes Carolo\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/\",\"name\":\"Les Flammes Carolo s'offrent Bourges en EuroLigue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png\",\"datePublished\":\"2026-01-21T20:20:26+00:00\",\"dateModified\":\"2026-01-28T20:03:10+00:00\",\"description\":\"EUROLIGUE FEMMES 2025\\\/2026 - Devant de bout en bout, les Flammes Carolo n'ont pas laiss\u00e9 de chance \u00e0 Bourges et s'imposent 65-59.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Flammes Carolo s'offrent Bourges en EuroLigue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-flammes-carolo-soffrent-bourges-en-euroligue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Flammes Carolo s&rsquo;offrent Bourges en EuroLigue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Shiclette94\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/arlette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Flammes Carolo s'offrent Bourges en EuroLigue","description":"EUROLIGUE FEMMES 2025\/2026 - Devant de bout en bout, les Flammes Carolo n'ont pas laiss\u00e9 de chance \u00e0 Bourges et s'imposent 65-59.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Flammes Carolo s'offrent Bourges en EuroLigue","og_description":"EUROLIGUE FEMMES 2025\/2026 - Devant de bout en bout, les Flammes Carolo n'ont pas laiss\u00e9 de chance \u00e0 Bourges et s'imposent 65-59.","og_url":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-01-21T20:20:26+00:00","article_modified_time":"2026-01-28T20:03:10+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Les Flammes Carolo s&rsquo;offrent Bourges en EuroLigue","datePublished":"2026-01-21T20:20:26+00:00","dateModified":"2026-01-28T20:03:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png","keywords":["br\u00e8ve","Euroleague Femmes","Euroleague women","euroligue f\u00e9minine","EuroLigue Femmes","Flammes Carolo"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/","url":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/","name":"Les Flammes Carolo s'offrent Bourges en EuroLigue","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png","datePublished":"2026-01-21T20:20:26+00:00","dateModified":"2026-01-28T20:03:10+00:00","description":"EUROLIGUE FEMMES 2025\/2026 - Devant de bout en bout, les Flammes Carolo n'ont pas laiss\u00e9 de chance \u00e0 Bourges et s'imposent 65-59.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Flammes-Carolo-soffrent-Bourges-en-EuroLigue.png","width":1200,"height":674,"caption":"Les Flammes Carolo s'offrent Bourges en EuroLigue"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-flammes-carolo-soffrent-bourges-en-euroligue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Flammes Carolo s&rsquo;offrent Bourges en EuroLigue"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=640192"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640192\/revisions"}],"predecessor-version":[{"id":642261,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640192\/revisions\/642261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/640290"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=640192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=640192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=640192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}