{"id":640231,"date":"2026-01-21T17:49:15","date_gmt":"2026-01-21T16:49:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=640231&#038;preview=true&#038;preview_id=640231"},"modified":"2026-01-21T18:08:07","modified_gmt":"2026-01-21T17:08:07","slug":"les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/","title":{"rendered":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>EURO MASCULIN DE FUTSAL 2026 &#8211; D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un match nul contre la Croatie (2-2).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Il y aura forc\u00e9ment un peu de regrets pour les Fran\u00e7ais, qui ont vite r\u00e9agi apr\u00e8s l\u2019ouverture du score croate, menant m\u00eame au score apr\u00e8s une premi\u00e8re p\u00e9riode pourtant domin\u00e9e globalement par leurs adversaires. Sc\u00e9nario inverse en seconde p\u00e9riode. Alors qu\u2019ils ma\u00eetrisaient mieux les d\u00e9bats, les Bleus ont \u00e9t\u00e9 saisis par <strong>Kustura<\/strong>, qui a sign\u00e9 un doubl\u00e9 pour tenir le nul 2-2.<\/p>\n<h2 style=\"text-align: justify;\">Les Bleus m\u00e8nent\u2026 contre le cours du jeu<\/h2>\n<p style=\"text-align: justify;\">Entr\u00e9s timidement dans leur Euro, les Bleus ont pass\u00e9 beaucoup de temps \u00e0 d\u00e9fendre dans les premi\u00e8res minutes. Et c\u2019est finalement <strong>Francis Lokoka<\/strong> qui \u00e9tait le plus en vue c\u00f4t\u00e9 tricolore apr\u00e8s plusieurs alertes croates. Le portier a repouss\u00e9 le plus longtemps possible l\u2019ouverture du score mais <strong>Duje Kustura<\/strong> a puni les impr\u00e9cisions techniques fran\u00e7aises (13\u203210). En d\u00e9licatesse pour se projeter, les Bleus n\u2019avaient alors que peu mis \u00e0 l\u2019\u00e9preuve <strong>Piplica<\/strong>, \u00e0 l\u2019image d\u2019<strong>Abdessamad Mohammed<\/strong>. Le pivot et meilleur buteur de la s\u00e9lection nationale \u00e9tait bien verrouill\u00e9 et peu aliment\u00e9 par ses partenaires.<\/p>\n<p style=\"text-align: justify;\">Mais le but croate avait l\u2019avantage de r\u00e9veiller les hommes de <strong>Rapha\u00ebl Reynaud<\/strong>. Moins de deux minutes plus tard, <strong>Mamadou Tour\u00e9<\/strong> n\u2019a eu besoin de personne pour \u00e9galiser. Remontant le terrain en solitaire c\u00f4t\u00e9 gauche, il ajustait le gardien et ouvrait parfaitement son pied (1-1). En confiance, les Bleus ont rendu le pressing \u00e0 leurs adversaires et les ont pouss\u00e9s \u00e0 la faute. Sur une relance plein axe, <strong>Ouassini Guirio<\/strong> interceptait le cuir, fixait <strong>Piplica<\/strong> et doublait la mise. Loin de dominer les d\u00e9bats, l\u2019\u00e9quipe de France r\u00e9alisait le bon coup apr\u00e8s 20 minutes.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udd25 Il a remont\u00e9 tout le terrain pour \u00e9galiser : quel but de Mamadou Tour\u00e9 !<\/p>\n<p>Suivez le match en direct sur la chaine L\u2019\u00c9quipe <a href=\"https:\/\/twitter.com\/hashtag\/lequipeFUTSAL?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeFUTSAL<\/a> <a href=\"https:\/\/t.co\/qe6NtJjSf6\">pic.twitter.com\/qe6NtJjSf6<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/2013998894976237636?ref_src=twsrc%5Etfw\">January 21, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La Croatie \u00e9galise\u2026 contre le cours du jeu<\/h2>\n<p style=\"text-align: justify;\">Malheureusement \u00e7a ne tiendra pas pour les Bleus. Pourtant plus entreprenants en deuxi\u00e8me p\u00e9riode, ils ne parvenaient pas \u00e0 se mettre davantage \u00e0 l\u2019abri. En manque de finition, ils s\u2019exposaient aux contres croates. Et \u00e7a ne manquait pas. La frappe d\u2019<strong>Antonio Sekulic<\/strong> \u00e9tait l\u00e9g\u00e8rement d\u00e9tourn\u00e9e par <strong>Kustura<\/strong>, encore lui. Assez pour surprendre <strong>Lokoka<\/strong> (34\u2032). Le K.O pouvait tomber \u00e0 tout moment de part et d\u2019autre mais finalement Fran\u00e7ais et Croates n\u2019arrivaient pas \u00e0 se d\u00e9partager. L\u2019ultime tentative de Tour\u00e9 ne trouvait pas le cadre. C\u2019est cette mire qu\u2019il faudra r\u00e9gler lors de la 2<sup>\u00e8me<\/sup> journ\u00e9e face \u00e0 la Lettonie.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Nos Bleus d\u00e9crochent 1 point dans ce match d\u2019ouverture de l\u2019Euro Futsal face \u00e0 la Croatie \ud83c\udded\ud83c\uddf7<\/p>\n<p>\ud83d\udd1c Prochain match dimanche contre la Lettonie \ud83d\udcaa <a href=\"https:\/\/t.co\/d1JZDcYQyp\">pic.twitter.com\/d1JZDcYQyp<\/a><\/p>\n<p>\u2014 FFF (@FFF) <a href=\"https:\/\/twitter.com\/FFF\/status\/2014018015268917339?ref_src=twsrc%5Etfw\">January 21, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3>Dicodusport vous conseille<\/h3>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/un-nouveau-statut-a-confirmer-pour-les-bleus-du-futsal-a-leuro\/\" class=\"vlp-link\" title=\"Un nouveau statut \u00e0 confirmer pour les Bleus du futsal \u00e0 l\u2019Euro\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-nouveau-statut-a-confirmer-pour-les-Bleus-du-futsal-a-lEuro.png\" class=\"attachment-800x445 size-800x445\" alt=\"Un nouveau statut \u00e0 confirmer pour les Bleus du futsal \u00e0 l\u2019Euro\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-nouveau-statut-a-confirmer-pour-les-Bleus-du-futsal-a-lEuro.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-nouveau-statut-a-confirmer-pour-les-Bleus-du-futsal-a-lEuro-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-nouveau-statut-a-confirmer-pour-les-Bleus-du-futsal-a-lEuro-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Un-nouveau-statut-a-confirmer-pour-les-Bleus-du-futsal-a-lEuro-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Un nouveau statut \u00e0 confirmer pour les Bleus du futsal \u00e0 l\u2019Euro<\/div><div class=\"vlp-block-1 vlp-link-summary\">FUTSAL - Engag\u00e9s dans le deuxi\u00e8me Championnat d\u2019Europe de leur histoire, les Bleus ne se fixent aucune limite et attaqueront avec ambition la comp\u00e9tition en Lettonie le 21 janvier prochain.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\" style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>EURO MASCULIN DE FUTSAL 2026 &#8211; D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).<\/p>\n","protected":false},"author":18,"featured_media":640252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[15138],"tags":[16878,47385,47386],"class_list":["post-640231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futsal","tag-breve","tag-euro-futsal","tag-france-futsal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie<\/title>\n<meta name=\"description\" content=\"EURO MASCULIN DE FUTSAL 2026 - D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie\" \/>\n<meta property=\"og:description\" content=\"EURO MASCULIN DE FUTSAL 2026 - D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-21T16:49:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T17:08:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie\",\"datePublished\":\"2026-01-21T16:49:15+00:00\",\"dateModified\":\"2026-01-21T17:08:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/\"},\"wordCount\":608,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png\",\"keywords\":[\"br\u00e8ve\",\"Euro futsal\",\"France futsal\"],\"articleSection\":[\"Futsal\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/\",\"name\":\"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png\",\"datePublished\":\"2026-01-21T16:49:15+00:00\",\"dateModified\":\"2026-01-21T17:08:07+00:00\",\"description\":\"EURO MASCULIN DE FUTSAL 2026 - D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png\",\"width\":1200,\"height\":674,\"caption\":\"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie","description":"EURO MASCULIN DE FUTSAL 2026 - D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie","og_description":"EURO MASCULIN DE FUTSAL 2026 - D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).","og_url":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2026-01-21T16:49:15+00:00","article_modified_time":"2026-01-21T17:08:07+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie","datePublished":"2026-01-21T16:49:15+00:00","dateModified":"2026-01-21T17:08:07+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/"},"wordCount":608,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png","keywords":["br\u00e8ve","Euro futsal","France futsal"],"articleSection":["Futsal"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/","url":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/","name":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png","datePublished":"2026-01-21T16:49:15+00:00","dateModified":"2026-01-21T17:08:07+00:00","description":"EURO MASCULIN DE FUTSAL 2026 - D\u00e9but de comp\u00e9tition timide pour les Fran\u00e7ais, qui d\u00e9butent avec un nul contre la Croatie (2-2).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Les-Bleus-du-futsal-lancent-leur-Euro-avec-un-nul-contre-la-Croatie.png","width":1200,"height":674,"caption":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-bleus-du-futsal-lancent-leur-euro-avec-un-nul-contre-la-croatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Bleus du futsal lancent leur Euro avec un nul contre la Croatie"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=640231"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640231\/revisions"}],"predecessor-version":[{"id":640262,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640231\/revisions\/640262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/640252"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=640231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=640231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=640231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}