{"id":640254,"date":"2026-02-03T18:00:27","date_gmt":"2026-02-03T17:00:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=640254&#038;preview=true&#038;preview_id=640254"},"modified":"2026-02-04T16:13:31","modified_gmt":"2026-02-04T15:13:31","slug":"ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/","title":{"rendered":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&rsquo;hiver 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 voir \u00e9galement : <a href=\"https:\/\/dicodusport.fr\/blog\/jo-dhiver-2026-modes-de-qualification-et-francais-qualifies-sport-par-sport\/\">JO d\u2019hiver 2026 : Les Fran\u00e7ais qualifi\u00e9s, sport par sport<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Matias Roche (ski big air)<\/h2>\n<p style=\"text-align: justify;\">Si <strong>Romain Allemand<\/strong> se positionne comme un candidat de plus en plus cr\u00e9dible \u00e0 la m\u00e9daille en snowboard, en big air comme en slopestyle, <a href=\"https:\/\/dicodusport.fr\/blog\/romain-allemand-slopestyle-vainqueur-pour-la-premiere-fois-en-coupe-du-monde-a-trois-semaines-des-jeux-olympiques\/\">apr\u00e8s sa premi\u00e8re victoire en Coupe du monde mi-janvier<\/a>, l\u2019ambition est un peu plus mesur\u00e9e en ski. Pourtant, <strong>Matias Roche<\/strong> pourrait bien cr\u00e9er la surprise. Arriv\u00e9 tardivement sur le circuit de Coupe du monde, le jeune Fran\u00e7ais tourne autour d\u2019un gros r\u00e9sultat au plus haut niveau. Sa d\u00e9couverte des championnats du monde l\u2019an dernier a confirm\u00e9 son potentiel, comme en atteste sa huiti\u00e8me place en big air, discipline sur laquelle il sera le plus attendu.<\/p>\n<p style=\"text-align: justify;\">Cette ann\u00e9e, <strong>Roche<\/strong> s\u2019est distingu\u00e9 en big air en remportant les qualifications de deux des trois Coupes du monde disput\u00e9es (et en terminant cinqui\u00e8me de la troisi\u00e8me). En revanche, il n\u2019a pas encore trouv\u00e9 la solution pour concr\u00e9tiser en finale. \u00c0 la diff\u00e9rence des qualifications, o\u00f9 seul le meilleur run est comptabilis\u00e9, la finale fonctionne sur l\u2019addition des deux meilleurs runs sur trois.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">ROMAIN ALLEMAND DEVIENT LE PREMIER FRANCAIS VAINQUEUR SUR UNE COUPE DU MONDE DE SNOWBOARD SLOPESTYLE ! \ud83c\uddeb\ud83c\uddf7\ud83e\udd47\ud83c\udfc2<\/p>\n<p>Le Fran\u00e7ais a assomm\u00e9 la concurrence avec un run somptueux ! Il signe sa premi\u00e8re victoire en carri\u00e8re et son troisi\u00e8me podium en 10 d\u00e9parts !<\/p>\n<p>(vid\u00e9o FIS Snowboarding) <a href=\"https:\/\/t.co\/D2TFPjfIDZ\">pic.twitter.com\/D2TFPjfIDZ<\/a><\/p>\n<p>\u2014 Victor CLOT-AMIOT (@VictorClotAmiot) <a href=\"https:\/\/twitter.com\/VictorClotAmiot\/status\/2012889634133491832?ref_src=twsrc%5Etfw\">January 18, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/matias-roche-ski-freestyle-a-la-veille-de-sa-finale-en-coupe-du-monde-si-on-peut-aller-chercher-une-medaille-on-y-va\/\">Plus t\u00f4t dans la saison, il nous confiait d\u2019ailleurs \u00eatre plus \u00e0 l\u2019aise sur le format des qualifications<\/a>, se sentant plus libre de tout donner sur un run. S\u2019il a tout pour cr\u00e9er la surprise \u00e0 Livigno dans quelques jours, il devra toutefois trouver les cl\u00e9s : aux Jeux, contrairement \u00e0 ce qui s\u2019est fait cette saison en Coupe du monde, les qualifications se disputeront selon le format des finales.<\/p>\n<p style=\"text-align: justify;\">Chez les femmes, on surveillera \u00e9galement <strong>Kim Dumont-Zanella<\/strong> (deux finales en big air sur les deux derni\u00e8res comp\u00e9titions). Elle aura cependant fort \u00e0 faire, puisqu\u2019elle devrait notamment \u00eatre oppos\u00e9e \u00e0 la championne olympique en titre <strong>Eileen Gu<\/strong> et \u00e0 <strong>Mathilde Gremaud<\/strong>, m\u00e9daill\u00e9e de bronze. Les deux femmes n\u2019\u00e9taient d\u2019ailleurs pas pr\u00e9sentes lors des finales disput\u00e9es par la Fran\u00e7aise.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/jo-2026-a-milan-cortina-les-chances-de-medailles-de-la-france\/\" class=\"vlp-link\" title=\"JO 2026 \u00e0 Milan-Cortina : les chances de m\u00e9dailles de la France\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-2026-a-Milan-Cortina-les-chances-de-medailles-de-la-France.png\" class=\"attachment-800x445 size-800x445\" alt=\"JO 2026 \u00e0 Milan-Cortina les chances de m\u00e9dailles de la France\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-2026-a-Milan-Cortina-les-chances-de-medailles-de-la-France.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-2026-a-Milan-Cortina-les-chances-de-medailles-de-la-France-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-2026-a-Milan-Cortina-les-chances-de-medailles-de-la-France-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-2026-a-Milan-Cortina-les-chances-de-medailles-de-la-France-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">JO 2026 \u00e0 Milan-Cortina : les chances de m\u00e9dailles de la France<\/div><div class=\"vlp-block-1 vlp-link-summary\">\u00c0 l\u2019approche des JO 2026 \u00e0 Milan-Cortina, tour d\u2019horizon des meilleures chances de m\u00e9dailles fran\u00e7aises et des athl\u00e8tes \u00e0 suivre durant les Jeux.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Romane Miradoli et les g\u00e9antistes messieurs (ski alpin)<\/h2>\n<p style=\"text-align: justify;\">Si nous les avons cit\u00e9s parmi les paris de la r\u00e9daction, voir un g\u00e9antiste fran\u00e7ais monter sur la bo\u00eete repr\u00e9senterait malgr\u00e9 tout une surprise. Bien que <a href=\"https:\/\/dicodusport.fr\/blog\/marco-odermatt-dompte-la-tempete-lors-du-geant-dadelboden-leo-anguenot-retrouve-le-podium\/\"><strong>L\u00e9o Anguenot<\/strong> ait termin\u00e9 troisi\u00e8me \u00e0 Adelboden<\/a> en janvier, tout comme <strong>Alban Elezi Cannaferina<\/strong> plus r\u00e9cemment, il n\u2019y a actuellement aucun Fran\u00e7ais dans le top 10 du classement g\u00e9n\u00e9ral de la discipline.<\/p>\n<p style=\"text-align: justify;\">Les deux hommes ne seront \u00e9videmment pas favoris dans une \u00e9preuve domin\u00e9e par <strong>Marco Odermatt<\/strong>, mais joueront leur carte sans complexe pour tenter de cr\u00e9er la surprise, \u00e0 l\u2019image de <strong>Steve Missillier<\/strong>, m\u00e9daill\u00e9 d\u2019argent en 2014, ou de <strong>Mathieu Faivre<\/strong>, en bronze en 2022. <strong>Alban Elezi Cannaferina<\/strong> devrait \u00e9galement \u00eatre au d\u00e9part de la descente et du super-G.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L\u00e9o Anguenot \u00e9norme \u00e0 Adelboden \ud83e\udd49<\/p>\n<p>Quatri\u00e8me apr\u00e8s la premi\u00e8re manche, notre skieur tricolore fait le troisi\u00e8me temps de la seconde et d\u00e9croche son deuxi\u00e8me podium en Coupe du monde \ud83c\uddeb\ud83c\uddf7\ud83d\udd25<a href=\"https:\/\/t.co\/xPH2N6Jroq\">pic.twitter.com\/xPH2N6Jroq<\/a><\/p>\n<p>\u2014 Equipe France (@EquipeFRA) <a href=\"https:\/\/twitter.com\/EquipeFRA\/status\/2009982453629497441?ref_src=twsrc%5Etfw\">January 10, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Romane Miradoli<\/strong>, quant \u00e0 elle, semble produire son meilleur ski cet hiver. La Fran\u00e7aise sera particuli\u00e8rement attendue en super-G, o\u00f9 elle tentera de cr\u00e9er la surprise en devenant la premi\u00e8re skieuse tricolore m\u00e9daill\u00e9e depuis <strong>Carole Merle<\/strong> en 1992. Bien qu\u2019elle ne soit pas favorite, elle a prouv\u00e9 cette saison qu\u2019elle pouvait se m\u00ealer \u00e0 la lutte avec les meilleures, comme en t\u00e9moignent <a href=\"https:\/\/dicodusport.fr\/blog\/romane-miradoli-soffre-un-superbe-podium-en-super-g-a-saint-moritz-alice-robinson-domine-les-favorites\/\">sa deuxi\u00e8me place \u00e0 Saint-Moritz<\/a> et sa quatri\u00e8me \u00e0 Tarvisio mi-janvier. En descente, la t\u00e2che sera sans doute plus ardue, mais ses deux tops 10 en cinq descentes cette saison peuvent lui permettre de r\u00eaver.<\/p>\n<h2 style=\"text-align: justify;\">Benjamin Cavet (ski de bosses)<\/h2>\n<p style=\"text-align: justify;\">Il y a quatre ans, \u00e0 P\u00e9kin, <strong>Benjamin Cavet<\/strong> abordait les Jeux Olympiques avec une \u00e9tiquette d\u2019outsider. Le Fran\u00e7ais arrivait en forme, fort d\u2019un podium \u00e0 Idre Fj\u00e4ll en d\u00e9but d\u2019hiver et de plusieurs tops 10. Cette fois-ci, la donne est diff\u00e9rente. Malgr\u00e9 une septi\u00e8me place lors de l\u2019\u00e9preuve d\u2019ouverture \u00e0 Ruka en d\u00e9but de saison, <strong>Cavet<\/strong> est \u00e0 la peine, la faute \u00e0 une blessure au talon remontant \u00e0 f\u00e9vrier dernier. De fait, le natif de Maidstone, au Royaume-Uni, avance pas \u00e0 pas. Une seizi\u00e8me place, une quarante-cinqui\u00e8me et une vingt-neuvi\u00e8me sur une \u00e9preuve de parall\u00e8le : pas de quoi s\u2019extasier.<\/p>\n<p style=\"text-align: justify;\">Pour autant, il n\u2019y a pas lieu de s\u2019inqui\u00e9ter. L\u2019objectif \u00e9tant les Jeux Olympiques, l\u2019id\u00e9e \u00e9tait avant tout de reprendre des marques et de tester son talon. Aucun int\u00e9r\u00eat donc \u00e0 se l\u00e2cher et risquer une rechute. Et visiblement, les signaux sont au vert. Ainsi, c\u2019est un <strong>Benjamin Cavet<\/strong> lucide et \u00e0 l\u2019\u00e9coute de son corps qui abordera ses quatri\u00e8mes Jeux Olympiques. Au moment de s\u2019\u00e9lancer, il ne sera certes pas favori, mais pourrait \u00eatre en mesure de tout l\u00e2cher pour cr\u00e9er la surprise.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/jo-milan-cortina-record-de-medailles-biathlon-en-feu-surprises-nos-paris-fous-pour-les-bleus\/\" class=\"vlp-link\" title=\"JO Milan-Cortina : record de m\u00e9dailles, biathlon en feu, surprises\u2026 nos paris fous pour les Bleus\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 792px;\" width=\"792\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-Milan-Cortina-record-de-medailles-biathlon-en-feu-surprises-nos-paris-fous-pour-les-Bleus.png\" class=\"attachment-800x445 size-800x445\" alt=\"JO Milan-Cortina record de m\u00e9dailles, biathlon en feu, surprises, nos paris fous pour les Bleus\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-Milan-Cortina-record-de-medailles-biathlon-en-feu-surprises-nos-paris-fous-pour-les-Bleus.png 1200w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-Milan-Cortina-record-de-medailles-biathlon-en-feu-surprises-nos-paris-fous-pour-les-Bleus-300x169.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-Milan-Cortina-record-de-medailles-biathlon-en-feu-surprises-nos-paris-fous-pour-les-Bleus-1024x575.png 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/JO-Milan-Cortina-record-de-medailles-biathlon-en-feu-surprises-nos-paris-fous-pour-les-Bleus-768x431.png 768w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">JO Milan-Cortina : record de m\u00e9dailles, biathlon en feu, surprises\u2026 nos paris fous pour les Bleus<\/div><div class=\"vlp-block-1 vlp-link-summary\">Dicodusport se risque au jeu des pronostics et vous livre ses paris pour la d\u00e9l\u00e9gation fran\u00e7aise.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Oscar Lombardot (biathlon)<\/h2>\n<p style=\"text-align: justify;\">Difficile d\u2019associer \u00ab biathlon \u00bb et \u00ab surprise potentielle \u00bb dans la m\u00eame phrase. Pourtant, <a href=\"https:\/\/dicodusport.fr\/blog\/la-question-qui-fache-lombardot-doit-il-remplacer-jacquelin-sur-le-relais-masculin-des-jo-2026\/\"><strong>Oscar Lombardot<\/strong><\/a> peut pr\u00e9tendre cr\u00e9er la surprise \u00e0 Antholz-Anterselva. Depuis son retour en Coupe du monde \u00e0 <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-hochfilzen-2025-programme-horaires-et-resultats\/\">Hochfilzen<\/a> en d\u00e9cembre, le Fran\u00e7ais ne cesse de monter en puissance.<\/p>\n<p style=\"text-align: justify;\">L\u2019\u00e9tape de <a href=\"https:\/\/dicodusport.fr\/blog\/biathlon-ruhpolding-2026-programme-horaires-et-resultats\/\">Ruhpolding<\/a>, mi-janvier, semble lui avoir permis de franchir un cap. Appel\u00e9 de derni\u00e8re minute sur le relais, il a sign\u00e9 un passage remarquable malgr\u00e9 trente kilom\u00e8tres disput\u00e9s le matin m\u00eame. Deux jours plus tard, il terminait quatorzi\u00e8me du sprint, une place qui pourrait sembler anodine mais qui ne l\u2019est pas.<\/p>\n<p style=\"text-align: justify;\">En effet, <strong>Lombardot<\/strong> a r\u00e9alis\u00e9 un troisi\u00e8me tour impressionnant, parvenant \u00e0 tenir les skis de <strong>Sebastian Samuelsson<\/strong>, vainqueur et auteur du meilleur temps de ski. C\u2019est toutefois \u00e0 Nove Mesto, le 22 janvier, que le jeune Fran\u00e7ais a sign\u00e9 sa plus belle performance.<\/p>\n<p style=\"text-align: justify;\">Une quatri\u00e8me place sur l\u2019individuel court, malgr\u00e9 une faute qui lui co\u00fbte un premier podium au plus haut niveau. Ce n\u2019est sans doute que partie remise. Cinqui\u00e8me dans la hi\u00e9rarchie fran\u00e7aise, il pourrait saisir sa chance en cas de contre-performance de l\u2019un des quatre devant lui. Et ensuite, qui sait ?<\/p>\n<h2 style=\"text-align: justify;\">Myl\u00e8ne Ballet-Baz (ski cross)<\/h2>\n<p style=\"text-align: justify;\">Pass\u00e9e du ski alpin au ski cross, <strong>Myl\u00e8ne Ballet-Baz<\/strong> a acquis depuis 2020 une solide exp\u00e9rience en Coupe du monde. Il lui aura n\u00e9anmoins fallu attendre son trente-huiti\u00e8me d\u00e9part pour d\u00e9crocher son premier podium. <a href=\"https:\/\/dicodusport.fr\/blog\/les-bleus-du-skicross-demarrent-fort-a-val-thorens-mylene-ballet-baz-et-youri-kergomard-duplessis-sur-le-podium\/\">C\u2019\u00e9tait \u00e0 Val Thorens en d\u00e9cembre<\/a>. La skieuse de 24 ans fait d\u00e9sormais preuve d\u2019une belle r\u00e9gularit\u00e9, comme en t\u00e9moignent ses trois tops 10 cette saison. Aux Jeux, elle ne sera pas favorite face \u00e0 des concurrentes de la trempe de <strong>Sandra Naeslund<\/strong>, <strong>Fanny Smith<\/strong>, <strong>Daniela Maier<\/strong> ou encore <strong>Marielle Berger-Sabbatel<\/strong>, mais elle pourrait surprendre.<\/p>\n<p style=\"text-align: justify;\">Le ski cross a cette facult\u00e9 d\u2019offrir un spectacle ultra t\u00e9l\u00e9g\u00e9nique, avec des sc\u00e9narios parfois impr\u00e9visibles. Si elle peut b\u00e9n\u00e9ficier d\u2019al\u00e9as de course, la Fran\u00e7aise cherchera avant tout \u00e0 passer les tours \u00e0 la r\u00e9guli\u00e8re, gr\u00e2ce \u00e0 sa glisse, son flair et l\u2019autorit\u00e9 n\u00e9cessaire pour se faire une place. Dans son sillage, on pourrait \u00e9galement retrouver <strong>Jade Grillet-Aubert<\/strong> et <strong>Anouck Errard<\/strong>, elles aussi pr\u00eates \u00e0 tout pour cr\u00e9er la surprise.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">PODIUM \u00c0 DOMICILE ! \ud83c\uddeb\ud83c\uddf7<\/p>\n<p>La grosse perf&rsquo; de Myl\u00e8ne Ballet-Baz, 3e, qui vient s&rsquo;offrir son tout premier podium en coupe du monde \u00e0 Val Thorens !<br \/>\nLa saison est lanc\u00e9e \ud83e\udd29<\/p>\n<p>\ud83d\udcf8 Agence Zoom <a href=\"https:\/\/t.co\/doOmGFeMGp\">pic.twitter.com\/doOmGFeMGp<\/a><\/p>\n<p>\u2014 FFS &#8211; F\u00e9d\u00e9ration Fran\u00e7aise de Ski (@FedFranceSki) <a href=\"https:\/\/twitter.com\/FedFranceSki\/status\/1999121708259647602?ref_src=twsrc%5Etfw\">December 11, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Mais encore&#8230;<\/h2>\n<p style=\"text-align: justify;\">Ils sont loin d\u2019\u00eatre favoris, mais tenteront eux aussi de cr\u00e9er la surprise. C\u2019est le cas du <strong>relais femmes en short-track<\/strong>, de <strong>Violette Braun<\/strong> (3 000 m) et de <strong>Mathieu Belloir<\/strong> (mass start) en patinage de vitesse, des <strong>descendeurs fran\u00e7ais<\/strong> et des <strong>Bleus du combin\u00e9 alpin<\/strong> en ski alpin, de <strong>Valentin Foubert<\/strong> en saut \u00e0 ski, des <strong>Bleus align\u00e9s sur le sprint par \u00e9quipes<\/strong> en ski de fond et de l\u2019ensemble des <strong>repr\u00e9sentants masculins du snowboard cross<\/strong>. La fronti\u00e8re entre surprise potentielle et chance cr\u00e9dible de m\u00e9daille est parfois t\u00e9nue. En r\u00e9sum\u00e9, l\u2019\u00e9quipe de France dispose de nombreuses cartes pour r\u00e9aliser de tr\u00e8s beaux Jeux Olympiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.<\/p>\n","protected":false},"author":91,"featured_media":643722,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[44003],"tags":[16878,46887,46888,47094,24],"class_list":["post-640254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-2026","tag-breve","tag-jeux-olympiques-2026","tag-jo-2026","tag-jo-dhiver","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&#039;hiver 2026<\/title>\n<meta name=\"description\" content=\"Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&#039;hiver 2026\" \/>\n<meta property=\"og:description\" content=\"Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T17:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T15:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Victor Clot-Amiot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&#039;hiver 2026\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/VictorClotAmiot\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/\"},\"author\":{\"name\":\"Victor Clot-Amiot\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/b623199cba9ba90fe84a3d16e9282360\"},\"headline\":\"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&rsquo;hiver 2026\",\"datePublished\":\"2026-02-03T17:00:27+00:00\",\"dateModified\":\"2026-02-04T15:13:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/\"},\"wordCount\":1653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png\",\"keywords\":[\"br\u00e8ve\",\"Jeux Olympiques 2026\",\"JO 2026\",\"JO d'hiver\",\"sport\"],\"articleSection\":[\"JO d'hiver 2026\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/\",\"name\":\"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png\",\"datePublished\":\"2026-02-03T17:00:27+00:00\",\"dateModified\":\"2026-02-04T15:13:31+00:00\",\"description\":\"Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png\",\"width\":1200,\"height\":674,\"caption\":\"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&rsquo;hiver 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/b623199cba9ba90fe84a3d16e9282360\",\"name\":\"Victor Clot-Amiot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_20190826_114722-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_20190826_114722-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_20190826_114722-150x150.jpg\",\"caption\":\"Victor Clot-Amiot\"},\"description\":\"Passionn\u00e9 de sport depuis toujours, un jour \u00e0 l'adolescence mes parents m'ont dit : \\\"quitte \u00e0 passer ton temps \u00e0 regarder du sport, au moins va le voir en vrai\\\" ! Depuis, cette remarque ne m'a plus quitt\u00e9 et je passe une grande partie de mon temps libre \u00e0 assister \u00e0 des comp\u00e9titions de tous sports. Je m\u00eale d'ailleurs mes deux passions, le sport et les voyages afin de faire une pierre deux coups ! Outre l'US Open ou l'Euro 2021 par exemple, j'ai assist\u00e9 cet \u00e9t\u00e9 aux Mondiaux d'athl\u00e9tisme \u00e0 Budapest. Mon plus gros coup dur est et restera les JO 2020-2021 pour lesquels j'avais r\u00e9serv\u00e9 17 \u00e9preuves. La suite, vous la connaissez...\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/VictorClotAmiot\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/victor-clot-amiot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026","description":"Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026","og_description":"Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.","og_url":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-02-03T17:00:27+00:00","article_modified_time":"2026-02-04T15:13:31+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png","type":"image\/png"}],"author":"Victor Clot-Amiot","twitter_card":"summary_large_image","twitter_title":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026","twitter_creator":"@https:\/\/x.com\/VictorClotAmiot","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/"},"author":{"name":"Victor Clot-Amiot","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/b623199cba9ba90fe84a3d16e9282360"},"headline":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&rsquo;hiver 2026","datePublished":"2026-02-03T17:00:27+00:00","dateModified":"2026-02-04T15:13:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/"},"wordCount":1653,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png","keywords":["br\u00e8ve","Jeux Olympiques 2026","JO 2026","JO d'hiver","sport"],"articleSection":["JO d'hiver 2026"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/","url":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/","name":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png","datePublished":"2026-02-03T17:00:27+00:00","dateModified":"2026-02-04T15:13:31+00:00","description":"Outsiders, talents \u00e9mergents, profils inattendus : d\u00e9couvrez les athl\u00e8tes fran\u00e7ais capables de cr\u00e9er la surprise lors des Jeux Olympiques de 2026 \u00e0 Milan-Cortina.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-JO-dhiver-2026.png","width":1200,"height":674,"caption":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d'hiver 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ces-athletes-francais-qui-peuvent-dejouer-les-pronostics-aux-jo-dhiver-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ces athl\u00e8tes fran\u00e7ais qui peuvent d\u00e9jouer les pronostics aux JO d&rsquo;hiver 2026"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/b623199cba9ba90fe84a3d16e9282360","name":"Victor Clot-Amiot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/IMG_20190826_114722-150x150.jpg","caption":"Victor Clot-Amiot"},"description":"Passionn\u00e9 de sport depuis toujours, un jour \u00e0 l'adolescence mes parents m'ont dit : \"quitte \u00e0 passer ton temps \u00e0 regarder du sport, au moins va le voir en vrai\" ! Depuis, cette remarque ne m'a plus quitt\u00e9 et je passe une grande partie de mon temps libre \u00e0 assister \u00e0 des comp\u00e9titions de tous sports. Je m\u00eale d'ailleurs mes deux passions, le sport et les voyages afin de faire une pierre deux coups ! Outre l'US Open ou l'Euro 2021 par exemple, j'ai assist\u00e9 cet \u00e9t\u00e9 aux Mondiaux d'athl\u00e9tisme \u00e0 Budapest. Mon plus gros coup dur est et restera les JO 2020-2021 pour lesquels j'avais r\u00e9serv\u00e9 17 \u00e9preuves. La suite, vous la connaissez...","sameAs":["https:\/\/x.com\/https:\/\/x.com\/VictorClotAmiot"],"url":"https:\/\/dicodusport.fr\/blog\/author\/victor-clot-amiot\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=640254"}],"version-history":[{"count":6,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640254\/revisions"}],"predecessor-version":[{"id":643911,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640254\/revisions\/643911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/643722"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=640254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=640254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=640254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}