{"id":640774,"date":"2026-01-23T18:42:55","date_gmt":"2026-01-23T17:42:55","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=640774&#038;preview=true&#038;preview_id=640774"},"modified":"2026-01-23T18:42:55","modified_gmt":"2026-01-23T17:42:55","slug":"oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/","title":{"rendered":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RALLYE MONTE-CARLO WRC 2026 &#8211; Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l&rsquo;issue d&rsquo;une nouvelle journ\u00e9e dantesque. \u00c0 plus d&rsquo;une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d&rsquo;Evans.<\/em><\/strong><\/p>\n<ul>\n<li><strong>\u00c0 ce sujet \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/rallye-monte-carlo-2026-programme-horaires-et-resultats\/\">Rallye Monte-Carlo 2026 : Programme, Horaires et R\u00e9sultats<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Oliver Solberg poursuit son r\u00e9cital avant de g\u00e9rer<\/h2>\n<p style=\"text-align: justify;\">Brillant au milieu du chaos hier, <strong>Oliver Solberg<\/strong> (Toyota) n\u2019a pas ralenti son incroyable cadence en profitant \u00e0 fond de sa bonne position de d\u00e9part (8\u00e8me). S\u2019il a l\u00e2ch\u00e9 du lest \u00e0 la fin de l\u2019ES5 en \u00e9tant victime d\u2019une crevaison tardive, il a compens\u00e9 en d\u00e9crochant haut la main la victoire sur les deux autres sp\u00e9ciales matinales pour poss\u00e9der plus d\u2019une minute d\u2019avance sur <strong>Elfyn Evans<\/strong> (Toyota).<\/p>\n<ul>\n<li><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-survole-la-premiere-journee-du-rallye-de-monte-carlo-sebastien-ogier-relegue-a-plus-dune-minute\/\">Oliver Solberg survole la premi\u00e8re journ\u00e9e du rallye de Monte-Carlo, S\u00e9bastien Ogier rel\u00e9gu\u00e9 \u00e0 plus d\u2019une minute<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Il a ensuite continu\u00e9 \u00e0 prouver sa sup\u00e9riorit\u00e9 en signant un nouveau scratch dans une ES7 tr\u00e8s resserr\u00e9e. Plus discret dans une fin de journ\u00e9e d\u00e9licate, il caracole tout de m\u00eame toujours largement en t\u00eate du rallye \u00e0 mi-parcours avec plus d\u2019une minute d\u2019avance sur son dauphin (<strong>+1:08.4<\/strong>).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Mastering the Monte conditions \u2744\ufe0f<\/p>\n<p>What a drive so far by <a href=\"https:\/\/twitter.com\/OliverSolberg01?ref_src=twsrc%5Etfw\">@OliverSolberg01<\/a> and <a href=\"https:\/\/twitter.com\/EAERallying?ref_src=twsrc%5Etfw\">@EAERallying<\/a> \ud83d\udcaa<a href=\"https:\/\/twitter.com\/hashtag\/ToyotaGAZOORacing?src=hash&amp;ref_src=twsrc%5Etfw\">#ToyotaGAZOORacing<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/GRYaris?src=hash&amp;ref_src=twsrc%5Etfw\">#GRYaris<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/WRC?src=hash&amp;ref_src=twsrc%5Etfw\">#WRC<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RallyeMonteCarlo?src=hash&amp;ref_src=twsrc%5Etfw\">#RallyeMonteCarlo<\/a> \ud83c\uddf2\ud83c\udde8 <a href=\"https:\/\/t.co\/jboIbObU5R\">pic.twitter.com\/jboIbObU5R<\/a><\/p>\n<p>\u2014 TOYOTA GAZOO Racing WRT (@TGR_WRC) <a href=\"https:\/\/twitter.com\/TGR_WRC\/status\/2014743215400775725?ref_src=twsrc%5Etfw\">January 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Evans et Ogier \u00e0 la lutte pour la 2\u00e8me place, Hyundai en retrait<\/h2>\n<p style=\"text-align: justify;\">Loin derri\u00e8re le Su\u00e9dois volant, la bataille qui se dessinait d\u00e9j\u00e0 entre <strong>S\u00e9bastien Ogier<\/strong> (Toyota) et <strong>Elfyn Evans<\/strong> (Toyota) s\u2019est confirm\u00e9e. L\u2019un apr\u00e8s l\u2019autre, les deux hommes ont pris le dessus sur l\u2019autre en se tenant dans un mouchoir de poche, mais aussi en \u00e9vitant tout probl\u00e8me m\u00e9canique. Cependant, la fin de journ\u00e9e a vir\u00e9 \u00e0 son avantage. Sur la longue ES8 de plus de 28km, puis une ES9 aux conditions dantesques en nocturne, le Fran\u00e7ais a sign\u00e9 les scratchs, ce qui lui a permis de revenir dans le short de son rival (+6.5).<\/p>\n<ul>\n<li><strong>\u00c0 ce propos \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/rallye-monte-carlo-2026-classement-general-en-direct\/\">Rallye Monte-Carlo 2026 \u2013 Classement g\u00e9n\u00e9ral en direct<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Alors qu\u2019il tenait la corde pour jouer le r\u00f4le d\u2019arbitre au milieu des Toyota, <strong>Thierry Neuville<\/strong> (Hyundai) a altern\u00e9 le chaud et le froid. Capable de tenir le rythme sur certaines sp\u00e9ciales, mais aussi de conc\u00e9der des secondes par dizaines sur d\u2019autres, il a fini par l\u00e2cher trois minutes en sortant de route sur l&rsquo;ES9. Une erreur qui fait voler en \u00e9clats un potentiel podium, mais qui le fait \u00e9galement glisser en 5\u00e8me position du g\u00e9n\u00e9ral.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">This is classic Rallye Monte Carlo \ud83e\udd0c\ud83c\udffb<a href=\"https:\/\/twitter.com\/hashtag\/WRC?src=hash&amp;ref_src=twsrc%5Etfw\">#WRC<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/RallyeMonteCarlo?src=hash&amp;ref_src=twsrc%5Etfw\">#RallyeMonteCarlo<\/a> \ud83c\uddf2\ud83c\udde8 <a href=\"https:\/\/t.co\/xill2F7xKZ\">pic.twitter.com\/xill2F7xKZ<\/a><\/p>\n<p>\u2014 FIA World Rally Championship (@OfficialWRC) <a href=\"https:\/\/twitter.com\/OfficialWRC\/status\/2014686079920574677?ref_src=twsrc%5Etfw\">January 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Pas m\u00e9nag\u00e9, Fourmaux passe au travers des gouttes, le cauchemar de Katsuta<\/h2>\n<p style=\"text-align: justify;\"><strong>Adrien Fourmaux<\/strong> (Hyundai) a en effet r\u00e9ussi \u00e0 la surpasser au terme d&rsquo;une nouvelle journ\u00e9e \u00e9prouvante. Malgr\u00e9 un probl\u00e8me de frein \u00e0 main qui lui a co\u00fbt\u00e9 de pr\u00e9cieuses secondes dans les \u00e9pingles finales de l\u2019ES7, mais aussi une p\u00e9nalit\u00e9 de 30 secondes apr\u00e8s s\u2019\u00eatre pr\u00e9sent\u00e9 au retard de l\u2019ES8, le Fran\u00e7ais a b\u00e9n\u00e9fici\u00e9 des malheurs de ses camarades. En d\u00e9pit de ses propres difficult\u00e9s, et en accusant plus de cinq minutes de retard sur la t\u00eate, il s&#8217;empare de la 4\u00e8me position avec une minute d&rsquo;avance sur Neuville !<\/p>\n<p style=\"text-align: justify;\">En revanche, apr\u00e8s<strong> Gr\u00e9goire Munster<\/strong> (M-Sport) et <strong>Sami Pajari<\/strong> (Toyota) hier, <strong>Takamoto Katsuta<\/strong> (Toyota) a quitt\u00e9 le Top 10 du g\u00e9n\u00e9ral en devant boucler plus de deux sp\u00e9ciales sans direction assist\u00e9e. D\u00e9j\u00e0 victime de deux crevaisons pr\u00e9c\u00e9demment, le Japonais vit un cauchemar. D\u00e9j\u00e0 \u00e9cart\u00e9 du g\u00e9n\u00e9ral, <strong>Joshua McErlean<\/strong> (M-Sport) a carr\u00e9ment termin\u00e9 dans un foss\u00e9 lors de l&rsquo;ES9.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">They&rsquo;re called co-drivers for a reason \ud83e\udd1d<a href=\"https:\/\/twitter.com\/hashtag\/WRC?src=hash&amp;ref_src=twsrc%5Etfw\">#WRC<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/RallyeMonteCarlo?src=hash&amp;ref_src=twsrc%5Etfw\">#RallyeMonteCarlo<\/a> \ud83c\uddf2\ud83c\udde8 <a href=\"https:\/\/t.co\/ERQu5OyZHH\">pic.twitter.com\/ERQu5OyZHH<\/a><\/p>\n<p>\u2014 FIA World Rally Championship (@OfficialWRC) <a href=\"https:\/\/twitter.com\/OfficialWRC\/status\/2014730369375826108?ref_src=twsrc%5Etfw\">January 23, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">En cons\u00e9quence, les \u00e9carts sont abyssaux, mais rien n\u2019est encore fig\u00e9. En raison des conditions climatiques changeantes encore attendues sur les deux derniers jours, de nombreuses cartes peuvent \u00eatre rabattues.<\/p>\n<h3>\u00c0 lire aussi<\/h3>\n<ul>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/rallye-monte-carlo-2026-a-quelle-heure-et-sur-quelle-chaine-tv\/\"><strong>Rallye Monte-Carlo 2026 : \u00c0 quelle heure et sur quelle cha\u00eene TV<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/rallye-wrc-2026-le-calendrier-complet\/\"><strong>Rallye WRC 2026 \u2013 Le calendrier complet<\/strong><\/a><\/li>\n<\/ul>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -14px; top: 40.9091px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RALLYE MONTE-CARLO WRC 2026 &#8211; Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l&rsquo;issue d&rsquo;une nouvelle journ\u00e9e dantesque. \u00c0 plus d&rsquo;une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d&rsquo;Evans.<\/p>\n","protected":false},"author":55,"featured_media":640784,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47088],"tags":[16878,3861,2235,13750],"class_list":["post-640774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rallye-wrc","tag-breve","tag-rallye-wrc","tag-wrc","tag-wrc-monte-carlo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo<\/title>\n<meta name=\"description\" content=\"RALLYE MONTE-CARLO WRC 2026 - Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l&#039;issue d&#039;une nouvelle journ\u00e9e dantesque. \u00c0 plus d&#039;une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d&#039;Evans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo\" \/>\n<meta property=\"og:description\" content=\"RALLYE MONTE-CARLO WRC 2026 - Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l&#039;issue d&#039;une nouvelle journ\u00e9e dantesque. \u00c0 plus d&#039;une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d&#039;Evans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T17:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo\",\"datePublished\":\"2026-01-23T17:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\"},\"wordCount\":758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png\",\"keywords\":[\"br\u00e8ve\",\"Rallye WRC\",\"WRC\",\"WRC Monte-Carlo\"],\"articleSection\":[\"Rallye WRC\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\",\"name\":\"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png\",\"datePublished\":\"2026-01-23T17:42:55+00:00\",\"description\":\"RALLYE MONTE-CARLO WRC 2026 - Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l'issue d'une nouvelle journ\u00e9e dantesque. \u00c0 plus d'une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d'Evans.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png\",\"width\":1200,\"height\":674,\"caption\":\"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo","description":"RALLYE MONTE-CARLO WRC 2026 - Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l'issue d'une nouvelle journ\u00e9e dantesque. \u00c0 plus d'une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d'Evans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/","og_locale":"fr_FR","og_type":"article","og_title":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo","og_description":"RALLYE MONTE-CARLO WRC 2026 - Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l'issue d'une nouvelle journ\u00e9e dantesque. \u00c0 plus d'une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d'Evans.","og_url":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2026-01-23T17:42:55+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo","datePublished":"2026-01-23T17:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/"},"wordCount":758,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png","keywords":["br\u00e8ve","Rallye WRC","WRC","WRC Monte-Carlo"],"articleSection":["Rallye WRC"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/","url":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/","name":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png","datePublished":"2026-01-23T17:42:55+00:00","description":"RALLYE MONTE-CARLO WRC 2026 - Oliver Solberg a solidement conserv\u00e9 la t\u00eate du g\u00e9n\u00e9ral \u00e0 l'issue d'une nouvelle journ\u00e9e dantesque. \u00c0 plus d'une minute, S\u00e9bastien Ogier se rapproche de la 2\u00e8me place d'Evans.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2026\/01\/Oliver-Solberg-seul-au-monde-Sebastien-Ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-Monte-Carlo.png","width":1200,"height":674,"caption":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/oliver-solberg-seul-au-monde-sebastien-ogier-se-revolte-le-resume-de-la-2eme-journee-du-rallye-de-monte-carlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Oliver Solberg seul au monde, S\u00e9bastien Ogier se r\u00e9volte : le r\u00e9sum\u00e9 de la 2\u00e8me journ\u00e9e du rallye de Monte-Carlo"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=640774"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640774\/revisions"}],"predecessor-version":[{"id":640787,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/640774\/revisions\/640787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/640784"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=640774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=640774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=640774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}